{"id":41473,"date":"2023-08-06T19:57:09","date_gmt":"2023-08-06T17:57:09","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/"},"modified":"2023-08-06T19:57:09","modified_gmt":"2023-08-06T17:57:09","slug":"afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/","title":{"rendered":"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/64cfc38a48fbef06fa730308.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der AfD-Spitzenkandidat zur Europawahl, Maximilian Krah, bezeichnete Washington als Urheber der Explosionen an den Nord-Stream-Gasleitungen. Krah betonte, die Pipelines geh\u00f6rten zur kritischen Infrastruktur f\u00fcr Deutschland.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Maximilian Krah, der Spitzenkandidat der Alternative f\u00fcr Deutschland (AfD) f\u00fcr die Wahlen zum Europ\u00e4ischen Parlament im Jahr 2024, hat die USA f\u00fcr die Sabotage der Gaspipelines Nord Stream und Nord Stream 2 verantwortlich gemacht. Seine Auffassung brachte der Politiker am Rande des AfD-Kongresses in Magdeburg zum Ausdruck. W\u00f6rtlich hie\u00df es:<\/p>\n<blockquote>\n<p><em>&#8220;Nord Stream wurde gesprengt. Das hei\u00dft, kritische Infrastruktur, von der die Wettbewerbsf\u00e4higkeit der deutschen Industrie abh\u00e4ngt, ist vor unseren Augen weggesprengt worden. Jetzt habe ich immer noch genug Kontakte in die USA, dass mir meine amerikanischen Freunde sagen k\u00f6nnen: Nat\u00fcrlich waren es die Vereinigten Staaten, wer sonst?&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Am 27. September 2022 meldete die Nord Stream AG &#8220;noch nie dagewesene Sch\u00e4den&#8221; an den Pipelines Nord Stream und Nord Stream 2. Schwedische Seismologen hatten einen Tag zuvor, am 26. September, zwei Explosionen registriert. Daraufhin leitete die russische Generalstaatsanwaltschaft ein Verfahren wegen eines internationalen Terroranschlags ein. Auch in Deutschland wurden Ermittlungen aufgenommen.<\/p>\n<p>Im Februar berichtete der auf investigativen Journalismus spezialisierte US-Publizist Seymour Hersh in seinem Artikel unter Berufung auf eine Quelle, dass im Juni 2022 unter dem Deckmantel der BALTOPS-\u00dcbung von Tauchern der US-Marine mit Unterst\u00fctzung norwegischer Spezialisten Sprengs\u00e4tze unter russischen Gaspipelines platziert worden seien. Laut Hersh sei die Entscheidung zur Durchf\u00fchrung der Sabotage von US-Pr\u00e4sident Joe Biden nach neunmonatigen Diskussionen mit den nationalen Sicherheitsbeamten der Regierung getroffen worden. Das Wei\u00dfe Haus dementiert diese Informationen kategorisch.<\/p>\n<p>Sp\u00e4ter berichteten deutsche und US-amerikanische Medien unter Berufung auf Quellen \u00fcber eine &#8220;proukrainische Gruppe&#8221;, die an den Bombenanschl\u00e4gen beteiligt gewesen sein soll. Die ukrainischen Beh\u00f6rden streiten jede Beteiligung ab.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/kurz.rt.com\/3r0q\">Anschl\u00e4ge auf Nord Stream: D\u00e4nemark legt dem UN-Sicherheitsrat Ermittlungsstand vor<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/177162-afd-spitzenkandidat-hinter-nord-stream\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der AfD-Spitzenkandidat zur Europawahl, Maximilian Krah, bezeichnete Washington als Urheber der Explosionen an den Nord-Stream-Gasleitungen. Krah betonte, die Pipelines geh\u00f6rten zur kritischen Infrastruktur f\u00fcr Deutschland. Maximilian Krah, der Spitzenkandidat der Alternative f\u00fcr Deutschland (AfD) f\u00fcr die Wahlen zum Europ\u00e4ischen Parlament im Jahr 2024, hat die USA f\u00fcr die Sabotage der Gaspipelines Nord Stream und Nord [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":41474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1691344959"],"wp_automatic_camp":["217"],"77785b8c56de2e3b3bb813602019d3c5":["AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA"],"original_link":["https:\/\/de.rt.com\/international\/177162-afd-spitzenkandidat-hinter-nord-stream\/"],"_thumbnail_id":["41474"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-08-06 20:03:41\";}"],"jnews_social_counter_last_update":["1778581559"]},"categories":[19,23],"tags":[47485,4440,47486,33515,6148,193],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA\" \/>\n<meta property=\"og:description\" content=\"Der AfD-Spitzenkandidat zur Europawahl, Maximilian Krah, bezeichnete Washington als Urheber der Explosionen an den Nord-Stream-Gasleitungen. Krah betonte, die Pipelines geh\u00f6rten zur kritischen Infrastruktur f\u00fcr Deutschland. Maximilian Krah, der Spitzenkandidat der Alternative f\u00fcr Deutschland (AfD) f\u00fcr die Wahlen zum Europ\u00e4ischen Parlament im Jahr 2024, hat die USA f\u00fcr die Sabotage der Gaspipelines Nord Stream und Nord [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-06T17:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA\",\"datePublished\":\"2023-08-06T17:57:09+00:00\",\"dateModified\":\"2023-08-06T17:57:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg\",\"keywords\":[\"AfDSpitzenkandidat\",\"hinter\",\"Krah\",\"NordStreamSabotage\",\"stecken\",\"USA\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/\",\"name\":\"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg\",\"datePublished\":\"2023-08-06T17:57:09+00:00\",\"dateModified\":\"2023-08-06T17:57:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg\",\"width\":460,\"height\":259,\"caption\":\"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/","og_locale":"de_DE","og_type":"article","og_title":"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA","og_description":"Der AfD-Spitzenkandidat zur Europawahl, Maximilian Krah, bezeichnete Washington als Urheber der Explosionen an den Nord-Stream-Gasleitungen. Krah betonte, die Pipelines geh\u00f6rten zur kritischen Infrastruktur f\u00fcr Deutschland. Maximilian Krah, der Spitzenkandidat der Alternative f\u00fcr Deutschland (AfD) f\u00fcr die Wahlen zum Europ\u00e4ischen Parlament im Jahr 2024, hat die USA f\u00fcr die Sabotage der Gaspipelines Nord Stream und Nord [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-08-06T17:57:09+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA","datePublished":"2023-08-06T17:57:09+00:00","dateModified":"2023-08-06T17:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg","keywords":["AfDSpitzenkandidat","hinter","Krah","NordStreamSabotage","stecken","USA"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/","url":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/","name":"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg","datePublished":"2023-08-06T17:57:09+00:00","dateModified":"2023-08-06T17:57:09+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/AfD-Spitzenkandidat-Krah-Hinter-Nord-Stream-Sabotage-stecken-USA.jpg","width":460,"height":259,"caption":"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/afd-spitzenkandidat-krah-hinter-nord-stream-sabotage-stecken-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"AfD-Spitzenkandidat Krah: Hinter Nord-Stream-Sabotage stecken USA"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/41473"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=41473"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/41473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/41474"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=41473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=41473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=41473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}