{"id":40932,"date":"2023-07-27T18:05:17","date_gmt":"2023-07-27T16:05:17","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/"},"modified":"2023-07-27T18:05:17","modified_gmt":"2023-07-27T16:05:17","slug":"russlands-angebot-an-afrika-hilfe-zur-souveraenitaet","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/","title":{"rendered":"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t"},"content":{"rendered":"<div class=\"Text-root Text-type_1 \">\n                Das alles diene nur dazu, neue Abh\u00e4ngigkeiten zu erzeugen, ist die westliche Reaktion auf die Angebote, die Russland auf dem Russland-Afrika-Gipfel macht. Selbst aber ist man zu derartigen Angeboten nicht bereit, und das aus gutem Grund.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Dagmar Henn<\/em><\/p>\n<p>Logistikzentren, Unterst\u00fctzung bei der Landwirtschaft und beim Bau afrikanischer Eisenbahnen? Die Antwort darauf aus dem Westen steht schon fest: Russland will damit nur Abh\u00e4ngigkeiten schaffen &#8230;<\/p>\n<p>Aber wie steht es denn damit tats\u00e4chlich? Der einfachste Schritt, um zu bewerten, wo die Probleme und die Entwicklungsm\u00f6glichkeiten eines Landes liegen, ist ein Blick auf die Karten. Karten mit Rohstoffen wie Karten der Verkehrswege. Das Sch\u00f6ne an solchen Karten ist: Sie werden nicht nach einer Agenda erstellt, sondern sollen schlicht die Wirklichkeit so darstellen, wie sie ist.<\/p>\n<p>Nehmen wir eine <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/diercke.de\/content\/afrika-bergbau-978-3-14-100770-1-179-3-0\">Karte<\/a> mit Rohstoffen. Eine Tatsache sticht auf den ersten Blick ins Auge: Mit Ausnahme des s\u00fcdlichen Afrika sind die K\u00fcstenregionen auf diesen Rohstoffkarten absolut dominant. Viel leichter zu finden sind Karten, die landwirtschaftliche Produkte zeigen, dabei vor allem jene, die exportiert werden: Kakao, Erdn\u00fcsse, Palm\u00f6l, Baumwolle.<\/p>\n<p>Sobald man Karten zu Verkehrswegen sucht, st\u00f6\u00dft man bereits auf ideologische Pr\u00e4gungen. Ein sch\u00f6nes Beispiel <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/sciencev2.orf.at\/stories\/1764860\/index.html\">lieferte<\/a> die Wissenschaftssendung des <em>ORF<\/em> im Jahr 2015. Einen Bericht \u00fcber den Bau von insgesamt 53.000 Kilometern Stra\u00dfen in Afrika betitelte sie mit &#8220;Neue Stra\u00dfen bedrohen Afrikas Umwelt&#8221;. Zum Vergleich: Allein das bundesdeutsche Autobahnnetz hat eine Gesamtl\u00e4nge von 13.200 Kilometern. Die Fl\u00e4che des afrikanischen Kontinents betr\u00e4gt 30,2 Millionen Quadratkilometer, die Fl\u00e4che Deutschlands nur 357.588 Quadratkilometer. F\u00fcr eine vergleichbare Stra\u00dfendichte \u2013 nur der Autobahnen, wohlgemerkt \u2013 m\u00fcsste in Afrika grob eine Million Stra\u00dfenkilometer gebaut werden.<\/p>\n<p>Die Stra\u00dfenprojekte, so der damalige Beitrag, &#8220;zerschneiden Naturschutzgebiete und setzen bisher nur wenig besiedelte Gebiete einem hohen Umweltdruck aus&#8221;. Wie gesagt, wir reden von einem Kontinent, in den Deutschland fast hundertmal hineinpasst, und von ganzen 53.000 Kilometern Stra\u00dfe.<\/p>\n<p>Es ist ein alter Topos des Kolonialismus, der schon unter &#8220;Serengeti darf nicht sterben&#8221; und unter der \u00c4gide des WWF verkauft wurde. Die sch\u00f6nen exotischen Elefanten, Nash\u00f6rner und Giraffen, deren Lebensr\u00e4ume bedroht sind. Wenn man mit dem gleichen Ansatz auf Europa blickte, m\u00fcsste man einen breiten Korridor von Niedersachsen bis Wei\u00dfrussland von menschlicher Besiedlung r\u00e4umen, um den Lebensraum der Wisente wiederherzustellen. Niemand kommt auf diesen Gedanken, aber bezogen auf Afrika ist er v\u00f6llig nat\u00fcrlich.<\/p>\n<p>Die Karte, die mit der damaligen Sendung geliefert wird, zeigt auch, wie wenige Stra\u00dfen vorhanden sind, die den Kontinent wirklich queren. Das ist das Erbe der offenen Kolonialherrschaft: Jede Kolonialmacht hatte nur an einem Infrastrukturprojekt wirkliches Interesse, an dem Hafen, der die aus dem Land gezogenen G\u00fcter ins &#8220;Mutterland&#8221; brachte und dazu diente, etwas der eigenen Waren dort abzuwerfen. Verkehrswege, die die afrikanischen L\u00e4nder miteinander verbinden? Die wurden schon allein deshalb nicht gebaut, weil eine britische Kolonie neben einer franz\u00f6sischen, deutschen oder portugiesischen lag. Und nach der formellen Unabh\u00e4ngigkeit gelang es sehr schnell, die Kontrolle so weit wieder zu \u00fcbernehmen, dass Infrastrukturprojekte vor allem dazu dienten, die Schuldknechtschaft zu erhalten.<\/p>\n<p>Blicken wir auf die Karte der Verkehrswege. Ja, es gibt Verbindungen ins Innere. Aber diese Stra\u00dfen sind oft nur Lehmstra\u00dfen, also zu bestimmten Zeiten des Jahres nicht befahrbar, und im g\u00fcnstigsten Fall haben sie eine Spur pro Richtung. Sehr, sehr langsam werden innerhalb der L\u00e4nder Stra\u00dfen gebaut, die dem entsprechen, auf dem der europ\u00e4ische G\u00fcterverkehr l\u00e4uft, soweit er per Lkw abgewickelt wird, mehrspurige, geteerte Autobahnen auf einem soliden Fundament. Bahnlinien, die eine gr\u00f6\u00dfere Transportkapazit\u00e4t haben, gibt es wenige, und sie reichen nicht von einer Seite des Kontinents zur anderen. Es gibt Flugh\u00e4fen, aber nur wenige sind f\u00fcr gro\u00dfe Flugzeuge geeignet. Und bei jedem Blick auf eine dieser Karten darf man die Gr\u00f6\u00dfenordnung nicht vergessen. In den klein wirkenden Fl\u00e4chen zwischen zwei Stra\u00dfen k\u00f6nnte man die gesamte Bundesrepublik unterbringen.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64c26e4648fbef5c42673a5f.png 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64c26e4648fbef5c42673a5f.png 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64c26e4648fbef5c42673a5f.png 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64c26e4648fbef5c42673a5f.png 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64c26e4648fbef5c42673a5f.png\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64c26e4648fbef5c42673a5f.png\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Verkehrswege in Afrika<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Fanny Schertzer, CC BY-SA 3.0 , via Wikimedia Commons<\/span><\/span><\/figcaption><\/figure>\n<p>Was g\u00e4nzlich fehlt, sind Kanalverbindungen zwischen den Einzugsgebieten der gro\u00dfen Fl\u00fcsse. Deren Bedeutung untersch\u00e4tzt man gerne, auch, weil viele dieser Kan\u00e4le in Europa schon vor Jahrhunderten gebaut wurden. Entlang der Loire beispielsweise; und der erste Rhein-Main-Donau-Kanal geht schon auf Karl den Gro\u00dfen zur\u00fcck (\u00fcbrigens sollen die milit\u00e4rischen Lieferungen an die Ukraine \u00fcberwiegend \u00fcber Rhein und Donau laufen). Genauso wie das Stra\u00dfennetz, das sich von der Jungsteinzeit \u00fcber die R\u00f6mer bis heute schrittweise entwickelte, ist die Anwesenheit wirtschaftlich wichtiger Kan\u00e4leh\u00e4fen etwas, das meist gar nicht bewusst wahrgenommen wird. Sie sind eben einfach da.<\/p>\n<p>Aber die Bev\u00f6lkerungsdichte in Europa war schon lange weit h\u00f6her als in Afrika, und es ist letztlich die Zunahme der Bev\u00f6lkerung, die dazu f\u00fchrt, dass W\u00e4lder gerodet und Stra\u00dfen gebaut werden. Man kann die Spuren noch finden, wenn man einmal abfragt, wie viele St\u00e4dte mit dem Namen Neustadt es in Deutschland gibt. Es sind mehr als 40. Jede von ihnen begann als frisch gerodetes Siedlungsgebiet. Aber Afrikaner, die sind nun einmal daf\u00fcr da, uns Wei\u00dfen die unber\u00fchrte, menschenlose Umwelt zu liefern, weshalb sie selbstverst\u00e4ndlich das, was hier bereits vor Jahrhunderten geschah, nicht nachvollziehen d\u00fcrfen.<\/p>\n<p>Es gibt alte Handelswege durch Afrika, die Salzhandelsrouten durch die Sahara beispielsweise. Es gibt sogar Relikte antiker sudanesischer K\u00f6nigreiche im Osten, die darauf hinweisen, dass Handelsverbindungen bis in die Gegend der Stadt Benin in Westafrika bestanden. Aber diese Handelswege entwickelten sich ab einem bestimmten Punkt nicht weiter, und der Grund daf\u00fcr kam aus Europa.<\/p>\n<p>Westafrika etwa kennt urbane Kulturen l\u00e4nger als Mitteleuropa. Aber \u00fcber einen Zeitraum von mehr als zweihundert Jahren waren viele der Bewohner Handelsware, die \u00fcber den Atlantik hinweg verschifft wurde. Es ist bekannt, dass in der Regel die H\u00e4lfte der Gefangenen den Transport nicht \u00fcberlebte. Welche Folgen hat es f\u00fcr die Gesellschaften, wenn \u00fcber so eine lange Zeit kommerziell betriebene Sklavenjagd das bedeutendste Gesch\u00e4ft ist, und die europ\u00e4ischen Kunden ihren Anspruch auf die Ware mit milit\u00e4rischer \u00dcberlegenheit durchsetzen? Die K\u00fcstenbewohner hatten nur die Wahl, entweder Sklaven zu liefern oder selbst versklavt zu werden. Die Folge des Sklavenhandels waren von endlosen Kriegen gepr\u00e4gte Jahrhunderte.<\/p>\n<p>Nordafrika? Die Franzosen machten sich Mitte des 19. Jahrhunderts, absolut unverh\u00fcllt, daran, die Bev\u00f6lkerung Algeriens auszurotten, um Platz f\u00fcr franz\u00f6sische Siedler zu schaffen. Marokko war spanische Kolonie; Putschgeneral Francisco Franco stammte aus den spanischen Kolonialtruppen, die mit Bombenfliegern und Giftgas gegen die Kolonialbev\u00f6lkerung vorgingen. Und wer Wert darauf legt, dass es ihm wirklich \u00fcbel wird, kann sich mit den Belgiern im Kongo besch\u00e4ftigen.<\/p>\n<p>Es gibt sehr gro\u00dfe \u00c4hnlichkeiten zwischen dem Vorgehen der Kolonialm\u00e4chte und dem, was die Nazis in Europa taten, insbesondere dem Generalplan Ost. Aber Afrika hatte damit nicht nur zw\u00f6lf Jahre lang zu tun, sondern mehr als zwei Jahrhunderte. Wenn man sich der Verw\u00fcstungen bewusst ist, die angerichtet wurden, erkennt man, dass es nicht um mangelnde Entwicklung oder gar nicht vorhandene Entwicklungsf\u00e4higkeit geht, sondern darum, dass jede Entwicklung verhindert wurde.<\/p>\n<p>Es ist ziemlich genau bekannt, was man tun muss, damit sich ein Land entwickelt. Es braucht Stra\u00dfen, Stromnetze, Eisenbahnen. Es braucht Produktion, und zwar industrielle \u2013 bis heute ist im Afrika unterhalb der Sahara abgesehen von S\u00fcdafrika Burkina Faso das Land mit der h\u00f6chsten Industrialisierung. Das genau war der Grund f\u00fcr den Mord an Thomas Sankara. Es braucht alle Voraussetzungen f\u00fcr Souver\u00e4nit\u00e4t, und dazu geh\u00f6rt auch Ern\u00e4hrungssicherheit.<\/p>\n<p>Abgesehen von den Regionen, die vor allem f\u00fcr den Export produzieren, wie westafrikanische Kakaoplantagen, sind nach wie vor gro\u00dfe Gebiete in Afrika von Subsistenzlandwirtschaft gepr\u00e4gt. Die Exportpolitik etwa der EU trug immer wieder dazu bei, selbst diese Subsistenzwirtschaft noch zu gef\u00e4hrden, durch den Export von subventionierten H\u00fchnerteilen beispielsweise. Die Freihandelsvertr\u00e4ge, die aus Europa &#8220;angeboten&#8221; werden, f\u00fchren meist dazu, dass nicht nur die Entwicklung der Landwirtschaft nicht gef\u00f6rdert wird, sondern die vorhandene sich noch zur\u00fcckentwickelt. Warum? Das Ziel ist eben nicht die Souver\u00e4nit\u00e4t dieser L\u00e4nder, sondern ihre Abh\u00e4ngigkeit.<\/p>\n<p>Der Gebrauch von Fremdw\u00e4hrungen im Handel und bei Krediten ist ein weiterer wichtiger Punkt, um die Abh\u00e4ngigkeit zu erhalten. Man sieht das an der augenblicklichen Inflation. Auf dem Weltmarkt stiegen die Getreidepreise, was Importe wesentlich verteuert, die in Dollar bezahlt werden m\u00fcssen. Diese Inflation setzt sich im Landesinneren verst\u00e4rkt fort (aus einer globalen Inflation von acht Prozent werden vierzig oder f\u00fcnfzig), wodurch die heimische W\u00e4hrung an Wert verliert, was wiederum die Importe noch teurer macht. Kredite bei Institutionen wie dem IWF oder bei privaten Banken, die ebenfalls in Dollar nominiert sind, sind dementsprechend schwieriger abzul\u00f6sen, was zum Ausl\u00f6ser einer Krise der Staatsfinanzen wird.<\/p>\n<p>Wenn Handel und Kredite in Landesw\u00e4hrung stattfinden, sorgt das also f\u00fcr eine Stabilisierung. Die Wirkung ist \u00e4hnlich wie die eines Tauschhandels, den etwa die Sowjetunion \u00fcber Jahrzehnte mit Indien vollzog, \u00fcber Milliardenwerte \u00fcbrigens, was einen gewaltigen Beitrag dazu leistete, dass Indien nach der Unabh\u00e4ngigkeit eine Industrie aufbauen konnte.<\/p>\n<p>\u00dcbrigens hat Russland noch eine F\u00e4higkeit zu bieten. Es gibt kein Land der Erde, in dem die Suche nach Rohstoffen so systematisch und wissenschaftlich betrieben wurde wie in der Sowjetunion. Die ungeheure Fl\u00e4che der afrikanischen L\u00e4nder ist fast schon in sich eine Garantie daf\u00fcr, dass der Kontinent autark sein k\u00f6nnte, wenn seine Reicht\u00fcmer angemessen erschlossen und genutzt w\u00fcrden. Nicht die Erkundung, wohl jedoch die Erschlie\u00dfung ist aber abh\u00e4ngig von der Infrastruktur der Verkehrswege, denn wenn es n\u00f6tig ist, erst eine Stra\u00dfe zu bauen, um \u00fcberhaupt abbauen zu k\u00f6nnen, rentiert es sich sehr schnell nicht mehr.<\/p>\n<p>Aber zur\u00fcck zu der entscheidenden Frage: ist das, was Russland anbietet, von Nutzen f\u00fcr die afrikanischen L\u00e4nder? Die Antwort findet sich sehr schnell, wenn man die Frage anders formuliert. Warum haben bis heute die ehemaligen Kolonialm\u00e4chte nie angeboten, Handel in der Landesw\u00e4hrung zu treiben oder n\u00f6tigen sogar, wie Frankreich mit dem CFA-Franc, den L\u00e4ndern eine W\u00e4hrung auf? Es w\u00e4re technisch betrachtet kein Problem, den Handel entsprechend umzustellen. Es geschieht nicht, weil damit ein \u00f6konomischer Vorteil f\u00fcr die westlichen L\u00e4nder verloren ginge. Im Grunde muss man nur sehen, was die Kolonialm\u00e4chte nicht tun, um zu wissen, was den afrikanischen L\u00e4ndern helfen w\u00fcrde, ihr volles Potenzial zu entfalten. Die russischen Angebote sind auf jeden Fall ein Schritt in die richtige Richtung. Kein Wunder, dass den Kolonialm\u00e4chten der Schaum vor dem Mund steht.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.live\/meinung\/171070-afrikanische-jahrhundert\/\">Das afrikanische Jahrhundert<\/a>\u00a0<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/176353-russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das alles diene nur dazu, neue Abh\u00e4ngigkeiten zu erzeugen, ist die westliche Reaktion auf die Angebote, die Russland auf dem Russland-Afrika-Gipfel macht. Selbst aber ist man zu derartigen Angeboten nicht bereit, und das aus gutem Grund. Von Dagmar Henn Logistikzentren, Unterst\u00fctzung bei der Landwirtschaft und beim Bau afrikanischer Eisenbahnen? Die Antwort darauf aus dem Westen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":40933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1690474315"],"wp_automatic_camp":["217"],"d9672e25fa80f7af36f60525475e7e8a":["Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t"],"original_link":["https:\/\/de.rt.com\/meinung\/176353-russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/"],"_thumbnail_id":["40933"],"jnews_social_counter_last_update":["1778483192"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-07-27 18:12:56\";}"]},"categories":[19,23],"tags":[18099,4259,7571,142,20302,581],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t\" \/>\n<meta property=\"og:description\" content=\"Das alles diene nur dazu, neue Abh\u00e4ngigkeiten zu erzeugen, ist die westliche Reaktion auf die Angebote, die Russland auf dem Russland-Afrika-Gipfel macht. Selbst aber ist man zu derartigen Angeboten nicht bereit, und das aus gutem Grund. Von Dagmar Henn Logistikzentren, Unterst\u00fctzung bei der Landwirtschaft und beim Bau afrikanischer Eisenbahnen? Die Antwort darauf aus dem Westen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-27T16:05:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"792\" \/>\n\t<meta property=\"og:image:height\" content=\"764\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t\",\"datePublished\":\"2023-07-27T16:05:17+00:00\",\"dateModified\":\"2023-07-27T16:05:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\"},\"wordCount\":1791,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png\",\"keywords\":[\"Afrika\",\"Angebot\",\"Hilfe\",\"Russlands\",\"Souver\u00e4nit\u00e4t\",\"zur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\",\"name\":\"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png\",\"datePublished\":\"2023-07-27T16:05:17+00:00\",\"dateModified\":\"2023-07-27T16:05:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png\",\"width\":792,\"height\":764,\"caption\":\"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/","og_locale":"de_DE","og_type":"article","og_title":"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t","og_description":"Das alles diene nur dazu, neue Abh\u00e4ngigkeiten zu erzeugen, ist die westliche Reaktion auf die Angebote, die Russland auf dem Russland-Afrika-Gipfel macht. Selbst aber ist man zu derartigen Angeboten nicht bereit, und das aus gutem Grund. Von Dagmar Henn Logistikzentren, Unterst\u00fctzung bei der Landwirtschaft und beim Bau afrikanischer Eisenbahnen? Die Antwort darauf aus dem Westen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-07-27T16:05:17+00:00","og_image":[{"width":792,"height":764,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png","type":"image\/png"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t","datePublished":"2023-07-27T16:05:17+00:00","dateModified":"2023-07-27T16:05:17+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/"},"wordCount":1791,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png","keywords":["Afrika","Angebot","Hilfe","Russlands","Souver\u00e4nit\u00e4t","zur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/","url":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/","name":"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png","datePublished":"2023-07-27T16:05:17+00:00","dateModified":"2023-07-27T16:05:17+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Russlands-Angebot-an-Afrika-Hilfe-zur-Souveraenitaet.png","width":792,"height":764,"caption":"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russlands-angebot-an-afrika-hilfe-zur-souveraenitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russlands Angebot an Afrika: Hilfe zur Souver\u00e4nit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/40932"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=40932"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/40932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/40933"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=40932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=40932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=40932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}