{"id":40151,"date":"2023-07-14T20:33:35","date_gmt":"2023-07-14T18:33:35","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/"},"modified":"2023-07-14T20:33:35","modified_gmt":"2023-07-14T18:33:35","slug":"chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/","title":{"rendered":"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64b16aa7b480cc44ff1a1277.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Sprecherin des chinesischen Au\u00dfenministeriums Hua Chunying reagierte auf die \u00c4u\u00dferungen der NATO \u00fcber die angebliche Infragestellung von Werten durch die Politik in Peking. Sie erinnerte an die Bombardierung Jugoslawiens und auch den dabei erfolgten Angriff auf die chinesische Botschaft in Belgrad.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Das chinesische Au\u00dfenministerium reagierte auf das Kommuniqu\u00e9 der Nordatlantischen Allianz zu den Ergebnissen des ersten Tages des NATO-Gipfels, der am 11. Juli in Vilnius stattgefunden hatte. Die Sprecherin des chinesischen Au\u00dfenministeriums Hua Chunying kritisierte diese Erkl\u00e4rung und erinnerte dabei an die Bombardierung Jugoslawiens im Jahre 1999. Sie twitterte:<\/p>\n<blockquote>\n<p><em>&#8220;Wir haben die Blutschuld der NATO gegen\u00fcber dem chinesischen Volk f\u00fcr die Bombardierung der chinesischen Botschaft in Jugoslawien nicht vergessen. Die L\u00e4nder des asiatisch-pazifischen Raums hei\u00dfen keine Kriegsmaschinerie willkommen, schon gar nicht eine &#8216;asiatisch-pazifische Version der NATO&#8217;, die eine Blockkonfrontation oder einen neuen Kalten Krieg anheizt.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die NATO hatte in dem Kommuniqu\u00e9 behauptet, Chinas hege &#8220;Ambitionen und Zwangsma\u00dfnahmen, (die) unsere Interessen, unsere Sicherheit und unsere Werte infrage stellen&#8221; und beschuldigte China zugleich, &#8220;die auf Regeln basierende internationale Ordnung zu untergraben&#8221;. Der NATO-Block betonte:<\/p>\n<blockquote>\n<p><em>&#8220;Als Verb\u00fcndete arbeiten wir verantwortungsvoll zusammen, um die systemischen Herausforderungen, die China f\u00fcr die euro-atlantische Sicherheit darstellt, anzugehen und die F\u00e4higkeit der NATO, die Verteidigung und Sicherheit der Verb\u00fcndeten zu gew\u00e4hrleisten, nachhaltig zu sichern.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die NATO kritisierte in dem Kommuniqu\u00e9 auch die Zusammenarbeit zwischen Russland und China und forderte Peking auf, Russlands Sonderoperation in der Ukraine zu verurteilen. Die Milit\u00e4rallianz behauptete, sie sei offen f\u00fcr eine Zusammenarbeit mit China, werde aber ihre eigenen Interessen sch\u00fctzen.<\/p>\n<p>Die diplomatische Vertretung Chinas bei der Europ\u00e4ischen Union erkl\u00e4rte daraufhin, dass Peking seinerseits ebenfalls seine Interessen verteidigen werde und gegen die Osterweiterung der NATO-Allianz sei. Die chinesische diplomatische Vertretung stellte w\u00f6rtlich fest:<\/p>\n<blockquote>\n<p><em>&#8220;Jegliche Aktionen, die Chinas legitimen Rechten und Interessen schaden, werden entschieden abgelehnt.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die Diplomaten \u00e4u\u00dferten sich auch besorgt \u00fcber das Vorgehen der NATO &#8220;im Zusammenhang mit der derzeitigen Verschlechterung der internationalen Sicherheitslage&#8221;. Nach Ansicht der chinesischen Seite denke die NATO &#8220;nicht an ihre eigene Verantwortung&#8221; und versch\u00e4rfe die Konfrontation und die Spannungen durch \u00c4u\u00dferungen im atomaren Bereich.<\/p>\n<p>Auf dem letztj\u00e4hrigen NATO-Gipfel verabschiedete das atlantische B\u00fcndnis ein strategisches Konzept f\u00fcr das n\u00e4chste Jahrzehnt. Darin wurde China bereits als eine &#8220;systemische Herausforderung f\u00fcr die Welt&#8221; bezeichnet. Damals erinnerte Peking den Milit\u00e4rblock auch an dessen Angriffe auf die chinesische Botschaft in Jugoslawien. Der Sprecher des chinesischen Au\u00dfenministeriums Zhao Lijian sagte:<\/p>\n<blockquote>\n<p><em>&#8220;Die H\u00e4nde der NATO sind mit dem Blut der Menschen in der Welt befleckt.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Es geht um die Milit\u00e4roperation &#8220;Operation Allied Force&#8221; des NATO-Blocks gegen Jugoslawien, die vom 24. M\u00e4rz bis zum 10. Juni 1999 andauerte. Der Grund f\u00fcr die multinationale westliche Intervention war der ethnische Konflikt zwischen Albanern und Serben im Kosovo.<\/p>\n<p>Die Operation wurde vom damaligen Generalsekret\u00e4r der NATO Javier Solana verk\u00fcndet und ohne v\u00f6lkerrechtliche Genehmigung des UN-Sicherheitsrats durchgef\u00fchrt. Insgesamt wurden mehrere tausend Angriffe mit Bombern und Marschflugk\u00f6rpern durchgef\u00fchrt. Bei der Operation wurden im ehemaligen Jugoslawien etwa 3.000 Menschen get\u00f6tet und 5.000 Menschen verwundet. Mehr als 1.000 Menschen werden noch vermisst.<\/p>\n<p>Am 7. Mai 1999 zerst\u00f6rte im Rahmen dieser Intervention eine Bombe die chinesische Botschaft in Belgrad, wobei drei Menschen starben und 27 verletzt wurden. Sp\u00e4ter wurde der Anschlag seitens der NATO als &#8220;irrt\u00fcmlich&#8221; bezeichnet. Die USA zahlten als &#8220;Entsch\u00e4digung&#8221; 4,5 Millionen US-Dollar an die Verletzten und die Familien der Todesopfer.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.live\/international\/175067-china-warnt-nato-vor-erweiterung\/\">China warnt NATO vor Erweiterung nach Asien und in den Pazifik<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/175284-chinesisches-aussenministerium-erinnert-an-nato\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Sprecherin des chinesischen Au\u00dfenministeriums Hua Chunying reagierte auf die \u00c4u\u00dferungen der NATO \u00fcber die angebliche Infragestellung von Werten durch die Politik in Peking. Sie erinnerte an die Bombardierung Jugoslawiens und auch den dabei erfolgten Angriff auf die chinesische Botschaft in Belgrad. Das chinesische Au\u00dfenministerium reagierte auf das Kommuniqu\u00e9 der Nordatlantischen Allianz zu den Ergebnissen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":40152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1689360136"],"wp_automatic_camp":["217"],"9c441ebffeeb5825150fc6426dca1a24":["Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad"],"original_link":["https:\/\/de.rt.com\/international\/175284-chinesisches-aussenministerium-erinnert-an-nato\/"],"_thumbnail_id":["40152"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-07-14 20:43:25\";}"],"jnews_social_counter_last_update":["1788313343"]},"categories":[19,23],"tags":[16681,967,186,3713,6155,82,23552,46754],"class_list":["post-40151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-aussenministerium","tag-belgrad","tag-botschaft","tag-chinesischen","tag-chinesisches","tag-der","tag-erinnert","tag-natobombardierung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad\" \/>\n<meta property=\"og:description\" content=\"Die Sprecherin des chinesischen Au\u00dfenministeriums Hua Chunying reagierte auf die \u00c4u\u00dferungen der NATO \u00fcber die angebliche Infragestellung von Werten durch die Politik in Peking. Sie erinnerte an die Bombardierung Jugoslawiens und auch den dabei erfolgten Angriff auf die chinesische Botschaft in Belgrad. Das chinesische Au\u00dfenministerium reagierte auf das Kommuniqu\u00e9 der Nordatlantischen Allianz zu den Ergebnissen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-14T18:33:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad\",\"datePublished\":\"2023-07-14T18:33:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/\"},\"wordCount\":603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg\",\"keywords\":[\"Au\u00dfenministerium\",\"Belgrad\",\"Botschaft\",\"chinesischen\",\"Chinesisches\",\"der\",\"ERINNERT\",\"NATOBombardierung\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/\",\"name\":\"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg\",\"datePublished\":\"2023-07-14T18:33:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg\",\"width\":460,\"height\":259,\"caption\":\"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/","og_locale":"de_DE","og_type":"article","og_title":"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad","og_description":"Die Sprecherin des chinesischen Au\u00dfenministeriums Hua Chunying reagierte auf die \u00c4u\u00dferungen der NATO \u00fcber die angebliche Infragestellung von Werten durch die Politik in Peking. Sie erinnerte an die Bombardierung Jugoslawiens und auch den dabei erfolgten Angriff auf die chinesische Botschaft in Belgrad. Das chinesische Au\u00dfenministerium reagierte auf das Kommuniqu\u00e9 der Nordatlantischen Allianz zu den Ergebnissen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-07-14T18:33:35+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad","datePublished":"2023-07-14T18:33:35+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/"},"wordCount":603,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg","keywords":["Au\u00dfenministerium","Belgrad","Botschaft","chinesischen","Chinesisches","der","ERINNERT","NATOBombardierung"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/","url":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/","name":"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg","datePublished":"2023-07-14T18:33:35+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Chinesisches-Aussenministerium-erinnert-an-NATO-Bombardierung-der-chinesischen-Botschaft-in-Belgrad.jpg","width":460,"height":259,"caption":"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/chinesisches-aussenministerium-erinnert-an-nato-bombardierung-der-chinesischen-botschaft-in-belgrad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Chinesisches Au\u00dfenministerium erinnert an NATO-Bombardierung der chinesischen Botschaft in Belgrad"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/40151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=40151"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/40151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/40152"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=40151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=40151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=40151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}