{"id":39965,"date":"2023-07-12T13:05:32","date_gmt":"2023-07-12T11:05:32","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/"},"modified":"2023-07-12T13:05:32","modified_gmt":"2023-07-12T11:05:32","slug":"nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/","title":{"rendered":"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64ae7d59b480cc63044a9e53.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das nordkoreanische Milit\u00e4r hat am Mittwoch mit dem Start einer ballistischen Interkontinentalrakete einen Rekord aufgestellt. Das Projektil legte eine Strecke von rund 1.000 Kilometern zur\u00fcck und war 74 Minuten in der Luft, bevor es ins Japanische Meer st\u00fcrzte.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Nach \u00fcbereinstimmenden Angaben aus S\u00fcdkorea und Japan hat Nordkorea am 12. Juli eine ballistische Rakete in Richtung des Japanischen Meeres abgefeuert. Die s\u00fcdkoreanische Nachrichtenagentur <em>Yonhap<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.yna.co.kr\/view\/AKR20230712073200504?section=politics\/all\">berichtet<\/a> unter Berufung auf den Generalstab in Seoul, dass es sich um eine ballistische Langstreckenrakete gehandelt habe. Vermutlich sei dies eine Interkontinentalrakete (ICBM) gewesen. Der Start sei gegen 10 Uhr Ortszeit (sieben Stunden weniger in Deutschland) in der Gegend um die Hauptstadt Pj\u00f6ngjang erfolgt.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"ja\" dir=\"ltr\">\u5317\u671d\u9bae\u306eICBM\u7d1a\u30df\u30b5\u30a4\u30eb \u98db\u3057\u3087\u304674\u5206 \u904e\u53bb\u6700\u9577\u305d\u306e\u3068\u304d\u3001\u65e5\u672c\u653f\u5e9c\u306f\u3069\u3046\u52d5\u3044\u305f\uff1f<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/B3oD584P8d\">https:\/\/t.co\/B3oD584P8d<\/a><\/p>\n<p>\u2014 NHK\u30cb\u30e5\u30fc\u30b9 (@nhk_news) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/nhk_news\/status\/1679058322324955137?ref_src=twsrc%5Etfw\">July 12, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Das japanische\u00a0Milit\u00e4r best\u00e4tigte den Start. Verteidigungsminister Yasukazu Hamada teilte mit, dass die Rakete au\u00dferhalb der ausschlie\u00dflichen Wirtschaftszone des Landes etwa 250 Kilometer vor der Insel Hokkaid\u014d ins Japanische Meer gest\u00fcrzt sei. Die \u00f6rtlichen Medien schrieben unter Berufung auf einen Milit\u00e4rsprecher, dass das Projektil eine Strecke von rund 1.000 Kilometern zur\u00fcckgelegt habe. Dabei habe es eine maximale Flugh\u00f6he von 6.000 Kilometern erreicht. Diesmal wurde eine rekordlange Flugzeit gemeldet: 74 Minuten gegen\u00fcber dem fr\u00fcheren Rekord von 71 Minuten im M\u00e4rz 2022.<\/p>\n<p>Der japanische Fernsehsender <em>NHK<\/em> berichtete, dass die nordkoreanische Rakete in einem steilen Winkel gestartet worden sei. Unter Ber\u00fccksichtigung der oben genannten Flugparameter k\u00f6nnte sich ihre Reichweite auf etwa 15.000 Kilometer belaufen, weswegen sie bei einer normalen Flugbahn jeden beliebigen Ort auf US-Territorium h\u00e4tte erreichen k\u00f6nnen.<\/p>\n<p>Zuletzt hatte das nordkoreanische Milit\u00e4r am 15. Juni eine ballistische Rakete getestet. Seit dem Jahr 2017 feuerte das asiatische Land 14 Raketen mit einer Reichweite von \u00fcber 5.500 Kilometern ab. Sieben Tests erfolgten allein im Jahr 2022. Im laufenden Jahr waren es bereits vier Starts.<\/p>\n<p>Erst am Dienstag drohte Kim Yo-jong, die Vize-Direktorin der Abteilung f\u00fcr Propaganda und Agitation der Partei der Arbeit Koreas, den USA mit schweren Konsequenzen, sollten US-Milit\u00e4rflugzeuge die ausschlie\u00dfliche Wirtschaftszone des asiatischen Landes erneut verletzen. Die Schwester des nordkoreanischen F\u00fchrers Kim Jong-un gab bekannt, dass ein strategisches Aufkl\u00e4rungsflugzeug der US-Luftwaffe am 10. Juli in den Luftraum \u00fcber der ausschlie\u00dflichen Wirtschaftszone Nordkoreas im Japanischen Meer illegal eingedrungen sei, &#8220;um einen Akt der Luftspionage zu begehen&#8221;. Dabei habe das US-Luftfahrzeug den Luftraum achtmal verletzt.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.life\/international\/174926-nordkorea-warnt-usa-vor-verletzung\/\">Nordkorea warnt USA vor Verletzung des Luftraums seiner ausschlie\u00dflichen Wirtschaftszone<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/175047-nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das nordkoreanische Milit\u00e4r hat am Mittwoch mit dem Start einer ballistischen Interkontinentalrakete einen Rekord aufgestellt. Das Projektil legte eine Strecke von rund 1.000 Kilometern zur\u00fcck und war 74 Minuten in der Luft, bevor es ins Japanische Meer st\u00fcrzte. Nach \u00fcbereinstimmenden Angaben aus S\u00fcdkorea und Japan hat Nordkorea am 12. Juli eine ballistische Rakete in Richtung [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1689160383"],"wp_automatic_camp":["217"],"750a43db205bad3dbbcef3a6dcec74b8":["Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit"],"original_link":["https:\/\/de.rt.com\/international\/175047-nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert\/"],"_thumbnail_id":["39966"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-07-12 13:14:15\";}"],"jnews_social_counter_last_update":["1788329606"]},"categories":[19,23],"tags":[19840,23175,363,46640,771,5111,10407,14355,766],"class_list":["post-39965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-abgefeuert","tag-ballistische","tag-bei","tag-flugzeit","tag-haben","tag-interkontinentalrakete","tag-nordkorea","tag-rekord","tag-soll"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit\" \/>\n<meta property=\"og:description\" content=\"Das nordkoreanische Milit\u00e4r hat am Mittwoch mit dem Start einer ballistischen Interkontinentalrakete einen Rekord aufgestellt. Das Projektil legte eine Strecke von rund 1.000 Kilometern zur\u00fcck und war 74 Minuten in der Luft, bevor es ins Japanische Meer st\u00fcrzte. Nach \u00fcbereinstimmenden Angaben aus S\u00fcdkorea und Japan hat Nordkorea am 12. Juli eine ballistische Rakete in Richtung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-12T11:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit\",\"datePublished\":\"2023-07-12T11:05:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/\"},\"wordCount\":408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg\",\"keywords\":[\"abgefeuert\",\"ballistische\",\"bei\",\"Flugzeit\",\"haben\",\"Interkontinentalrakete\",\"Nordkorea\",\"Rekord\",\"soll\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/\",\"name\":\"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg\",\"datePublished\":\"2023-07-12T11:05:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg\",\"width\":460,\"height\":259,\"caption\":\"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/","og_locale":"de_DE","og_type":"article","og_title":"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit","og_description":"Das nordkoreanische Milit\u00e4r hat am Mittwoch mit dem Start einer ballistischen Interkontinentalrakete einen Rekord aufgestellt. Das Projektil legte eine Strecke von rund 1.000 Kilometern zur\u00fcck und war 74 Minuten in der Luft, bevor es ins Japanische Meer st\u00fcrzte. Nach \u00fcbereinstimmenden Angaben aus S\u00fcdkorea und Japan hat Nordkorea am 12. Juli eine ballistische Rakete in Richtung [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-07-12T11:05:32+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit","datePublished":"2023-07-12T11:05:32+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/"},"wordCount":408,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg","keywords":["abgefeuert","ballistische","bei","Flugzeit","haben","Interkontinentalrakete","Nordkorea","Rekord","soll"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/","url":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/","name":"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg","datePublished":"2023-07-12T11:05:32+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Nordkorea-soll-ballistische-Interkontinentalrakete-abgefeuert-haben-Rekord-bei-Flugzeit.jpg","width":460,"height":259,"caption":"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/nordkorea-soll-ballistische-interkontinentalrakete-abgefeuert-haben-rekord-bei-flugzeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Nordkorea soll ballistische Interkontinentalrakete abgefeuert haben: Rekord bei Flugzeit"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=39965"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/39966"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=39965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=39965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=39965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}