{"id":39327,"date":"2023-07-02T20:04:34","date_gmt":"2023-07-02T18:04:34","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/"},"modified":"2023-07-02T20:04:34","modified_gmt":"2023-07-02T18:04:34","slug":"ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/","title":{"rendered":"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/64a176d2b480cc35b91bfbe2.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Noch vor wenigen Jahren war die Bloggerin und begabte Rednerin Tulsi Gabbard der Hoffnungstr\u00e4ger f\u00fcr die Erneuerung der Demokratischen Partei. Nun hat der ehemalige Politstar in mehreren \u00f6ffentlichen Auftritten die Biden-Regierung scharf kritisiert.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die ehemalige US-Pr\u00e4sidentschaftskandidatin und Abgeordnete Tulsi Gabbard hat sich in den letzten Jahren von einem linken Politstar der Demokratischen Partei zur Dissidentin mit Verbindungen zum konservativen Lager entwickelt. Am Samstag hat sie US-Pr\u00e4sident Joe Biden erneut vorgeworfen, die Welt angesichts der weiteren Eskalation des Ukraine-Konflikts an den Rand eines Atomkriegs zu treiben.<\/p>\n<p>&#8220;Wir sind mit der Realit\u00e4t konfrontiert. Die Aktionen und die Politik von Pr\u00e4sident Biden haben uns an den Rand eines Atomkriegs gebracht. Dies ist eine existenzielle Krise, nicht nur f\u00fcr uns hier, sondern f\u00fcr die ganze Welt. Dieser Stellvertreterkrieg gegen Russland, bei dem das Leben des ukrainischen Volkes missbraucht wird, eskaliert immer weiter&#8221;, sagte Gabbard am Samstag bei einer Veranstaltung in einer Universit\u00e4t in Centennial im US-Bundesstaat Colorado, die in den sozialen Medien \u00fcbertragen wurde.<\/p>\n<p>Die Politikerin warnte, dass die Waffenlieferungen der NATO an die Ukraine &#8220;die Wahrscheinlichkeit&#8221; einer m\u00f6glichen direkten Konfrontation zwischen den Vereinigten Staaten, den NATO-Mitgliedstaaten und Russland erh\u00f6hen w\u00fcrden.<\/p>\n<blockquote>\n<p><em>&#8220;Wenn man Pr\u00e4sident Biden und seine Regierung \u2026 dar\u00fcber reden h\u00f6rt, reden sie \u00fcber den Dritten Weltkrieg und einen Atomkrieg, als ob es nur ein weiterer Krieg, nur ein weiterer Konflikt w\u00e4re. \u2026 Das ist so weit von der Realit\u00e4t entfernt. \u2026 Sie sind nicht ehrlich gegen\u00fcber dem amerikanischen Volk, wie die Kosten und Konsequenzen dieser Kriege aussehen w\u00fcrden&#8221;, f\u00fcgte Gabbard hinzu.<\/em><\/p>\n<\/blockquote>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Today\u2019s Democratic Party has led us to the brink of nuclear war. The party is led by cowardly warmongers who are firmly in the grips of the military industrial complex, and don\u2019t know or care about the cost of war, or who pays the price. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/oZCjHOt0O4\">pic.twitter.com\/oZCjHOt0O4<\/a><\/p>\n<p>\u2014 Tulsi Gabbard \ud83c\udf3a (@TulsiGabbard) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/TulsiGabbard\/status\/1675099412346068993?ref_src=twsrc%5Etfw\">July 1, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Nach dem Beginn der russischen Milit\u00e4roperation im Februar 2022 hatten mehrere westliche L\u00e4nder damit begonnen, die Ukraine finanziell, humanit\u00e4r und milit\u00e4risch zu unterst\u00fctzen. Die Unterst\u00fctzung reichte von zun\u00e4chst leichterer Artilleriemunition und milit\u00e4rischer Ausbildung bis hin zu schweren Waffen, einschlie\u00dflich Panzern, im sp\u00e4teren Jahresverlauf und im Jahr 2023.<\/p>\n<p>Russland hat die L\u00e4nder, die Waffen an die Ukraine liefern, gewarnt, dass es Milit\u00e4rlieferungen als legitime Ziele betrachtet. Au\u00dferdem hat der russische Au\u00dfenminister Sergei Lawrow erkl\u00e4rt, dass die Bewaffnung und Ausbildung der Ukrainer durch die NATO-Verb\u00fcndeten einer direkten Beteiligung an dem Konflikt gleichkommt. Mehrere westliche Politiker, darunter auch die deutsche Au\u00dfenministerin Annalena Baerbock, gaben \u00f6ffentlich zu, dass der Westen sich im Krieg mit Russland befinde.\u00a0<\/p>\n<p>Nicht zum ersten Mal beschuldigte Gabbard die Biden-Regierung, die Vereinigten Staaten gef\u00e4hrlich nahe an einen Atomkrieg heranzuf\u00fchren. Im Oktober verurteilte sie die &#8220;Kriegstreiber&#8221; in Washington und erkl\u00e4rte, diese seien einer der Gr\u00fcnde, warum sie die Demokratische Partei verlassen habe. Unmittelbar nach der Bekanntgabe ihres Austritts trat sie bei <em>Fox News<\/em> in der Show von Tucker Carlson auf. Sie <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.dailymail.co.uk\/news\/article-11305751\/Tulsi-Gabbard-accuses-Biden-actively-pushing-brink-nuclear-holocaust.html\">sagte<\/a>, dass sie mit der Russlandpolitik der Regierung Biden nicht einverstanden sei und beschuldigte sie, &#8220;uns aktiv an den Rand eines nuklearen Holocausts zu treiben&#8221;.\u00a0<\/p>\n<p>Die 41-j\u00e4hrige Gabbard kandidierte f\u00fcr die Demokraten bei den US-Pr\u00e4sidentschaftswahlen im Jahr 2020, gab aber ihre Kandidatur zugunsten des jetzigen Pr\u00e4sidenten Biden auf. Derzeit tritt sie als Rednerin auf verschiedenen Veranstaltungen und in Talkshows auf und kommentiert das politische Geschehen in Blogs und den sozialen Medien.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/meinungsfreiheit.rtde.life\/international\/173861-sergei-karaganow-warum-ein-atomschlag-gegen-westeuropa\/\">Sergei Karaganow: Warum Russland einen Atomschlag gegen Westeuropa in Betracht ziehen muss<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/174193-ex-us-praesidentschaftskandidatin-gabbard-wirft\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noch vor wenigen Jahren war die Bloggerin und begabte Rednerin Tulsi Gabbard der Hoffnungstr\u00e4ger f\u00fcr die Erneuerung der Demokratischen Partei. Nun hat der ehemalige Politstar in mehreren \u00f6ffentlichen Auftritten die Biden-Regierung scharf kritisiert. Die ehemalige US-Pr\u00e4sidentschaftskandidatin und Abgeordnete Tulsi Gabbard hat sich in den letzten Jahren von einem linken Politstar der Demokratischen Partei zur Dissidentin [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1688322121"],"wp_automatic_camp":["217"],"6567e7d428692c1dedb19c26f971d2b4":["Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor"],"original_link":["https:\/\/de.rt.com\/international\/174193-ex-us-praesidentschaftskandidatin-gabbard-wirft\/"],"_thumbnail_id":["39328"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-07-02 20:23:04\";}"],"jnews_social_counter_last_update":["1778548837"]},"categories":[19,23],"tags":[1348,46299,5342,31370,18812,320,7129],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor\" \/>\n<meta property=\"og:description\" content=\"Noch vor wenigen Jahren war die Bloggerin und begabte Rednerin Tulsi Gabbard der Hoffnungstr\u00e4ger f\u00fcr die Erneuerung der Demokratischen Partei. Nun hat der ehemalige Politstar in mehreren \u00f6ffentlichen Auftritten die Biden-Regierung scharf kritisiert. Die ehemalige US-Pr\u00e4sidentschaftskandidatin und Abgeordnete Tulsi Gabbard hat sich in den letzten Jahren von einem linken Politstar der Demokratischen Partei zur Dissidentin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-02T18:04:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor\",\"datePublished\":\"2023-07-02T18:04:34+00:00\",\"dateModified\":\"2023-07-02T18:04:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg\",\"keywords\":[\"Biden\",\"ExUSPr\u00e4sidentschaftskandidatin\",\"Gabbard\",\"Kriegstreiberei\",\"nukleare\",\"vor\",\"wirft\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/\",\"name\":\"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg\",\"datePublished\":\"2023-07-02T18:04:34+00:00\",\"dateModified\":\"2023-07-02T18:04:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg\",\"width\":460,\"height\":259,\"caption\":\"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/","og_locale":"de_DE","og_type":"article","og_title":"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor","og_description":"Noch vor wenigen Jahren war die Bloggerin und begabte Rednerin Tulsi Gabbard der Hoffnungstr\u00e4ger f\u00fcr die Erneuerung der Demokratischen Partei. Nun hat der ehemalige Politstar in mehreren \u00f6ffentlichen Auftritten die Biden-Regierung scharf kritisiert. Die ehemalige US-Pr\u00e4sidentschaftskandidatin und Abgeordnete Tulsi Gabbard hat sich in den letzten Jahren von einem linken Politstar der Demokratischen Partei zur Dissidentin [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-07-02T18:04:34+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor","datePublished":"2023-07-02T18:04:34+00:00","dateModified":"2023-07-02T18:04:34+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg","keywords":["Biden","ExUSPr\u00e4sidentschaftskandidatin","Gabbard","Kriegstreiberei","nukleare","vor","wirft"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/","url":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/","name":"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg","datePublished":"2023-07-02T18:04:34+00:00","dateModified":"2023-07-02T18:04:34+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/Ex-US-Praesidentschaftskandidatin-Gabbard-wirft-Biden-nukleare-Kriegstreiberei-vor.jpg","width":460,"height":259,"caption":"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-us-praesidentschaftskandidatin-gabbard-wirft-biden-nukleare-kriegstreiberei-vor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ex-US-Pr\u00e4sidentschaftskandidatin Gabbard wirft Biden nukleare Kriegstreiberei vor"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39327"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=39327"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/39328"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=39327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=39327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=39327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}