{"id":39275,"date":"2023-07-01T15:57:31","date_gmt":"2023-07-01T13:57:31","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/"},"modified":"2023-07-01T15:57:31","modified_gmt":"2023-07-01T13:57:31","slug":"alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/","title":{"rendered":"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk"},"content":{"rendered":"<div class=\"Text-root Text-type_1 \">\n                Die Journalistin und Schriftstellerin Marina Achmedowa ist oft in den Kriegsgebieten des Donbass unterwegs und schreibt \u00fcber die Begegnungen, die sie auf ihren Reisen hat, Kurzerz\u00e4hlungen, mit denen sie den Menschen vor Ort eine Stimme verleiht.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Marina Achmedowa<\/em><\/p>\n<p>Wir sahen den alten Mann, der Himbeeren verkaufte, am Stra\u00dfenrand und hielten an. Er sa\u00df unter einem staubigen Walnussbaum mit seinen S\u00e4cken und Gl\u00e4sern.<\/p>\n<p>Die Fernstra\u00dfe hier erzeugt viel L\u00e4rm, Autos rauschen unentwegt vorbei. Auf beiden Seiten der Trasse sind Einfamilienh\u00e4user wie dieses, vor dem wir nun stehen. Aus dem Hof kommt eine Frau mit einem Hund auf dem Arm.<\/p>\n<p><em>&#8220;Ich bringe Ihnen eine Kiste, damit die Himbeeren w\u00e4hrend der Fahrt nicht matschig werden&#8221;<\/em>, bietet sie mir an.<\/p>\n<p>W\u00e4hrend sie die Kiste holt, \u00fcberlege ich mir, ob sie die Frau des alten Mannes mit den Himbeeren ist. Ehe ich mir einen Reim darauf gemacht habe, kommt sie mit dem Hund und der Kiste zur\u00fcck. Der Hund leckt ihr die Nase ab.<\/p>\n<p><em>&#8220;Na, mein S\u00f6hnchen&#8221;<\/em>, erwidert die Frau die Z\u00e4rtlichkeit.<\/p>\n<p>Ich versuche, mich von meiner humorigen Seite zu zeigen:<\/p>\n<p><em>&#8220;Ist Ihr Sohn nicht eifers\u00fcchtig auf den Hund?&#8221;<\/em><\/p>\n<p>Sie muss Enkelkinder im Teenageralter haben, denke ich dabei, ohne es auszusprechen. Mir f\u00e4llt auf, dass sie und das H\u00fcndchen fast die gleichen Augen haben \u2013 eingefallene, traurige Augen. Es kommt oft vor, dass Tiere ihren Herrchen und Frauchen in irgendwelchen markanten Gesichtsz\u00fcgen \u00e4hnlich sind oder mit der Zeit werden.\u00a0<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fcfebb480cc54250e3605.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fcfebb480cc54250e3605.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fcfebb480cc54250e3605.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fcfebb480cc54250e3605.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fcfebb480cc54250e3605.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fcfebb480cc54250e3605.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Das Eisenbahndepot von Ilowajsk nach einem ukrainischen Beschuss im Januar 2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Waleri Melnikow, RIA Nowosti<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p><em>&#8220;Ich habe keinen Sohn&#8221;<\/em>, antwortet die Frau und blickt mir dabei in die Augen, <em>&#8220;Er ist 2014 gefallen, er war in Giwis Kompanie. Mein Mann ist auch tot, er ist meinem Sohn gefolgt und fiel ebenfalls.&#8221;<\/em><\/p>\n<p><em>&#8220;Und Enkelkinder?&#8221;<\/em>\u00a0Ich frage das jetzt kleinlaut und vorsichtig und schaue verstohlen in ihren verwahrlosten, mit Rosen bepflanzten Garten. Ich sehe kein Kinderspielzeug darin.<\/p>\n<p><em>&#8220;Auch keine Enkelkinder&#8221;<\/em>, antwortet sie. <em>&#8220;Ich bin ganz allein.&#8221;<\/em><\/p>\n<p>Sie f\u00e4ngt zu weinen an, h\u00f6rt aber schnell wieder auf:\u00a0<\/p>\n<p><em>&#8220;Ich habe viele Jahre geweint, ich weinte jeden Tag allein im Haus, all diese Jahre lang, bis mir die Nachbarn diesen Hund geschenkt haben. Ja, S\u00f6hnchen?&#8221;<\/em><\/p>\n<p>Sie k\u00fcsst das H\u00fcndchen auf die Nase.\u00a0<\/p>\n<p>Auf der Fernstra\u00dfe rauschen die Autos an uns vorbei. Der alte Mann, der mir all seine Himbeeren verkauft hat, sitzt weiter unter dem staubigen Nussbaum und h\u00f6rt unserem Gespr\u00e4ch zu. Wir sind in Ilowajsk.<\/p>\n<p>Die Frau versucht, es mir zu erkl\u00e4ren:\u00a0<\/p>\n<p><em>&#8220;Wissen Sie, wie es hier bei uns war? 2014, als die Nazis kamen, sa\u00dfen sie in der Schule auf dieser Seite. Stimmt&#8217;s, Gro\u00dfvater? Und alle unsere Jungs aus der Stra\u00dfe gingen sofort auf die andere Seite, zu den Aufst\u00e4ndischen. Sieh mal, wie viele Sterne an den H\u00e4usern h\u00e4ngen, f\u00fcr jeden gefallenen Helden unserer Volksrepublik ein Stern.&#8221;<\/em><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd0a248fbef4d4a194a14.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd0a248fbef4d4a194a14.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd0a248fbef4d4a194a14.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd0a248fbef4d4a194a14.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd0a248fbef4d4a194a14.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd0a248fbef4d4a194a14.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Privath\u00e4user in Ilowajsk w\u00e4hrend er Kriegshandlungen im August 2014<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Gennadi Dubowoi<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p>Sie zeigt auf ein leeres Haus, auf dem kein Stern angebracht ist:\u00a0<\/p>\n<p><em>&#8220;Meine Nachbarin ging zu den Nazis in die Schule und die gingen zu ihr, und von ihr kamen sie zu mir. &#8216;Man hat uns gesagt, dein Sohn ist zu den Separatisten gegangen.&#8217; Sie packten mich an den Haaren, schleiften mich auf dem Boden herum \u2026&#8221;<\/em><\/p>\n<p>Sie k\u00fcsst den Hund.<\/p>\n<p><em>&#8220;Sie traten meinen Mann in die Rippen. Als sie weggingen, sagte er: &#8216;Ich werde in den Krieg ziehen und mindestens einen Mistkerl erschie\u00dfen, aber ich werde ihn erschie\u00dfen.&#8217; Und ich weinte und weinte. Aber was kann man da machen? Ja, kleiner Mann? Ja, Kleiner?&#8221;<\/em><\/p>\n<p><em>&#8220;Wo sind diese Nachbarn jetzt?&#8221;<\/em>, frage ich.<\/p>\n<p><em>&#8220;Sie sind in die Ukraine gezogen. Und sie haben ihre beiden S\u00f6hne dorthin geschickt. Sie hat uns alle (den ukrainischen Beh\u00f6rden) verraten, und als sie wegging, sagte sie uns: &#8216;Ich hasse euch alle so sehr!&#8217; Bekommt aber eine Rente der Volksrepublik. Vielleicht hat sie richtig gehandelt, um die Haut ihrer S\u00f6hne zu retten. Ihre S\u00f6hne sind am Leben. Aber mein Sohn w\u00e4re nicht weggelaufen, auch wenn ich es ihm befohlen h\u00e4tte. Ich w\u00e4re ja auch nicht geflohen.&#8221;<\/em><\/p>\n<p>Die Augen der Frau sind jetzt trocken und sie gl\u00e4nzen. Sie zeigt auf die Sterne auf den anderen H\u00e4usern.\u00a0<\/p>\n<p><em>&#8220;Die Nachbarin wird nicht mehr in ihr Haus zur\u00fcckkehren. Sie wird uns niemals in die Augen sehen k\u00f6nnen. Denn der Junge dort dr\u00fcben ist tot, der dort dr\u00fcben ist auch tot. Und meiner ist tot.&#8221;<\/em><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd2dab480cc54924c807a.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd2dab480cc54924c807a.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd2dab480cc54924c807a.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd2dab480cc54924c807a.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd2dab480cc54924c807a.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/649fd2dab480cc54924c807a.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Aufst\u00e4ndische der Volksrepublik Donezk in Ilowajsk, August 2014<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Gennadi Dubowoi \/ RIA Nowosti<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p>Dann bricht sie ihre Erz\u00e4hlung ab und fragt mich:<\/p>\n<p><em>&#8220;Wei\u00dft du, warum sie heute Nacht wieder so geschossen haben? Werden sie jetzt angreifen? Ich werde nicht weglaufen. Ich werde mich ins Geb\u00fcsch legen und schie\u00dfen. Sollen sie mir ein Gewehr geben! Wenn sie es nicht tun, habe ich eine Mistgabel. Viele Frauen hier haben Heugabeln.&#8221;<\/em><\/p>\n<p>Sie l\u00e4sst den Hund los und geht in ihren Hof. Der Hund l\u00e4uft ihr hinterher.<\/p>\n<p><em>&#8220;Lassen Sie ihn nicht auf die Fahrbahn&#8221;<\/em>, rufe ich ihr hinterher, da ich mich pl\u00f6tzlich vor dem Gedanken f\u00fcrchte, dass der Hund unter die R\u00e4der kommen k\u00f6nnte und diese Frau, Ewgenija, dann wieder allein w\u00e4re.<\/p>\n<p><em>&#8220;Davor habe ich selbst Angst&#8221;<\/em>, h\u00e4lt sie inne. Und dann: <em>&#8220;Und ihr, bitte, arbeitet, bringt die Dinge in Ordnung.&#8221;<\/em><\/p>\n<p>Wir, mein Fahrer und ich, gehen an dem staubigen Nussbaum vorbei. Ich habe keinen Appetit mehr auf Himbeeren. Der alte Mann klappt seinen Stuhl zusammen und huscht ebenfalls davon. Er beklagt sich, dass es bald regnen wird und dass seine Rente zu klein ist.\u00a0<\/p>\n<p>Formell gilt Ewgenija nicht als Witwe und Mutter gefallener Soldaten. 2014 z\u00e4hlt nicht f\u00fcr die russische B\u00fcrokratie \u2026 Wie viel es doch noch zu tun gibt!<\/p>\n<p>Auf dem R\u00fcckweg zum Auto denke ich, dass der Sieg, unser obligatorischer Sieg, uns von diesen stillen rechtschaffenen Frauen mit traurigen, eingefallenen Augen erlitten wird, die einsam in H\u00e4usern mit Sternen darauf leben.<\/p>\n<p><em>Marina Achmedowa\u00a0ist Schriftstellerin, Journalistin, Mitglied des Menschenrechtsrates der Russischen F\u00f6deration und seit Kurzem Chefredakteurin des Nachrichtenportals <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/regnum.ru\">regnum.ru<\/a>. Ihre Berichte \u00fcber die Arbeit als Menschenrechtsaktivistin und ihre Reisen durch die Krisenregion kann man auf ihrem\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/Marinaslovo\">Telegramkanal<\/a>\u00a0nachlesen.\u00a0<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.life\/europa\/149536-julia-moerderin\/\">&#8220;Halte durch, Kleines&#8221; \u2013 Julia, der Leidensweg einer unschuldig verhafteten jungen Frau<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/174078-alle-jungs-in-unserer-strasse\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Journalistin und Schriftstellerin Marina Achmedowa ist oft in den Kriegsgebieten des Donbass unterwegs und schreibt \u00fcber die Begegnungen, die sie auf ihren Reisen hat, Kurzerz\u00e4hlungen, mit denen sie den Menschen vor Ort eine Stimme verleiht. Von Marina Achmedowa Wir sahen den alten Mann, der Himbeeren verkaufte, am Stra\u00dfenrand und hielten an. Er sa\u00df unter [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1688220594"],"wp_automatic_camp":["217"],"13e27dd1d81639f4170d66e0774a2019":["&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk"],"original_link":["https:\/\/de.rt.com\/meinung\/174078-alle-jungs-in-unserer-strasse\/"],"_thumbnail_id":["39276"],"jnews_social_counter_last_update":["1788313437"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-07-01 16:10:56\";}"]},"categories":[19,23],"tags":[679,48,275,29503,46269,27780,18890,24399,3378,36562,18937,44782],"class_list":["post-39275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-aus","tag-den","tag-eine","tag-erzaehlung","tag-ilowajsk","tag-jungs","tag-kriegquot","tag-quotalle","tag-strasse","tag-tragische","tag-unserer","tag-zogen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk\" \/>\n<meta property=\"og:description\" content=\"Die Journalistin und Schriftstellerin Marina Achmedowa ist oft in den Kriegsgebieten des Donbass unterwegs und schreibt \u00fcber die Begegnungen, die sie auf ihren Reisen hat, Kurzerz\u00e4hlungen, mit denen sie den Menschen vor Ort eine Stimme verleiht. Von Marina Achmedowa Wir sahen den alten Mann, der Himbeeren verkaufte, am Stra\u00dfenrand und hielten an. Er sa\u00df unter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-01T13:57:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1720\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk\",\"datePublished\":\"2023-07-01T13:57:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/\"},\"wordCount\":1090,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg\",\"keywords\":[\"aus\",\"den\",\"eine\",\"Erz\u00e4hlung\",\"Ilowajsk\",\"Jungs\",\"Kriegquot\",\"quotAlle\",\"Stra\u00dfe\",\"tragische\",\"unserer\",\"zogen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/\",\"name\":\"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg\",\"datePublished\":\"2023-07-01T13:57:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg\",\"width\":1720,\"height\":1080,\"caption\":\"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk","og_description":"Die Journalistin und Schriftstellerin Marina Achmedowa ist oft in den Kriegsgebieten des Donbass unterwegs und schreibt \u00fcber die Begegnungen, die sie auf ihren Reisen hat, Kurzerz\u00e4hlungen, mit denen sie den Menschen vor Ort eine Stimme verleiht. Von Marina Achmedowa Wir sahen den alten Mann, der Himbeeren verkaufte, am Stra\u00dfenrand und hielten an. Er sa\u00df unter [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-07-01T13:57:31+00:00","og_image":[{"width":1720,"height":1080,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk","datePublished":"2023-07-01T13:57:31+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/"},"wordCount":1090,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg","keywords":["aus","den","eine","Erz\u00e4hlung","Ilowajsk","Jungs","Kriegquot","quotAlle","Stra\u00dfe","tragische","unserer","zogen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/","url":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/","name":"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg","datePublished":"2023-07-01T13:57:31+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/07\/quotAlle-Jungs-in-unserer-Strasse-zogen-2014-in-den-Kriegquot.jpg","width":1720,"height":1080,"caption":"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/alle-jungs-in-unserer-strasse-zogen-2014-in-den-krieg-eine-tragische-erzaehlung-aus-ilowajsk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Alle Jungs in unserer Stra\u00dfe zogen 2014 in den Krieg&quot; \u2013 eine tragische Erz\u00e4hlung aus Ilowajsk"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=39275"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/39276"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=39275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=39275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=39275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}