{"id":39022,"date":"2023-06-27T21:29:38","date_gmt":"2023-06-27T19:29:38","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/"},"modified":"2023-06-27T21:29:38","modified_gmt":"2023-06-27T19:29:38","slug":"saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/","title":{"rendered":"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/649adb41b480cc73e231806f.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Ein Mitglied des Saporoschje-Gebietsverwaltungsrates sagt, die ukrainischen Streitkr\u00e4fte f\u00fchrten aktive Offensiven durch. Demnach seien sie in mehrere D\u00f6rfer in der N\u00e4he des Wremewski-Vorsprungs eingedrungen, und es besteht die Wahrscheinlichkeit einer Besetzung.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die russischen Truppen in dem Frontabschnitt Saporoschje befinden sich in &#8220;aktiver Verteidigung&#8221;, wobei es fast entlang der gesamten Kontaktlinie zu Artillerieduellen kommt, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/vrogov\/10582\">meldete<\/a> Wladimir Rogow als Mitglied des Hauptrates der Regionalverwaltung von Saporoschje auf seinem Telegram-Kanal.<\/p>\n<p>Demnach finden die schwersten Gefechte in der N\u00e4he des Wremewski-Vorsprungs statt, einem kleinen Gebiet im Hochland an der Grenze zwischen dem Gebiet Saporoschje und der Volksrepublik Donezk. Er wies darauf hin, dass die russischen Streitkr\u00e4fte allein in der N\u00e4he des Dorfes Rownopol im westlichen Teil des Vorsprungs vier ukrainische Angriffe abwehren konnten. Rogow erkl\u00e4rte:<\/p>\n<blockquote>\n<p><em>&#8220;Der Feind befindet sich jetzt nicht nur in den n\u00e4chstgelegenen Zufahrten, sondern auch in den Siedlungen Rownopol, Lewadnoje und Makarowka. Wenn sich diese Konstellation in diesem Frontabschnitt fortsetzt, wird es dem Feind mit gro\u00dfer Wahrscheinlichkeit gelingen, den Wremewski-Vorsprung zu besetzen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Er sprach auch von K\u00e4mpfen in anderen Frontabschnitten:<\/p>\n<ul>\n<li>Im Frontabschnitt Wassiljewka befindet sich das Dorf Pjatichatki weiterhin in einer Grauzone, in der sich die ukrainischen Streitkr\u00e4fte neu gruppieren und wohin Truppen als Verst\u00e4rkung verlegt werden;<\/li>\n<li>Im Frontabschnitt Orechow ist es den russischen Truppen gelungen, die Kontrolle \u00fcber das Gebiet Nowodanilowka-Rabotino wiederzuerlangen, der Feind unternimmt erfolglose Angriffsversuche in kleinen Gruppen, die Lage bleibt &#8220;stabil angespannt&#8221;.<\/li>\n<\/ul>\n<p>Der russische Pr\u00e4sident Wladimir Putin hatte mitgeteilt, die ukrainische Gegenoffensive sei seit dem 4. Juni im Gange. Am 22. Juni erkl\u00e4rte sein Sekret\u00e4r Nikolai Patruschew auf einer Sitzung des russischen Sicherheitsrates, dass die ukrainischen Streitkr\u00e4fte w\u00e4hrend der bisherigen Offensive etwa 13.000 Soldaten, fast 250 Panzer, mehr als 260 Drohnen, zehn Kampfjets, vier Hubschrauber, mehr als 40 Mehrfachraketenwerfer, zwei Flugabwehrraketensysteme und viel andere Ausr\u00fcstung verloren h\u00e4tten.<\/p>\n<p>Das russische Verteidigungsministerium berichtet regelm\u00e4\u00dfig \u00fcber die Abwehr von Angriffen des ukrainischen Milit\u00e4rs aus verschiedenen Richtungen. So meldete das Milit\u00e4r in einem Bericht vom 26. Juni, dass ukrainische Angriffe in den Richtungen Saporoschje und S\u00fcd-Donezk zur\u00fcckgeschlagen wurden, unter anderem im Bereich des Wremewski-Vorsprungs. Rogow berichtet seit dem 5. Juni regelm\u00e4\u00dfig \u00fcber ukrainische Durchbruchsversuche an dieser Frontlinie.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.me\/europa\/173437-ukrainische-niederlage-in-panzerschlacht\/\">Ukrainische Niederlage in Panzerschlacht: Bergepanzer zerst\u00f6rt und von der Frontlinie abgezogen<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/173775-saporoschje-behoerden-ukrainische-streitkraefte-koennen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Mitglied des Saporoschje-Gebietsverwaltungsrates sagt, die ukrainischen Streitkr\u00e4fte f\u00fchrten aktive Offensiven durch. Demnach seien sie in mehrere D\u00f6rfer in der N\u00e4he des Wremewski-Vorsprungs eingedrungen, und es besteht die Wahrscheinlichkeit einer Besetzung. Die russischen Truppen in dem Frontabschnitt Saporoschje befinden sich in &#8220;aktiver Verteidigung&#8221;, wobei es fast entlang der gesamten Kontaktlinie zu Artillerieduellen kommt, meldete Wladimir [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1687895761"],"wp_automatic_camp":["217"],"d5f6ecec56ab6a5bb2f548a992217665":["Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen"],"original_link":["https:\/\/de.rt.com\/international\/173775-saporoschje-behoerden-ukrainische-streitkraefte-koennen\/"],"_thumbnail_id":["39023"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-06-27 21:57:02\";}"],"jnews_social_counter_last_update":["1778250569"]},"categories":[19,23],"tags":[907,48,4296,38524,17702,905,46120],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen\" \/>\n<meta property=\"og:description\" content=\"Ein Mitglied des Saporoschje-Gebietsverwaltungsrates sagt, die ukrainischen Streitkr\u00e4fte f\u00fchrten aktive Offensiven durch. Demnach seien sie in mehrere D\u00f6rfer in der N\u00e4he des Wremewski-Vorsprungs eingedrungen, und es besteht die Wahrscheinlichkeit einer Besetzung. Die russischen Truppen in dem Frontabschnitt Saporoschje befinden sich in &#8220;aktiver Verteidigung&#8221;, wobei es fast entlang der gesamten Kontaktlinie zu Artillerieduellen kommt, meldete Wladimir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-27T19:29:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen\",\"datePublished\":\"2023-06-27T19:29:38+00:00\",\"dateModified\":\"2023-06-27T19:29:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg\",\"keywords\":[\"besetzen\",\"den\",\"k\u00f6nnen\",\"SaporoschjeBeh\u00f6rden\",\"Streitkr\u00e4fte\",\"Ukrainische\",\"WremewskiVorsprung\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/\",\"name\":\"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg\",\"datePublished\":\"2023-06-27T19:29:38+00:00\",\"dateModified\":\"2023-06-27T19:29:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/","og_locale":"de_DE","og_type":"article","og_title":"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen","og_description":"Ein Mitglied des Saporoschje-Gebietsverwaltungsrates sagt, die ukrainischen Streitkr\u00e4fte f\u00fchrten aktive Offensiven durch. Demnach seien sie in mehrere D\u00f6rfer in der N\u00e4he des Wremewski-Vorsprungs eingedrungen, und es besteht die Wahrscheinlichkeit einer Besetzung. Die russischen Truppen in dem Frontabschnitt Saporoschje befinden sich in &#8220;aktiver Verteidigung&#8221;, wobei es fast entlang der gesamten Kontaktlinie zu Artillerieduellen kommt, meldete Wladimir [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-06-27T19:29:38+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen","datePublished":"2023-06-27T19:29:38+00:00","dateModified":"2023-06-27T19:29:38+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg","keywords":["besetzen","den","k\u00f6nnen","SaporoschjeBeh\u00f6rden","Streitkr\u00e4fte","Ukrainische","WremewskiVorsprung"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/","url":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/","name":"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg","datePublished":"2023-06-27T19:29:38+00:00","dateModified":"2023-06-27T19:29:38+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Saporoschje-Behoerden-Ukrainische-Streitkraefte-koennen-den-Wremewski-Vorsprung-besetzen.jpg","width":460,"height":259,"caption":"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/saporoschje-behoerden-ukrainische-streitkraefte-koennen-den-wremewski-vorsprung-besetzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Saporoschje-Beh\u00f6rden: Ukrainische Streitkr\u00e4fte k\u00f6nnen den Wremewski-Vorsprung besetzen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39022"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=39022"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/39022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/39023"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=39022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=39022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=39022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}