{"id":37359,"date":"2023-06-03T14:11:06","date_gmt":"2023-06-03T12:11:06","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/"},"modified":"2023-06-03T14:11:06","modified_gmt":"2023-06-03T12:11:06","slug":"kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/","title":{"rendered":"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/647b2485b480cc3754302b24.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Wie der ukrainische Landwirtschaftsminister Nikolai Solski in einem Interview sagte, habe die Ukraine einen &#8220;Plan B&#8221;, um weiterhin Getreide zu exportieren, falls Russland aus dem Abkommen aussteige. Moskau fordert seinerseits die Wiederaufnahme der Ausfuhr von Ammoniakd\u00fcngern.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der ukrainische Minister f\u00fcr Agrarpolitik und Ern\u00e4hrung, Nikolai Solski, hat in einem am\u00a0Freitag ver\u00f6ffentlichten Interview mit der Nachrichtenagentur <em>Reuters <\/em>behauptet, dass Russland nun die Registrierung von Schiffen im Rahmen des Getreide-Deals einschr\u00e4nke und die Wiederaufnahme der Ammoniakd\u00fcnger-Exporte fordere. In dieser Hinsicht, so Solski, sei die Ukraine bereit f\u00fcr einen &#8220;Plan B&#8221;, der Russland von dem Abkommen ausschlie\u00dfe. Der Beamte w\u00f6rtlich:<\/p>\n<blockquote>\n<p><em>&#8220;Wir werden zu einem Plan B bereit sein, der von uns und von der UNO abh\u00e4ngt. Ich glaube nicht, dass wir ruhen werden, wenn das in naher Zukunft so weitergeht.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Er unterstrich, dass der &#8220;Plan B&#8221; eine &#8220;vierte Partei&#8221; in dieser Beziehung ausschlie\u00dfe,\u00a0und zwar Russland. Solski pr\u00e4zisierte ferner, dass dieser &#8220;Plan B&#8221; die Bereitstellung von Garantien f\u00fcr Transportunternehmen beinhalte. Zu diesem Zweck sei in der Ukraine ein Sonderfonds in H\u00f6he von 547 Mio. US-Dollar eingerichtet worden. Gleichzeitig betonte der Minister, dass diese Option erst dann zur Verf\u00fcgung stehe, wenn die Ukraine &#8220;nichts mehr zu verlieren&#8221; habe. Im Moment wolle die ukrainische Seite aber daf\u00fcr sorgen, dass das Getreideabkommen in seiner jetzigen Form umgesetzt werde.<\/p>\n<p>Am 1. Juni teilten die Vereinten Nationen mit, dass Russland das Gemeinsame Koordinierungszentrum in Istanbul \u00fcber seine Entscheidung informiert habe, die Registrierung von Schiffen im Hafen Juschny bei Odessa einzuschr\u00e4nken, weil kein russisches Ammoniak ausgef\u00fchrt werde. Der Sekret\u00e4r des ukrainischen Nationalen Sicherheitsrates, Alexei Danilow, schloss nicht aus, die Wiederaufnahme des Ammoniak-Transits durch die Pipeline Toljatti-Odessa zu einem sp\u00e4teren Zeitpunkt zu erw\u00e4gen, verlangte jedoch Garantien von den Partnern. Es gehe um die M\u00f6glichkeiten, das Getreide zu exportieren, das sich &#8220;in den H\u00e4fen angesammelt hat&#8221;, pr\u00e4zisierte er, ohne Einzelheiten zu nennen.<\/p>\n<p>Der Getreide-Deal wurde am 18. Mai um weitere zwei Monate verl\u00e4ngert. F\u00fcr die n\u00e4chste Verl\u00e4ngerung fordert das russische Au\u00dfenministerium, russischen Schiffen das Einlaufen in ausl\u00e4ndische H\u00e4fen zu erm\u00f6glichen, die Bedingungen f\u00fcr die Versicherung von Trockenladungen zu \u00e4ndern, die Rosselchosbank (Russische Landwirtschaftsbank) an SWIFT anzuschlie\u00dfen und die Ammoniak-Pipeline Toljatti-Odessa in Betrieb zu nehmen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/kurz.rt.com\/3nve\">Nebensja: Weder die UN noch sonst jemand hilft uns beim Export von Getreide und D\u00fcngemitteln<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/171727-kiew-falls-getreide-deal-scheitert\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie der ukrainische Landwirtschaftsminister Nikolai Solski in einem Interview sagte, habe die Ukraine einen &#8220;Plan B&#8221;, um weiterhin Getreide zu exportieren, falls Russland aus dem Abkommen aussteige. Moskau fordert seinerseits die Wiederaufnahme der Ausfuhr von Ammoniakd\u00fcngern. Der ukrainische Minister f\u00fcr Agrarpolitik und Ern\u00e4hrung, Nikolai Solski, hat in einem am\u00a0Freitag ver\u00f6ffentlichten Interview mit der Nachrichtenagentur Reuters [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":37360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1685794275"],"wp_automatic_camp":["217"],"b482e5c5f1b88cfcdcb158438ff94341":["Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;"],"original_link":["https:\/\/de.rt.com\/international\/171727-kiew-falls-getreide-deal-scheitert\/"],"_thumbnail_id":["37360"],"jnews_social_counter_last_update":["1778364061"]},"categories":[19,23],"tags":[45002,768,28337,35158,1002,1025,45001,1160],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;\" \/>\n<meta property=\"og:description\" content=\"Wie der ukrainische Landwirtschaftsminister Nikolai Solski in einem Interview sagte, habe die Ukraine einen &#8220;Plan B&#8221;, um weiterhin Getreide zu exportieren, falls Russland aus dem Abkommen aussteige. Moskau fordert seinerseits die Wiederaufnahme der Ausfuhr von Ammoniakd\u00fcngern. Der ukrainische Minister f\u00fcr Agrarpolitik und Ern\u00e4hrung, Nikolai Solski, hat in einem am\u00a0Freitag ver\u00f6ffentlichten Interview mit der Nachrichtenagentur Reuters [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-03T12:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;\",\"datePublished\":\"2023-06-03T12:11:06+00:00\",\"dateModified\":\"2023-06-03T12:11:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg\",\"keywords\":[\"Bquot\",\"einen\",\"Falls\",\"Getreidedeal\",\"gibt\",\"Kiew\",\"quotPlan\",\"scheitert\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/\",\"name\":\"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg\",\"datePublished\":\"2023-06-03T12:11:06+00:00\",\"dateModified\":\"2023-06-03T12:11:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg\",\"width\":460,\"height\":259,\"caption\":\"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/","og_locale":"de_DE","og_type":"article","og_title":"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;","og_description":"Wie der ukrainische Landwirtschaftsminister Nikolai Solski in einem Interview sagte, habe die Ukraine einen &#8220;Plan B&#8221;, um weiterhin Getreide zu exportieren, falls Russland aus dem Abkommen aussteige. Moskau fordert seinerseits die Wiederaufnahme der Ausfuhr von Ammoniakd\u00fcngern. Der ukrainische Minister f\u00fcr Agrarpolitik und Ern\u00e4hrung, Nikolai Solski, hat in einem am\u00a0Freitag ver\u00f6ffentlichten Interview mit der Nachrichtenagentur Reuters [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-06-03T12:11:06+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;","datePublished":"2023-06-03T12:11:06+00:00","dateModified":"2023-06-03T12:11:06+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg","keywords":["Bquot","einen","Falls","Getreidedeal","gibt","Kiew","quotPlan","scheitert"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/","url":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/","name":"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg","datePublished":"2023-06-03T12:11:06+00:00","dateModified":"2023-06-03T12:11:06+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/06\/Kiew-Falls-Getreide-Deal-scheitert-gibt-es-einen-quotPlan-Bquot.jpg","width":460,"height":259,"caption":"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/kiew-falls-getreide-deal-scheitert-gibt-es-einen-plan-b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Kiew: Falls Getreide-Deal scheitert, gibt es einen &quot;Plan B&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/37359"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=37359"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/37359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/37360"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=37359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=37359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=37359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}