{"id":36598,"date":"2023-05-23T14:26:20","date_gmt":"2023-05-23T12:26:20","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/"},"modified":"2023-05-23T14:26:20","modified_gmt":"2023-05-23T12:26:20","slug":"studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/","title":{"rendered":"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/646ca85548fbef721c56f16e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das M\u00fcnchner ifo-Institut zeigt in einer aktuellen Studie unter anderem, dass Sanktionen in \u00e4rmeren L\u00e4ndern nicht nur das Wirtschaftswachstum dr\u00fccken, sondern auch die Lebenserwartung vor allem des \u00e4rmeren Teils der Bev\u00f6lkerung verk\u00fcrzen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wirtschaftssanktionen erzeugen hohe Kosten, vor allem f\u00fcr die \u00e4rmere Bev\u00f6lkerung in den Ziell\u00e4ndern.\u00a0Dies zeigt eine am Dienstag ver\u00f6ffentlichte Studie des in M\u00fcnchen ans\u00e4ssigen ifo-Instituts.<\/p>\n<p>Laut der Studie f\u00fchrten Sanktionen durch die\u00a0Vereinten Nationen dazu, dass das Wachstum in den sanktionierten L\u00e4ndern j\u00e4hrlich um 2 Prozent zur\u00fcckgehe. Auf zehn Jahre hochgerechnet komme dies einem Einbruch der Wirtschaftsleistung pro Kopf um 25 Prozent gleich.<\/p>\n<p>Einseitige Sanktionen durch die USA f\u00fchrten zu einem j\u00e4hrlichen R\u00fcckgang des Wachstums um knapp 1 Prozent in den betroffenen L\u00e4ndern. Langfristig entspreche dies laut der Studie einem Einbruch der\u00a0Wirtschaftsleistung pro Kopf um 13 Prozent.<\/p>\n<p>&#8220;Wirtschaftssanktionen treffen regelm\u00e4\u00dfig den Teil der Bev\u00f6lkerung in den sanktionierten L\u00e4ndern am st\u00e4rksten, der in oder nahe der Armut lebt&#8221;, schreibt Florian Neumeier, Leiter der ifo-Forschungsgruppe Steuer und Finanzpolitik auf der Webseite des Instituts. Und er f\u00fcgt hinzu:<\/p>\n<blockquote>\n<p><em>&#8220;Dies war in der Vergangenheit vor allem bei US-Sanktionen der Fall. Studien zeigen zum Beispiel, dass durch die 2012 verh\u00e4ngten Sanktionen gegen den Iran vor allem die junge, ungebildete Bev\u00f6lkerung auf dem Land zu leiden hatte.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die Zahlen der Studie basieren auf Auswertungen von Daten aus 160 L\u00e4ndern. Von diesen L\u00e4ndern waren 67 im Zeitraum von 1976 bis 2012 von Wirtschaftssanktionen betroffen.<\/p>\n<p>Im Hinblick auf die gegen Russland verh\u00e4ngten Sanktionen schreibt Neumeier:<\/p>\n<blockquote>\n<p><em>&#8220;In der Vergangenheit wurden Sanktionen meist gegen kleinere Volkswirtschaften verh\u00e4ngt. Aus den Analysen k\u00f6nnen wir daher nicht ableiten, wie die aktuellen Sanktionen auf eine gro\u00dfe Volkswirtschaft wie Russland wirken.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Weiter stellten die Macher der Studie fest, dass in \u00e4rmeren L\u00e4ndern Wirtschaftssanktionen auch zu einer geringeren Lebenserwartung in der Bev\u00f6lkerung f\u00fchren. Sanktionen durch die Vereinten Nationen verringerten demnach die Lebenserwartung der Bev\u00f6lkerung um durchschnittlich 1,2 bis 1,4 Jahre. Bei Sanktionen durch die USA verringere sich die Lebenserwartung laut der Studie um knapp ein halbes Jahr.<\/p>\n<p>Zudem seien den Daten zufolge Frauen von der Verh\u00e4ngung von Sanktionen st\u00e4rker betroffen als M\u00e4nner.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.life\/international\/170683-de-dollarisierung-laeuft-auf-hochtouren\/\">Die De-Dollarisierung l\u00e4uft auf Hochtouren, und der Hegemon blutet von innen aus<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2Flukaschenko-westen-gelang-es-nicht-russland-und-uns-die-luft-abzudrehen%3A9\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/170781-studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das M\u00fcnchner ifo-Institut zeigt in einer aktuellen Studie unter anderem, dass Sanktionen in \u00e4rmeren L\u00e4ndern nicht nur das Wirtschaftswachstum dr\u00fccken, sondern auch die Lebenserwartung vor allem des \u00e4rmeren Teils der Bev\u00f6lkerung verk\u00fcrzen. Wirtschaftssanktionen erzeugen hohe Kosten, vor allem f\u00fcr die \u00e4rmere Bev\u00f6lkerung in den Ziell\u00e4ndern.\u00a0Dies zeigt eine am Dienstag ver\u00f6ffentlichte Studie des in M\u00fcnchen ans\u00e4ssigen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36599,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1684845119"],"wp_automatic_camp":["217"],"7d5d3a6bd833d242bfd1c0c2c059b0aa":["Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern"],"original_link":["https:\/\/de.rt.com\/international\/170781-studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/"],"_thumbnail_id":["36599"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-05-23 14:32:57\";}"],"jnews_social_counter_last_update":["1788381450"]},"categories":[19,23],"tags":[9301,44646,27586,82,713,10038,3240,354,320,44647],"class_list":["post-36598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-allem","tag-aermeren","tag-bevoelkerung","tag-der","tag-sanktionen","tag-studie","tag-teil","tag-treffen","tag-vor","tag-ziellaendern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern\" \/>\n<meta property=\"og:description\" content=\"Das M\u00fcnchner ifo-Institut zeigt in einer aktuellen Studie unter anderem, dass Sanktionen in \u00e4rmeren L\u00e4ndern nicht nur das Wirtschaftswachstum dr\u00fccken, sondern auch die Lebenserwartung vor allem des \u00e4rmeren Teils der Bev\u00f6lkerung verk\u00fcrzen. Wirtschaftssanktionen erzeugen hohe Kosten, vor allem f\u00fcr die \u00e4rmere Bev\u00f6lkerung in den Ziell\u00e4ndern.\u00a0Dies zeigt eine am Dienstag ver\u00f6ffentlichte Studie des in M\u00fcnchen ans\u00e4ssigen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-23T12:26:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern\",\"datePublished\":\"2023-05-23T12:26:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg\",\"keywords\":[\"Allem\",\"\u00e4rmeren\",\"Bev\u00f6lkerung\",\"der\",\"Sanktionen\",\"STUDIE\",\"Teil\",\"Treffen\",\"vor\",\"Ziell\u00e4ndern\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/\",\"name\":\"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg\",\"datePublished\":\"2023-05-23T12:26:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg\",\"width\":460,\"height\":259,\"caption\":\"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/","og_locale":"de_DE","og_type":"article","og_title":"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern","og_description":"Das M\u00fcnchner ifo-Institut zeigt in einer aktuellen Studie unter anderem, dass Sanktionen in \u00e4rmeren L\u00e4ndern nicht nur das Wirtschaftswachstum dr\u00fccken, sondern auch die Lebenserwartung vor allem des \u00e4rmeren Teils der Bev\u00f6lkerung verk\u00fcrzen. Wirtschaftssanktionen erzeugen hohe Kosten, vor allem f\u00fcr die \u00e4rmere Bev\u00f6lkerung in den Ziell\u00e4ndern.\u00a0Dies zeigt eine am Dienstag ver\u00f6ffentlichte Studie des in M\u00fcnchen ans\u00e4ssigen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-05-23T12:26:20+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern","datePublished":"2023-05-23T12:26:20+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg","keywords":["Allem","\u00e4rmeren","Bev\u00f6lkerung","der","Sanktionen","STUDIE","Teil","Treffen","vor","Ziell\u00e4ndern"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/","url":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/","name":"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg","datePublished":"2023-05-23T12:26:20+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Studie-Sanktionen-treffen-vor-allem-aermeren-Teil-der-Bevoelkerung-in.jpg","width":460,"height":259,"caption":"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/studie-sanktionen-treffen-vor-allem-aermeren-teil-der-bevoelkerung-in-ziellaendern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Studie: Sanktionen treffen vor allem \u00e4rmeren Teil der Bev\u00f6lkerung in Ziell\u00e4ndern"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=36598"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/36599"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=36598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=36598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=36598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}