{"id":36283,"date":"2023-05-18T11:20:02","date_gmt":"2023-05-18T09:20:02","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/"},"modified":"2023-05-18T11:20:02","modified_gmt":"2023-05-18T09:20:02","slug":"sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/","title":{"rendered":"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/6465e47448fbef0c1e1b6760.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Boris Pistorius st\u00e4rkt seinem Kabinettskollegen Robert Habeck den R\u00fccken. Zumindest vordergr\u00fcndig. Es sei &#8220;schade&#8221;, dass sich der Gr\u00fcne in einer schwierigen Phase befindet. Pistorius erkl\u00e4rte aber auch, dass niemand wisse, was das Steinumdrehen noch ergebe.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der deutsche Verteidigungsminister, Boris Pistorius, hat die Zukunft seines Kabinettskollegen Robert Habeck als &#8220;offen&#8221; bezeichnet. In der <em>ARD<\/em>-Talkshow <em>Maischberger<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.ardmediathek.de\/video\/maischberger\/maischberger-am-17-05-2023\/das-erste\/Y3JpZDovL2Rhc2Vyc3RlLmRlL21lbnNjaGVuIGJlaSBtYWlzY2hiZXJnZXIvMjAyMy0wNS0xN18yMi01MC1NRVNa\">nannte<\/a>\u00a0der SPD-Mann Pistorius die Entlassung des Staatssekret\u00e4rs Patrick Graichen durch den Wirtschaftsminister &#8220;ganz sicher richtig&#8221; (etwa bei Minute 20). Er sagte aber auch:<\/p>\n<blockquote>\n<p><em>&#8220;Ich wei\u00df ja nicht, ob es noch etwas gibt. Ich gehe davon aus, dass es nichts mehr gibt. Aber wissen tue ich das eben nicht. Deswegen sage ich ja: Der weitere Spielverlauf entscheidet am Ende \u00fcber die Bewertung: War das jetzt ein Befreiungsschlag oder ein Eigentor?&#8221;<\/em><strong><\/strong><\/p>\n<\/blockquote>\n<p>Es sei offen, wie es bei Habeck weitergehe:<\/p>\n<blockquote>\n<p><em>&#8220;Das h\u00e4ngt jetzt an vielen Faktoren, die niemand mehr beeinflussen kann. Niemand wei\u00df, was das Steinumdrehen noch erbringt. Das sind Situationen, in denen so ein Haus ein Eigenleben sehr schnell entwickeln kann. Und der ein oder andere f\u00fchlt sich vielleicht bem\u00fc\u00dfigt oder ermuntert, das ein oder andere durchzustechen. Das ist eine schwierige Phase f\u00fcr Robert Habeck. Das ist wirklich sehr schade.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Habeck hatte am Mittwoch seinen Vertrauten Graichen entlassen, nachdem eine Pr\u00fcfung im Ministerium neue Unregelm\u00e4\u00dfigkeiten ergeben hatte. Diesmal ging es um die Vergabe von Mitteln in H\u00f6he\u00a0600.000 Euro an\u00a0den BUND Berlin. Graichens Schwester Verena sitzt im Vorstand dieses Landesverbandes der Umweltorganisation.<\/p>\n<p>Zuvor war Graichen\u00a0die Einsetzung seines Trauzeugen als Chef der bundeseigenen Deutschen Energie-Agentur (Dena) vorgeworfen worden. Auch die Verbindungen zwischen dem Wirtschaftsministerium und den einflussreichen &#8220;Denkfabriken&#8221; &#8220;\u00d6ko-Institut&#8221; und &#8220;Agora Energiewende&#8221; waren in die Kritik geraten. Anders als die Filzvorw\u00fcrfe im Ministerium sind die Abh\u00e4ngigkeiten dieser &#8220;Denkfabriken&#8221; von der Finanzindustrie bislang nur vereinzelt in der Berichterstattung aufgetaucht.<\/p>\n<p>Pistorius&#8217; \u00c4u\u00dferungen selbst d\u00fcrften Habecks Lage nicht einfacher machen. Auch wenn der Verteidigungsminister sein Bedauern \u00fcber dessen Lage ausdr\u00fcckte (&#8220;sehr schade&#8221;), wirken seine \u00c4u\u00dferungen wie eine Distanzierung von dem fr\u00fcheren Kinderbuchautor (&#8220;Niemand wei\u00df, was das Steinumdrehen noch erbringt&#8221;).<\/p>\n<p>Tats\u00e4chlich k\u00f6nnte der SPD eine Schw\u00e4chung des &#8220;Ministers f\u00fcr Wirtschaft und Klimaschutz&#8221; durchaus gelegen kommen. Die Partei vertritt bei den Themen &#8220;Klimaschutz&#8221; und Heizungsverordnung einen moderateren Kurs als die Gr\u00fcnen, ohne allerdings die zugrundeliegende Logik der CO2-Reduzierung infrage zu stellen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.live\/inland\/170299-spaetes-bauernopfer-habecks-stellungnahme-zur\/\">Sp\u00e4tes Bauernopfer? Habecks Stellungnahme zur Entlassung von Staatssekret\u00e4r Patrick Graichen<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FHabeck_beklagt_rechte_und_pro-russische_Hetze%3A3\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/170374-sehr-schade-pistorius-bezeichnet-habecks\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boris Pistorius st\u00e4rkt seinem Kabinettskollegen Robert Habeck den R\u00fccken. Zumindest vordergr\u00fcndig. Es sei &#8220;schade&#8221;, dass sich der Gr\u00fcne in einer schwierigen Phase befindet. Pistorius erkl\u00e4rte aber auch, dass niemand wisse, was das Steinumdrehen noch ergebe. Der deutsche Verteidigungsminister, Boris Pistorius, hat die Zukunft seines Kabinettskollegen Robert Habeck als &#8220;offen&#8221; bezeichnet. In der ARD-Talkshow Maischberger\u00a0nannte\u00a0der SPD-Mann [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1684401668"],"wp_automatic_camp":["217"],"e13b452d7c2cffb61dd85d4bf6ad68dd":["&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;"],"original_link":["https:\/\/de.rt.com\/inland\/170374-sehr-schade-pistorius-bezeichnet-habecks\/"],"_thumbnail_id":["36284"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-05-18 11:22:13\";}"],"jnews_social_counter_last_update":["1783993575"]},"categories":[19,23],"tags":[273,7183,27726,39179,44453,18787,37378,3250],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;\" \/>\n<meta property=\"og:description\" content=\"Boris Pistorius st\u00e4rkt seinem Kabinettskollegen Robert Habeck den R\u00fccken. Zumindest vordergr\u00fcndig. Es sei &#8220;schade&#8221;, dass sich der Gr\u00fcne in einer schwierigen Phase befindet. Pistorius erkl\u00e4rte aber auch, dass niemand wisse, was das Steinumdrehen noch ergebe. Der deutsche Verteidigungsminister, Boris Pistorius, hat die Zukunft seines Kabinettskollegen Robert Habeck als &#8220;offen&#8221; bezeichnet. In der ARD-Talkshow Maischberger\u00a0nannte\u00a0der SPD-Mann [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-18T09:20:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;\",\"datePublished\":\"2023-05-18T09:20:02+00:00\",\"dateModified\":\"2023-05-18T09:20:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/\"},\"wordCount\":425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg\",\"keywords\":[\"als\",\"bezeichnet\",\"Habecks\",\"Pistorius\",\"quotoffenquot\",\"quotsehr\",\"schadequot\",\"Zukunft\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/\",\"name\":\"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg\",\"datePublished\":\"2023-05-18T09:20:02+00:00\",\"dateModified\":\"2023-05-18T09:20:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;","og_description":"Boris Pistorius st\u00e4rkt seinem Kabinettskollegen Robert Habeck den R\u00fccken. Zumindest vordergr\u00fcndig. Es sei &#8220;schade&#8221;, dass sich der Gr\u00fcne in einer schwierigen Phase befindet. Pistorius erkl\u00e4rte aber auch, dass niemand wisse, was das Steinumdrehen noch ergebe. Der deutsche Verteidigungsminister, Boris Pistorius, hat die Zukunft seines Kabinettskollegen Robert Habeck als &#8220;offen&#8221; bezeichnet. In der ARD-Talkshow Maischberger\u00a0nannte\u00a0der SPD-Mann [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-05-18T09:20:02+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;","datePublished":"2023-05-18T09:20:02+00:00","dateModified":"2023-05-18T09:20:02+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/"},"wordCount":425,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg","keywords":["als","bezeichnet","Habecks","Pistorius","quotoffenquot","quotsehr","schadequot","Zukunft"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/","url":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/","name":"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg","datePublished":"2023-05-18T09:20:02+00:00","dateModified":"2023-05-18T09:20:02+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/quotSehr-schadequot-Pistorius-bezeichnet-Habecks-Zukunft-als-quotoffenquot.jpg","width":460,"height":259,"caption":"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/sehr-schade-pistorius-bezeichnet-habecks-zukunft-als-offen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Sehr schade&quot;: Pistorius bezeichnet Habecks Zukunft als &quot;offen&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36283"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=36283"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/36284"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=36283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=36283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=36283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}