{"id":36277,"date":"2023-05-18T09:37:09","date_gmt":"2023-05-18T07:37:09","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/"},"modified":"2023-05-18T09:37:09","modified_gmt":"2023-05-18T07:37:09","slug":"russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/","title":{"rendered":"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/6464c99648fbef0c3a0f6284.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Am Mittwoch haben Moskau und Teheran den Bau einer Eisenbahnstrecke im Nordwesten des Irans vereinbart. Die Route Rascht-Astara wird der letzte Abschnitt des internationalen Verkehrskorridors zwischen Sankt Petersburg und Mumbai werden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Russland nimmt am Bau einer neuen Eisenbahnlinie zwischen den iranischen St\u00e4dten Rascht und Astara teil.\u00a0Am Mittwoch haben die Vertreter der beiden L\u00e4nder, Russlands Minister f\u00fcr Transport, Witali Saweljew, und Irans Minister f\u00fcr Stra\u00dfen und Stadtentwicklung, Mehrdad Bazrpash, das entsprechende Abkommen\u00a0in Teheran\u00a0unterzeichnet.\u00a0Demnach werden Russland und der Iran die gemeinsame Finanzierung\u00a0der Projektarbeit und des Baus sowie weiterer Lieferungen von Waren und Dienstleistungen vornehmen.<\/p>\n<p>Russlands\u00a0Pr\u00e4sident Wladimir Putin, der per Videoschaltung an der Unterzeichnungszeremonie teilnahm, hob die besondere Bedeutung der Eisenbahnstrecke f\u00fcr die Diversifizierung der weltweiten Verkehrswege hervor.\u00a0Ihm zufolge stelle sie aus logistischer Sicht eine bedeutende Erg\u00e4nzung zum Suezkanal und den Meerengen des Schwarzen Meeres dar.\u00a0Dar\u00fcber hinaus wies Putin auf betr\u00e4chtliche Wettbewerbsvorteile hin:<\/p>\n<blockquote>\n<p><em>&#8220;Zum Beispiel wird die Frachtlieferung von Sankt Petersburg nach, sagen wir, Mumbai etwa zehn Tage in Anspruch nehmen. Im Vergleich dazu dauert es auf den traditionellen Handelsrouten 30 bis 45 Tage. Das bedeutet eine erhebliche Ersparnis an Zeit und Kosten.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der stellvertretende russische Ministerpr\u00e4sident Alexander Nowak, der sich auf einer Dienstreise in Teheran befindet, erkl\u00e4rte gegen\u00fcber Journalisten, dass f\u00fcr das Projekt ein zwischenstaatlicher Kredit in H\u00f6he von 1,3 Milliarden Euro bereitgestellt werde. Die Gesamtkosten\u00a0sollen\u00a0sich auf 1,6 Milliarden Euro belaufen.<\/p>\n<p>Rund\u00a0170 Kilometer betr\u00e4gt\u00a0die Strecke\u00a0Rascht-Astara, welche der letzte Teil des internationalen Verkehrskorridors Nord-S\u00fcd sein wird.\u00a0Die Transkaspische Bodenroute verkn\u00fcpft Sankt Petersburg in Russland\u00a0mit dem\u00a0indischen Mumbai \u00fcber den Iran und dient als Alternative zur traditionellen Seeroute durch das Mittelmeer und den Suezkanal.<\/p>\n<p><strong>Mehr zum Thema\u00a0\u2013<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/gegenzensur.rtde.live\/der-nahe-osten\/170182-zunehmender-bedeutungsverlust-westens-in-region\/\">Zunehmender Bedeutungsverlust des Westens in der Region: Baerbock im Nahen Osten<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/170316-russland-und-iran-bauen-eisenbahnstrecke\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Mittwoch haben Moskau und Teheran den Bau einer Eisenbahnstrecke im Nordwesten des Irans vereinbart. Die Route Rascht-Astara wird der letzte Abschnitt des internationalen Verkehrskorridors zwischen Sankt Petersburg und Mumbai werden. Russland nimmt am Bau einer neuen Eisenbahnlinie zwischen den iranischen St\u00e4dten Rascht und Astara teil.\u00a0Am Mittwoch haben die Vertreter der beiden L\u00e4nder, Russlands Minister [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1684396860"],"wp_automatic_camp":["217"],"0772928fd950228a1a0ec71e07d5d5b1":["Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett"],"original_link":["https:\/\/de.rt.com\/international\/170316-russland-und-iran-bauen-eisenbahnstrecke\/"],"_thumbnail_id":["36278"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-05-18 10:02:00\";}"],"jnews_social_counter_last_update":["1778436209"]},"categories":[19,23],"tags":[5644,275,44447,44448,1786,5811,44449,126,140,374,6580],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett\" \/>\n<meta property=\"og:description\" content=\"Am Mittwoch haben Moskau und Teheran den Bau einer Eisenbahnstrecke im Nordwesten des Irans vereinbart. Die Route Rascht-Astara wird der letzte Abschnitt des internationalen Verkehrskorridors zwischen Sankt Petersburg und Mumbai werden. Russland nimmt am Bau einer neuen Eisenbahnlinie zwischen den iranischen St\u00e4dten Rascht und Astara teil.\u00a0Am Mittwoch haben die Vertreter der beiden L\u00e4nder, Russlands Minister [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-18T07:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett\",\"datePublished\":\"2023-05-18T07:37:09+00:00\",\"dateModified\":\"2023-05-18T07:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg\",\"keywords\":[\"bauen\",\"eine\",\"Eisenbahnstrecke\",\"Handelsroute\",\"Iran\",\"komplett\",\"NordS\u00fcd\",\"russland\",\"und\",\"wird\",\"zusammen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/\",\"name\":\"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg\",\"datePublished\":\"2023-05-18T07:37:09+00:00\",\"dateModified\":\"2023-05-18T07:37:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg\",\"width\":460,\"height\":259,\"caption\":\"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/","og_locale":"de_DE","og_type":"article","og_title":"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett","og_description":"Am Mittwoch haben Moskau und Teheran den Bau einer Eisenbahnstrecke im Nordwesten des Irans vereinbart. Die Route Rascht-Astara wird der letzte Abschnitt des internationalen Verkehrskorridors zwischen Sankt Petersburg und Mumbai werden. Russland nimmt am Bau einer neuen Eisenbahnlinie zwischen den iranischen St\u00e4dten Rascht und Astara teil.\u00a0Am Mittwoch haben die Vertreter der beiden L\u00e4nder, Russlands Minister [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-05-18T07:37:09+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett","datePublished":"2023-05-18T07:37:09+00:00","dateModified":"2023-05-18T07:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg","keywords":["bauen","eine","Eisenbahnstrecke","Handelsroute","Iran","komplett","NordS\u00fcd","russland","und","wird","zusammen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/","url":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/","name":"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg","datePublished":"2023-05-18T07:37:09+00:00","dateModified":"2023-05-18T07:37:09+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Russland-und-Iran-bauen-eine-Eisenbahnstrecke-zusammen-\u2013-Handelsroute-Nord-Sued.jpg","width":460,"height":259,"caption":"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-iran-bauen-eine-eisenbahnstrecke-zusammen-handelsroute-nord-sued-wird-komplett\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russland und Iran bauen eine Eisenbahnstrecke zusammen \u2013 Handelsroute Nord-S\u00fcd wird komplett"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36277"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=36277"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/36278"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=36277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=36277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=36277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}