{"id":36104,"date":"2023-05-15T17:17:02","date_gmt":"2023-05-15T15:17:02","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/"},"modified":"2023-05-15T17:17:02","modified_gmt":"2023-05-15T15:17:02","slug":"selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/","title":{"rendered":"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;"},"content":{"rendered":"<div class=\"Text-root Text-type_1 \">\n                Der Besuch Selenskijs in Rom hatte ein sp\u00fcrbares Ergebnis: Die Friedensinitiativen des Vatikans k\u00f6nnen als gescheitert angesehen werden \u2013 noch bevor \u00fcberhaupt jemals dar\u00fcber verhandelt wurde. Ansonsten fiel auf, dass \u2013 neben der Gastgeberin Meloni \u2013 auch Selenskij dort ganz in Schwarz gekleidet war. Ein Hauch von Mussolinis faschistischen Schwarzhemden wehte \u00fcber Rom.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Wladimir Kornilow<\/em><\/p>\n<p>Der Wunsch des Anf\u00fchrers Wladimir Selenskij vom ukrainischen Regime, auch beim Eurovisions-Finale quasi im Namen der Ukraine auftreten zu d\u00fcrfen, wurde ausnahmsweise mal nicht erf\u00fcllt. Selenskij erhielt von den Organisatoren des diesmal in Gro\u00dfbritannien ausgetragenen Song-Wettbewerbs eine schmerzhafte Abfuhr.\u00a0Um sich diese bittere Pille zu vers\u00fc\u00dfen, organisierte er sich einen eint\u00e4gigen &#8220;Ferienaufenthalt&#8221; in Italien \u2013 so nannten es jedenfalls die Illustratoren der Zeitung <em>Corriere della Sera<\/em>.<\/p>\n<p>Tats\u00e4chlich wurde diese Reise in der italienischen Presse als &#8220;Friedensbesuch&#8221; angek\u00fcndigt. Zun\u00e4chst schrieb man nicht so sehr \u00fcber Selenskijs Treffen mit Regierungsvertretern, sondern vor allem \u00fcber seine Absicht, dem Papst einen Besuch abstatten zu d\u00fcrfen. Das Oberhaupt der r\u00f6misch-katholischen Kirche hatte selbst k\u00fcrzlich eine Reihe von Friedensinitiativen angek\u00fcndigt.<\/p>\n<p>W\u00e4hrend einige im Vatikan offenbar etwas naiv glaubten, dass mit dem Anf\u00fchrer der Ukraine \u00fcber Frieden gesprochen werden k\u00f6nne, zerst\u00f6rte Selenskij jegliche dieser Erwartungen noch vor seiner Audienz bei Franziskus. In einer kurzen Pressekonferenz mit der italienischen Ministerpr\u00e4sidentin Giorgia Meloni dankte er Italien und ihr pers\u00f6nlich f\u00fcr die milit\u00e4rische Unterst\u00fctzung und die Bereitstellung neuer t\u00f6dlicher Waffen. Und das, obwohl Matteo Salvini als stellvertretender Ministerpr\u00e4sident ihrer Koalitionsregierung seine Chefin am Vortag noch eindringlich gebeten hatte, den von Selenskij entfachten Krieg nicht mit noch mehr Waffen anzuheizen.<\/p>\n<p>Das Treffen zwischen Meloni und Selenskij war insgesamt sehr symboltr\u00e4chtig. Italien reagiert derzeit sehr lebhaft auf viele seiner Jubil\u00e4en und Jahrestage. Angesichts der Tatsache, dass zum ersten Mal seit dem Zweiten Weltkrieg die geistigen Erben von Mussolinis Partei an die Macht gekommen sind, gab es gro\u00dfe Diskussionen dar\u00fcber, wie man auf den 100. Jahrestag von Mussolinis &#8220;Marsch der Schwarzhemden auf Rom&#8221; sowie auf den Tag der Befreiung vom Faschismus reagieren sollte.<\/p>\n<p>Meloni hatte bislang versucht, sich aus diesen Diskussionen herauszuhalten. Als sie und Selenskij aber vor der Ehrengarde ganz in schwarz gekleidet vorbeidefilierten (es ist schwer zu sagen, ob sie sich \u00fcber die Kleiderordnung des Treffens geeinigt hatten oder ob es ein Zufall war), sp\u00fcrte jeder Betrachter deutlich die Atmosph\u00e4re der historischen Auferstehung und des Revanchismus in der Luft \u00fcber Rom. Die kriegerischen Reden dieser beiden &#8220;Schwarzhemden&#8221; unserer Tage unterschieden sich nicht sehr von denen des ideologischen Vorl\u00e4ufers der &#8220;Br\u00fcder Italiens&#8221;.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/64621ea648fbef1e6e5bc820.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/64621ea648fbef1e6e5bc820.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/64621ea648fbef1e6e5bc820.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/64621ea648fbef1e6e5bc820.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/64621ea648fbef1e6e5bc820.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/64621ea648fbef1e6e5bc820.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Zufall oder nicht: Gastgeberin Meloni (rechts) und Gast Selenskij waren beide in schwarz gekleidet.<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">ALBERTO PIZZOLI \/ AFP<\/span><span class=\"RTImage-captionItem\"> \/ AFP<\/span><\/span><\/figcaption><\/figure>\n<p>In dieser Atmosph\u00e4re konnte selbst der Papst nichts mehr bewirken. Seine Beamten forderten zwar am Vorabend des Treffens des Pontifex mit Selenskij erneut ein Ende der Waffenlieferungen an die Ukraine, einen Waffenstillstand und die Aufnahme von Verhandlungen. Doch der Gast aus Kiew antwortete unverhohlen h\u00f6hnisch: &#8220;Wir brauchen keine Vermittler zwischen der Ukraine und dem Aggressor.&#8221; Stattdessen lud Selenskij den Papst &#8220;und alle anderen Friedensstifter&#8221; ein, sich seiner ber\u00fcchtigten &#8220;Friedensformel&#8221; anzuschlie\u00dfen, die in Wirklichkeit eine Forderung nach der vollst\u00e4ndigen Kapitulation Russlands ist.<\/p>\n<p>Das hei\u00dft, der gescheiterte Eurovisions-Finalist hat dem Papst verboten, heiliger sein zu wollen als er selbst, der &#8220;gr\u00f6\u00dfte Friedensstifter&#8221;. Alles, was Selenskij dem Pontifex gn\u00e4dig erlaubte, war, sich weiter mit dem &#8220;Problem&#8221; der durch Russland angeblich &#8220;entf\u00fchrten&#8221; Kinder zu befassen.<\/p>\n<p>Zum jetzigen Zeitpunkt kann man also sagen, dass alle Friedensmissionen des Papstes gescheitert sind, bevor sie \u00fcberhaupt beginnen konnten. Was Selenskij w\u00e4hrend seiner wenigen Stunden in Rom sagte, zeigt, dass er immer noch entschlossen ist, sein Land &#8220;bis zum letzten Ukrainer&#8221; k\u00e4mpfen zu lassen. Au\u00dferdem hat er wiederholt erkl\u00e4rt, dass andernfalls die Europ\u00e4er (insbesondere auch die Italiener) an die Front m\u00fcssten. Auf die Idee, dass er damit verlangt, angeblich f\u00fcr Europa zun\u00e4chst Millionen von Ukrainern zu Kanonenfutter zu machen, ist er nicht gekommen.<\/p>\n<p>Meloni erkl\u00e4rte, Italien werde der Ukraine eine &#8220;360-Grad-Rundumunterst\u00fczung&#8221; gew\u00e4hren. Mit dieser wohl unfreiwilligen Assoziation betonte Meloni einmal mehr auch eine gewissen ideologische Verwandtschaft zur mittlerweile ber\u00fchmten deutschen Geometrieexpertin Annalena Baerbock, die Selenskij unmittelbar nach dem Besuch in Rom wieder treffen durfte.<\/p>\n<p>Selenskijs &#8220;italienische Ferien&#8221; best\u00e4tigten also einmal mehr: Europa wird von Inkompetenz regiert, niemand sucht dort nach Frieden, und Russland bleibt gar keine andere Wahl, als unerbittlich auf dem Schlachtfeld gewinnen zu m\u00fcssen. Und selbst der Papst vermag an dieser Situation derzeit nichts zu \u00e4ndern.<\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ria.ru\/20230515\/zelenskiy-1871672554.html\">Russischen<\/a>. Der Artikel erschien auf ria.ru am 15. Mai 2023.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.tech\/inland\/170080-selenskij-ist-kriegstreiber-proteste-gegen\/\">&#8220;Selenskij ist ein Kriegstreiber&#8221; \u2013 Proteste gegen Karlspreisverleihung an Selenskij<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/170124-selenskij-brueskiert-papst-und-bekommt\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Besuch Selenskijs in Rom hatte ein sp\u00fcrbares Ergebnis: Die Friedensinitiativen des Vatikans k\u00f6nnen als gescheitert angesehen werden \u2013 noch bevor \u00fcberhaupt jemals dar\u00fcber verhandelt wurde. Ansonsten fiel auf, dass \u2013 neben der Gastgeberin Meloni \u2013 auch Selenskij dort ganz in Schwarz gekleidet war. Ein Hauch von Mussolinis faschistischen Schwarzhemden wehte \u00fcber Rom. Von Wladimir [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1684164302"],"wp_automatic_camp":["217"],"d9d5b7024aa90ba30221842da590ee2f":["Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;"],"original_link":["https:\/\/de.rt.com\/meinung\/170124-selenskij-brueskiert-papst-und-bekommt\/"],"_thumbnail_id":["36105"],"jnews_social_counter_last_update":["1784128767"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-05-15 17:26:02\";}"]},"categories":[19,23],"tags":[13666,9970,48,43,2665,44336,6158,140,50],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;\" \/>\n<meta property=\"og:description\" content=\"Der Besuch Selenskijs in Rom hatte ein sp\u00fcrbares Ergebnis: Die Friedensinitiativen des Vatikans k\u00f6nnen als gescheitert angesehen werden \u2013 noch bevor \u00fcberhaupt jemals dar\u00fcber verhandelt wurde. Ansonsten fiel auf, dass \u2013 neben der Gastgeberin Meloni \u2013 auch Selenskij dort ganz in Schwarz gekleidet war. Ein Hauch von Mussolinis faschistischen Schwarzhemden wehte \u00fcber Rom. Von Wladimir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-15T15:17:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1553\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;\",\"datePublished\":\"2023-05-15T15:17:02+00:00\",\"dateModified\":\"2023-05-15T15:17:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/\"},\"wordCount\":806,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg\",\"keywords\":[\"bekommt\",\"br\u00fcskiert\",\"den\",\"Italien\",\"papst\",\"quot360GradRundumschutzquot\",\"Selenskij\",\"und\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/\",\"name\":\"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg\",\"datePublished\":\"2023-05-15T15:17:02+00:00\",\"dateModified\":\"2023-05-15T15:17:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg\",\"width\":1553,\"height\":1080,\"caption\":\"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;","og_description":"Der Besuch Selenskijs in Rom hatte ein sp\u00fcrbares Ergebnis: Die Friedensinitiativen des Vatikans k\u00f6nnen als gescheitert angesehen werden \u2013 noch bevor \u00fcberhaupt jemals dar\u00fcber verhandelt wurde. Ansonsten fiel auf, dass \u2013 neben der Gastgeberin Meloni \u2013 auch Selenskij dort ganz in Schwarz gekleidet war. Ein Hauch von Mussolinis faschistischen Schwarzhemden wehte \u00fcber Rom. Von Wladimir [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-05-15T15:17:02+00:00","og_image":[{"width":1553,"height":1080,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;","datePublished":"2023-05-15T15:17:02+00:00","dateModified":"2023-05-15T15:17:02+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/"},"wordCount":806,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg","keywords":["bekommt","br\u00fcskiert","den","Italien","papst","quot360GradRundumschutzquot","Selenskij","und","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/","url":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/","name":"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg","datePublished":"2023-05-15T15:17:02+00:00","dateModified":"2023-05-15T15:17:02+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Selenskij-brueskiert-den-Papst-und-bekommt-von-Italien-quot360-Grad-Rundumschutzquot.jpg","width":1553,"height":1080,"caption":"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskij-brueskiert-den-papst-und-bekommt-von-italien-360-grad-rundumschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Selenskij br\u00fcskiert den Papst und bekommt von Italien &quot;360-Grad-Rundumschutz&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36104"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=36104"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/36104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/36105"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=36104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=36104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=36104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}