{"id":35518,"date":"2023-05-06T11:36:18","date_gmt":"2023-05-06T09:36:18","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/"},"modified":"2023-05-06T11:36:18","modified_gmt":"2023-05-06T09:36:18","slug":"ukraine-blogger-gonzalo-lira-verhaftet","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/","title":{"rendered":"Ukraine: Blogger Gonzalo Lira verhaftet"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/645619deb480cc13452adc8c.png\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der bekannte chilenisch-amerikanische Blogger und Filmemacher Gonzalo Lira ist am Freitag im ukrainischen Charkow verhaftet worden. Der SBU wirft ihm vor, die &#8220;russische Aggression&#8221; zu rechtfertigen und die oberste F\u00fchrung des Landes &#8220;zu diskreditieren&#8221;.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Medienberichten zufolge hat der ukrainische Sicherheitsdienst SBU am Freitag in Charkow den bekannten Blogger und Filmemacher Gonzalo Lira verhaftet. Videoaufnahmen in sozialen Netzwerken zeigen die Verhaftung.\u00a0<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"fr\" dir=\"ltr\">UKRAINE ARRESTS GONZALO LIRA<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/0k4zpUqBlb\">pic.twitter.com\/0k4zpUqBlb<\/a><\/p>\n<p>\u2014 The_Real_Fly (@The_Real_Fly) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/The_Real_Fly\/status\/1654588212361265152?ref_src=twsrc%5Etfw\">May 5, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Gonzalo Lira lebt seit einigen Jahren in der Ukraine und berichtete kritisch \u00fcber die Lage im Land. Im M\u00e4rz vergangenen Jahres wurde er schon einmal <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.life\/meinung\/136766-us-journalist-wird-in-ukraine\/\">verhaftet<\/a>, kam nach einer Woche jedoch wieder frei. Ungeachtet dieser Erfahrung blieb er in der Ukraine. Nunmehr beschuldigen die Strafverfolgungsbeh\u00f6rden ihn, die &#8220;russische Besatzung&#8221; zu unterst\u00fctzen und Moskaus &#8220;offensichtliche Kriegsverbrechen w\u00e4hrend des Krieges&#8221; zu verherrlichen. Au\u00dferdem soll er versucht haben, die h\u00f6chste milit\u00e4rische und politische F\u00fchrung der Ukraine zu diskreditieren.<\/p>\n<p>Der SBU wirft ihm auch vor, die Fakten der russischen Raketenangriffe auf ukrainische St\u00e4dte und die Massent\u00f6tung von Zivilisten durch die Invasionstruppen zu leugnen.<\/p>\n<p>Bei einer Durchsuchung seines Besitzes fanden die Strafverfolgungsbeh\u00f6rden Mobiltelefone und einen Computer, die angeblich Beweise f\u00fcr seine &#8220;illegalen Aktivit\u00e4ten&#8221; enthalten sollen. Gegen den Journalisten wurde inzwischen von einem Gericht Untersuchungshaft angeordnet. Die Ermittlungen dauern an.<\/p>\n<p>Gonzalo Lira ist von Beruf Autor und Filmregisseur, er hat in Chile mehrere Romane ver\u00f6ffentlicht. Er ist chilenischer und US-amerikanischer Staatsb\u00fcrger, lebte aber schon vor Beginn der russischen Milit\u00e4roperation in der Ukraine, hat Frau und Kinder in Charkow. Anfang M\u00e4rz 2022 begann er per Video und Diskussionen im Livestream aus der Ukraine zu berichten, vor allem in seinen privaten Kan\u00e4len auf YouTube und Twitter. Er berichtete dabei auch \u00fcber die Umst\u00e4nde, unter denen er sich in Charkow befand. Es sei ihm nicht m\u00f6glich, die Ukraine zu verlassen, weil er an jedem Kontrollpunkt verhaftet werden k\u00f6nnte.\u00a0<\/p>\n<p>Am 15. April 2022 wurde Lira vom ukrainischen Geheimdienst SBU festgenommen, auch damals wurden sein Computer und sein Mobiltelefon beschlagnahmt. Am 22. April 2022 gab es dann wieder ein Lebenszeichen von ihm, als er nach seiner Entlassung <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.life\/international\/136786-gonzalo-lira-lebt-und-gibt\/\">ein Videointerview<\/a> gab. Er gab damals an, die\u00a0&#8220;offizielle Seite&#8221; habe ihm ausdr\u00fccklich\u00a0untersagt, Charkow zu verlassen.\u00a0<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.life\/international\/136786-gonzalo-lira-lebt-und-gibt\/\">Ein US-Journalist wird in der Ukraine vermisst \u2013 Das Schweigen dar\u00fcber ist ohrenbet\u00e4ubend<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/169399-ukraine-blogger-gonzalo-lira-verhaftet\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der bekannte chilenisch-amerikanische Blogger und Filmemacher Gonzalo Lira ist am Freitag im ukrainischen Charkow verhaftet worden. Der SBU wirft ihm vor, die &#8220;russische Aggression&#8221; zu rechtfertigen und die oberste F\u00fchrung des Landes &#8220;zu diskreditieren&#8221;. Medienberichten zufolge hat der ukrainische Sicherheitsdienst SBU am Freitag in Charkow den bekannten Blogger und Filmemacher Gonzalo Lira verhaftet. Videoaufnahmen in [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":35519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1683365946"],"wp_automatic_camp":["217"],"35254c2f5d022bd477da48a2634bbe69":["Ukraine: Blogger Gonzalo Lira verhaftet"],"original_link":["https:\/\/de.rt.com\/international\/169399-ukraine-blogger-gonzalo-lira-verhaftet\/"],"_thumbnail_id":["35519"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-05-06 11:40:18\";}"],"jnews_social_counter_last_update":["1788311747"]},"categories":[19,23],"tags":[5185,4010,4011,127,8346],"class_list":["post-35518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-blogger","tag-gonzalo","tag-lira","tag-ukraine","tag-verhaftet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ukraine: Blogger Gonzalo Lira verhaftet - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ukraine: Blogger Gonzalo Lira verhaftet\" \/>\n<meta property=\"og:description\" content=\"Der bekannte chilenisch-amerikanische Blogger und Filmemacher Gonzalo Lira ist am Freitag im ukrainischen Charkow verhaftet worden. Der SBU wirft ihm vor, die &#8220;russische Aggression&#8221; zu rechtfertigen und die oberste F\u00fchrung des Landes &#8220;zu diskreditieren&#8221;. Medienberichten zufolge hat der ukrainische Sicherheitsdienst SBU am Freitag in Charkow den bekannten Blogger und Filmemacher Gonzalo Lira verhaftet. Videoaufnahmen in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-06T09:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ukraine: Blogger Gonzalo Lira verhaftet\",\"datePublished\":\"2023-05-06T09:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/\"},\"wordCount\":401,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png\",\"keywords\":[\"Blogger\",\"Gonzalo\",\"Lira\",\"ukraine\",\"verhaftet\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/\",\"name\":\"Ukraine: Blogger Gonzalo Lira verhaftet - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png\",\"datePublished\":\"2023-05-06T09:36:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png\",\"width\":460,\"height\":259,\"caption\":\"Ukraine: Blogger Gonzalo Lira verhaftet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-blogger-gonzalo-lira-verhaftet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ukraine: Blogger Gonzalo Lira verhaftet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ukraine: Blogger Gonzalo Lira verhaftet - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/","og_locale":"de_DE","og_type":"article","og_title":"Ukraine: Blogger Gonzalo Lira verhaftet","og_description":"Der bekannte chilenisch-amerikanische Blogger und Filmemacher Gonzalo Lira ist am Freitag im ukrainischen Charkow verhaftet worden. Der SBU wirft ihm vor, die &#8220;russische Aggression&#8221; zu rechtfertigen und die oberste F\u00fchrung des Landes &#8220;zu diskreditieren&#8221;. Medienberichten zufolge hat der ukrainische Sicherheitsdienst SBU am Freitag in Charkow den bekannten Blogger und Filmemacher Gonzalo Lira verhaftet. Videoaufnahmen in [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-05-06T09:36:18+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png","type":"image\/png"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ukraine: Blogger Gonzalo Lira verhaftet","datePublished":"2023-05-06T09:36:18+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/"},"wordCount":401,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png","keywords":["Blogger","Gonzalo","Lira","ukraine","verhaftet"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/","url":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/","name":"Ukraine: Blogger Gonzalo Lira verhaftet - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png","datePublished":"2023-05-06T09:36:18+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/05\/Ukraine-Blogger-Gonzalo-Lira-verhaftet.png","width":460,"height":259,"caption":"Ukraine: Blogger Gonzalo Lira verhaftet"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-blogger-gonzalo-lira-verhaftet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ukraine: Blogger Gonzalo Lira verhaftet"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/35518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=35518"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/35518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/35519"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=35518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=35518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=35518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}