{"id":34415,"date":"2023-04-20T06:00:00","date_gmt":"2023-04-20T04:00:00","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/"},"modified":"2023-04-20T06:00:00","modified_gmt":"2023-04-20T04:00:00","slug":"russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/","title":{"rendered":"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/643fff8eb480cc57f33181f0.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der Internationale Leo-Tolstoi-Friedenspreis wird dieses Jahr zum ersten Mal f\u00fcr Leistungen verliehen, die zu gegenseitigem Verst\u00e4ndnis und Vertrauen, Frieden und Zusammenarbeit zwischen den V\u00f6lkern f\u00fchren. Einreichungen sind bis 12. Juni m\u00f6glich.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der Internationale Leo-Tolstoi-Friedenspreis wird im Jahr 2023 zum ersten Mal verliehen. Die nach dem gro\u00dfen russischen Schriftsteller benannte Auszeichnung wird f\u00fcr herausragende Aktivit\u00e4ten verliehen, die auf die F\u00f6rderung universeller Sicherheit auf der Grundlage der Regeln des V\u00f6lkerrechts, die Verhinderung einer nuklearen Katastrophe, den Aufbau einer multipolaren und gewaltfreien Welt und andere bedeutende Leistungen abzielen, die zu gegenseitigem Verst\u00e4ndnis und Vertrauen, Frieden und Zusammenarbeit zwischen den V\u00f6lkern f\u00fchren.<\/p>\n<p>Die Bewerber f\u00fcr den Preis k\u00f6nnen von Einzelpersonen und Initiativgruppen, nationalen und internationalen nichtstaatlichen Stiftungen, Organisationen und Bewegungen, Hochschul- und Forschungszentren sowie Bildungseinrichtungen nominiert werden.<\/p>\n<p>Die Entscheidung \u00fcber die Preistr\u00e4ger trifft eine Jury, die sich aus bedeutenden Pers\u00f6nlichkeiten des \u00f6ffentlichen Lebens und der Politik sowie aus Vertretern von Kultur, Wissenschaft und Wirtschaft in Russland und anderen L\u00e4ndern zusammensetzt. Alle Preistr\u00e4ger erhalten eine Urkunde, eine Goldmedaille mit dem Bild von Leo Tolstoi und ein Preisgeld.<\/p>\n<p>Vorschl\u00e4ge f\u00fcr Nominierungen k\u00f6nnen vom 12. April bis 12. Juni an die Stiftung Leo-Tolstoi-Friedenspreis unter der Anschrift 121069, Moskau, Postfach 38 eingereicht werden. Es werden Dokumente in russischer und englischer Sprache akzeptiert.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/gegenzensur.rtde.live\/meinung\/166788-olympische-spiele-2024-russland-kann\/\">Olympische Spiele 2024: Russland kann sich keine Defensive mehr leisten<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/168084-russland-schreibt-internationalen-leo-tolstoi\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Internationale Leo-Tolstoi-Friedenspreis wird dieses Jahr zum ersten Mal f\u00fcr Leistungen verliehen, die zu gegenseitigem Verst\u00e4ndnis und Vertrauen, Frieden und Zusammenarbeit zwischen den V\u00f6lkern f\u00fchren. Einreichungen sind bis 12. Juni m\u00f6glich. Der Internationale Leo-Tolstoi-Friedenspreis wird im Jahr 2023 zum ersten Mal verliehen. Die nach dem gro\u00dfen russischen Schriftsteller benannte Auszeichnung wird f\u00fcr herausragende Aktivit\u00e4ten verliehen, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1681963617"],"wp_automatic_camp":["217"],"256463f2ecf7b2a41911c99647a45600":["Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus"],"original_link":["https:\/\/de.rt.com\/russland\/168084-russland-schreibt-internationalen-leo-tolstoi\/"],"_thumbnail_id":["34416"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-04-20 06:08:06\";}"],"jnews_social_counter_last_update":["1788351816"]},"categories":[19,23],"tags":[679,524,43292,126,7778],"class_list":["post-34415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-aus","tag-internationalen","tag-leotolstoifriedenspreis","tag-russland","tag-schreibt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus\" \/>\n<meta property=\"og:description\" content=\"Der Internationale Leo-Tolstoi-Friedenspreis wird dieses Jahr zum ersten Mal f\u00fcr Leistungen verliehen, die zu gegenseitigem Verst\u00e4ndnis und Vertrauen, Frieden und Zusammenarbeit zwischen den V\u00f6lkern f\u00fchren. Einreichungen sind bis 12. Juni m\u00f6glich. Der Internationale Leo-Tolstoi-Friedenspreis wird im Jahr 2023 zum ersten Mal verliehen. Die nach dem gro\u00dfen russischen Schriftsteller benannte Auszeichnung wird f\u00fcr herausragende Aktivit\u00e4ten verliehen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus\",\"datePublished\":\"2023-04-20T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/\"},\"wordCount\":240,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg\",\"keywords\":[\"aus\",\"internationalen\",\"LeoTolstoiFriedenspreis\",\"russland\",\"schreibt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/\",\"name\":\"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg\",\"datePublished\":\"2023-04-20T04:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg\",\"width\":460,\"height\":259,\"caption\":\"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/","og_locale":"de_DE","og_type":"article","og_title":"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus","og_description":"Der Internationale Leo-Tolstoi-Friedenspreis wird dieses Jahr zum ersten Mal f\u00fcr Leistungen verliehen, die zu gegenseitigem Verst\u00e4ndnis und Vertrauen, Frieden und Zusammenarbeit zwischen den V\u00f6lkern f\u00fchren. Einreichungen sind bis 12. Juni m\u00f6glich. Der Internationale Leo-Tolstoi-Friedenspreis wird im Jahr 2023 zum ersten Mal verliehen. Die nach dem gro\u00dfen russischen Schriftsteller benannte Auszeichnung wird f\u00fcr herausragende Aktivit\u00e4ten verliehen, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-04-20T04:00:00+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus","datePublished":"2023-04-20T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/"},"wordCount":240,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg","keywords":["aus","internationalen","LeoTolstoiFriedenspreis","russland","schreibt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/","url":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/","name":"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg","datePublished":"2023-04-20T04:00:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Russland-schreibt-Internationalen-Leo-Tolstoi-Friedenspreis-aus.jpg","width":460,"height":259,"caption":"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-schreibt-internationalen-leo-tolstoi-friedenspreis-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russland schreibt Internationalen Leo-Tolstoi-Friedenspreis aus"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/34415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=34415"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/34415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/34416"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=34415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=34415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=34415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}