{"id":33478,"date":"2023-04-03T21:45:16","date_gmt":"2023-04-03T19:45:16","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/"},"modified":"2023-04-03T21:45:16","modified_gmt":"2023-04-03T19:45:16","slug":"ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/","title":{"rendered":"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/642adfd2b480cc50a34e3326.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                F\u00fcr die Aufstockung seiner Armee ist Kiew jeder Vorwand recht. Nach der Stationierung russischer Atomwaffen in Wei\u00dfrussland ist in der Ukraine von einer m\u00f6glichen zweiten Front die Rede, die zweifellos eine Verst\u00e4rkung der Mobilisierungskampagne nach sich ziehen w\u00fcrde.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Eine Analyse von Darja Wolkowa und Tatjana Kossolapowa<\/em><\/p>\n<p>Am 27. M\u00e4rz hat David Arachamia, Abgeordneter der Werchowna Rada und Mitglied des Komitees f\u00fcr nationale Sicherheit, Verteidigung und Geheimdienstaktivit\u00e4ten, erkl\u00e4rt, dass die Ukraine die Mobilisierung aufgrund der Stationierung russischer taktischer Atomwaffen in Wei\u00dfrussland verst\u00e4rken k\u00f6nnte. Ihm zufolge ben\u00f6tigen die ukrainischen Streitkr\u00e4fte &#8220;mindestens acht weitere Brigaden, um eine derart lange Frontlinie kontrollieren zu k\u00f6nnen&#8221;.<\/p>\n<p>&#8220;Wenn sie es wirklich ernst meinen, stehen wir meiner Meinung nach vor einer richtigen Herausforderung, die mit der Er\u00f6ffnung einer zweiten Front einhergehen w\u00fcrde. Ich denke, das w\u00e4ren dann \u00fcber eintausend Kilometer, \u00fcber die sich eine potenzielle Front mit Wei\u00dfrussland erstrecken k\u00f6nnte&#8221;, sagte der Fraktionsvorsitzende der Partei &#8220;Diener des Volkes&#8221; in der Rada.<\/p>\n<p>Zuvor hatte der russische Pr\u00e4sident Wladimir Putin die Stationierung taktischer Atomwaffen in Wei\u00dfrussland angek\u00fcndigt. &#8220;Wir haben Wei\u00dfrussland bereits bei der Umr\u00fcstung der Flugzeuge geholfen. Zehn Flugzeuge k\u00f6nnen jetzt mit Atomwaffen ausgestattet werden. Wir haben ihnen auch Iskander-Raketensysteme \u00fcbergeben. Ab dem 3. April werden wir mit der Ausbildung von Besatzungen und dem Bau eines Atomwaffenlagers beginnen. Wir \u00fcbergeben Wei\u00dfrussland unsere taktischen Atomwaffen nicht. Wir stationieren sie dort nur und bilden das milit\u00e4rische Personal aus, wie die USA das in Europa tun&#8221;, erkl\u00e4rte Putin.<\/p>\n<p>Der russische Pr\u00e4sident\u00a0wies darauf hin, dass die Stationierung der Atomwaffen im Einklang mit allen entsprechenden internationalen Verpflichtungen durchgef\u00fchrt werden w\u00fcrde.\u00a0Putin zufolge sei dieser Schritt aufgrund Londons Aussage \u00fcber die Lieferung von Uranmunition an die ukrainischen Streitkr\u00e4fte notwendig geworden, was die Risikolage in Osteuropa erheblich versch\u00e4rfen w\u00fcrde.<\/p>\n<p>Experten sind der Ansicht, dass die ukrainische Regierung ihr Land auf diese Weise in eine Lage versetzt hat, in der London die ukrainische Armee mit Urangeschossen vollpumpt, w\u00e4hrend Russland im Interesse seiner eigenen nationalen Sicherheit gezwungen ist, mit der Verlegung taktischer Atomwaffen n\u00e4her an die Grenze zur NATO zu antworten. Anstatt den Weg der Deeskalation zu w\u00e4hlen, verk\u00fcndet David Arachamia weitere Mobilisierungen in der Ukraine.<\/p>\n<p>&#8220;Tats\u00e4chlich benutzt Arachamia das Schreckgespenst einer nuklearen Bedrohung, um die Mobilisierung erneut zu rechtfertigen&#8221;, erkl\u00e4rt der Ex-Botschafter der LV<a><\/a>R in Russland Rodion Miroschnik. &#8220;Aber das ist eine komplette Farce. Die ukrainische Regierung klammert sich an jeden Strohhalm, um ihrem Volk Angst einzufl\u00f6\u00dfen. Wie sollen acht Brigaden aus mobilisierten B\u00fcrgern der ukrainischen Armee helfen, auf den m\u00f6glichen Einsatz taktischer Atomwaffen zu reagieren?&#8221;<\/p>\n<p>&#8220;Was das Mobilisierungspotenzial betrifft, so ist es sicherlich vorhanden. Aber von motivierten und gesunden\u00a0Eingezogenen kann hier keine Rede sein. Diese Ressource ist l\u00e4ngst ersch\u00f6pft. Letztendlich sind noch diejenigen \u00fcbrig, die sich nur als Kanonenfutter eignen und die man mit vorgehaltener Waffe zusammentreiben muss&#8221;, meint der Ex-Botschafter.<\/p>\n<p>&#8220;Ich gehe davon aus, dass die Ukraine in naher Zukunft immer &#8216;kreativere&#8217; Methoden anwenden wird, um die B\u00fcrger in die Reihen der ukrainischen Armee zu treiben. Zus\u00e4tzlich zur Intensivierung von Razzien und S\u00e4uberungsaktionen wird der Machtapparat zus\u00e4tzliche Befugnisse sowie Zugriff auf Datenbanken von B\u00fcrgern f\u00fcr die Rekrutierung erhalten&#8221;, so Miroschnik.<\/p>\n<p>&#8220;Ich denke, Arachamia zielt mit solchen Aussagen darauf ab, den Grad der politischen Eskalation in Europa zu erh\u00f6hen. Die ukrainische Regierung versucht deutlich zu machen, dass die Stationierung russischer taktischer Atomwaffen auf wei\u00dfrussischem Staatsgebiet die Situation im Kampfgebiet weiter versch\u00e4rfen w\u00fcrde. Au\u00dferdem geh\u00f6rt es zum guten Ton, Russland an allem die Schuld zu geben&#8221;, erkl\u00e4rt Larissa Schessler, Vorsitzende des Verbands politischer Immigranten und politischer Gefangener der Ukraine.<\/p>\n<p>&#8220;Es steht fest, dass all dies im Einvernehmen mit den Verb\u00fcndeten in Europa und den USA geschieht, die in aller Deutlichkeit eine Politik der Doppelmoral zur Schau stellen. Sie bezeichnen die Stationierung russischer Raketen in Wei\u00dfrussland als ungeheuerlich, w\u00e4hrend die USA gleichzeitig in anderen europ\u00e4ischen L\u00e4ndern in aller Seelenruhe genauso verfahren&#8221;, f\u00fcgt Schessler hinzu.<\/p>\n<p>Experten weisen darauf hin, dass die Mobilisierungen in der Ukraine weiterhin nicht aufh\u00f6ren. In erster Linie trifft es die Bewohner gro\u00dfer russischsprachiger St\u00e4dte und die Einwohner des westukrainischen Hinterlandes. Kiew bleibt hingegen praktisch vollst\u00e4ndig von der Mobilisierung verschont, da die ukrainische F\u00fchrung versucht, f\u00fcr ein positives Klima in der Stadt zu sorgen.<\/p>\n<p>In Anbetracht dieser Tatsachen verschlechtert sich die Lage des ukrainischen Milit\u00e4rs nicht nur infolge der Kampfhandlungen, sondern auch aus wirtschaftlichen Gr\u00fcnden. Die Zeitung <em>Wsgljad<\/em>\u00a0schilderte bereits ausf\u00fchrlich, dass das Budget der Ukraine nicht ausreiche, um die Streitkr\u00e4fte zu finanzieren und die Sozialleistungen f\u00fcr Milit\u00e4rangeh\u00f6rige aufrechtzuerhalten. Vergangene Woche wurde in der Werchowna Rada auf dieses Problem hingewiesen. Es wurde vorgeschlagen, die Sozialleistungen durch Stipendien f\u00fcr Veteranen zu ersetzen, die im Laufe von zwei bis drei Jahren ausgezahlt werden w\u00fcrden.<\/p>\n<p>Trotzdem verf\u00fcgt die Ukraine immer noch \u00fcber erhebliche Mobilisierungsressourcen und ist durchaus in der Lage, acht Brigaden mit einer Mannst\u00e4rke von jeweils 28.000 bis 40.000 Soldaten aufzustellen. &#8220;Das Land ist gro\u00df und die Ausreise f\u00fcr M\u00e4nner ist praktisch unm\u00f6glich, wenn man von illegalen Wegen der Ausreise einmal absieht. In einem Dorf in der Region Odessa wurde erst vor Kurzem einem 80-J\u00e4hrigen ein Einberufungsschreiben \u00fcberreicht. Ihm wurde gesagt, er s\u00e4he kr\u00e4ftig genug aus und w\u00fcrde im Lagerhaus arbeiten&#8221;, berichtet der Politik- und Wirtschaftswissenschaftler Iwan Lisan.<\/p>\n<p>Man sollte also nicht darauf hoffen, dass sich das Mobilisierungspotenzial der Ukraine bald ersch\u00f6pfen w\u00fcrde. &#8220;Dass lebende Menschen nicht gegen taktische Atomwaffen k\u00e4mpfen k\u00f6nnen, ist dagegen etwas ganz anderes&#8221;, meint der Experte.<\/p>\n<p>&#8220;Deswegen benutzt die ukrainische F\u00fchrung diese Situation h\u00f6chstwahrscheinlich als Vorwand, um eine gesetzliche Basis f\u00fcr eine nicht endende Mobilisierung zu schaffen. Genug Leute zu rekrutieren ist kein Problem. Die wird man schon auftreiben k\u00f6nnen. Die Rekrutierungsoffiziere sehen darin eine Art Wettbewerb, bei dem ihnen Pr\u00e4mien zustehen. Die Frage ist nur, wo sie die n\u00f6tige Technik f\u00fcr acht neue Brigaden hernehmen werden&#8221;, so Lisan.<\/p>\n<p><em>\u00dcbersetzt aus dem Russischen und zuerst erschienen bei <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/vz.ru\/world\/2023\/3\/27\/1204922.html\">Wsgljad<\/a>.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/international\/166675-doch-keine-gegenoffensive-kiew-daempft\/\">Doch keine Gegenoffensive? Kiew d\u00e4mpft Erwartungen des Westens und bettelt um Waffen<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/166875-ukraine-nicht-endende-mobilisierung-unter\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr die Aufstockung seiner Armee ist Kiew jeder Vorwand recht. Nach der Stationierung russischer Atomwaffen in Wei\u00dfrussland ist in der Ukraine von einer m\u00f6glichen zweiten Front die Rede, die zweifellos eine Verst\u00e4rkung der Mobilisierungskampagne nach sich ziehen w\u00fcrde. Eine Analyse von Darja Wolkowa und Tatjana Kossolapowa Am 27. M\u00e4rz hat David Arachamia, Abgeordneter der Werchowna [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":33479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1680552060"],"wp_automatic_camp":["217"],"74ac6b50d6cc75113f55c9e60524d763":["Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand"],"original_link":["https:\/\/de.rt.com\/international\/166875-ukraine-nicht-endende-mobilisierung-unter\/"],"_thumbnail_id":["33479"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-04-03 22:01:59\";}"],"jnews_social_counter_last_update":["1788169884"]},"categories":[19,23],"tags":[42742,42743,32784,800,127,908,26759],"class_list":["post-33478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-endende","tag-fadenscheinigem","tag-mobilisierung","tag-nicht","tag-ukraine","tag-unter","tag-vorwand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr die Aufstockung seiner Armee ist Kiew jeder Vorwand recht. Nach der Stationierung russischer Atomwaffen in Wei\u00dfrussland ist in der Ukraine von einer m\u00f6glichen zweiten Front die Rede, die zweifellos eine Verst\u00e4rkung der Mobilisierungskampagne nach sich ziehen w\u00fcrde. Eine Analyse von Darja Wolkowa und Tatjana Kossolapowa Am 27. M\u00e4rz hat David Arachamia, Abgeordneter der Werchowna [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-03T19:45:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand\",\"datePublished\":\"2023-04-03T19:45:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/\"},\"wordCount\":1069,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg\",\"keywords\":[\"endende\",\"fadenscheinigem\",\"Mobilisierung\",\"nicht\",\"ukraine\",\"unter\",\"Vorwand\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/\",\"name\":\"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg\",\"datePublished\":\"2023-04-03T19:45:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg\",\"width\":460,\"height\":259,\"caption\":\"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/","og_locale":"de_DE","og_type":"article","og_title":"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand","og_description":"F\u00fcr die Aufstockung seiner Armee ist Kiew jeder Vorwand recht. Nach der Stationierung russischer Atomwaffen in Wei\u00dfrussland ist in der Ukraine von einer m\u00f6glichen zweiten Front die Rede, die zweifellos eine Verst\u00e4rkung der Mobilisierungskampagne nach sich ziehen w\u00fcrde. Eine Analyse von Darja Wolkowa und Tatjana Kossolapowa Am 27. M\u00e4rz hat David Arachamia, Abgeordneter der Werchowna [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-04-03T19:45:16+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand","datePublished":"2023-04-03T19:45:16+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/"},"wordCount":1069,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg","keywords":["endende","fadenscheinigem","Mobilisierung","nicht","ukraine","unter","Vorwand"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/","url":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/","name":"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg","datePublished":"2023-04-03T19:45:16+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/Ukraine-Nicht-endende-Mobilisierung-unter-fadenscheinigem-Vorwand.jpg","width":460,"height":259,"caption":"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ukraine-nicht-endende-mobilisierung-unter-fadenscheinigem-vorwand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ukraine: Nicht endende Mobilisierung unter fadenscheinigem Vorwand"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/33478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=33478"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/33478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/33479"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=33478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=33478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=33478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}