{"id":32912,"date":"2023-03-24T18:10:16","date_gmt":"2023-03-24T16:10:16","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/"},"modified":"2023-03-24T18:10:16","modified_gmt":"2023-03-24T16:10:16","slug":"als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/","title":{"rendered":"Als Netflix-Promi bei den Oscars &#8211;  Claudia Roth zahlt Ticketkosten nun zur\u00fcck"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/641d63ed48fbef1cdb7f8906.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Netflix bezahlte der gr\u00fcnen Staatsministerin das begehrte VIP-Ticket f\u00fcr die Oscar-Nacht in Los Angeles. Die Offerte erfolgte vermeintlich auf Initiative des Regisseurs und sp\u00e4teren Oscar-Gewinners Edward Berger. Roth zahlt nun aus eigener Tasche die 2.250 Dollar an das Streaming-Unternehmen zur\u00fcck.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Am 15. Februar dieses Jahres schrieb die Staatsministerin f\u00fcr Kultur und Medien, Claudia Roth (B\u00fcndnis 90\/Die Gr\u00fcnen), einen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.sueddeutsche.de\/kultur\/filmfoerderung-claudia-roth-1.5751744\">Gastbeitrag<\/a> f\u00fcr die <em>S\u00fcddeutsche Zeitung. <\/em> Das Thema lautete, warum das &#8220;gut ausgestattete deutsche Film-F\u00f6rdersystem&#8221; nicht die Erfolge vorweisen k\u00f6nnte, wie etwa der Streaming-Dienst Netflix unter anderem mit seiner aktuell mehrfach Oscar nominierten deutschen Produktion &#8220;Im Westen nichts Neues&#8221;. Diese Realit\u00e4ten w\u00fcrden einen &#8220;tiefgreifenden Wandel des Filmschaffens&#8221; darstellen.<\/p>\n<p>Am 12. M\u00e4rz kam es dann bei der 95. Verleihung der Oscars zum gro\u00dfen Netflix-Erfolgsabend dank der Filmarbeit Made in Germany. Der Film &#8220;Im Westen nichts Neues&#8221; war f\u00fcr neun Oscars nominiert, um dann endlich vier der begehrten Troph\u00e4en zu <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.sueddeutsche.de\/kultur\/oscars-2023-im-westen-nichts-neues-gewinner-internationaler-film-edward-berger-vier-trophaeen-1.5767621\">gewinnen<\/a>. Anwesend und jubilierend im Dolby Theater in Los Angeles vor Ort ist Claudia Roth. Der <em>Berliner Tagesspiegel<\/em> erkl\u00e4rt <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.tagesspiegel.de\/politik\/2250-dollar-an-netflix-claudia-roth-zahlt-oscar-ticket-nachtraglich-selbst-9553352.html\">diesbez\u00fcglich<\/a>:<\/p>\n<blockquote>\n<p><em>&#8220;Roth sei in der Bundesregierung f\u00fcr die F\u00f6rderung des deutschen Films verantwortlich und habe &#8220;einen auch international viel beachteten Vorschlag zur Reform des F\u00f6rdersystems vorgelegt&#8221;.\u00a0<\/em><\/p>\n<\/blockquote>\n<p>Die<em> S\u00fcddeutsche Zeitung<\/em> (<em>SZ)<\/em> konnte anhand von Recherchen und Anfragen nun <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.sueddeutsche.de\/kultur\/oscars-claudia-roth-netflix-1.5774428\">nachzeichnen<\/a> (Bezahlschranke), wie die Kulturstaatsministerin in den Besitz eines der hei\u00df begehrten und teuren VIP-Tickets kam. Selbst &#8220;Academy-Mitglieder m\u00fcssen sich daf\u00fcr bewerben, denn es gibt davon wesentlich mehr als Sitze im Dolby Theater&#8221;. Demnach habe Martin Moszkowicz, Chef der deutschen Filmfirma Constantin, sein pers\u00f6nliches Oscar-Ticket an Claudia Roth verschenkt, da er &#8220;den Abend (der Verleihung) lieber bei Freunden schaue&#8221;.<\/p>\n<p>Die\u00a0<em>SZ<\/em>\u00a0hakte diesbez\u00fcglich bei der Filmfirma nach und erfuhr, dass &#8220;die Bemerkung\u00a0an einem Abend in privater Runde als deutlich erkennbarer Witz\u00a0gefallen sei&#8221;. Die n\u00e4chste Anfrage ging dann an das\u00a0B\u00fcro der Staatsministerin f\u00fcr Kultur und Medien. Die Beantwortung lie\u00df auff\u00e4llige drei Tage auf sich warten und lautete:<\/p>\n<blockquote>\n<p><em>&#8220;Auf ausdr\u00fccklichen Wunsch von Regisseur Edward Berger sollte Kulturstaatsministerin Claudia Roth Teil der Delegation f\u00fcr &#8216;Im Westen nichts Neues&#8217; sein. Diese kurz vor der Zeremonie ausgesprochene Einladung, die auch von der Academy abgesegnet worden war, hat die Kulturstaatsministerin gerne angenommen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Es habe sich mittlerweile jedoch laut Antwort des B\u00fcros von Roth &#8220;herausgestellt&#8221; (sic!), dass\u00a0Netflix USA &#8220;offenkundig f\u00fcr diese Tickets der begleitenden Filmcrew, zu denen das der Staatsministerin angebotene Ticket geh\u00f6rte, bezahlt hatte&#8221;. Dazu\u00a0kommentiert die SZ:<\/p>\n<blockquote>\n<p><em>&#8220;Oha!\u00a0Herausgestellt\u00a0hat es sich \u00fcbrigens erst nach der Anfrage der SZ. Aber immer mit der Ruhe \u2013 die Staatsministerin jedenfalls hat nun also doch noch &#8216;diese Kosten umgehend an Netflix erstattet, aus ihren privaten\u00a0Mitteln&#8217;.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Im Rahmen einer weiteren Nachfrage verriet das B\u00fcro Roth dann noch, dass die Ministerin die aufregende und erfreuliche Abwechslung vom Berliner Alltag insgesamt 2.250 Dollar kostete. 1.500 Dollar stellten dabei den Anteil f\u00fcr &#8220;die Teilnahme am anschlie\u00dfenden Governors Ball, bei dem Claudia Roth dann aber gar nicht gewesen ist&#8221;. Den &#8220;h\u00e4tte sie sich\u00a0geschenkt&#8221;.<\/p>\n<p>Die Atlantik-\u00dcberquerung \u00fcbernahm ungefragt nat\u00fcrlich der Steuerzahler, da Claudia Roth im Namen der Bundesregierung schlicht ihrer gut dotierten Funktion einer Kultur-Repr\u00e4sentantin nachkam. Bereits im Jahr 2019\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bild.de\/bild-plus\/politik\/inland\/politik-inland\/17-tonnen-ausstoss-gruene-roth-fliegt-41-000-km-um-das-klima-zu-retten-61219364.bild.html\">informierte<\/a>\u00a0ein Presseartikel \u00fcber die anscheinend unver\u00e4nderten\u00a0Roth-Wahrnehmungen, hinsichtlich vermeintlich berufsbedingter Sonderkonditionen:<\/p>\n<blockquote>\n<p><em>&#8220;Politik unter Palmen \u2013 Um das Klima zu retten, wollte sich Bundestagsvizepr\u00e4sidentin Claudia Roth ein eigenes Bild von der Lage vor Ort machen \u2013 und flog daf\u00fcr kurzerhand 41.000 Kilometer.&#8221;<\/em><\/p>\n<\/blockquote>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/pressefreiheit.rtde.tech\/meinung\/165465-sehr-geehrte-damen-und-herren\/\">Sehr geehrte Damen und Herren, liebe Indianer \u2013 Habeck macht den L\u00fcbke<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/166117-ausser-spesen-nichts-gewesen-claudia\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Netflix bezahlte der gr\u00fcnen Staatsministerin das begehrte VIP-Ticket f\u00fcr die Oscar-Nacht in Los Angeles. Die Offerte erfolgte vermeintlich auf Initiative des Regisseurs und sp\u00e4teren Oscar-Gewinners Edward Berger. Roth zahlt nun aus eigener Tasche die 2.250 Dollar an das Streaming-Unternehmen zur\u00fcck. Am 15. Februar dieses Jahres schrieb die Staatsministerin f\u00fcr Kultur und Medien, Claudia Roth (B\u00fcndnis [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1679674865"],"wp_automatic_camp":["217"],"3c86bb92b93a7821ecba705363825bcd":["Als Netflix-Promi bei den Oscars -  Claudia Roth zahlt Ticketkosten nun zur\u00fcck"],"original_link":["https:\/\/de.rt.com\/inland\/166117-ausser-spesen-nichts-gewesen-claudia\/"],"_thumbnail_id":["32913"],"jnews_social_counter_last_update":["1778638495"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-03-24 18:22:14\";}"]},"categories":[19,23],"tags":[273,363,7576,48,42388,2121,9618,20404,42389,20031,3337],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck\" \/>\n<meta property=\"og:description\" content=\"Netflix bezahlte der gr\u00fcnen Staatsministerin das begehrte VIP-Ticket f\u00fcr die Oscar-Nacht in Los Angeles. Die Offerte erfolgte vermeintlich auf Initiative des Regisseurs und sp\u00e4teren Oscar-Gewinners Edward Berger. Roth zahlt nun aus eigener Tasche die 2.250 Dollar an das Streaming-Unternehmen zur\u00fcck. Am 15. Februar dieses Jahres schrieb die Staatsministerin f\u00fcr Kultur und Medien, Claudia Roth (B\u00fcndnis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-24T16:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Als Netflix-Promi bei den Oscars &#8211; Claudia Roth zahlt Ticketkosten nun zur\u00fcck\",\"datePublished\":\"2023-03-24T16:10:16+00:00\",\"dateModified\":\"2023-03-24T16:10:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg\",\"keywords\":[\"als\",\"bei\",\"Claudia\",\"den\",\"NetflixPromi\",\"nun\",\"Oscars\",\"Roth\",\"Ticketkosten\",\"zahlt\",\"zur\u00fcck\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/\",\"name\":\"Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg\",\"datePublished\":\"2023-03-24T16:10:16+00:00\",\"dateModified\":\"2023-03-24T16:10:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg\",\"width\":460,\"height\":259,\"caption\":\"Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Als Netflix-Promi bei den Oscars &#8211; Claudia Roth zahlt Ticketkosten nun zur\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/","og_locale":"de_DE","og_type":"article","og_title":"Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck","og_description":"Netflix bezahlte der gr\u00fcnen Staatsministerin das begehrte VIP-Ticket f\u00fcr die Oscar-Nacht in Los Angeles. Die Offerte erfolgte vermeintlich auf Initiative des Regisseurs und sp\u00e4teren Oscar-Gewinners Edward Berger. Roth zahlt nun aus eigener Tasche die 2.250 Dollar an das Streaming-Unternehmen zur\u00fcck. Am 15. Februar dieses Jahres schrieb die Staatsministerin f\u00fcr Kultur und Medien, Claudia Roth (B\u00fcndnis [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-03-24T16:10:16+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Als Netflix-Promi bei den Oscars &#8211; Claudia Roth zahlt Ticketkosten nun zur\u00fcck","datePublished":"2023-03-24T16:10:16+00:00","dateModified":"2023-03-24T16:10:16+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg","keywords":["als","bei","Claudia","den","NetflixPromi","nun","Oscars","Roth","Ticketkosten","zahlt","zur\u00fcck"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/","url":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/","name":"Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg","datePublished":"2023-03-24T16:10:16+00:00","dateModified":"2023-03-24T16:10:16+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Als-Netflix-Promi-bei-den-Oscars-Claudia-Roth-zahlt-Ticketkosten.jpg","width":460,"height":259,"caption":"Als Netflix-Promi bei den Oscars - Claudia Roth zahlt Ticketkosten nun zur\u00fcck"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/als-netflix-promi-bei-den-oscars-claudia-roth-zahlt-ticketkosten-nun-zurueck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Als Netflix-Promi bei den Oscars &#8211; Claudia Roth zahlt Ticketkosten nun zur\u00fcck"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/32912"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=32912"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/32912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/32913"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=32912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=32912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=32912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}