{"id":32556,"date":"2023-03-19T11:59:21","date_gmt":"2023-03-19T09:59:21","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/"},"modified":"2023-03-19T11:59:21","modified_gmt":"2023-03-19T09:59:21","slug":"deutsche-medien-sind-auf-den-goebbels-gekommen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/","title":{"rendered":"Deutsche Medien sind auf den Goebbels gekommen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/6416c924b480cc6f682cae1f.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Betrachtet man die deutschen Medien, kann man zu dem Schluss kommen: Goebbels ist wieder da. So sehr, wie der hiesige Mainstream die Parole verbreitet: Krieg macht Sinn. Vorreiter dabei ist der deutsche Staatsfunk. Ein aktuelles Beispiel zeigt, wie selbst Kinder daf\u00fcr missbraucht werden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Uli Gellermann<\/em><\/p>\n<p>Die deutschen Medien sind auf den Goebbels gekommen: Es geistert ein\u00a0<em>dpa<\/em>-Foto durch den Medienraum. Ein fotogener Junge in ukrainischer Milit\u00e4runiform h\u00e4lt eine Gewehrattrappe in der Hand. Untertitelt ist das Bild so: &#8220;Ein sieben Jahre alter ukrainischer Junge steht nahe der Stadt Tschernihiw inmitten zerst\u00f6rter russischer Milit\u00e4rfahrzeuge.&#8221; Will uns die Reichs-Presse-Agentur vom letzten Aufgebot erz\u00e4hlen? Oder davon, wie brutal der Russe ist, wenn er jetzt auch noch gegen Siebenj\u00e4hrige k\u00e4mpft? Die Agentur <em>Reuters<\/em> begl\u00fcckt das deutsche Publikum mit dem Foto eines entz\u00fcckenden P\u00e4rchens, das wird so untertextet: &#8220;Trotz des Kriegs verlieren die Menschen in der Ukraine nicht ihren Glauben an sich. Der ukrainische Soldat Wolodymyr macht seiner Freundin Viktoria am Bahnsteig in Kramatorsk einen Heiratsantrag.&#8221; Krieg kann ja so idyllisch sein! Und die Ukrainer sind einfach irre menschlich! Ganz anders als die Russen!<\/p>\n<h4><strong>Rheinmetall-Aktie legt um 60 Prozent zu<\/strong><\/h4>\n<p>Ein Foto aus dem Rheinmetall-Kasino fehlt: Von jenem Moment, in dem die Aktion\u00e4re im Champagner baden. Der Ukraine-Krieg war gerade einmal eine Woche alt, da hatte die Aktie des deutschen Waffenherstellers Rheinmetall schon um 60 Prozent zugelegt. Von da aus ging es weiter nach oben, ein Jahr sp\u00e4ter steht das Plus bei 157 Prozent. Auch beim Branchenkollegen Hensoldt (fr\u00fcher Airbus Defence and Space f\u00fcr Sensortechnologie) ging es mit 138 Prozent \u00e4hnlich stark nach oben. Die beiden deutschen Hersteller profitieren von dem 100 Milliarden Euro schweren Sonderverm\u00f6gen, mit dem die Bundesregierung die Bundeswehr in den kommenden Jahren sanieren will.<\/p>\n<h4><strong>Deutsche Bank und die Commerzbank st\u00fcrzten ab<\/strong><\/h4>\n<p>Doch nicht allen Aktion\u00e4ren geht es so gut wie den R\u00fcstungsmachern: Die Deutsche Bank und die Commerzbank st\u00fcrzten beide von \u00fcber zw\u00f6lf Euro auf die psychologische Marke von zehn Euro ab. Der Kurs der Credit Suisse, eines der gr\u00f6\u00dften global t\u00e4tigen Finanzdienstleistungsunternehmen mit einer Bilanz-Summe von 531,4 Milliarden Schweizer Franken, war zeitweise um bis zu 31 Prozent eingebrochen. Der Krieg kennt Gewinner, aber eben auch Verlierer. Denn gewonnen wird er letztlich auf dem Schlachtfeld \u2013 nicht an der B\u00f6rse. Wer darauf spekuliert, dass die Russen den Krieg verlieren, kennt weder die Geschichte noch das gro\u00dfe Land. Dort wei\u00df man, dass man als Land, als Nation erledigt ist, wenn man die Ukraine verliert. W\u00e4hrend der Westen gern bis zum letzten Ukrainer k\u00e4mpft, k\u00e4mpfen die Russen um ihr \u00dcberleben. Diesen Kampf haben sie noch nie verloren, dieser Kampf mobilisiert ganz andere Ressourcen, als dem Westen zur Verf\u00fcgung stehen.<\/p>\n<h4><strong>Krieg verl\u00e4ngern<\/strong><\/h4>\n<p>So sehr die russischen Rohstoffe die gierige Fantasie der B\u00f6rsianer bewegen, so wenig werden die Russen ihren Boden preisgeben; sie haben keinen Grund zum Selbstmord. Wer sich im Westen nicht von der Gier den Kopf vernebeln l\u00e4sst, der wei\u00df das, der setzt nicht auf einen Sieg in der Ukraine. Und doch verh\u00e4lt sich der Westen wie ein verzweifelter Spieler, der alles auf eine Karte setzt. Nur so ist zu erkl\u00e4ren, dass Polen jetzt als Handpuppe der USA agiert und vier Kampfflugzeuge vom Typ MiG-29 an die Ukraine liefert. Weitere sollen folgen. Man wei\u00df im Westen, dass die MiG-29 keinen Krieg entscheiden. Auch die Ank\u00fcndigung von Kanzler Scholz weiterer deutscher Waffenlieferungen in die Ukraine k\u00f6nnen keinen Krieg zur Entscheidung bringen. Aber sie verl\u00e4ngern ihn um ein paar Hundert oder Tausende Tote.<\/p>\n<h4><strong>Goldene Flucht<\/strong><\/h4>\n<p>Wer aus dem Krieg und dem unsicheren Finanzsystem fliehen will, der flieht ins Gold: Die Zentralbanken kaufen das Metall wie wild \u2013 seit Anfang November ist der Goldpreis um beinahe\u00a0zehn Prozent gestiegen. Auch diese Fluchtbewegung zeigt: Der Westen gibt den Krieg verloren. Zugleich treibt er ihn trotzdem weiter. Dem muss Einhalt geboten werden. Zurzeit zeigen sich in Deutschland nur wenige Kr\u00e4fte, die den Weg des Friedens gehen wollen. Die letzte Initiative von Sarah Wagenknecht und Alice Schwarzer hat trotz aller ideologischer Verrenkungen gezeigt, dass es sie gibt, die Friedensbewegung. Das Pfl\u00e4nzchen will gepflegt werden.<\/p>\n<h4><strong><em>ARD<\/em> als Agent der Regierung<\/strong><\/h4>\n<p>Es sind die Medien, die auf der zarten Pflanze des Friedens herumtrampeln. Das gilt besonders f\u00fcr die <em>ARD<\/em> und den <em>MDR<\/em>, die mit einer illegalen Befragung der Erstunterzeichner des &#8220;Manifest f\u00fcr den Frieden&#8221; versuchen, die Unterzeichner &#8216;umzudrehen&#8217;, wie es im Agentenjargon hei\u00dft. Tats\u00e4chlich agieren die \u00f6ffentlich-rechtlichen Sender als Agenten einer Regierung, die den Krieg in der Ukraine im Interesse der USA mit Waffen f\u00fcttert, um das Sterben zu verl\u00e4ngern.<\/p>\n<p><em>Zuerst <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rationalgalerie.de\/home\/krieg-macht-sinn\">ver\u00f6ffentlicht<\/a> auf der Medienplattform Rationalgalerie am 17. M\u00e4rz 2023.<\/em><\/p>\n<p><em><strong>Uli Gellermann\u00a0<\/strong>ist Filmemacher und Journalist. Seine Erfahrungen mit den \u00f6ffentlich-rechtlichen Sendern grundieren seine Medienkritik. Er ist Herausgeber der Internetseite\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rationalgalerie.de\/home\/die-kampagne-fuer-frieden-geht-los\">RATIONALGALERIE<\/a>.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/gegenzensur.rtde.life\/meinung\/165562-deutsche-medien-immer-wieder-im\/\">Klage gegen den MDR: Beitrag hatte &#8220;Ans\u00e4tze der Volksverhetzung&#8221;<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/165715-deutsche-medien-sind-auf-goebbels\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Betrachtet man die deutschen Medien, kann man zu dem Schluss kommen: Goebbels ist wieder da. So sehr, wie der hiesige Mainstream die Parole verbreitet: Krieg macht Sinn. Vorreiter dabei ist der deutsche Staatsfunk. Ein aktuelles Beispiel zeigt, wie selbst Kinder daf\u00fcr missbraucht werden. Von Uli Gellermann Die deutschen Medien sind auf den Goebbels gekommen: Es [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1679220233"],"wp_automatic_camp":["217"],"5b7c6148878194be33b7139ca58f194d":["Deutsche Medien sind auf den Goebbels gekommen"],"original_link":["https:\/\/de.rt.com\/meinung\/165715-deutsche-medien-sind-auf-goebbels\/"],"_thumbnail_id":["32557"],"jnews_social_counter_last_update":["1788300880"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-03-19 12:05:04\";}"]},"categories":[19,23],"tags":[133,48,2374,15535,20685,580,1046],"class_list":["post-32556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auf","tag-den","tag-deutsche","tag-gekommen","tag-goebbels","tag-medien","tag-sind"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deutsche Medien sind auf den Goebbels gekommen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsche Medien sind auf den Goebbels gekommen\" \/>\n<meta property=\"og:description\" content=\"Betrachtet man die deutschen Medien, kann man zu dem Schluss kommen: Goebbels ist wieder da. So sehr, wie der hiesige Mainstream die Parole verbreitet: Krieg macht Sinn. Vorreiter dabei ist der deutsche Staatsfunk. Ein aktuelles Beispiel zeigt, wie selbst Kinder daf\u00fcr missbraucht werden. Von Uli Gellermann Die deutschen Medien sind auf den Goebbels gekommen: Es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-19T09:59:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Deutsche Medien sind auf den Goebbels gekommen\",\"datePublished\":\"2023-03-19T09:59:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/\"},\"wordCount\":829,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/03\\\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg\",\"keywords\":[\"AUF\",\"den\",\"Deutsche\",\"gekommen\",\"Goebbels\",\"Medien\",\"sind\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/\",\"name\":\"Deutsche Medien sind auf den Goebbels gekommen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/03\\\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg\",\"datePublished\":\"2023-03-19T09:59:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/03\\\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/03\\\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Deutsche Medien sind auf den Goebbels gekommen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-medien-sind-auf-den-goebbels-gekommen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutsche Medien sind auf den Goebbels gekommen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deutsche Medien sind auf den Goebbels gekommen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/","og_locale":"de_DE","og_type":"article","og_title":"Deutsche Medien sind auf den Goebbels gekommen","og_description":"Betrachtet man die deutschen Medien, kann man zu dem Schluss kommen: Goebbels ist wieder da. So sehr, wie der hiesige Mainstream die Parole verbreitet: Krieg macht Sinn. Vorreiter dabei ist der deutsche Staatsfunk. Ein aktuelles Beispiel zeigt, wie selbst Kinder daf\u00fcr missbraucht werden. Von Uli Gellermann Die deutschen Medien sind auf den Goebbels gekommen: Es [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-03-19T09:59:21+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Deutsche Medien sind auf den Goebbels gekommen","datePublished":"2023-03-19T09:59:21+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/"},"wordCount":829,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg","keywords":["AUF","den","Deutsche","gekommen","Goebbels","Medien","sind"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/","url":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/","name":"Deutsche Medien sind auf den Goebbels gekommen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg","datePublished":"2023-03-19T09:59:21+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/03\/Deutsche-Medien-sind-auf-den-Goebbels-gekommen.jpg","width":460,"height":259,"caption":"Deutsche Medien sind auf den Goebbels gekommen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-medien-sind-auf-den-goebbels-gekommen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Deutsche Medien sind auf den Goebbels gekommen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/32556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=32556"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/32556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/32557"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=32556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=32556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=32556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}