{"id":30422,"date":"2023-02-15T12:44:10","date_gmt":"2023-02-15T10:44:10","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/"},"modified":"2023-02-15T12:44:10","modified_gmt":"2023-02-15T10:44:10","slug":"ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/","title":{"rendered":"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63ecb72148fbef1569224d0e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Ungarns Au\u00dfenminister Szijj\u00e1rt\u00f3 hat nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin Colonna erkl\u00e4rt, die westlichen Staaten seien der Ansicht, dass die Ukraine Friedensverhandlungen erst dann aufnehmen solle, wenn die Lage f\u00fcr sie milit\u00e4risch g\u00fcnstig sei.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin\u00a0Catherine Colonna in Paris am Dienstag hat\u00a0Ungarns Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/publi24.hu\/szijjarto-a-parizsi-kulugyminiszteri-talalkozojarol-volt-benne-kakao-156055.html\">verk\u00fcndet<\/a>, dass die Lage rund um die Ukraine mehr als die H\u00e4lfte der anderthalbst\u00fcndigen Diskussion in Anspruch genommen habe.<\/p>\n<p>Laut Szijj\u00e1rt\u00f3 waren sie sich nur in einem Punkt einig, n\u00e4mlich darin, dass sie beide Frieden in der Ukraine wollen. Ihre diesbez\u00fcgliche Sichtweise unterscheide sich jedoch, wenn es darum gehe, wie dieses Ziel erreicht werden k\u00f6nnte, nach welchem \u200b\u200b\u200b\u200bZeitplan und durch welche politische Schritte, hie\u00df es.<\/p>\n<p>Budapest wolle so schnell wie m\u00f6glich Frieden, einen sofortigen Waffenstillstand und die Aufnahme von Friedensverhandlungen, so der Minister. Frankreich aber, ebenso wie fast alle andere EU-Mitglieder, erwarte, dass sich eine f\u00fcr die Ukraine g\u00fcnstigere Situation auf dem Schlachtfeld entwickeln werde. Die Meinung sei, dass es in diesem Fall eine vorteilhafte Position geben werde, um Verhandlungen mit Russland aufzunehmen. Szijj\u00e1rt\u00f3 erl\u00e4uterte:<\/p>\n<blockquote>\n<p><em>&#8220;Wir glauben nicht daran. Wir sind der Ansicht, dass das Leiden der Menschen sofort beendet werden muss. Der Frieden wird jetzt gebraucht.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Zugleich sagte der Minister, dass Ungarn Meinungen anderer L\u00e4nder akzeptiere, weil das gesamte System der zwischenstaatlichen Beziehungen auf gegenseitigem Respekt beruhen sollte. Die Friedensgespr\u00e4che zwischen Russland und der Ukraine waren auch das zentrale Thema beim Besuch Szijj\u00e1rt\u00f3s in Minsk am Montag, wo er mit seinem wei\u00dfrussischen Amtskollegen Sergei Aleinik zusammentraf. Dort sagte er, der Krieg k\u00f6nne nicht beendet werden, wenn man nicht miteinander rede. Und weiter:<\/p>\n<blockquote>\n<p><em>&#8220;Es gibt derzeit keine wichtigere Aufgabe, als die Rettung von Menschenleben. Menschenleben k\u00f6nnen aber nur dann gerettet werden, wenn dieser Krieg beendet wird. Und dieser Krieg kann beendet werden, wenn unverz\u00fcglich ein Waffenstillstand erkl\u00e4rt wird und Friedensverhandlungen aufgenommen werden.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Szijj\u00e1rt\u00f3 betonte auch, dass Ungarn im Gegensatz zu vielen anderen L\u00e4ndern die Kontakte zu Moskau nicht abbreche, &#8220;denn, wenn wir die Kommunikationskan\u00e4le schlie\u00dfen, werden wir die Hoffnung auf Frieden verlieren&#8221;.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/europa\/162730-ungarischer-aussenminister-beschuldigt-europaeisches-parlament\/\">Ungarischer Au\u00dfenminister beschuldigt Europ\u00e4isches Parlament der Korruption<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-vk\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/vk.com\/video_ext.php?oid=-134310637&amp;id=456263788&amp;hash=272c56928110a512\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/162963-ungarn-wir-unterstuetzen-friedensgespraeche\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ungarns Au\u00dfenminister Szijj\u00e1rt\u00f3 hat nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin Colonna erkl\u00e4rt, die westlichen Staaten seien der Ansicht, dass die Ukraine Friedensverhandlungen erst dann aufnehmen solle, wenn die Lage f\u00fcr sie milit\u00e4risch g\u00fcnstig sei. Nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin\u00a0Catherine Colonna in Paris am Dienstag hat\u00a0Ungarns Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 verk\u00fcndet, dass die Lage [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":30423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1676458078"],"wp_automatic_camp":["217"],"886b3b849cece4118dd5353496e02711":["Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge"],"original_link":["https:\/\/de.rt.com\/europa\/162963-ungarn-wir-unterstuetzen-friedensgespraeche\/"],"_thumbnail_id":["30423"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-02-15 12:49:05\";}"],"jnews_social_counter_last_update":["1788320895"]},"categories":[19,23],"tags":[7121,40829,29201,35288,27113,11664,1190,14368,1801],"class_list":["post-30422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-andere","tag-aufukrainische","tag-erfolge","tag-eustaaten","tag-friedensgespraeche","tag-ungarn","tag-unterstuetzen","tag-warten","tag-wir"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge\" \/>\n<meta property=\"og:description\" content=\"Ungarns Au\u00dfenminister Szijj\u00e1rt\u00f3 hat nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin Colonna erkl\u00e4rt, die westlichen Staaten seien der Ansicht, dass die Ukraine Friedensverhandlungen erst dann aufnehmen solle, wenn die Lage f\u00fcr sie milit\u00e4risch g\u00fcnstig sei. Nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin\u00a0Catherine Colonna in Paris am Dienstag hat\u00a0Ungarns Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 verk\u00fcndet, dass die Lage [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-15T10:44:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge\",\"datePublished\":\"2023-02-15T10:44:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg\",\"keywords\":[\"andere\",\"aufukrainische\",\"Erfolge\",\"EUStaaten\",\"Friedensgespr\u00e4che\",\"Ungarn\",\"unterst\u00fctzen\",\"warten\",\"Wir\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/\",\"name\":\"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg\",\"datePublished\":\"2023-02-15T10:44:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg\",\"width\":460,\"height\":259,\"caption\":\"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/","og_locale":"de_DE","og_type":"article","og_title":"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge","og_description":"Ungarns Au\u00dfenminister Szijj\u00e1rt\u00f3 hat nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin Colonna erkl\u00e4rt, die westlichen Staaten seien der Ansicht, dass die Ukraine Friedensverhandlungen erst dann aufnehmen solle, wenn die Lage f\u00fcr sie milit\u00e4risch g\u00fcnstig sei. Nach einem Treffen mit seiner franz\u00f6sischen Amtskollegin\u00a0Catherine Colonna in Paris am Dienstag hat\u00a0Ungarns Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 verk\u00fcndet, dass die Lage [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-02-15T10:44:10+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge","datePublished":"2023-02-15T10:44:10+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg","keywords":["andere","aufukrainische","Erfolge","EUStaaten","Friedensgespr\u00e4che","Ungarn","unterst\u00fctzen","warten","Wir"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/","url":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/","name":"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg","datePublished":"2023-02-15T10:44:10+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Ungarn-Wir-unterstuetzen-Friedensgespraeche-andere-EU-Staaten-warten-auf-ukrainische-Erfolge.jpg","width":460,"height":259,"caption":"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ungarn-wir-unterstuetzen-friedensgespraeche-andere-eu-staaten-warten-auf-ukrainische-erfolge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ungarn: Wir unterst\u00fctzen Friedensgespr\u00e4che, andere EU-Staaten warten auf\u00a0ukrainische Erfolge"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/30422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=30422"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/30422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/30423"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=30422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=30422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=30422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}