{"id":30417,"date":"2023-02-15T11:11:05","date_gmt":"2023-02-15T09:11:05","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/"},"modified":"2023-02-15T11:11:05","modified_gmt":"2023-02-15T09:11:05","slug":"waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/","title":{"rendered":"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63eca09bb480cc3d537a2b36.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Trotz der Warnungen aus Russland vor einer weiteren Eskalation liefern die USA Panzer. Aufnahmen zeigen 60 Sch\u00fctzenpanzer und weiteres milit\u00e4risches Ger\u00e4t zum Weitertransport in Bremerhaven. Wahrscheinliches Ziel: die Ukraine. Damit treiben die USA den Konflikt weiter voran.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Laut Berichten der Nordsee-Zeitung wird Bremerhaven als Umschlagplatz f\u00fcr Panzer vom Typ Bradley und milit\u00e4risches Ger\u00e4t f\u00fcr die Ukraine genutzt. Bereits am Freitag ist das Frachtschiff &#8220;Arc Integrity&#8221; in Bremerhaven angekommen.\u00a0Milit\u00e4risches Ger\u00e4t wurde auf dem Kai geparkt. Inzwischen zeigen Bilder, wie die Panzer zum Weitertransport auf Lkw verladen wurden.\u00a0<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/Bradleys?src=hash&amp;ref_src=twsrc%5Etfw\">#Bradleys<\/a> are leaving the <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/German?src=hash&amp;ref_src=twsrc%5Etfw\">#German<\/a> port of <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/Bremerhaven?src=hash&amp;ref_src=twsrc%5Etfw\">#Bremerhaven<\/a> and are heading east towards <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/Ukraine?src=hash&amp;ref_src=twsrc%5Etfw\">#Ukraine<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/sVk7fUPzvk\">pic.twitter.com\/sVk7fUPzvk<\/a><\/p>\n<p>\u2014 Stepan Gronk (@StepanGronk) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/StepanGronk\/status\/1625713669656170498?ref_src=twsrc%5Etfw\">February 15, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Bilder zeigen 60 Sch\u00fctzenpanzer vom Typ BMP Bradley und weitere Einheiten technisches Ger\u00e4t, die laut Zeitung vermutlich f\u00fcr die Ukraine bestimmt sind.\u00a0<\/p>\n<p><em>&#8220;Bremerhaven ist wieder einmal Drehscheibe f\u00fcr Milit\u00e4rfahrzeuge aus den USA. Derzeit werden im Hafen rund 150 Panzer verladen \u2013 Ziel ist wahrscheinlich die Ukraine&#8221;<\/em>, schreibt die Zeitung. Weiter hei\u00dft es, dass am Montag aus der Luft rund 440 Milit\u00e4rfahrzeuge der US-Armee auf einem Stellplatz des von der US-Armee genutzten Teils des Hafengebiets auszumachen waren.\u00a0<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Photos from the German port of Bremerhaven, where military equipment arrives for further shipment to Ukraine. American Bradley infantry fighting vehicles arrived there on Friday. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/T9WHd3lmoh\">pic.twitter.com\/T9WHd3lmoh<\/a><\/p>\n<p>\u2014 Revolution Radio \u26aa\ufe0f (@Freedom_Slips) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Freedom_Slips\/status\/1625681361674842113?ref_src=twsrc%5Etfw\">February 15, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Die Lieferung ist Berichten zufolge Teil des 2,5 Milliarden Dollar umfassenden R\u00fcstungspakets, das die USA der Ukraine versprochen haben. Es umfasst neben Bradley-Sch\u00fctzenpanzern noch Radpanzer vom Typ &#8220;Stryker&#8221; sowie weitere gepanzerte Fahrzeuge und Munition. Schwere Kampfpanzer vom Typ M1 Abrams sind in der Lieferung nicht enthalten.\u00a0<\/p>\n<p>Eine weitere Waffenlieferung wird in Bremerhaven am kommenden Wochenende erwartet. Sie soll weitere Panzer umfassen. Mit den Waffenlieferungen glauben die USA, die strategische Position der Ukraine verbessern zu k\u00f6nnen.\u00a0<\/p>\n<p>Die Nachricht von umfangreichen Waffenlieferungen der USA an die Ukraine \u00fcber deutschen Boden fand unmittelbar Verbreitung in russischen Medien.<\/p>\n<p>Russland hat die Waffenlieferungen des Westens an die Ukraine wiederholt verurteilt. Laut dem russischen Au\u00dfenministerium dient dies lediglich einer Eskalation des Konflikts. Russland hat zudem mehrfach erkl\u00e4rt, dass die Waffenlieferungen des Westens am Ergebnis der Milit\u00e4roperation nichts \u00e4ndern, sie die Operation lediglich in die L\u00e4nge ziehen und den Schaden und die Opferzahlen f\u00fcr die Ukraine erh\u00f6hen werden.<\/p>\n<p>Ungeachtet der Warnungen vor einer Verl\u00e4ngerung des Konflikts und der damit einhergehenden Opfer, die von der Ukraine zu erbringen sind, bedankte sich der ukrainische Pr\u00e4sident Selenskij unterdessen auf Twitter f\u00fcr die Lieferung der US-Waffen.\u00a0<\/p>\n<p><strong>Mehr zum Thema\u00a0\u2013 <\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/fromrussiawithlove.rtde.live\/inland\/162906-pistorius-panzerkoalition-fuer-ukraine-laeuft\/\">Pistorius: Panzerkoalition f\u00fcr Ukraine l\u00e4uft &#8220;nicht so berauschend&#8221;<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/162953-waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trotz der Warnungen aus Russland vor einer weiteren Eskalation liefern die USA Panzer. Aufnahmen zeigen 60 Sch\u00fctzenpanzer und weiteres milit\u00e4risches Ger\u00e4t zum Weitertransport in Bremerhaven. Wahrscheinliches Ziel: die Ukraine. Damit treiben die USA den Konflikt weiter voran. Laut Berichten der Nordsee-Zeitung wird Bremerhaven als Umschlagplatz f\u00fcr Panzer vom Typ Bradley und milit\u00e4risches Ger\u00e4t f\u00fcr die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":30418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1676452320"],"wp_automatic_camp":["217"],"1ab60f76cfaac7f497ca268ed273b85a":["Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen"],"original_link":["https:\/\/de.rt.com\/inland\/162953-waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer\/"],"_thumbnail_id":["30418"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-02-15 11:13:13\";}"],"jnews_social_counter_last_update":["1788256640"]},"categories":[19,23],"tags":[20888,179,45,20807,221,127,40827,40826],"class_list":["post-30417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-bremerhaven","tag-deutschland","tag-die","tag-eingetroffen","tag-fuer","tag-ukraine","tag-usschuetzenpanzer","tag-waffenumschlagplatz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen\" \/>\n<meta property=\"og:description\" content=\"Trotz der Warnungen aus Russland vor einer weiteren Eskalation liefern die USA Panzer. Aufnahmen zeigen 60 Sch\u00fctzenpanzer und weiteres milit\u00e4risches Ger\u00e4t zum Weitertransport in Bremerhaven. Wahrscheinliches Ziel: die Ukraine. Damit treiben die USA den Konflikt weiter voran. Laut Berichten der Nordsee-Zeitung wird Bremerhaven als Umschlagplatz f\u00fcr Panzer vom Typ Bradley und milit\u00e4risches Ger\u00e4t f\u00fcr die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-15T09:11:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen\",\"datePublished\":\"2023-02-15T09:11:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg\",\"keywords\":[\"Bremerhaven\",\"Deutschland\",\"die\",\"eingetroffen\",\"f\u00fcr\",\"ukraine\",\"USSch\u00fctzenpanzer\",\"WaffenUmschlagplatz\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/\",\"name\":\"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg\",\"datePublished\":\"2023-02-15T09:11:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/","og_locale":"de_DE","og_type":"article","og_title":"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen","og_description":"Trotz der Warnungen aus Russland vor einer weiteren Eskalation liefern die USA Panzer. Aufnahmen zeigen 60 Sch\u00fctzenpanzer und weiteres milit\u00e4risches Ger\u00e4t zum Weitertransport in Bremerhaven. Wahrscheinliches Ziel: die Ukraine. Damit treiben die USA den Konflikt weiter voran. Laut Berichten der Nordsee-Zeitung wird Bremerhaven als Umschlagplatz f\u00fcr Panzer vom Typ Bradley und milit\u00e4risches Ger\u00e4t f\u00fcr die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-02-15T09:11:05+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen","datePublished":"2023-02-15T09:11:05+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg","keywords":["Bremerhaven","Deutschland","die","eingetroffen","f\u00fcr","ukraine","USSch\u00fctzenpanzer","WaffenUmschlagplatz"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/","url":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/","name":"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg","datePublished":"2023-02-15T09:11:05+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Waffen-Umschlagplatz-Bremerhaven-US-Schuetzenpanzer-fuer-die-Ukraine-in-Deutschland-eingetroffen.jpg","width":460,"height":259,"caption":"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/waffen-umschlagplatz-bremerhaven-us-schuetzenpanzer-fuer-die-ukraine-in-deutschland-eingetroffen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Waffen-Umschlagplatz Bremerhaven: US-Sch\u00fctzenpanzer f\u00fcr die Ukraine in Deutschland eingetroffen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/30417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=30417"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/30417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/30418"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=30417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=30417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=30417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}