{"id":29818,"date":"2023-02-08T10:10:25","date_gmt":"2023-02-08T08:10:25","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/"},"modified":"2023-02-08T10:10:25","modified_gmt":"2023-02-08T08:10:25","slug":"wolfgang-bittner-wir-sind-im-kriegsmodus","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/","title":{"rendered":"Wolfgang Bittner: Wir sind im Kriegsmodus"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e2648548fbef5c363cba2f.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der Kanzler schickt bereits Panzer, nun will Kiew Kampfflugzeuge und Langstreckenraketen. Die Weltuntergangsuhr, so der Autor Wolfgang Bittner, steht auf 90 Sekunden vor Mitternacht.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Wolfgang Bittner<\/em><\/p>\n<p>Als Joseph Biden 2014 davon sprach, der russische Pr\u00e4sident Wladimir Putin m\u00fcsse die Souver\u00e4nit\u00e4t der Ukraine respektieren, sonst werde sich Russland zunehmenden Konsequenzen gegen\u00fcbersehen, war der von den USA lange vorbereitete Staatsstreich in Kiew \u2013 unter Missachtung der Souver\u00e4nit\u00e4t der Ukraine \u2013 bereits vollzogen, und der B\u00fcrgerkrieg in der Ostukraine hatte begonnen. Kurz darauf n\u00f6tigte US-Pr\u00e4sident Barack Obama die f\u00fchrenden europ\u00e4ischen Politiker, Russland mit harten Sanktionen zu belegen.<\/p>\n<p>Das war der Beginn einer gewollten Auseinandersetzung, in die Deutschland und die Europ\u00e4ische Union mehr und mehr hineingezogen wurden. Lange vergessen ist das Kooperationsangebot Putins von 2001, als er in seiner denkw\u00fcrdigen Rede im Deutschen Bundestag f\u00fcr einen gemeinsamen Wirtschaftsraum von Wladiwostok bis Lissabon warb. Die USA haben das verhindert. Sie haben die Ukraine nach dem von ihnen initiierten Putsch auf kaltem Wege \u00fcbernommen und vor der Haust\u00fcr Russlands einen Brandherd gelegt, den sie immer wieder anheizten.<\/p>\n<p>Das Minsker Abkommen wurde von Kiew ignoriert, die berechtigten Forderungen Russlands nach Sicherheitsgarantien blieben unbeantwortet und Mitte Februar 2022 eskalierten die Angriffe auf die Volksrepubliken Donezk und Lugansk. Daraufhin marschierten am 24. Februar 2022 russische Truppen in die Ukraine ein. Die Folge war ein Aufschrei des sogenannten Wertewestens mit einer gigantischen Kriegspropaganda, begleitet von umfangreichen Waffenlieferungen an die Ukraine. Die USA und die NATO begannen, mithilfe der instrumentalisierten Ukraine einen verdeckten Krieg gegen Russland zu f\u00fchren.<\/p>\n<p><strong>Ideologisierte Politiker machen alles noch schlimmer<\/strong><\/p>\n<p>Inzwischen zeigt die Weltuntergangsuhr 90 Sekunden vor Mitternacht. Dennoch folgen devote, ideologisierte Politiker in der Europ\u00e4ischen Union den Vorgaben aus Washington zum Nachteil ihrer L\u00e4nder. Sowohl Deutschland als angebliche europ\u00e4ische F\u00fchrungsmacht als auch die EU mit der aufgrund von Manipulationen an die Macht gekommenen Kommissionspr\u00e4sidentin Ursula von der Leyen tragen zur Versch\u00e4rfung der Lage bei und \u00fcberschreiten damit st\u00e4ndig ihre Befugnisse, indem sie ihren prim\u00e4ren Auftrag, Frieden und Sicherheit zu bewahren, verraten. Um es noch deutlicher zu sagen: Die deutsche Regierung und die EU-Kommission missbrauchen ihr Mandat.<\/p>\n<p>Putin hatte den Westen mehrmals davor gewarnt, die Ukraine mit Offensivwaffen auszur\u00fcsten und Verhandlungen angeboten. Seine Erkl\u00e4rungen, Moskau sei trotz der westlichen Aggressionspolitik an einer Kooperation mit allen ausl\u00e4ndischen Partnern interessiert, wurden als Propaganda abgetan. Auch die Bem\u00fchungen des russischen Au\u00dfenministers Sergei Lawrow, der vor einer hochgef\u00e4hrlichen Ausweitung des Ukraine-Krieges gewarnt hatte, liefen ins Leere. Lawrow hatte schon vor Wochen von einem hybriden Krieg gegen Russland gesprochen, der das Ziel habe, das Land zu ruinieren und einen politischen Umsturz herbeizuf\u00fchren.<\/p>\n<p><strong>Westen: Russland muss verlieren<\/strong><\/p>\n<p>Festzustellen ist, dass die von den USA gef\u00fchrte westliche Allianz beabsichtigt, Russland mit allen zur Verf\u00fcgung stehenden Mitteln zu besiegen. Was sich in dieser Konstellation zwischen Deutschland und Russland angebahnt hat, ist eine Trag\u00f6die und eine Jahrhundertkatastrophe. Besonders tragisch ist, dass sich Deutschland zum dritten Mal gegen Russland in Stellung bringen l\u00e4sst. Das war im Ersten und Zweiten Weltkrieg so und ist auch jetzt wieder der Fall. Durch die bedingungslose Kapitulation 1945 geriet Deutschland vollkommen in die Hand der USA, die seit \u00fcber einem Jahrhundert eine Langzeitstrategie verfolgen, die vor allem der Verhinderung einer Kooperation zwischen Deutschland und Russland als einer wirtschaftlichen und milit\u00e4rischen Konkurrenz dient.<\/p>\n<p>Jetzt wird Deutschland als Speerspitze gegen Russland eingesetzt, Japan und S\u00fcdkorea stehen gegen China. Die USA wollen mit aller Macht ihren durch nichts begr\u00fcndeten Anspruch auf globale Herrschaft durchsetzen, selbst wenn es dabei zum gro\u00dfen Krieg kommt. Diese Hybris geht von den Neokonservativen in Washington mit den dortigen Finanz- und Wirtschafseliten und ihrer Galionsfigur Joseph Biden aus, der fast alle Konflikte und Kriege der letzten Jahrzehnte mitzuverantworten hat. Er ist es auch, der Deutschland zur bedingungslosen Unterst\u00fctzung der Ukraine verpflichtet, zur Teilnahme an einem Abnutzungskrieg, von dem die USA wirtschaftlich au\u00dferordentlich profitieren.<\/p>\n<p>Eine nochmalige Zuspitzung in den Beziehungen Russlands mit den Westalliierten ist nach einer best\u00fcrzenden Aussage der ehemaligen Bundeskanzlerin Angela Merkel eingetreten. In einem Interview sagte sie im Dezember 2022, das Minsker Abkommen von 2014 sei vom Westen geschlossen worden, um der Ukraine Zeit zu geben, st\u00e4rker zu werden. Der ehemalige franz\u00f6sische Pr\u00e4sident Hollande und der ukrainische Ex-Pr\u00e4sident Poroschenko haben das best\u00e4tigt. Demnach war Krieg mit Russland von vornherein die Absicht, die der Westen in und mit der Ukraine verfolgt hat. Was da zutage tritt, ist eine Ungeheuerlichkeit: Die Regierungen von Deutschland, Frankreich, der Ukraine und den USA haben in den Jahren vor dem russischen Einmarsch doppeltes Spiel getrieben, das hei\u00dft intrigiert, gelogen und Kriegsvorbereitungen getroffen.<\/p>\n<p><strong>Der Panzer-Kanzler und seine Au\u00dfenministerin<\/strong><\/p>\n<p>Putin zeigte sich tief entt\u00e4uscht. Er beklagte einen Mangel an Ehrlichkeit und stellte die Frage, ob es \u00fcberhaupt noch jemanden gebe, mit dem man sich einigen k\u00f6nne und welche Garantien es dann gebe. Nach diesen Enth\u00fcllungen sei das Vertrauen fast auf dem Nullpunkt, aber \u2013 so f\u00fcgte er hinzu \u2013 letztlich m\u00fcsse eine Einigung erzielt werden und Russland sei dazu bereit und offen. Anstatt darauf einzugehen, fand ein regelrechtes Kesseltreiben auf die Berliner Regierung statt, Leopard-Kampfpanzer, also schwere Offensivwaffen, an die Ukraine zu liefern, was nun geschehen ist. Jetzt fordert der ukrainische Machthaber Wladimir Selenskij Kampfflugzeuge und Langstreckenraketen.<\/p>\n<p>Dass die Lieferung solcher Waffen die Situation in der Ukraine nur versch\u00e4rfen kann, hat sich in den vergangenen Wochen bewiesen. Je mehr der Westen liefert, desto l\u00e4nger wird diese Auseinandersetzung dauern. Die Ukraine geht dabei zugrunde, aber auch Deutschland, das st\u00e4ndig Waffen schickt und Milliarden an Kiew zahlt, wird ruiniert. Dass ein gro\u00dfer Teil der deutschen Bev\u00f6lkerung Frieden mit Russland will, wird von der eigenen Regierung aufgrund des Drucks aus Washington und einiger Vasallenstaaten missachtet. Selenskij kann die deutsche Regierung beleidigen und beschimpfen, doch Olaf Scholz und Au\u00dfenministerin Annalena Baerbock versichern ihm weiterhin ihre unbegrenzte Unterst\u00fctzung. Viele fragen sich, wie die Berliner Politiker dazu kommen, solche Versprechungen abzugeben und warum Deutschland der Ukraine \u00fcberhaupt irgendetwas schulden sollte.<\/p>\n<p>Einen Paradigmenwechsel in der Einsch\u00e4tzung des Ukraine-Krieges auf westlicher Seite leitete k\u00fcrzlich der Vorsitzende des Vereinigten Generalstabs der Streitkr\u00e4fte der USA, General Mark Milley, ein, als er in einem Interview in der <em>New York Times<\/em> \u2013 entgegen der Politik Bidens \u2013 zu Verhandlungen mit Russland aufrief. Offenbar f\u00fcrchten hohe Milit\u00e4rs in den USA und Europa inzwischen die Inkompetenz von Politikern wie Biden, Austin, Selenskij oder Baerbock und melden sich allm\u00e4hlich zu Wort.<\/p>\n<p><strong>Zwei Atomm\u00e4chte im Stellvertreterkrieg<\/strong><\/p>\n<p>Das ficht US-Pr\u00e4sident Biden offenbar nicht an. Er w\u00e4hnt sich am Ziel seiner jahrzehntelangen Bem\u00fchungen, Russland zu ruinieren und den westlichen Begehrlichkeiten wie auch den strategischen Interessen zu unterwerfen. Aber das wird die russische Regierung verhindern. Russland wird nichts \u00fcbrig bleiben, als sich in dieser Auseinandersetzung, trotz der immensen Waffenlieferungen der westlichen Allianz, durchzusetzen. Etwas anderes ist gar nicht m\u00f6glich. Russland ist eine Atommacht und wird eine Niederlage, die mit einer Zerst\u00fcckelung des Landes einherginge, niemals zulassen.<\/p>\n<p>Abgesehen von der akuten atomaren Bedrohung sind die Folgen der von den USA provozierten Auseinandersetzung gravierend. Russland hat schon l\u00e4nger damit begonnen, sich vom Westen abzukoppeln, neue Wege mit neuen Partnern zu gehen und sich gegen die Aggressionspolitik der USA zur Wehr zu setzen. Damit ist Russland nicht allein. Mehr als die H\u00e4lfte der Menschheit will sich die Zumutungen und die Unterdr\u00fcckung durch die USA nicht mehr gefallen lassen.<\/p>\n<p>Zu registrieren ist, dass die BRICS-Organisation und die Schanghaier Organisation f\u00fcr Zusammenarbeit immer mehr Zulauf erhalten. Gearbeitet wird an einem anderen als dem westlichen, von den USA dominierten Wirtschafts- und Finanzsystem. Unter anderem ist die Herrschaft des Dollar als Weltleitw\u00e4hrung infrage gestellt, was allerdings weitere, hochgef\u00e4hrliche Auseinandersetzungen nach sich zieht. Denn die USA werden sich nicht ohne Gegenwehr in den Bankrott treiben lassen. Sie verf\u00fcgen \u00fcber die gr\u00f6\u00dfte Milit\u00e4rmacht der Welt, und das ist bei allem zu ber\u00fccksichtigen, was k\u00fcnftig in den Bem\u00fchungen um eine friedlichere Welt unternommen wird. Zurzeit stehen sich zwei Atomm\u00e4chte in einem Stellvertreterkrieg gegen\u00fcber, der jede Minute ausufern kann.<\/p>\n<p>M\u00f6ge uns das erspart bleiben.<\/p>\n<p><em>Von Wolfgang Bittner ist k\u00fcrzlich im Verlag zeitgeist das Buch &#8220;Ausnahmezustand \u2013 Geopolitische Einsichten und Analysen unter Ber\u00fccksichtigung der Ukraine-Krise&#8221; erschienen.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/international\/160846-magier-im-kreml-in-frankreich\/\">&#8220;Der Magier im Kreml&#8221;: In Frankreich sorgt ein Buch \u00fcber Putin f\u00fcr Angst um die nationale Politik<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FUkraine_defacto_NATO-Land_Ukrainischer_Verteidigungsminister%3A5\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/162195-wir-sind-im-kriegsmodus\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Kanzler schickt bereits Panzer, nun will Kiew Kampfflugzeuge und Langstreckenraketen. Die Weltuntergangsuhr, so der Autor Wolfgang Bittner, steht auf 90 Sekunden vor Mitternacht. Von Wolfgang Bittner Als Joseph Biden 2014 davon sprach, der russische Pr\u00e4sident Wladimir Putin m\u00fcsse die Souver\u00e4nit\u00e4t der Ukraine respektieren, sonst werde sich Russland zunehmenden Konsequenzen gegen\u00fcbersehen, war der von den [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":29819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1675844471"],"wp_automatic_camp":["217"],"5bcd3cef176628ff120e94af612d0eb2":["Wolfgang Bittner: Wir sind im Kriegsmodus"],"original_link":["https:\/\/de.rt.com\/meinung\/162195-wir-sind-im-kriegsmodus\/"],"_thumbnail_id":["29819"],"jnews_social_counter_last_update":["1784149191"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-02-08 10:22:12\";}"]},"categories":[19,23],"tags":[20375,24048,1046,1801,167],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wolfgang Bittner: Wir sind im Kriegsmodus - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wolfgang Bittner: Wir sind im Kriegsmodus\" \/>\n<meta property=\"og:description\" content=\"Der Kanzler schickt bereits Panzer, nun will Kiew Kampfflugzeuge und Langstreckenraketen. Die Weltuntergangsuhr, so der Autor Wolfgang Bittner, steht auf 90 Sekunden vor Mitternacht. Von Wolfgang Bittner Als Joseph Biden 2014 davon sprach, der russische Pr\u00e4sident Wladimir Putin m\u00fcsse die Souver\u00e4nit\u00e4t der Ukraine respektieren, sonst werde sich Russland zunehmenden Konsequenzen gegen\u00fcbersehen, war der von den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-08T08:10:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Wolfgang Bittner: Wir sind im Kriegsmodus\",\"datePublished\":\"2023-02-08T08:10:25+00:00\",\"dateModified\":\"2023-02-08T08:10:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/\"},\"wordCount\":1413,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg\",\"keywords\":[\"Bittner\",\"Kriegsmodus\",\"sind\",\"Wir\",\"Wolfgang\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/\",\"name\":\"Wolfgang Bittner: Wir sind im Kriegsmodus - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg\",\"datePublished\":\"2023-02-08T08:10:25+00:00\",\"dateModified\":\"2023-02-08T08:10:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg\",\"width\":460,\"height\":259,\"caption\":\"Wolfgang Bittner: Wir sind im Kriegsmodus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wolfgang Bittner: Wir sind im Kriegsmodus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wolfgang Bittner: Wir sind im Kriegsmodus - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/","og_locale":"de_DE","og_type":"article","og_title":"Wolfgang Bittner: Wir sind im Kriegsmodus","og_description":"Der Kanzler schickt bereits Panzer, nun will Kiew Kampfflugzeuge und Langstreckenraketen. Die Weltuntergangsuhr, so der Autor Wolfgang Bittner, steht auf 90 Sekunden vor Mitternacht. Von Wolfgang Bittner Als Joseph Biden 2014 davon sprach, der russische Pr\u00e4sident Wladimir Putin m\u00fcsse die Souver\u00e4nit\u00e4t der Ukraine respektieren, sonst werde sich Russland zunehmenden Konsequenzen gegen\u00fcbersehen, war der von den [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-02-08T08:10:25+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Wolfgang Bittner: Wir sind im Kriegsmodus","datePublished":"2023-02-08T08:10:25+00:00","dateModified":"2023-02-08T08:10:25+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/"},"wordCount":1413,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg","keywords":["Bittner","Kriegsmodus","sind","Wir","Wolfgang"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/","url":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/","name":"Wolfgang Bittner: Wir sind im Kriegsmodus - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg","datePublished":"2023-02-08T08:10:25+00:00","dateModified":"2023-02-08T08:10:25+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Wolfgang-Bittner-Wir-sind-im-Kriegsmodus.jpg","width":460,"height":259,"caption":"Wolfgang Bittner: Wir sind im Kriegsmodus"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/wolfgang-bittner-wir-sind-im-kriegsmodus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Wolfgang Bittner: Wir sind im Kriegsmodus"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/29818"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=29818"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/29818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/29819"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=29818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=29818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=29818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}