{"id":29638,"date":"2023-02-06T21:56:29","date_gmt":"2023-02-06T19:56:29","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/"},"modified":"2023-02-06T21:56:29","modified_gmt":"2023-02-06T19:56:29","slug":"gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/","title":{"rendered":"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung"},"content":{"rendered":"<div class=\"Text-root Text-type_1 \">\n                Auf der Friedenskundgebung in K\u00f6ln sprach auch ein Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange. Der sp\u00e4tere gr\u00fcne BW-Landesvorsitzende erkl\u00e4rte, dass gr\u00fcne Werte verraten wurden und warum Russland kein Interesse habe, den Westen zu erobern. Man br\u00e4uchte kein Putinversteher zu sein, um zu erkennen, warum Russland keine Stationierung von Atomwaffen an seinen Grenzen zulassen k\u00f6nne.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Initiative &#8220;K\u00f6ln ist aktiv&#8221; hatte am Samstag unter dem Motto, &#8220;wir stehen weltweit f\u00fcr Frieden&#8221; zu einem Friedensspaziergang durch K\u00f6ln aufgerufen. Nach Polizeiangaben beteiligten sich daran etwa 700 Menschen.<\/p>\n<p>Gegen die Kundgebung hatte sich in f\u00fcnfzig Meter Abstand auf dem K\u00f6lner Alter Markt eine kleine Gegendemo formiert, die die Friedensaktivisten lautstark attackierten. Zum Auftakt der Demonstration wurde das Friedenslied &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=oIO5lfJ9dhs\">99 Luftballons<\/a>&#8221; von Nena gespielt. Ein Aktivist hatte daf\u00fcr zeitnah vor Ort Luftballons aufgeblasen, die er an die Demonstranten verteilte.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e116f848fbef2e6d5bf07d.JPG 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e116f848fbef2e6d5bf07d.JPG 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e116f848fbef2e6d5bf07d.JPG 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e116f848fbef2e6d5bf07d.JPG 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e116f848fbef2e6d5bf07d.JPG\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e116f848fbef2e6d5bf07d.JPG\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Mit &#8220;99&#8221; Friedensluftballons, Demonstration gegen Waffenlieferungen an die Ukraine, K\u00f6ln 4.02.2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<blockquote>\n<p><em>&#8220;99 Kriegsminister, Streichholz und Benzinkanister, hielten sich f\u00fcr schlaue Leute, witterten schon fette Beute&#8221;,<\/em><\/p>\n<\/blockquote>\n<p>schallte es da \u00fcber den K\u00f6lner Alter Markt. In seiner Er\u00f6ffnungsrede sprach einer der Veranstalter von &#8220;K\u00f6ln ist aktiv&#8221; dar\u00fcber, wie sehr er sich gew\u00fcnscht habe, dass Deutschland im Krieg in der Ukraine als Vermittler und Friedensbotschafter gegl\u00e4nzt h\u00e4tte und nicht als Waffenlieferant. Die bundesweit engagierte Friedensaktivistin Sandra Gabriel verurteilte in ihrem Vortrag zu Beginn die angeblich linken Teilnehmer der lauten Gegendemo. &#8220;Ihr seid keine Linken \u2013 ihr seid neoliberale Stiefelknechte des Kapitals&#8221;, rief sie in deren Richtung.<\/p>\n<blockquote>\n<p><em>&#8220;Diese angeblich linken Gegendemonstranten, wann haben sie sich f\u00fcr die Linken, die seit 2014 im Donbass ermordet werden, interessiert? Denen rammen sie ein Messer in den R\u00fccken!&#8221;<\/em><\/p>\n<\/blockquote>\n<p>In diesem Krieg ginge es um die Profite der Gro\u00dfkonzerne, insbesondere die des milit\u00e4risch-industriellen Komplexes und die Dividenden superreicher Aktion\u00e4re. Das lie\u00dfe sich leicht an der Entwicklung der Aktienm\u00e4rkte erkennen und die nach dem Zweiten Weltkrieg f\u00fcr Deutschland geltende Mahnung, &#8220;von deutschem Boden darf nie wieder Krieg ausgehen&#8221;, w\u00fcrde nicht mehr interessieren.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e117ca48fbef75c8698062.JPG 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e117ca48fbef75c8698062.JPG 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e117ca48fbef75c8698062.JPG 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e117ca48fbef75c8698062.JPG 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e117ca48fbef75c8698062.JPG\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e117ca48fbef75c8698062.JPG\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Demonstration gegen Waffenlieferungen in die Ukraine, K\u00f6ln 4.02.2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<p>Schlie\u00dflich trat eines der Gr\u00fcndungsmitglieder der Partei Die Gr\u00fcnen auf die Kundgebungsb\u00fchne: Torsten Lange. Der Gr\u00fcnen-Mitbegr\u00fcnder wurde sp\u00e4ter deren Landesvorsitzender in Baden-W\u00fcrttemberg. Er war Obmann des Verteidigungsausschusses der BRD und Mitglied im Unterausschuss R\u00fcstungskontrolle unter der Leitung von Egon Bahr.<\/p>\n<p>Lange, der mittlerweile l\u00e4ngst bei den Gr\u00fcnen ausgetreten ist, erinnerte noch einmal daran, dass diese Partei, die sich jetzt f\u00fcr Waffen- und Panzerlieferungen einsetze, urspr\u00fcnglich aus der Friedens- und \u00d6kologiebewegung hervorgegangen sei. Heute nehme man das gro\u00dfe Risiko eines Atomkriegs nicht mehr ernst, sorgte sich der ehemalige gr\u00fcne Spitzenpolitiker. Der Weltkrieg werde geradezu herbeigeredet. Zu den Kriegstreibern bei den Gr\u00fcnen geh\u00f6re insbesondere der fr\u00fchere Bundesvorsitzende Anton Hofreiter (bis 2021). Hofreiter versuche geradezu, die Stimmung f\u00fcr Krieg und Waffenlieferungen anzuheizen.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11845b480cc79fb20ecf8.JPG 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11845b480cc79fb20ecf8.JPG 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11845b480cc79fb20ecf8.JPG 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11845b480cc79fb20ecf8.JPG 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11845b480cc79fb20ecf8.JPG\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11845b480cc79fb20ecf8.JPG\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Demonstration gegen Waffenlieferungen in die Ukraine, K\u00f6ln 4.02.2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e118a1b480cc7a3a6b9e97.JPG 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e118a1b480cc7a3a6b9e97.JPG 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e118a1b480cc7a3a6b9e97.JPG 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e118a1b480cc7a3a6b9e97.JPG 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e118a1b480cc7a3a6b9e97.JPG\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e118a1b480cc7a3a6b9e97.JPG\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Demonstration gegen Waffenlieferungen in die Ukraine, K\u00f6ln 4.02.2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11906b480cc79da48d7f9.JPG 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11906b480cc79da48d7f9.JPG 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11906b480cc79da48d7f9.JPG 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11906b480cc79da48d7f9.JPG 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11906b480cc79da48d7f9.JPG\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11906b480cc79da48d7f9.JPG\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Demonstration gegen Waffenlieferungen in die Ukraine, K\u00f6ln 4.02.2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<p>Dabei h\u00e4tten die Gr\u00fcnen noch im Wahlkampf 2021, Plakate mit dem Konterfei von Annalena Baerbock verbreitet, auf denen sie mit dem Slogan f\u00fcr sich warben: &#8220;Keine Waffen in Kriegsgebiete!&#8221; Sie versprachen also vor der Wahl, wenn die Gr\u00fcnen an die Regierung k\u00e4men, gebe es keine Waffenlieferungen. Mit diesem Wahlversprechen sammelten die Gr\u00fcnen bei der letzten Bundestagswahl W\u00e4hlerstimmen, erinnerte Langer.<\/p>\n<p>Es sei pure Propaganda, erkl\u00e4rte der Gr\u00fcnen-Gr\u00fcnder, dass Putin den Westen erobern wolle, daran k\u00f6nne Russland \u00fcberhaupt kein Interesse haben. Man br\u00e4uchte kein Putinversteher zu sein, um einzusehen, dass Atomm\u00e4chte an ihren Grenzen die Stationierung von Atomraketen nicht zulassen k\u00f6nnten.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11a0f48fbef2e6d5bf08a.png 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11a0f48fbef2e6d5bf08a.png 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11a0f48fbef2e6d5bf08a.png 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11a0f48fbef2e6d5bf08a.png 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11a0f48fbef2e6d5bf08a.png\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11a0f48fbef2e6d5bf08a.png\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Torsten Lange, Gr\u00fcndungsmitglied der Gr\u00fcnen auf der Friedensdemo in K\u00f6ln, 4.02.2023.<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<p>Im anschlie\u00dfenden Gespr\u00e4ch mit RT erkl\u00e4rte Lange, wie es zu so einer Umkehr der Werte in der einstigen Friedenspartei kommen konnte. Gegr\u00fcndet im Jahr 1980, seien die Gr\u00fcnen urspr\u00fcnglich aus unterschiedlichen B\u00fcrgerinitiativen heraus entstanden: Anti-Atombewegung, \u00d6kologie-Bewegung und Abr\u00fcstungsbewegung. Im Jahr 1983 seien sie erstmals im Parlament vertreten gewesen. Im Prinzip sei die Partei &#8220;ein Kind von Helmut Schmidt&#8221; gewesen, weil die SPD die Themen \u00d6kologie und Atomkraft nicht angemessen aufgegriffen habe.<\/p>\n<p>W\u00e4hrend die gr\u00fcne Basis weiterhin idealistisch geblieben sei, h\u00e4tte es Lange zufolge bei den Bestrebungen an die Regierungsmacht zu kommen, unter den Gr\u00fcnen von Anfang an zwei unterschiedliche Motivlagen gegeben. Es habe diejenigen gr\u00fcnen Politiker gegeben, die an die Macht wollten, um etwas im Sinne der gr\u00fcnen Werte bewegen zu k\u00f6nnen, aber es habe eindeutig auch solche Personen gegeben, die nur um der reinen Macht willen mitregieren wollten, die sich um Ideale nicht scherten.<\/p>\n<p>W\u00e4hrend die Idealisten, f\u00fcr die Chance, ihre Ideale zu verwirklichen, bei zu vielen Kompromissen nachgaben, h\u00e4tten sich andere bei ihrem Ringen um Macht von vorneherein nicht mehr f\u00fcr gr\u00fcne Grunds\u00e4tze interessiert, so der ehemalige Gr\u00fcne. Schlie\u00dflich wurde er gefragt, was er gerne <em>RT <\/em>gegen\u00fcber mitteilen wolle.<\/p>\n<blockquote>\n<p><em>&#8220;Ich w\u00fcnsche mir, dass auch russische Medien wieder geh\u00f6rt und gesehen werden d\u00fcrfen&#8221;,<\/em>\u00a0<\/p>\n<\/blockquote>\n<p>so Lange. Von Russland w\u00fcnsche er sich, dass deutschen Lesern und Zuschauern m\u00f6glichst immer wieder verdeutlicht werde, dass es eine historische Freundschaft zwischen Russland und Deutschland gebe. Diese Freundschaft m\u00fcsse unter Ber\u00fccksichtigung beiderseitiger Sicherheitsinteressen gestaltet werden.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11ec4b480cc7a63362687.png 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11ec4b480cc7a63362687.png 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11ec4b480cc7a63362687.png 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11ec4b480cc7a63362687.png 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11ec4b480cc7a63362687.png\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11ec4b480cc7a63362687.png\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Demonstration gegen Waffenlieferungen in die Ukraine, K\u00f6ln 4.02.2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11aa548fbef2ebe6c96c6.JPG 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11aa548fbef2ebe6c96c6.JPG 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11aa548fbef2ebe6c96c6.JPG 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11aa548fbef2ebe6c96c6.JPG 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11aa548fbef2ebe6c96c6.JPG\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/63e11aa548fbef2ebe6c96c6.JPG\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Demonstration gegen Waffenlieferungen in die Ukraine, K\u00f6ln 4.02.2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Felicitas Rabe<\/span><\/span><\/figcaption><\/figure>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/pressefreiheit.rtde.tech\/meinung\/160062-herren-menschin-baerbock-will-putin\/\">Die Herren-Menschin: Baerbock will Putin abstrafen<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/162083-gruendungsmitglied-gruenen-torsten-lange-spricht\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf der Friedenskundgebung in K\u00f6ln sprach auch ein Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange. Der sp\u00e4tere gr\u00fcne BW-Landesvorsitzende erkl\u00e4rte, dass gr\u00fcne Werte verraten wurden und warum Russland kein Interesse habe, den Westen zu erobern. Man br\u00e4uchte kein Putinversteher zu sein, um zu erkennen, warum Russland keine Stationierung von Atomwaffen an seinen Grenzen zulassen k\u00f6nne. Die Initiative [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":29639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1675714078"],"wp_automatic_camp":["217"],"c340634162c07543fffba668ecdc7cd1":["Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung"],"original_link":["https:\/\/de.rt.com\/inland\/162083-gruendungsmitglied-gruenen-torsten-lange-spricht\/"],"_thumbnail_id":["29639"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-02-06 22:09:18\";}"],"jnews_social_counter_last_update":["1778531829"]},"categories":[19,23],"tags":[133,82,40303,40301,594,612,18679,4067,40302],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung\" \/>\n<meta property=\"og:description\" content=\"Auf der Friedenskundgebung in K\u00f6ln sprach auch ein Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange. Der sp\u00e4tere gr\u00fcne BW-Landesvorsitzende erkl\u00e4rte, dass gr\u00fcne Werte verraten wurden und warum Russland kein Interesse habe, den Westen zu erobern. Man br\u00e4uchte kein Putinversteher zu sein, um zu erkennen, warum Russland keine Stationierung von Atomwaffen an seinen Grenzen zulassen k\u00f6nne. Die Initiative [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T19:56:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung\",\"datePublished\":\"2023-02-06T19:56:29+00:00\",\"dateModified\":\"2023-02-06T19:56:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/\"},\"wordCount\":960,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG\",\"keywords\":[\"AUF\",\"der\",\"Friedenskundgebung\",\"Gr\u00fcndungsmitglied\",\"GR\u00dcNEN\",\"K\u00f6lner\",\"lange\",\"spricht\",\"Torsten\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/\",\"name\":\"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG\",\"datePublished\":\"2023-02-06T19:56:29+00:00\",\"dateModified\":\"2023-02-06T19:56:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG\",\"width\":1620,\"height\":1080,\"caption\":\"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/","og_locale":"de_DE","og_type":"article","og_title":"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung","og_description":"Auf der Friedenskundgebung in K\u00f6ln sprach auch ein Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange. Der sp\u00e4tere gr\u00fcne BW-Landesvorsitzende erkl\u00e4rte, dass gr\u00fcne Werte verraten wurden und warum Russland kein Interesse habe, den Westen zu erobern. Man br\u00e4uchte kein Putinversteher zu sein, um zu erkennen, warum Russland keine Stationierung von Atomwaffen an seinen Grenzen zulassen k\u00f6nne. Die Initiative [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-02-06T19:56:29+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung","datePublished":"2023-02-06T19:56:29+00:00","dateModified":"2023-02-06T19:56:29+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/"},"wordCount":960,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG","keywords":["AUF","der","Friedenskundgebung","Gr\u00fcndungsmitglied","GR\u00dcNEN","K\u00f6lner","lange","spricht","Torsten"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/","url":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/","name":"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG","datePublished":"2023-02-06T19:56:29+00:00","dateModified":"2023-02-06T19:56:29+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/02\/Gruendungsmitglied-der-Gruenen-Torsten-Lange-spricht-auf-Koelner-Friedenskundgebung.JPG","width":1620,"height":1080,"caption":"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/gruendungsmitglied-der-gruenen-torsten-lange-spricht-auf-koelner-friedenskundgebung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Gr\u00fcndungsmitglied der Gr\u00fcnen, Torsten Lange, spricht auf K\u00f6lner Friedenskundgebung"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/29638"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=29638"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/29638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/29639"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=29638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=29638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=29638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}