{"id":28594,"date":"2023-01-25T13:26:34","date_gmt":"2023-01-25T11:26:34","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/"},"modified":"2023-01-25T13:26:34","modified_gmt":"2023-01-25T11:26:34","slug":"us-regierung-wirft-google-monopolisierung-von-online-werbung-vor","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/","title":{"rendered":"US-Regierung wirft Google Monopolisierung von Online-Werbung vor"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63d10b03b480cc0527360a45.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die US-Regierung zieht Google vor Gericht. Laut der Klageschrift des Justizministeriums hat der IT-Konzern seine Dominanz im Bereich Online-Werbung missbraucht und einen gesunden Wettbewerb behindert. Google erkl\u00e4rt, dass der Staat Gewinner und Verlierer nicht bestimmen kann.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Am Dienstag hat das US-Justizministerium eine Kartellklage gegen Google vor dem Bundesbezirksgericht in Alexandria im Bundesstaat Virginia eingereicht. Die Beh\u00f6rde fordert von dem Unternehmen den Verkauf eines Teils seines Werbegesch\u00e4fts. Laut der <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/storage.courtlistener.com\/recap\/gov.uscourts.vaed.533508\/gov.uscourts.vaed.533508.1.0_1.pdf\">Klageschrift<\/a> soll Google wettbewerbswidrige und ausschlie\u00dfende Praktiken angewandt haben, um Bedrohungen seiner Vorherrschaft in der Online-Werbebranche illegal zu umgehen oder zu verringern. Das Werbegesch\u00e4ft macht etwa 80 Prozent der Einnahmen des IT-Konzerns aus.<\/p>\n<p>Google besetze marktbeherrschende Dienste, die es seinen Kunden erm\u00f6glichten, Werbefl\u00e4chen anzubieten, bessere Anzeigen zu erstellen und Verleger mit Werbetreibenden zusammenzubringen, hei\u00dft es in der Klage. Das Unternehmen soll seine Gr\u00f6\u00dfe und Reichweite ausgenutzt haben, um tats\u00e4chliche oder potenzielle Konkurrenten aufzukaufen oder sie zu hindern. Infolgedessen h\u00e4tten Werbetreibende und Webseiten kaum eine andere Wahl, als Google-Dienste zu nutzen.<\/p>\n<blockquote>\n<p><em>&#8220;Google hat sinnvollen Wettbewerb vereitelt und Innovationen in der digitalen Werbeindustrie behindert sowie wettbewerbs\u00fcbersteigende Gewinne gesammelt und ein faires Funktionieren des freien Markts verhindert, statt die Interessen der Werbetreibenden und Publisher zu unterst\u00fctzen, die das leistungsf\u00e4hige Internet heute m\u00f6glich machen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Google argumentiert, dass die Regierung versuche, Gewinner und Verlierer im hart umk\u00e4mpften Online-Werbegesch\u00e4ft zu bestimmen. In einer Erkl\u00e4rung betont das Unternehmen, dass das Justizministerium mit seinen fehlerhaften Argumenten weitgehend eine \u00e4hnliche Klage aus dem Bundesstaat Texas kopiere, die k\u00fcrzlich von einem Bundesgericht abgewiesen worden sei. Acht Bundesstaaten, darunter auch Googles Heimatstaat Kalifornien, schlossen sich der Regierung an. Der Generalstaatsanwalt des Bundesstaats Colorado Phil Weiser meint, man ergreife mit dieser Klage Ma\u00dfnahmen gegen das Monopol von Google und stelle den Wettbewerb im digitalen Werbegesch\u00e4ft wieder her.<\/p>\n<p>Im Jahr 2020 hatte die Regierung unter Ex-Pr\u00e4sident Donald Trump ebenfalls eine Kartellklage gegen Google eingereicht. Der Fall soll sp\u00e4ter in diesem Jahr vor Gericht verhandelt werden.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/wirtschaft\/160647-it-flucht-tech-giganten-verlagern-produktion\/\">IT-Flucht: Tech-Giganten verlagern ihre Produktion aus China in andere asiatische L\u00e4nder<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/nordamerika\/160935-us-regierung-wirft-google-monopolisierung\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die US-Regierung zieht Google vor Gericht. Laut der Klageschrift des Justizministeriums hat der IT-Konzern seine Dominanz im Bereich Online-Werbung missbraucht und einen gesunden Wettbewerb behindert. Google erkl\u00e4rt, dass der Staat Gewinner und Verlierer nicht bestimmen kann. Am Dienstag hat das US-Justizministerium eine Kartellklage gegen Google vor dem Bundesbezirksgericht in Alexandria im Bundesstaat Virginia eingereicht. Die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1674646224"],"wp_automatic_camp":["217"],"53d480af296e52e3db52a483e78d1d9e":["US-Regierung wirft Google Monopolisierung von Online-Werbung vor"],"original_link":["https:\/\/de.rt.com\/nordamerika\/160935-us-regierung-wirft-google-monopolisierung\/"],"_thumbnail_id":["28595"],"jnews_social_counter_last_update":["1783956747"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-01-25 13:31:25\";}"]},"categories":[19,23],"tags":[7556,39611,39612,13980,50,320,7129],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US-Regierung wirft Google Monopolisierung von Online-Werbung vor - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US-Regierung wirft Google Monopolisierung von Online-Werbung vor\" \/>\n<meta property=\"og:description\" content=\"Die US-Regierung zieht Google vor Gericht. Laut der Klageschrift des Justizministeriums hat der IT-Konzern seine Dominanz im Bereich Online-Werbung missbraucht und einen gesunden Wettbewerb behindert. Google erkl\u00e4rt, dass der Staat Gewinner und Verlierer nicht bestimmen kann. Am Dienstag hat das US-Justizministerium eine Kartellklage gegen Google vor dem Bundesbezirksgericht in Alexandria im Bundesstaat Virginia eingereicht. Die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-25T11:26:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"US-Regierung wirft Google Monopolisierung von Online-Werbung vor\",\"datePublished\":\"2023-01-25T11:26:34+00:00\",\"dateModified\":\"2023-01-25T11:26:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/\"},\"wordCount\":357,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg\",\"keywords\":[\"google\",\"Monopolisierung\",\"OnlineWerbung\",\"USRegierung\",\"von\",\"vor\",\"wirft\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/\",\"name\":\"US-Regierung wirft Google Monopolisierung von Online-Werbung vor - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg\",\"datePublished\":\"2023-01-25T11:26:34+00:00\",\"dateModified\":\"2023-01-25T11:26:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg\",\"width\":460,\"height\":259,\"caption\":\"US-Regierung wirft Google Monopolisierung von Online-Werbung vor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US-Regierung wirft Google Monopolisierung von Online-Werbung vor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US-Regierung wirft Google Monopolisierung von Online-Werbung vor - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/","og_locale":"de_DE","og_type":"article","og_title":"US-Regierung wirft Google Monopolisierung von Online-Werbung vor","og_description":"Die US-Regierung zieht Google vor Gericht. Laut der Klageschrift des Justizministeriums hat der IT-Konzern seine Dominanz im Bereich Online-Werbung missbraucht und einen gesunden Wettbewerb behindert. Google erkl\u00e4rt, dass der Staat Gewinner und Verlierer nicht bestimmen kann. Am Dienstag hat das US-Justizministerium eine Kartellklage gegen Google vor dem Bundesbezirksgericht in Alexandria im Bundesstaat Virginia eingereicht. Die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-01-25T11:26:34+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"US-Regierung wirft Google Monopolisierung von Online-Werbung vor","datePublished":"2023-01-25T11:26:34+00:00","dateModified":"2023-01-25T11:26:34+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/"},"wordCount":357,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg","keywords":["google","Monopolisierung","OnlineWerbung","USRegierung","von","vor","wirft"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/","url":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/","name":"US-Regierung wirft Google Monopolisierung von Online-Werbung vor - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg","datePublished":"2023-01-25T11:26:34+00:00","dateModified":"2023-01-25T11:26:34+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/US-Regierung-wirft-Google-Monopolisierung-von-Online-Werbung-vor.jpg","width":460,"height":259,"caption":"US-Regierung wirft Google Monopolisierung von Online-Werbung vor"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/us-regierung-wirft-google-monopolisierung-von-online-werbung-vor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"US-Regierung wirft Google Monopolisierung von Online-Werbung vor"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/28594"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=28594"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/28594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/28595"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=28594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=28594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=28594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}