{"id":27701,"date":"2023-01-14T07:30:00","date_gmt":"2023-01-14T05:30:00","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/"},"modified":"2023-01-14T07:30:00","modified_gmt":"2023-01-14T05:30:00","slug":"iran-will-kraftwerke-im-libanon-bauen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/","title":{"rendered":"Iran will Kraftwerke im Libanon bauen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63c19517b480cc648624ac18.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Angesichts der anhaltenden wirtschaftlichen und sozialen Krise im Libanon erkl\u00e4rte der iranische Au\u00dfenminister die Bereitschaft Irans, dem Land zu helfen. Er kommentierte zudem aktuelle diplomatische Vorg\u00e4nge im Nahen Osten.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Auf einer gemeinsamen Pressekonferenz mit seinem libanesischen Amtskollegen Abdallah Bou Habib am Freitag in Beirut hat der iranische Au\u00dfenminister Hossein Amir-Abdollahian erkl\u00e4rt, beide Seiten h\u00e4tten M\u00f6glichkeiten zur F\u00f6rderung der Zusammenarbeit in den Bereichen Handel, Wirtschaft und Tourismus im Einklang mit der Entwicklung und dem Fortschritt der beiden L\u00e4nder erkundet, berichtete die iranische Nachrichtenagentur <em>Tasnim<\/em>.<\/p>\n<p>Der iranische Au\u00dfenminister wies darauf hin, dass Iran \u00fcber erstklassige technologische Kapazit\u00e4ten verf\u00fcge und bereit sei, die vom Libanon ben\u00f6tigten Kraftwerke im Rahmen eines noch abzuschlie\u00dfenden Abkommens zu errichten.<\/p>\n<p>Amir-Abdollahian wies auf ein Abkommen hin, das w\u00e4hrend seines letzten Besuchs im Libanon unterzeichnet wurde, um das Leid der libanesischen Bev\u00f6lkerung und den auf ihm lastenden wirtschaftlichen Druck zu lindern, und sagte, dass bei der Umsetzung des Abkommens Fortschritte erzielt worden seien.<\/p>\n<p>Ein technisches Team aus dem Libanon sei nach Iran gereist, um die Pl\u00e4ne f\u00fcr die Zusammenarbeit und die Lieferung des vom Libanon ben\u00f6tigten Treibstoffs zu pr\u00fcfen, erkl\u00e4rte er. Der iranische Spitzendiplomat f\u00fcgte hinzu:<\/p>\n<blockquote>\n<p><em>&#8220;Wir sind bereit, unsere Verpflichtungen im Rahmen dieses Abkommens einzuhalten, um den Libanon stark zu unterst\u00fctzen. Wir betrachten die Sicherheit und den Fortschritt des Libanon als Sicherheit und Fortschritt f\u00fcr Iran und f\u00fcr die Region.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Zudem bekr\u00e4ftigte er:<\/p>\n<blockquote>\n<p><em>&#8220;Die Islamische Republik Iran wird auch weiterhin den Widerstand im Libanon und in Pal\u00e4stina gegen die Drohungen und Angriffe des zionistischen Regimes nach Kr\u00e4ften unterst\u00fctzen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Zur Lage im Libanon sagte Amir-Abdollahian:<\/p>\n<blockquote>\n<p><em>&#8220;Wir fordern alle politischen Str\u00f6mungen des Libanon auf, im Rahmen eines Dialogs einen Pr\u00e4sidenten zu w\u00e4hlen. Wir glauben, dass die politischen Str\u00f6mungen im Libanon \u00fcber die n\u00f6tige Erfahrung und Kompetenz verf\u00fcgen, um in k\u00fcrzester Zeit einen Pr\u00e4sidenten zu w\u00e4hlen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die Gespr\u00e4chen zwischen Syrien und der T\u00fcrkei kommentierte der iranische Diplomat folgenderma\u00dfen:<\/p>\n<blockquote>\n<p><em>&#8220;Wir freuen uns \u00fcber die Verhandlungen zwischen syrischen und t\u00fcrkischen Vertretern und begr\u00fc\u00dfen den Weg der Verhandlungen und des Dialogs zur L\u00f6sung der Probleme zwischen diesen beiden L\u00e4ndern.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Er betonte auch die Notwendigkeit, das Astana-Format mit dem Engagement Syriens zu st\u00e4rken, um sich st\u00e4rker auf politische L\u00f6sungen zwischen Ankara und Damaskus zu konzentrieren.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/der-nahe-osten\/158341-syrien-und-libanon-schicksalsgemeinschaft\/\">Syrien und der Libanon \u2013 eine Schicksalsgemeinschaft<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/der-nahe-osten\/159805-iran-will-kraftwerke-im-libanon\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angesichts der anhaltenden wirtschaftlichen und sozialen Krise im Libanon erkl\u00e4rte der iranische Au\u00dfenminister die Bereitschaft Irans, dem Land zu helfen. Er kommentierte zudem aktuelle diplomatische Vorg\u00e4nge im Nahen Osten. Auf einer gemeinsamen Pressekonferenz mit seinem libanesischen Amtskollegen Abdallah Bou Habib am Freitag in Beirut hat der iranische Au\u00dfenminister Hossein Amir-Abdollahian erkl\u00e4rt, beide Seiten h\u00e4tten M\u00f6glichkeiten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":27702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1673679059"],"wp_automatic_camp":["217"],"162ea05db6d15bed77052a769b4cd0aa":["Iran will Kraftwerke im Libanon bauen"],"original_link":["https:\/\/de.rt.com\/der-nahe-osten\/159805-iran-will-kraftwerke-im-libanon\/"],"_thumbnail_id":["27702"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-01-14 08:52:09\";}"],"jnews_social_counter_last_update":["1784113978"]},"categories":[19,23],"tags":[5644,1786,35252,16906],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iran will Kraftwerke im Libanon bauen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iran will Kraftwerke im Libanon bauen\" \/>\n<meta property=\"og:description\" content=\"Angesichts der anhaltenden wirtschaftlichen und sozialen Krise im Libanon erkl\u00e4rte der iranische Au\u00dfenminister die Bereitschaft Irans, dem Land zu helfen. Er kommentierte zudem aktuelle diplomatische Vorg\u00e4nge im Nahen Osten. Auf einer gemeinsamen Pressekonferenz mit seinem libanesischen Amtskollegen Abdallah Bou Habib am Freitag in Beirut hat der iranische Au\u00dfenminister Hossein Amir-Abdollahian erkl\u00e4rt, beide Seiten h\u00e4tten M\u00f6glichkeiten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-14T05:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Iran will Kraftwerke im Libanon bauen\",\"datePublished\":\"2023-01-14T05:30:00+00:00\",\"dateModified\":\"2023-01-14T05:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg\",\"keywords\":[\"bauen\",\"Iran\",\"Kraftwerke\",\"Libanon\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/\",\"name\":\"Iran will Kraftwerke im Libanon bauen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg\",\"datePublished\":\"2023-01-14T05:30:00+00:00\",\"dateModified\":\"2023-01-14T05:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Iran will Kraftwerke im Libanon bauen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iran will Kraftwerke im Libanon bauen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Iran will Kraftwerke im Libanon bauen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/","og_locale":"de_DE","og_type":"article","og_title":"Iran will Kraftwerke im Libanon bauen","og_description":"Angesichts der anhaltenden wirtschaftlichen und sozialen Krise im Libanon erkl\u00e4rte der iranische Au\u00dfenminister die Bereitschaft Irans, dem Land zu helfen. Er kommentierte zudem aktuelle diplomatische Vorg\u00e4nge im Nahen Osten. Auf einer gemeinsamen Pressekonferenz mit seinem libanesischen Amtskollegen Abdallah Bou Habib am Freitag in Beirut hat der iranische Au\u00dfenminister Hossein Amir-Abdollahian erkl\u00e4rt, beide Seiten h\u00e4tten M\u00f6glichkeiten [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-01-14T05:30:00+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Iran will Kraftwerke im Libanon bauen","datePublished":"2023-01-14T05:30:00+00:00","dateModified":"2023-01-14T05:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg","keywords":["bauen","Iran","Kraftwerke","Libanon"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/","url":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/","name":"Iran will Kraftwerke im Libanon bauen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg","datePublished":"2023-01-14T05:30:00+00:00","dateModified":"2023-01-14T05:30:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Iran-will-Kraftwerke-im-Libanon-bauen.jpg","width":460,"height":259,"caption":"Iran will Kraftwerke im Libanon bauen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/iran-will-kraftwerke-im-libanon-bauen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Iran will Kraftwerke im Libanon bauen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/27701"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=27701"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/27701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/27702"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=27701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=27701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=27701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}