{"id":27695,"date":"2023-01-14T07:24:01","date_gmt":"2023-01-14T05:24:01","guid":{"rendered":"http:\/\/just-now.news\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/"},"modified":"2023-01-14T07:24:01","modified_gmt":"2023-01-14T05:24:01","slug":"biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/","title":{"rendered":"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider"},"content":{"rendered":"<div>\n<p><em>Nachrichtenanalyse<\/em><\/p>\n<p>Laut dem Pr\u00e4sidenten eines High-Tech-Unternehmens in Japan k\u00f6nnten Chinas Biotechnologie- und saubere Energiesektoren die n\u00e4chsten Ziele von US-Sanktionen sein.<\/p>\n<p>Solche Sektoren werden nach Chinas schwer getroffener Halbleiterindustrie wahrscheinlich einen Abschwung erleben, sagte der Pr\u00e4sident, der aus Sicherheitsgr\u00fcnden nur als Desen identifiziert werden wollte, am 5. Januar gegen\u00fcber The Epoch Times.<\/p>\n<p><span style=\"color: #000000;\">Diese Sektoren werden b<\/span>Wir stagnieren, da die technologische Entkopplung zwischen den USA und China anh\u00e4lt, sagte Desen.<\/p>\n<p>W\u00e4hrend dieses Prozesses w\u00fcrden chinesische Unternehmen in diesen Bereichen die Grundlage verlieren, auf der sie lernen und nachahmen k\u00f6nnen.<\/p>\n<p>Die breitere wirtschaftliche Entkoppelung beschleunige auch den Abfluss internationalen Kapitals aus China, sagte er und f\u00fcgte hinzu, dass dies weiteren Druck auf die Wirtschaft aus\u00fcben werde.<\/p>\n<p>Die Abkoppelung von den Vereinigten Staaten wird sich auf Chinas billige Rohstoffe auswirken, da sie ihren Hauptmarkt verlieren werden.  Fabriken f\u00fcr neue Energiebatterien m\u00fcssen beispielsweise ihre Produktionskapazit\u00e4t verringern.<\/p>\n<p>Es wird zu einer Situation, in der kleine und mittelst\u00e4ndische Unternehmen mit dem \u00dcberlebensrisiko konfrontiert werden und m\u00f6glicherweise \u00fcbernommen werden.  Gro\u00dfe Unternehmen werden den Anreiz verlieren, die Produktion auszuweiten, sagte Desen.<\/p>\n<figure id=\"attachment_4980806\" style=\"width: 600px\" class=\"wp-caption alignnone\"> Ein Techniker verarbeitet Proben in einem Labor des chinesischen Biotech-Unternehmens Coyote, bevor er sie am 27. September 2020 in Peking im Flash 20 testet, einer Maschine, die als Schnelltest f\u00fcr das COVID-19-Coronavirus entwickelt wurde. (Greg Baker\/AFP via Getty Images)<\/figure>\n<h2><strong>Saubere Energie, neue Energietechnologie<\/strong><\/h2>\n<p>China macht einen gro\u00dfen Teil des globalen Marktes f\u00fcr saubere Energie und neue Energiefahrzeuge aus.<\/p>\n<p>Chinesische Staatsmedien haben behauptet, dass Chinas Produktion und Verkaufsvolumen von neuen Energiefahrzeugen seit 2015 weltweit an erster Stelle stehen. Cui Dongshu, Generalsekret\u00e4r der China Passenger Car Association (CPCA), sagte im August 2022: \u201eChina hat sein Ziel im Wesentlichen erreicht die Welt mit neuen Energiefahrzeugen zu \u00fcberholen\u201c, so CCTV.<\/p>\n<p>Aber die angepriesenen Aussichten f\u00fcr saubere Energie und neue Energiefahrzeuge in China k\u00f6nnten laut Desen nicht so vielversprechend sein.<\/p>\n<p>Chinesische Chip-Designlinien boomten, bevor sie von den Vereinigten Staaten sanktioniert wurden.  Im Jahr 2018 belegte Huaweis Chipfabrik Hisilicon beispielsweise den f\u00fcnften Platz in der Liste der 10 weltweit f\u00fchrenden Designunternehmen f\u00fcr integrierte Schaltkreise (IC), aber nachdem Huawei 2019 in die US-Unternehmensliste aufgenommen wurde, strichen Intel, Qualcomm und Xilinx ihre Gesch\u00e4fte mit Huawei ist Hisilicon inzwischen aus den Top 10 gefallen, schwindende Produktionswerte.<\/p>\n<p>Ab 2022 hat die US-amerikanische Biden-Regierung die Sanktionen gegen Chinas Halbleiterindustrie versch\u00e4rft.  Infolgedessen hat sich die Wachstumsrate der Zahl der chinesischen Halbleiterdesignunternehmen verlangsamt.<\/p>\n<p>Der nationale Sicherheitsberater der USA, Jake Sullivan, \u00e4u\u00dferte am 16. September 2022 Bedenken hinsichtlich Biotechnologie und sauberer Energietechnologie.<\/p>\n<p>Sullivan sagte, dass drei Technologiebereiche im n\u00e4chsten Jahrzehnt besonders wichtig sein w\u00fcrden.  Diese drei Technologiebereiche sind computerbezogene Technologien, einschlie\u00dflich Mikroelektronik, Quanteninformationssysteme und k\u00fcnstliche Intelligenz;  gefolgt von Biotechnologie und Bioherstellung;  und schlie\u00dflich saubere Energietechnologien.<\/p>\n<p>Desen glaubt, dass dies ein Zeichen daf\u00fcr sein k\u00f6nnte, dass sich die USA auf der Ebene der nationalen Sicherheit neben der Halbleitertechnologie auf High-End-Technologien in Biotechnologie und sauberer Energie konzentrieren.<\/p>\n<figure id=\"attachment_4980813\" style=\"width: 640px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy wp-image-4980813 size-large\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675419_593_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg\" alt=\"Epoch Times Foto\" width=\"640\" height=\"427\"> Arbeiter \u00fcberpr\u00fcfen am 19. November 2018 Laptop-Teile in einer Fabrik im Autoindustriepark Hangyong in der Stadt Lu&#8217;an in der chinesischen Provinz Anhui. (STR\/AFP via Getty Images)<\/figure>\n<h2><strong>Chinesische Chipindustrie<\/strong><\/h2>\n<p>Am 7. Oktober 2022 k\u00fcndigte die US-Regierung eine Reihe von Exportkontrollen an, die US-Unternehmen nicht nur verbieten, fortschrittliche Chips und Technologien nach China zu exportieren, sondern auch die Lieferung bestimmter Halbleiterchips, die mit US-Ausr\u00fcstung und -Werkzeugen hergestellt wurden, nach China verbieten, unabh\u00e4ngig davon ihren Ursprung in den Vereinigten Staaten.<\/p>\n<p>Die Exportkontrollen gelten seit den 1990er Jahren als gr\u00f6\u00dfter Politikwechsel bei US-Technologieexporten an die Kommunistische Partei Chinas (KPCh) und gelten als die umfassendsten und strengsten Exportkontrollma\u00dfnahmen.<\/p>\n<p>Wei Shaojun, Vorsitzender der IC-Design-Zweigstelle der China Semiconductor Industry Association, sagte in einer Rede auf einem Gipfel zum Design integrierter Schaltkreise am 26. Dezember 2022, dass die Sanktionen gegen Chinas Halbleiterindustrie \u201eimmer strenger werden\u201c. dass \u201eman angesichts des harten \u00e4u\u00dferen Umfelds nicht blind optimistisch sein sollte, alles tun zu k\u00f6nnen.\u201c<\/p>\n<p>Wei ist eine f\u00fchrende Pers\u00f6nlichkeit in Chinas Halbleiterindustrie und Professor am Institut f\u00fcr Mikro- und Nanoelektronik der Tsinghua-Universit\u00e4t, wo er seit langem an der Forschung und Entwicklung in der IC-Designtechnologie beteiligt ist.<\/p>\n<p>Dar\u00fcber hinaus setzte das US-Handelsministerium am 15. Dezember 2022 36 Technologieunternehmen und Einrichtungen mit Verbindungen zur KPCh auf die schwarze Liste, darunter Shanghai Micro Electronics Equipment (SMEE), ein f\u00fchrendes Unternehmen in Chinas Lithografieindustrie.<\/p>\n<p>In Bezug auf den aktuellen Stand der technologischen Entkopplung zwischen den USA und China und ihre Auswirkungen auf die Zukunft ver\u00f6ffentlichte das Institut f\u00fcr internationale strategische Studien der Peking-Universit\u00e4t am 31. Januar 2022 auf seiner offiziellen Website einen Forschungsbericht, in dem er zu dem Schluss kam, dass die Entkopplung zu Verlusten f\u00fcr f\u00fchren w\u00fcrde beide Seiten.  Der Bericht f\u00fcgte jedoch hinzu, dass Chinas Verluste erheblich gr\u00f6\u00dfer sein w\u00fcrden als die der Vereinigten Staaten und dass China bei einigen wichtigen technologischen Entwicklungen in einen Engpass geraten k\u00f6nnte, was einen Durchbruch erschweren w\u00fcrde.<\/p>\n<p>Laut einem Bericht von VOA vom 4. Februar 2022 war der Bericht nur wenige Tage online, bis er entfernt wurde.<\/p>\n<p>Der US-Mainstream wird eine h\u00e4rtere Haltung gegen\u00fcber China einnehmen, wenn er erkennt, dass die KPCh, sobald sie wirtschaftlich anschwillt, zu einer tickenden Zeitbombe f\u00fcr das Problem der Taiwanstra\u00dfe und zu einer wachsenden Bedrohung f\u00fcr den Rest der Welt werden wird, zitierte Desen der Versuch der KPCh, die Nation von universellen Werten wegzuf\u00fchren.<\/p>\n<p><em>Ellen Wan hat zu diesem Artikel beigetragen.<\/em><\/p>\n<\/div>\n<p><br \/>\n<b> Text ist eine \u00dcbersetzung vom Epoch Times Artikel:<\/p>\n<p><a href=\"https:\/\/www.theepochtimes.com\/biotech-clean-energy-sectors-in-china-face-uncertain-future-insider-says_4980756.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachrichtenanalyse Laut dem Pr\u00e4sidenten eines High-Tech-Unternehmens in Japan k\u00f6nnten Chinas Biotechnologie- und saubere Energiesektoren die n\u00e4chsten Ziele von US-Sanktionen sein. Solche Sektoren werden nach Chinas schwer getroffener Halbleiterindustrie wahrscheinlich einen Abschwung erleben, sagte der Pr\u00e4sident, der aus Sicherheitsgr\u00fcnden nur als Desen identifiziert werden wollte, am 5. Januar gegen\u00fcber The Epoch Times. Diese Sektoren werden bWir [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":27696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1673675420"],"wp_automatic_camp":["1164"],"6d151aaf3db9c57998088b13c1d05068":["Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider\n"],"original_link":["https:\/\/www.theepochtimes.com\/biotech-clean-energy-sectors-in-china-face-uncertain-future-insider-says_4980756.html"],"_thumbnail_id":["27696"],"wp_automatic_remove_first_image":["yes"],"_wptgpro_p2tg_sent2tg":["a:0:{}"],"jnews_social_counter_last_update":["1778341522"]},"categories":[21],"tags":[39033,192,212,39034,17549,3564,22901,2198,140,39035,320,3250],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider\" \/>\n<meta property=\"og:description\" content=\"Nachrichtenanalyse Laut dem Pr\u00e4sidenten eines High-Tech-Unternehmens in Japan k\u00f6nnten Chinas Biotechnologie- und saubere Energiesektoren die n\u00e4chsten Ziele von US-Sanktionen sein. Solche Sektoren werden nach Chinas schwer getroffener Halbleiterindustrie wahrscheinlich einen Abschwung erleben, sagte der Pr\u00e4sident, der aus Sicherheitsgr\u00fcnden nur als Desen identifiziert werden wollte, am 5. Januar gegen\u00fcber The Epoch Times. Diese Sektoren werden bWir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-14T05:24:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"epoch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"epoch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/\"},\"author\":{\"name\":\"epoch\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f\"},\"headline\":\"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider\",\"datePublished\":\"2023-01-14T05:24:01+00:00\",\"dateModified\":\"2023-01-14T05:24:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/\"},\"wordCount\":921,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg\",\"keywords\":[\"Biotech\",\"China\",\"einer\",\"Energiesektoren\",\"Insider\",\"sagt\",\"saubere\",\"stehen\",\"und\",\"ungewissen\",\"vor\",\"Zukunft\"],\"articleSection\":[\"China\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/\",\"url\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/\",\"name\":\"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg\",\"datePublished\":\"2023-01-14T05:24:01+00:00\",\"dateModified\":\"2023-01-14T05:24:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg\",\"width\":1200,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f\",\"name\":\"epoch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g\",\"caption\":\"epoch\"},\"url\":\"https:\/\/now-news.de\/de\/author\/epoch\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/","og_locale":"de_DE","og_type":"article","og_title":"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider","og_description":"Nachrichtenanalyse Laut dem Pr\u00e4sidenten eines High-Tech-Unternehmens in Japan k\u00f6nnten Chinas Biotechnologie- und saubere Energiesektoren die n\u00e4chsten Ziele von US-Sanktionen sein. Solche Sektoren werden nach Chinas schwer getroffener Halbleiterindustrie wahrscheinlich einen Abschwung erleben, sagte der Pr\u00e4sident, der aus Sicherheitsgr\u00fcnden nur als Desen identifiziert werden wollte, am 5. Januar gegen\u00fcber The Epoch Times. Diese Sektoren werden bWir [&hellip;]","og_url":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-01-14T05:24:01+00:00","og_image":[{"width":1200,"height":786,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg","type":"image\/jpeg"}],"author":"epoch","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"epoch","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/"},"author":{"name":"epoch","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f"},"headline":"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider","datePublished":"2023-01-14T05:24:01+00:00","dateModified":"2023-01-14T05:24:01+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/"},"wordCount":921,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg","keywords":["Biotech","China","einer","Energiesektoren","Insider","sagt","saubere","stehen","und","ungewissen","vor","Zukunft"],"articleSection":["China"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/","url":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/","name":"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg","datePublished":"2023-01-14T05:24:01+00:00","dateModified":"2023-01-14T05:24:01+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/1673675420_Biotech-und-saubere-Energiesektoren-in-China-stehen-vor-einer-ungewissen.jpg","width":1200,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/china\/biotech-und-saubere-energiesektoren-in-china-stehen-vor-einer-ungewissen-zukunft-sagt-insider\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Biotech und saubere Energiesektoren in China stehen vor einer ungewissen Zukunft, sagt Insider"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f","name":"epoch","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g","caption":"epoch"},"url":"https:\/\/now-news.de\/de\/author\/epoch\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/27695"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=27695"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/27695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/27696"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=27695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=27695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=27695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}