{"id":27483,"date":"2023-01-12T08:30:00","date_gmt":"2023-01-12T06:30:00","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/"},"modified":"2023-01-12T08:30:00","modified_gmt":"2023-01-12T06:30:00","slug":"liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/","title":{"rendered":"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab"},"content":{"rendered":"<div class=\"Text-root Text-type_1 \">\n                Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Lesen Sie hier die neuesten Entwicklungen.\n            <\/div>\n<p><\/p>\n<div class=\"ArticleView-liveUpdates\">\n<div class=\"LiveUpdates-root\">\n<div class=\"LiveUpdates-content\">\n<ul class=\"LiveUpdates-list Listing-root\" data-listing=\"LiveUpdates\" data-count=\"10\">\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdates-date\">\n<p class=\"HeaderNews-root HeaderNews-type_2 \">\n                12.01.2023 07:29 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                07:29 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Medienbericht: Scholz&#8217; Position zu Waffenlieferungen an die Ukraine stark von Biden abh\u00e4ngig<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf9ecd48fbef484e234484.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf9ecd48fbef484e234484.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf9ecd48fbef484e234484.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf9ecd48fbef484e234484.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf9ecd48fbef484e234484.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf9ecd48fbef484e234484.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Arcchivbild: US-Pr\u00e4sident Joe Biden und Bundeskanzler Olaf Scholz<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Clemens Bilan &#8211; Pool<\/span><span class=\"RTImage-captionItem\"> \/ Gettyimages.ru<\/span><\/span><\/figcaption><\/figure>\n<p>Die Haltung von Bundeskanzler Olaf Scholz zu Waffenlieferungen an die Ukraine h\u00e4ngt stark von US-Pr\u00e4sident Joe Biden ab, berichtet <em>Politico<\/em> unter Berufung auf zwei Beamte in deutschen Regierungskreisen.<\/p>\n<p>Scholz&#8217; habe seine Position \u00fcber Waffenlieferungen an die Ukraine vergangene Woche im Rahmen einer gemeinsamen Erkl\u00e4rung \u00fcber die Lieferung von Sch\u00fctzenpanzern aus Deutschland und den USA an die Ukraine mit Biden eng abgestimmt, sollen die deutschen Beamten <em>Politico<\/em> mitgeteilt haben.<\/p>\n<p>Auf einer Wahlkampfveranstaltung in Berlin hatte Scholz am Montag betont, wie wichtig es sei, mit dem US-Pr\u00e4sidenten \u00fcber Waffenlieferungen zu sprechen. Panzerlieferungen an die Ukraine m\u00fcssten &#8220;gemeinsam mit Freunden und Verb\u00fcndeten und vor allem mit unserem transatlantischen Partner, den Vereinigten Staaten von Amerika&#8221;, diskutiert werden, so der Bundeskanzler.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                07:04 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Ukrainische Soldaten beschie\u00dfen Makejewka in der Nacht<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf99a548fbef486e786ebd.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf99a548fbef486e786ebd.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf99a548fbef486e786ebd.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf99a548fbef486e786ebd.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf99a548fbef486e786ebd.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf99a548fbef486e786ebd.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Archivbild: Bruchst\u00fccke eines Geschosses der ukrainischen Streitkr\u00e4fte in der Stadt Makejewka am 6. Dezember 2022<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Sergei Baturin<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p>In der Nacht haben ukrainische Streitkr\u00e4fte drei Raketen aus einem Mehrfachraketenwerfer auf Makejewka in der Donezker Volksrepublik (DVR) abgefeuert. Dies <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/online_dnr_sckk\/20926\">teilt<\/a> die Vertretung der Volksrepublik beim Gemeinsamen Zentrum f\u00fcr die Kontrolle und Koordinierung von Kriegsverbrechen in der Ukraine am Donnerstagmorgen mit. Makejewka grenzt im Nordosten an Donezk.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdates-date\">\n<p class=\"HeaderNews-root HeaderNews-type_2 \">\n                11.01.2023 22:00 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                22:00 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p>Damit beenden wir f\u00fcr heute den Live-Ticker zur Lage im Ukraine-Konflikt. Morgen fr\u00fch ab 7 Uhr geht es mit der Berichterstattung weiter. Wir w\u00fcnschen unseren Lesern trotz aller Spannungen in der Welt eine gute Nacht!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                21:58 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Leiche eines der beiden in Soledar vermissten Briten gefunden<\/strong><\/p>\n<p>Der Pressedienst von Jewgeni Prigoschin, Leiter der Wagner-Gruppe, berichtet, dass die Leiche eines der beiden in Soledar vermissten Briten gefunden wurde. Bei dem Verstorbenen wurden Dokumente f\u00fcr beide vermissten M\u00e4nner gefunden. Ein Antrag auf Suche nach den beiden vermissten Briten in Soledar wurde am 8. Januar bei der &#8216;Ask Wagner&#8217;-Hotline gestellt. Die Nachricht des Pressedienstes <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/concordgroup_official\/263\">lautet<\/a>:<strong><\/strong><\/p>\n<p><em>&#8220;Am 8. Januar ging bei der Hotline &#8216;Ask Wagner&#8217; eine Anfrage zur Suche der beiden britischen Staatsb\u00fcrger Andrew Bagshaw und Christopher Parry ein, die seit dem 6. Januar in Soledar vermisst werden. Heute wurde die Leiche eines von ihnen gefunden, und bei ihm wurden die Dokumente der beiden Briten gefunden.&#8221;<\/em><\/p>\n<p>Am Montag hatte die Nationale Polizei der Ukraine mitgeteilt, dass die beiden britischen Staatsb\u00fcrger Andrew Bagshaw und Christopher Parry in der N\u00e4he von Soledar vermisst werden. Medienberichten zufolge waren die beiden Briten seit Freitag nicht auffindbar. Das britische Au\u00dfenministerium erkl\u00e4rte, es unterst\u00fctze die Familien der Vermissten.<em><\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                21:41 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Selenskij fordert, Ukrainern mit russischen P\u00e4ssen Staatsb\u00fcrgerschaft zu entziehen<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf1aa748fbef4896454597.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf1aa648fbef4896454596.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf1aa748fbef4896454597.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf1aa648fbef4896454596.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf1aa748fbef4896454597.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf1aa648fbef4896454596.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Archivbild: Der ukrainische Pr\u00e4sident Wladimir Selenskij<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Metin Aktas\/Anadolu Agency<\/span><span class=\"RTImage-captionItem\"> \/ Gettyimages.ru<\/span><\/span><\/figcaption><\/figure>\n<p>Ukrainern mit russischen P\u00e4ssen solle die Staatsb\u00fcrgerschaft entzogen werden, sagte der ukrainische Pr\u00e4sident Wladimir Selenskij bei einem Briefing in Lwow, von dem das Pr\u00e4sidialamt ein Video auf seinem Telegram-Kanal <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/OP_UA\/8541\">ver\u00f6ffentlichte<\/a>. Er behauptet:<strong><\/strong><\/p>\n<p><em>&#8220;Unsere Aufgabe ist es, dass alle Menschen, die eine doppelte oder dreifache Staatsb\u00fcrgerschaft haben, einschlie\u00dflich der russischen Staatsb\u00fcrgerschaft, die geistigen oder politischen Einfluss auf unser Land haben, alle diese Menschen sollten unbedingt mit nur einer Staatsb\u00fcrgerschaft, der russischen Staatsb\u00fcrgerschaft, bleiben und in dem jeweiligen Staat leben.&#8221;<\/em><\/p>\n<p>Am Vortag hatte Selenskij den Entzug der ukrainischen Staatsb\u00fcrgerschaft f\u00fcr die Abgeordneten der verbotenen Oppositionspartei Plattform\u00a0\u2013 F\u00fcr das Leben, Wiktor Medwedtschuk, Andrei Derkatsch, Taras Kosak und Renat Kusmin bef\u00fcrwortet. Er stellte fest, dass dies nicht die letzten Entscheidungen dieser Art waren.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                21:20 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Medwedew: Leopard und T-72 werden auseinanderfallende Ukraine nicht retten<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf152848fbef486e786e9a.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf152848fbef486e786e99.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf152848fbef486e786e9a.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf152848fbef486e786e99.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf152848fbef486e786e9a.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf152848fbef486e786e99.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Archivbild: Der ehemalige russische Pr\u00e4sident Dmitri Medwedew<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Pressedienst des russischen Pr\u00e4sidenten<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p>Die aufger\u00fcsteten T-72- oder Leopard-Panzer, die an die Ukraine geliefert werden, werden bald zu rostigem Schrott und k\u00f6nnen ein &#8220;k\u00fcnstliches Land&#8221;, das auseinanderfalle, nicht retten, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/medvedev_telegram\/247\">schrieb<\/a> der ehemalige russische Pr\u00e4sident Dmitri Medwedew.<\/p>\n<p>Er erw\u00e4hnte, dass Wladimir Selenskij heute in Lwow mit den polnischen und litauischen Pr\u00e4sidenten Andrzej Duda und Gitanas Naus\u0117da zusammengetroffen sei. Medwedew zufolge beten diese &#8220;drei, die unter den imperialen Ambitionen und dem Versagen ihrer L\u00e4nder in der Vergangenheit leiden, wie sich herausstellte, f\u00fcr Panzer&#8221;. Der ehemalige russische Pr\u00e4sident betonte, dass es sich um aufger\u00fcstete T-72, deutsche Leopard sowie einige &#8220;englische Ladenh\u00fcter&#8221; handele. Medwedew schrieb auf seinem Telegram-Kanal:<\/p>\n<p><em>&#8220;All dieses Eisen wird ohnehin bald zu rostigem Schrott werden und ein zerfallendes Kunstland nicht retten.&#8221;<\/em><\/p>\n<p>Er schlug auch vor, dass die Stadt Lwow, in der das Treffen stattfand, bald in Lemberg umbenannt werden soll. Ihm zufolge trafen sich die drei Staatsoberh\u00e4upter dort, um &#8220;die westlichen Gebiete der Ukraine an die neuen (ehemaligen) Herren zu binden&#8221;.<em><\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                20:59 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>&#8220;Unsere Vorr\u00e4te gehen zur Neige&#8221; \u2013 Stoltenberg fordert h\u00f6here Waffenproduktion zur Ukraine-Unterst\u00fctzung<\/strong><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-vk\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/vk.com\/video_ext.php?oid=-134310637&amp;id=456262349&amp;hash=c304b9e4a8e39fba\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Der Generalsekret\u00e4r der NATO, Jens Stoltenberg, die Pr\u00e4sidentin der EU-Kommission, Ursula von der Leyen, und der Pr\u00e4sident des EU-Rates, Charles Michel, haben in Br\u00fcssel eine Erkl\u00e4rung zur St\u00e4rkung der Zusammenarbeit zwischen der NATO und der EU <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/vk.com\/video-134310637_456262349\">unterzeichnet<\/a>.<\/p>\n<p>In dem Dokument zur Erneuerung des Atlantikpakts, der NATO und der Europ\u00e4ischen Union wird der Zustrom von Waffen in die Ukraine best\u00e4tigt und sogar verst\u00e4rkt. Angesichts der drastischen Reduktion der NATO-Arsenale hat Stoltenberg als langfristige L\u00f6sung eine Erh\u00f6hung der Waffenproduktion ins Auge gefasst.<strong><\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                20:48 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>SPD-Fraktionsvorsitzender M\u00fctzenich will Ukraine-Hilfe nicht auf Waffen beschr\u00e4nken<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bee0f4b480cc670f3e21a5.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bee0f4b480cc670f3e21a5.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bee0f4b480cc670f3e21a5.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bee0f4b480cc670f3e21a5.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bee0f4b480cc670f3e21a5.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bee0f4b480cc670f3e21a5.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Archivbild: Rolf M\u00fctzenich gibt eine Pressekonferenz im Bundestag, 13. Dezember 2022.<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">IMAGO \/ Christian Spicker \/ www.imago-images.de<\/span><span class=\"RTImage-captionItem\"> \/ www.globallookpress.com<\/span><\/span><\/figcaption><\/figure>\n<p>Bei der Unterst\u00fctzung der Ukraine will der SPD-Fraktionsvorsitzende Rolf M\u00fctzenich nicht nur \u00fcber Milit\u00e4rhilfe sprechen. Die Diskussion sei verengt, wenn in Deutschland nur \u00fcber einzelne Waffentypen wie den Kampfpanzer Leopard 2 gesprochen werde, sagte M\u00fctzenich am Mittwoch in Bremen.<\/p>\n<p><em>&#8220;Die Bundesregierung hat zusammen mit ihren Partnern viele R\u00fcstungsentscheidungen getroffen, die dem Selbstverteidigungsrecht der Ukraine entgegenkommen.&#8221;<\/em><\/p>\n<p>Die Beratungen mit den Partnerl\u00e4ndern \u00fcber Milit\u00e4rhilfe w\u00fcrden kommende Woche fortgesetzt, sagte der Politiker. Auf der anderen Seite wolle man dazu beitragen, dass einzelne diplomatische Initiativen erfolgreich seien. Als Beispiele nannte M\u00fctzenich den Gefangenenaustausch zwischen der Ukraine und Russland sowie das von den Vereinten Nationen und der T\u00fcrkei vermittelte Getreideabkommen.<\/p>\n<p><em>&#8220;Ich gew\u00f6hne mich manchmal nur schwer daran, dass, wie gesagt, wir allein \u00fcber milit\u00e4risches Ger\u00e4t sprechen und \u00fcber die anderen Facetten dieses Konfliktes zu wenig.&#8221;<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                20:24 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Chef der Gruppe Wagner best\u00e4tigt vollst\u00e4ndige Befreiung Soledars<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf0b6db480cc51ee4c57ac.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf0b6db480cc51ee4c57ab.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf0b6db480cc51ee4c57ac.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf0b6db480cc51ee4c57ab.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf0b6db480cc51ee4c57ac.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bf0b6db480cc51ee4c57ab.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Gr\u00fcnder der Gruppe Wagner Jewgeni Prigoschin mit zwei seiner K\u00e4mpfer in Soledar am 11. Januar 2023<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">RIA Nowosti<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p>Jewgeni Prigoschin, Gr\u00fcnder der Gruppe Wagner, meldet die Befreiung Soledars, wie sein Pressedienst auf Telegram <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/concordgroup_official\/259\">mitteilt<\/a>. Er stellte fest:<strong><\/strong><\/p>\n<p><em>&#8220;Ich m\u00f6chte noch einmal die vollst\u00e4ndige Befreiung und S\u00e4uberung des Gebiets Soledar von Einheiten der ukrainischen Armee best\u00e4tigen.&#8221;<\/em><\/p>\n<p>Laut Prigoschin wurden die Zivilisten aus der Stadt abgezogen.<em><\/em>Er gab auch an, dass russische K\u00e4mpfer 500 ukrainische Soldaten t\u00f6teten, die sich nicht ergeben wollten.<em><\/em><\/p>\n<p>In den vergangenen 24 Stunden gelang es den russischen Streitkr\u00e4ften auch, das Dorf Podgorodnoje bei Soledar unter ihre Kontrolle zu bringen. Die ukrainischen Streitkr\u00e4fte verloren bis zu 80 Soldaten, einen Panzer, drei gepanzerte Kampffahrzeuge und zwei weitere Fahrzeuge.<em><\/em><\/p>\n<p>Soledar ist f\u00fcr Kiew von strategischer Bedeutung, da es im Zentrum der Verteidigungslinie Artjomowsk-Sewersk liegt. Das ukrainische Milit\u00e4r hat hier starke Verteidigungsanlagen errichtet. Die Befreiung Soledars wird den direkten Nachschubweg zwischen Artjomowsk und Sewersk abschneiden und Artjomowsk von Norden her einkreisen.<em><\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                19:58 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>IAEO-Chef hofft auf baldiges Treffen mit Putin<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bef20948fbef489645456b.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bef20848fbef489645456a.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bef20948fbef489645456b.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bef20848fbef489645456a.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bef20948fbef489645456b.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/63bef20848fbef489645456a.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Archivbild: Rafael Grossi, Leiter der Internationalen Atomenergiebeh\u00f6rde<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Konstantin Michaltschewski<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p>Der Leiter der Internationalen Atomenergiebeh\u00f6rde (IAEO), Rafael Grossi, hofft auf ein baldiges Treffen mit dem russischen Pr\u00e4sidenten Wladimir Putin. Auf die Frage des italienischen Nachrichtensenders <em>Rainews24<\/em> nach einem bevorstehenden Treffen mit dem russischen Staatschef sagte Grossi:<strong><\/strong><\/p>\n<p><em>&#8220;Ich erwarte und hoffe, dass ich dies tun werde.&#8221;<\/em><\/p>\n<p>Er erkl\u00e4rte, dass sie sich darauf geeinigt h\u00e4tten, den Dialog \u00fcber die Frage des AKW Saporoschje w\u00e4hrend ihres Herbsttreffens in Sankt Petersburg fortzusetzen. Grossi stellte fest:<\/p>\n<p><em>&#8220;Putin sagte, dass es sich um eine technische Aufgabe handelt, und er ist bereit, sie zu erledigen.&#8221;<\/em><\/p>\n<p>Der IAEO-Chef f\u00fcgte hinzu:<\/p>\n<p><em>&#8220;Wir m\u00fcssen einer L\u00f6sung n\u00e4her kommen. Ich wiederhole, es ist nicht unm\u00f6glich.&#8221;<\/em><\/p>\n<p>In demselben Interview mit dem italienischen Fernsehen sagte Grossi, er werde n\u00e4chste Woche in die Ukraine reisen und danach voraussichtlich Russland besuchen.<em><\/em><\/p>\n<p>Das AKW Saporoschje befindet sich am linken Ufer des Dnjepr in der N\u00e4he der Stadt Energodar. Mit sechs Bl\u00f6cken von je 1 Gigawatt Leistung ist es das gr\u00f6\u00dfte Atomkraftwerk in Europa, was die Anzahl der Bl\u00f6cke und die installierte Leistung betrifft.<\/p>\n<p>Das ukrainische Milit\u00e4r beschie\u00dft weiterhin regelm\u00e4\u00dfig Energodar und die Umgebung des Atomkraftwerks Saporoschje. Der russische Verteidigungsminister Sergei Schoigu erkl\u00e4rte, das Kiewer Regime versuche, den Anschein einer drohenden nuklearen Katastrophe zu erwecken, indem es das Atomkraftwerk Saporoschje weiterhin gezielt beschie\u00dfe. Die IAEO wies wiederholt auf die Notwendigkeit hin, eine Sicherheitszone um das Atomkraftwerk einzurichten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<\/ul>\n<div class=\"Listing-isReact\" data-rtmodule=\"Listing\" onload=\"return {\n                page: '1',\n                limit: '10',\n                listing: '\/listing\/parent.6209f961b480cc2c7e35341b\/noprepare\/liveupdates\/10\/1',\n            };\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/131481-liveticker-ukraine-krieg-medien-scholz\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Lesen Sie hier die neuesten Entwicklungen. 12.01.2023 07:29 Uhr 07:29 Uhr Medienbericht: Scholz&#8217; Position zu Waffenlieferungen an die Ukraine stark von Biden abh\u00e4ngig Arcchivbild: US-Pr\u00e4sident Joe [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":27484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1673505988"],"wp_automatic_camp":["217"],"f8c62458163371f8d38d96837c148f67":["Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab"],"original_link":["https:\/\/de.rt.com\/international\/131481-liveticker-ukraine-krieg-medien-scholz\/"],"_thumbnail_id":["27484"],"jnews_social_counter_last_update":["1778477253"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-01-12 08:48:07\";}"]},"categories":[19,23],"tags":[1348,564,580,419,1001,12453,127,566,370],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab\" \/>\n<meta property=\"og:description\" content=\"Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Lesen Sie hier die neuesten Entwicklungen. 12.01.2023 07:29 Uhr 07:29 Uhr Medienbericht: Scholz&#8217; Position zu Waffenlieferungen an die Ukraine stark von Biden abh\u00e4ngig Arcchivbild: US-Pr\u00e4sident Joe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-12T06:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab\",\"datePublished\":\"2023-01-12T06:30:00+00:00\",\"dateModified\":\"2023-01-12T06:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/\"},\"wordCount\":1555,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg\",\"keywords\":[\"Biden\",\"Liveticker\",\"Medien\",\"mit\",\"Scholz\",\"stimmt\",\"ukraine\",\"UkraineKrieg\",\"Waffenlieferungen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/\",\"name\":\"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg\",\"datePublished\":\"2023-01-12T06:30:00+00:00\",\"dateModified\":\"2023-01-12T06:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/","og_locale":"de_DE","og_type":"article","og_title":"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab","og_description":"Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Lesen Sie hier die neuesten Entwicklungen. 12.01.2023 07:29 Uhr 07:29 Uhr Medienbericht: Scholz&#8217; Position zu Waffenlieferungen an die Ukraine stark von Biden abh\u00e4ngig Arcchivbild: US-Pr\u00e4sident Joe [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-01-12T06:30:00+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab","datePublished":"2023-01-12T06:30:00+00:00","dateModified":"2023-01-12T06:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/"},"wordCount":1555,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg","keywords":["Biden","Liveticker","Medien","mit","Scholz","stimmt","ukraine","UkraineKrieg","Waffenlieferungen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/","url":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/","name":"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg","datePublished":"2023-01-12T06:30:00+00:00","dateModified":"2023-01-12T06:30:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/01\/Liveticker-Ukraine-Krieg-\u2013-Medien-Scholz-stimmt-Waffenlieferungen-an-Ukraine-mit.jpg","width":1620,"height":1080,"caption":"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-medien-scholz-stimmt-waffenlieferungen-an-ukraine-mit-biden-ab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Liveticker Ukraine-Krieg \u2013 Medien: Scholz stimmt Waffenlieferungen an Ukraine mit Biden ab"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/27483"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=27483"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/27483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/27484"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=27483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=27483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=27483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}