{"id":2699,"date":"2022-04-23T05:45:07","date_gmt":"2022-04-23T06:45:07","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/"},"modified":"2022-04-23T05:45:07","modified_gmt":"2022-04-23T06:45:07","slug":"sexkrieg-in-der-friedenspartei","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/","title":{"rendered":"Sexkrieg in der &quot;Friedenspartei&quot;"},"content":{"rendered":"<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>von Diether Dehm<\/em><\/p>\n<p>Wenn &#8220;gegenw\u00e4rtig der Druck w\u00e4chst&#8221; auf die SPD-Spitze, namentlich auf Scholz und Schwesig, sich \u00f6ffentlich f\u00fcr fr\u00fchere Russenfreundlichkeit zu entschuldigen und endlich schwere Waffenlieferungen in die Ukraine zu akzeptieren, dann muss auch die gesamte Ostpolitik delegitimiert werden. Im \u00f6ffentlich-rechtlichen Fernsehen wurde Willy Brandt dieser Tage &#8220;portr\u00e4tiert&#8221; \u2013 weniger f\u00fcr Lob seiner Auss\u00f6hnung mit Russland, als f\u00fcrs Updaten von Sexskandalen, die dem Friedenskanzler einst nachgesagt worden waren. Ist es da ein Zufall, wenn auch die Linkspartei jetzt in den Strudel eines Sex-Skandals ger\u00e4t?<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.04\/thumbnail\/626003d948fbef67ef7d9384.jpg 850w,\n                https:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.04\/article\/626003d948fbef67ef7d9384.jpg 1960w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><source data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.04\/thumbnail\/626003d948fbef67ef7d9384.jpg 460w,\n              https:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.04\/article\/626003d948fbef67ef7d9384.jpg 980w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><!--[if IE 9]><\/video><![endif]--><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"https:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.04\/article\/626003d948fbef67ef7d9384.jpg\" alt=\"Vorsitzende der Linkspartei Hennig-Wellsow tritt zur\u00fcck\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/136598-linken-vorsitzende-hennig-wellsow-tritt\/\" class=\"Link-root Link-isFullCard \" rel=\"noopener\"><br \/>\n                Vorsitzende der Linkspartei Hennig-Wellsow tritt zur\u00fcck<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>&#8220;<a target=\"_blank\" href=\"https:\/\/m.tagesspiegel.de\/politik\/mit-sofortiger-wirkung-hennig-wellsow-tritt-als-linken-vorsitzende-zurueck\/28264444.html\" rel=\"noopener\">Sie hatte ihren R\u00fccktritt auch mit dem Umgang der Linken mit Sexismus in den eigenen Reihen begr\u00fcndet<\/a>, ein klarer Seitenhieb auf ihre Co-Chefin Janine Wissler&#8221;, schreibt am 22. April der <em>Tagesspiegel<\/em> \u00fcber Susanne Henning-Wellsow. Den Grund daf\u00fcr liefert der Dauerstreit \u00fcber Waffenexporte und NATO zwischen den &#8220;beiden tollen Fauen&#8221; \u2013 so waren sie einst den Parteitagsdelegierten vom Linken-Wahlkampfleiter und Drahtzieher J\u00f6rg Schindler angepriesen worden. Dem in neun Jahren als einziger &#8220;Erfolg&#8221; der R\u00fcckzug von Sahra Wagenknecht von der Fraktionsspitze nachzusagen ist. Schindler steht mit Hennig-Wellsow f\u00fcr dauerhafte linke Wahldesaster. Auch wegen \u00f6ffentlich zu seichter Kritik an NATO, Fluchtursachen, Russophobie und Corona-Diktaten. Und eben auch wegen Dauerzerm\u00fcrbung der langzeit-beliebtesten Politikerin Sahra Wagenknecht.<\/p>\n<p>Wenn Schindler, Wissler und Hennig-Wellsow also unmittelbar nach den vernichtenden 4,9 Prozent bei der letzten Bundestagswahl ihre Pl\u00e4tze ger\u00e4umt h\u00e4tten, w\u00e4re das Aufatmen in der linken Basis un\u00fcberh\u00f6rbar gewesen; meines auch. Nun verbellen aber NATO-Freunde die verbliebene Vorsitzende Janine Wissler, die noch gewisse linke Skrupel gegen R\u00fcstungsexporte und Massaker an Pal\u00e4stinensern bekundet, als &#8220;Radikale&#8221;. Ein Vorwurf gegen den jeder klardenkende Radikaldemokrat sie in Schutz nehmen muss, wenn geheimdienstlich orientierte Nachrichtendienste \u00e0 la <em>SPIEGEL<\/em>, <em>taz<\/em> oder <em>ZDF-heute<\/em> die Wissler jetzt der Hennig-Wellsow hinterher st\u00fcrzen wollen\u00a0\u2013 mit Sexismus-Ger\u00fcchten, die bei n\u00e4herer Betrachtung selbst sexistisch sind.<\/p>\n<p>Als ich vor zehn Jahren Altbundespr\u00e4sident Christian Wulff (CDU) gegen eine mediale Hetzjagd, angef\u00fchrt von <em>BILD <\/em>und <em>SPIEGEL<\/em>, verteidigt hatte (z.B. bei <em>Anne Will <\/em>und <em>Maischberger<\/em>), geschah dies nicht aus parteipolitischer Zuneigung, sondern, weil ich selbst oft Ziel ruft\u00f6tender Ger\u00fcchte war. Und aus Sympathie f\u00fcr Unschuldsvermutung und Rechtsstaat, die mit Friedensgebot und Sozialstaatlichkeit die Fundamente des Grundgesetzes bilden.<\/p>\n<p>Aber so, wie gerade das eherne Prinzip &#8220;Keine Waffenlieferung in Krisengebiete!&#8221; in der Linken relativiert wird, ist auch der Sozialstaat in der Linken l\u00e4ngst nicht mehr unumstritten. Als zum Beispiel der fr\u00fchere Parteivorsitzende Klaus Ernst vor zehn Jahren zur offensiven &#8220;R\u00fcckeroberung des Sozialstaats&#8221; geblasen hatte, munitionierten sogenannte Reformer gegnerische Medien stattdessen mit der Parole &#8220;f\u00fcr progressive Entstaatlichung&#8221;. Entstaatlichung ist in Demokratie und Grundgesetz aber weder f\u00fcr das Soziale noch f\u00fcr das Recht vorgesehen. Einen rechtsfreien Raum darf es nie wieder geben. Auch wenn Partei-Akteure interne Willk\u00fcr, also die Absenkung rechtsstaatlicher Standards, gerne unter dem bigotten Ruf tarnen, sie wollten in ihren Reihen ja &#8220;besonders hohe&#8221; Standards\u00a0\u2013 gegen ihre Gegenspieler, versteht sich. Nein, es gilt nach wie vor die Unschuldsvermutung, gleichbedeutend mit &#8220;im Zweifel f\u00fcr den Beschuldigten!&#8221;.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/thumbnail\/6151d76e48fbef6ce909ba86.jpg 850w,\n                https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/article\/6151d76e48fbef6ce909ba86.jpg 1960w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><source data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/thumbnail\/6151d76e48fbef6ce909ba86.jpg 460w,\n              https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/article\/6151d76e48fbef6ce909ba86.jpg 980w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data-sizes=\"auto\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/thumbnail\/6151d76e48fbef6ce909ba86.jpg\" alt=\"Pulverisiert: Warum der Linken-Absturz bei der Bundestagswahl keine \u00dcberraschung war\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/article\/6151d76e48fbef6ce909ba86.jpg\" alt=\"Pulverisiert: Warum der Linken-Absturz bei der Bundestagswahl keine \u00dcberraschung war\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-label\">\n            <span class=\"Label-root\"><br \/>\n                Meinung<br \/>\n            <\/span>\n        <\/div>\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a target=\"_blank\" href=\"https:\/\/de.rt.com\/meinung\/124856-pulverisiert-warum-der-linken-absturz-keine-ueberraschung-war\/\" class=\"Link-root Link-isFullCard \" rel=\"noopener\"><br \/>\n                Pulverisiert: Warum der Linken-Absturz bei der Bundestagswahl keine \u00dcberraschung war<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Nun heiligt der Zweck wieder einmal die Mittel, setzt der heilige Geifer Ger\u00fcchte \u00fcber Gerichte. Wenn da der heimliche Th\u00fcringer Regierungschef Benjamin Hoff gemeinsam mit Links-Berufs-Jugendlichen, &#8220;LinkeMeToo-Aktiven&#8221; und fr\u00fcheren MdBs, die w\u00e4hrend des Bundestagswahlkampfs k\u00fcrzlich mit Partei-Ausschluss-Forderungen gegen Sahra Wagenknecht gescheitert waren, jetzt sch\u00e4rfste Strafen fordern. Und zwar gegen solche, denen Ger\u00fcchte unterstellen, bei sexistischen \u00dcbergriffen weggeschaut zu haben. Was sie sogar mit Kindersch\u00e4ndungen in der katholischen Kirche gleichsetzen\u00a0\u2013 und damit Janine Wissler in die N\u00e4he von Papst Benedikt r\u00fccken.<\/p>\n<p>Stolz klopft sich da der <em>SPIEGEL<\/em> am 17. April auf die Schultern, das Vertrauen zur Linkspartei weiter &#8220;zerr\u00fcttet&#8221; zu haben und schreibt in aller Bescheidenheit zum Tsunami im linken Wasserglas:<\/p>\n<blockquote>\n<p><em>&#8220;Ausl\u00f6ser war ein Enth\u00fcllungsreport des Spiegel.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>W\u00e4hrend der Sozialstaat 100 Milliarden ans Milit\u00e4r abtreten soll, Gr\u00fcne und FDP schwere Waffen zur Verl\u00e4ngerung des Krieges anliefern, die Inflation den Menschen die Butter vom Brot frisst, w\u00e4hrend US-F\u00fchrer Europa gerade in einen dritten Weltkrieg dr\u00e4ngen, trudelt die &#8220;LINKE&#8221; bundesweit unter 4 Prozent. Dabei ist sie die einzige Bundestagspartei, die f\u00fcr Abr\u00fcstung eintritt. Aber sie liegt momentan bei zwei Prozent in NRW vor den dortigen Wahlen. Im M\u00e4rz stritt sie &#8220;wenigstens&#8221; noch \u00fcber Waffenexporte. Jetzt zerlegt sich die &#8220;Friedenspartei&#8221; \u00fcber einen Sex-Tweet, der ihren Bundesparteitag in zwei Monaten thematisch mehr beherrschen d\u00fcrfte, als die ukrainischen Terroristen, deren M\u00f6rser acht Jahre lang Tausende, auch Kinder und Frauen, im Donbass zerrissen und Minsk II so erledigt hatten.<\/p>\n<p>Der aktuelle Tatbestand: Dem <em>SPIEGEL<\/em> war aus der hessischen Partei-Jugend \u2013 via Th\u00fcringen!\u00a0\u2013 ein Screenshot aus dem Jahr 2018 zugespielt worden, an dem gleich vier <em>SPIEGEL<\/em>-Redakteure, eigenen Angaben zufolge, &#8220;recherchiert&#8221; hatten. Eine kurzerhand zur &#8220;Minderj\u00e4hrigen&#8221; umdefinierte junge Frau hatte vor vier Jahren, nach eigenem Bekunden, an die Parteivorsitzende Janine Wissler folgende Nachricht gesendet:\u00a0<\/p>\n<blockquote>\n<p><em>&#8220;<\/em><em>Entschuldige das hier bitte, Janine, aber ich drehe endg\u00fcltig durch, wenn Adrian nochmal nachts pl\u00f6tzlich auf meinem Balkon steht und das romantisch nennt.&#8221; <\/em><\/p>\n<\/blockquote>\n<p>Die fr\u00fchere hessische Linksfraktionschefin bestreitet diesen damaligen &#8220;Hilferuf&#8221; des &#8220;Opfers&#8221;, sowie einen zus\u00e4tzlich behaupteten Telefonatsverlauf. Was nun das &#8220;Opfer&#8221; vor Gericht bringt. Klar, die Vorw\u00fcrfe gegen die Beteiligten k\u00f6nnten alle stimmen und sie sind, weiss Gott, kein Pappenstiel. Auch wenn die Staatsanwaltschaft gerade eben erkl\u00e4rt hat, auf jegliche Ermittlungen gegen &#8220;den T\u00e4ter&#8221; zu verzichten. Aber Rechtskr\u00e4ftiges wartet der <em>SPIEGEL<\/em> nicht ab, wenn es um die Vernichtung der gesamten Linkspartei geht. W\u00e4hrend die von ihm befeuerten Shit-St\u00fcrmer im heiligen Krieg der verfeindeten Parteistr\u00f6mungen nie die gesamte Partei zu zerst\u00f6ren vorgeben, sondern nur die jeweils gegnerischen Teile. Die rechtsstaatliche Unschuldsvermutung giften sie dabei an als reaktion\u00e4ren Ballast eines &#8220;patriarchalen Grundgesetzes&#8221;. Und wer sich darauf beruft, sei ohnehin selbst ein potenzieller Vergewaltiger oder betriebe T\u00e4terschutz, wenn er oder sie rechtlich relevante Fragen zu stellen wagt, wie etwa die folgenden:<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/thumbnail\/6151bcf948fbef6cfa30acf6.jpg 850w,\n                https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/article\/6151bcf948fbef6cfa30acf5.jpg 1960w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><source data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/thumbnail\/6151bcf948fbef6cfa30acf6.jpg 460w,\n              https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/article\/6151bcf948fbef6cfa30acf5.jpg 980w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data-sizes=\"auto\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/thumbnail\/6151bcf948fbef6cfa30acf6.jpg\" alt=\"Wahlanalyse: Linkspartei schneidet bei Arbeitern und Arbeitslosen schlecht ab\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"https:\/\/cdni.russiatoday.com\/deutsch\/images\/2021.09\/article\/6151bcf948fbef6cfa30acf5.jpg\" alt=\"Wahlanalyse: Linkspartei schneidet bei Arbeitern und Arbeitslosen schlecht ab\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/124864-wahlanalyse-linkspartei-arbeiter-arbeitslose\/\" class=\"Link-root Link-isFullCard \" rel=\"noopener\"><br \/>\n                Wahlanalyse: Linkspartei schneidet bei Arbeitern und Arbeitslosen schlecht ab<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Wie war der &#8220;T\u00e4ter&#8221; \u00fcber den Balkon beim Opfer eingestiegen? In welchem Stockwerk geschah das damals? War er zum ersten Mal in der Liebesbeziehung zwischen &#8220;Opfer und T\u00e4ter&#8221; \u00fcber den Balkon gekommen? Hat er dazu die Balkont\u00fcr besch\u00e4digt? Kam es danach zu einer Vergewaltigung? Oder, wie vom &#8220;T\u00e4ter&#8221; behauptet, zu einvernehmlichem Sex? Was nannte der &#8220;T\u00e4ter&#8221; laut der weiterverbreiteten Kurznachricht der Betroffenen: &#8220;romantisch&#8221;?<\/p>\n<p>Warum hat sie nicht schon im Jahr 2018 sofort Strafanzeige erstattet? Bedurfte es erst des Jahres 2022 und dazu einer sogenannten <em>SPIEGEL<\/em>-Recherche? Wurde damals Druck auf das &#8220;Opfer&#8221; ausge\u00fcbt? Wurde die Liebesbeziehung vom &#8220;Opfer&#8221; danach, also im Jahr 2018, sofort abgebrochen?<\/p>\n<p>Wie musste dies alles bei Janine Wissler damals angekommen sein, die zu diesem Zeitpunkt ebenfalls mit dem &#8220;T\u00e4ter&#8221; liiert war? H\u00e4tte die Kurznachricht f\u00fcr Wissler auch als h\u00f6hnisch kaschierter Triumpf einer Nebenbuhlerin &#8220;miss&#8221;-verstanden werden k\u00f6nnen?<\/p>\n<p>Wie h\u00e4tte sich Janina Wissler korrekt verhalten sollen? Denn der <em>SPIEGEL<\/em> merkt noch an, der &#8220;T\u00e4ter&#8221; sei ja auch Angestellter der Fraktion gewesen, deren Chefin die Wissler war. Will der <em>SPIEGEL<\/em> damit sagen, dass diese als Arbeitgeberin einen Mitarbeiter h\u00e4tte entlassen sollen? Auf welcher Rechtsbasis? Und was w\u00fcrden gewerkschaftsorientierte Linke dazu sagen, wenn Arbeitgeber k\u00fcnftig das Liebesverhalten von Mitarbeitern jenseits der Arbeitszeit zum Gegenstand von Aussp\u00e4hung, Ger\u00fcchten und K\u00fcndigung machen w\u00fcrden?<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.03\/thumbnail\/62332dd248fbef4c2958f945.jpg 850w,\n                https:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.03\/article\/62332dd148fbef4c2958f944.jpg 1960w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><source data-srcset=\" \nhttps:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.03\/thumbnail\/62332dd248fbef4c2958f945.jpg 460w,\n              https:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.03\/article\/62332dd148fbef4c2958f944.jpg 980w,\n            \" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\"><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data-sizes=\"auto\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"https:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.03\/thumbnail\/62332dd248fbef4c2958f945.jpg\" alt=\"Oskar Lafontaine tritt aus der Partei Die Linke aus\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"https:\/\/cdni.russiatoday.com\/deutsch\/images\/2022.03\/article\/62332dd148fbef4c2958f944.jpg\" alt=\"Oskar Lafontaine tritt aus der Partei Die Linke aus\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/134047-oskar-lafontaine-tritt-aus-der-partei-die-linke-aus\/\" class=\"Link-root Link-isFullCard \" rel=\"noopener\"><br \/>\n                Oskar Lafontaine tritt aus der Partei Die Linke aus<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Es gibt noch mehr offene Fragen, die gerichtlich ausverhandelt sein wollen, bevor die Unschuldsvermutung gegen den &#8220;mutma\u00dflichen T\u00e4ter&#8221; f\u00e4llt. Aber mit dem Rechtsstaat stehen Medien oft auf \u00e4hnlichem Kriegsfuss wie die, die noch innerparteiliche Rechnungen offen haben. Einige wollen an deren Fleischt\u00f6pfe, anderen gen\u00fcgt der wichtigtuerische Rauschzustand, mal so richtig Schicksal spielen zu d\u00fcrfen: Wenn sie schon den R\u00fcstungs-Konzernen nicht weh tun k\u00f6nnen, dann wenigstens den eigenen Leuten. Und so zappeln sie siegesgewiss im digitalen Spinnennetz medialer Spindoktoren.<\/p>\n<p>Das Geheimrezept von identit\u00e4ren Bessermenschen ist allzumeist die Kolonialisierung fremder Opfer, die Aneignung fremden Leids zur eigenen Omnipotenz. Multipliziert mit der Medienpower BND-gest\u00fctzter Schreibagenten, die stets verl\u00e4sslich auf alles schiessen, was irgendwie nach Anti-NATO aussieht. Aus diesem medienbewehrten Schutzpanzer darf dann nach Lust und Laune die Ger\u00fcchtek\u00fcche befeuert und jeder drauflos gecancelt werden: als Nazi, Antisemit, Xenophober, Querfrontler, Putin-Kolonne, Corona- oder Klimaleugner. Auf den Spuren der Christenverfolger, der lustfeindlichen Hexenverbrenner, des MacCarthyismus und der orwellschen Sprachpolizei wollen diese Inquisitoren bestimmen, wo die Grenze verl\u00e4uft zwischen Flirt und toxischer M\u00e4nnlichkeit. Wollen mit der Stoppuhr messen, ab wann ein schmachtender Blick einer Vergewaltigung gleichkommt und eine Aufforderung zum Tanzen einer \u00dcbergriffshandlung. Die <em>ZEIT<\/em>-Chefredakteurin Sabine R\u00fcckert hatte einst, am 30. Juni 2016, \u00fcberspitzt gegen &#8220;Metoo&#8221; polemisiert: &#8220;Was leidenschaftliche Liebesnacht und was Vergewaltigung war, definiert Frau k\u00fcnftig am Tag danach.&#8221; Die AfD backt derweil das Popcorn auf und deutet auf die Leinwand: &#8220;Seht her, in solcherlei Hexenkessel landet ihr mit linkem Feminismus!&#8221;<\/p>\n<p>Der Regisseur Ken Loach erz\u00e4hlt in seinen Filmen mit gro\u00dfer k\u00fcnstlerischer Liebe, wie es proletarischen Frauen auf dieser Welt ergeht\u00a0\u2013 aber auch, wie sie k\u00e4mpfen. Und wie M\u00e4nner ihnen dabei zur Seite stehen k\u00f6nnen, gegen den Krieg, aber auch den der Geschlechter\u00a0\u2013 freundlich zu ihresgleichen und unfreundlich gegen das Gro\u00dfkapital.<\/p>\n<p>Und Loach beschreibt auch, wie die Macher dieser Arbeiter-Bewegung und deren B\u00fcndnispartnern in Kunst und Wissenschaft dann von Geheimdiensten registriert, ihnen Berufsverbote und Schlimmeres zugeteilt worden waren. Wie sie auf schwarzen Listen dann irgendwie irgendwann irgendwo abgeheftet wurden. Heute werden die giftgr\u00fcnen Exkremente aus den entz\u00fcndeten Organen hysterischer Denunziatoren nicht mehr auf saugf\u00e4higes Papier gebracht, sondern digitalisiert f\u00fcr die Ewigkeit. Vielleicht denken die trojanischen Shit-Storm-Fighter mal daran, dass das ihnen, wenn sie DIE LINKE leergebissen haben, niemand je danken wird, au\u00dfer vielleicht mit ein paar Festanstellungen beim \u00dcberwachungsstaat. Und dass ihnen dann statt ihres Lieblingsworts &#8220;fremdsch\u00e4men&#8221; bestenfalls bleibt, &#8220;sich-f\u00fcr-sich-selbst-zu-sch\u00e4men&#8221;.\u00a0\u00a0<\/p>\n<p><em>Dr. Diether Dehm ist <a target=\"_blank\" href=\"https:\/\/weltnetz.tv\/video\/2635-nato-luegen-verfangen-nicht-ostermarsch-2022-bruchkoebel\" rel=\"noopener noreferrer\">Unterhaltungsautor<\/a> und war lange f\u00fcr SPD und Die Linke im Bundestag.<\/em><\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/136505-sexuelle-ubergriffe-durch-mannerbunde-innerhalb\/\" rel=\"noopener\">Sexuelle \u00dcbergriffe durch M\u00e4nnerb\u00fcnde innerhalb der Linkspartei? Vorw\u00fcrfe l\u00f6sen #MeToo-Debatte aus<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/136826-sexkrieg-in-friedenspartei\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>von Diether Dehm Wenn &#8220;gegenw\u00e4rtig der Druck w\u00e4chst&#8221; auf die SPD-Spitze, namentlich auf Scholz und Schwesig, sich \u00f6ffentlich f\u00fcr fr\u00fchere Russenfreundlichkeit zu entschuldigen und endlich schwere Waffenlieferungen in die Ukraine zu akzeptieren, dann muss auch die gesamte Ostpolitik delegitimiert werden. Im \u00f6ffentlich-rechtlichen Fernsehen wurde Willy Brandt dieser Tage &#8220;portr\u00e4tiert&#8221; \u2013 weniger f\u00fcr Lob seiner Auss\u00f6hnung [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"d19633858a53d7220ead870c9f6b935f":["Sexkrieg in der &quot;Friedenspartei&quot;"],"original_link":["https:\/\/de.rt.com\/meinung\/136826-sexkrieg-in-friedenspartei\/"],"_thumbnail_id":["2700"],"wp_automatic_remove_first_image":["yes"],"_wptg_p2tg_sent2tg":["2022-04-23 05:50:27"],"jnews_social_counter_last_update":["1783946068"]},"categories":[19,23],"tags":[82,7816,7815],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sexkrieg in der &quot;Friedenspartei&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sexkrieg in der &quot;Friedenspartei&quot;\" \/>\n<meta property=\"og:description\" content=\"von Diether Dehm Wenn &#8220;gegenw\u00e4rtig der Druck w\u00e4chst&#8221; auf die SPD-Spitze, namentlich auf Scholz und Schwesig, sich \u00f6ffentlich f\u00fcr fr\u00fchere Russenfreundlichkeit zu entschuldigen und endlich schwere Waffenlieferungen in die Ukraine zu akzeptieren, dann muss auch die gesamte Ostpolitik delegitimiert werden. Im \u00f6ffentlich-rechtlichen Fernsehen wurde Willy Brandt dieser Tage &#8220;portr\u00e4tiert&#8221; \u2013 weniger f\u00fcr Lob seiner Auss\u00f6hnung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-23T06:45:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t<meta property=\"og:image:height\" content=\"622\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Sexkrieg in der &quot;Friedenspartei&quot;\",\"datePublished\":\"2022-04-23T06:45:07+00:00\",\"dateModified\":\"2022-04-23T06:45:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/\"},\"wordCount\":1715,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg\",\"keywords\":[\"der\",\"quotFriedensparteiquot\",\"Sexkrieg\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/\",\"name\":\"Sexkrieg in der &quot;Friedenspartei&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg\",\"datePublished\":\"2022-04-23T06:45:07+00:00\",\"dateModified\":\"2022-04-23T06:45:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg\",\"width\":1104,\"height\":622,\"caption\":\"Sexkrieg in der &quot;Friedenspartei&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sexkrieg in der &quot;Friedenspartei&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sexkrieg in der &quot;Friedenspartei&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/","og_locale":"de_DE","og_type":"article","og_title":"Sexkrieg in der &quot;Friedenspartei&quot;","og_description":"von Diether Dehm Wenn &#8220;gegenw\u00e4rtig der Druck w\u00e4chst&#8221; auf die SPD-Spitze, namentlich auf Scholz und Schwesig, sich \u00f6ffentlich f\u00fcr fr\u00fchere Russenfreundlichkeit zu entschuldigen und endlich schwere Waffenlieferungen in die Ukraine zu akzeptieren, dann muss auch die gesamte Ostpolitik delegitimiert werden. Im \u00f6ffentlich-rechtlichen Fernsehen wurde Willy Brandt dieser Tage &#8220;portr\u00e4tiert&#8221; \u2013 weniger f\u00fcr Lob seiner Auss\u00f6hnung [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-04-23T06:45:07+00:00","og_image":[{"width":1104,"height":622,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Sexkrieg in der &quot;Friedenspartei&quot;","datePublished":"2022-04-23T06:45:07+00:00","dateModified":"2022-04-23T06:45:07+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/"},"wordCount":1715,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg","keywords":["der","quotFriedensparteiquot","Sexkrieg"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/","url":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/","name":"Sexkrieg in der &quot;Friedenspartei&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg","datePublished":"2022-04-23T06:45:07+00:00","dateModified":"2022-04-23T06:45:07+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/Sexkrieg-in-der-quotFriedensparteiquot.jpg","width":1104,"height":622,"caption":"Sexkrieg in der &quot;Friedenspartei&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/sexkrieg-in-der-friedenspartei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Sexkrieg in der &quot;Friedenspartei&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/2699"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=2699"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/2699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/2700"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=2699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=2699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=2699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}