{"id":26436,"date":"2022-12-28T09:51:15","date_gmt":"2022-12-28T07:51:15","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/"},"modified":"2022-12-28T09:51:15","modified_gmt":"2022-12-28T07:51:15","slug":"deutschland-verwandelt-sich-in-einen-almosenstaat","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/","title":{"rendered":"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/63ab0301b480cc3c3a5723b6.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Deutschland ist auf dem Weg zu einem &#8220;Almosenstaat&#8221;, warnen deutsche Sozialexperten. Ihnen zufolge drohen die explodierenden Energiepreise und die steigenden Lebenshaltungskosten die gewohnte Lebensweise der deutschen Gesellschaft zu sprengen \u2013 was dramatische Folgen f\u00fcr das Land haben k\u00f6nnte.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Ende November hat NielsenIQ, ein Marktforschungsunternehmen f\u00fcr Verbraucherverhalten und Einzelhandel, eine Umfrage unter mehr als 10.000 Personen in Deutschland durchgef\u00fchrt. Die Studie ergab, dass 52 Prozent der Einwohner des Landes ihre Eink\u00e4ufe einschr\u00e4nken und nur f\u00fcr Produkte Geld ausgeben, die sie wirklich brauchen. Etwa 44 Prozent geben an, dass sie kein Geld f\u00fcr Unterhaltungsprodukte und Luxusartikel ausgeben, und 31 Prozent gehen fast nie ausw\u00e4rts essen. Etwa 30 Prozent der Befragten stimmten zu, dass sie unter den derzeitigen Umst\u00e4nden weniger einkaufen gehen.<\/p>\n<p>&#8220;Es ist bezeichnend, dass sich immer mehr Menschen fragen, worauf sie verzichten k\u00f6nnen, und dies dann auch tun&#8221;, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/inosmi.ru\/20221126\/krizis-258257810.html\">sagt<\/a> NielsenIQ-Experte Lothar Steiblin.<\/p>\n<p><strong>&#8220;Die Angst der Armen wird zur Verzweiflung&#8221;<\/strong><\/p>\n<p>Der Hauptgesch\u00e4ftsf\u00fchrer des Parit\u00e4tischen Gesamtverbandes Ulrich Schneider <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.focus.de\/finanzen\/sozialexperte-ulrich-schneider-warnt-bei-vielen-armen-schlaegt-die-angst-in-pure-verzweiflung-um_id_180455939.html\">teilte<\/a> dem Magazin <em>Focus<\/em> mit<em>,<\/em> Deutschland sei auf dem Weg zu einem &#8220;Almosenstaat&#8221;. Der Grund daf\u00fcr seien die explodierenden Energiepreise, die steigenden Lebenshaltungskosten und immer h\u00f6here Belastungen f\u00fcr B\u00fcrger, die eine soziale Krise und schwerwiegende Folgen f\u00fcr das Land nach sich z\u00f6gen.<\/p>\n<p>&#8220;Wir hatten in Deutschland schon vor der Explosion der Lebenshaltungskosten einen Rekordwert von 13,8 Millionen armen Menschen&#8221;, so der Sozialexperte. Aufgrund der aktuellen Krise k\u00e4men laut Umfragen noch einmal mehr als zw\u00f6lf Millionen Haushalte hinzu, &#8220;die zwar statistisch noch nicht zu den Armen z\u00e4hlen, aber am Monatsende nichts mehr \u00fcbrig haben&#8221;.<\/p>\n<p>Schneider: &#8220;Es sind keine Reserven da. Eine kaputte Waschmaschine oder eine notwendige Autoreparatur werden dann schnell zur Katastrophe. Nachzahlungen bei Strom und Gas oder h\u00f6here Abschlagszahlungen \u00fcberschreiten bei sehr vielen dieser Haushalte das M\u00f6gliche.&#8221; Der Experte warnt:<\/p>\n<blockquote>\n<p><em>&#8220;Die Not erreicht die Mittelschicht.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Schneider malt ein d\u00fcsteres Bild f\u00fcr den Fall, dass die Entwicklung ungebremst anh\u00e4lt. &#8220;Da die enormen Preissteigerungen f\u00fcr die untersten Einkommen nur unzureichend aufgefangen werden, droht unsere Gesellschaft am unteren Rand auseinanderzubrechen.&#8221;<\/p>\n<p>Bei denen, die sich gerade noch so \u00fcber Wasser halten, schl\u00fcgen die Sorgen langsam &#8220;in echte Angst&#8221; um, hat Schneider beobachtet. &#8220;Es gibt die Angst vor der n\u00e4chsten Preiswelle bei Lebensmitteln, die Angst vor der Stromnachzahlung, die Angst davor, sich die Ratenzahlungen nicht mehr leisten oder die Miete nicht mehr zahlen zu k\u00f6nnen.&#8221;<\/p>\n<p>Mitunter sei es noch schlimmer. &#8220;Bei vielen Armen schl\u00e4gt die Angst in pure Verzweiflung um&#8221;, so Schneider. &#8220;Der Ansturm auf die Tafeln zeugt davon, wie ausweglos f\u00fcr viele Menschen die Situation mittlerweile ist.&#8221; Schneider meint deshalb:<\/p>\n<blockquote>\n<p><em>&#8220;Deutschland war viele Jahrzehnte ein moderner Sozialstaat. Wir d\u00fcrfen nicht zulassen, dass er schleichend zum Almosenstaat mutiert, weil wir den Armen nicht geben, was sie brauchen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der Experte fordert ein gesetzliches Moratorium, was Energiesperren und Wohnungsk\u00fcndigungen in den n\u00e4chsten Monaten angeht. &#8220;Die Menschen brauchen die Sicherheit, nicht irgendwann in der K\u00e4lte und im Dunkeln zu sitzen und nicht ihre <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/kleinanzeige.focus.de\/immobilien\/\">Wohnungen<\/a> zu verlieren.&#8221;<\/p>\n<p>Schneider fuhr in dem Interview fort: &#8220;Zwar stellen wir nach wie vor die viertst\u00e4rkste Wirtschaftskraft der Welt, doch waren wir auch schon vor Corona-, Energie- und Preiskrise ein sozial sehr tief gespaltenes Land mit ungeheurem Reichtum auf der einen Seite, aber auch einer immer gr\u00f6\u00dfer werdenden Armut auf der anderen.&#8221;<\/p>\n<p><strong>Reduzierter Konsum<\/strong><\/p>\n<p>Die Tatsache, dass die Deutschen arm werden, wird auch von der <em>Welt<\/em> best\u00e4tigt. Jeder zweite Deutsche k\u00f6nne sich nur noch das N\u00f6tigste leisten, hei\u00dft es. Die Deutschen sind weniger geneigt, ihr Auto zu betanken, Medikamente und Kleidung zu kaufen, aber sie kaufen aus Angst vor weiteren Preissteigerungen eher Lebensmittel und Hygieneartikel.<\/p>\n<p>Au\u00dferdem erwarten die Deutschen keine Ver\u00e4nderung zum Besseren und planen daher, ihren Konsum weiter einzuschr\u00e4nken. Laut der Umfrage glauben 52 Prozent der deutschen B\u00fcrger, dass sich die Lebenssituation in Deutschland in den n\u00e4chsten drei Jahren verschlechtern wird. Dies zeigt, dass die Deutschen deutlich negativer eingestellt sind als der Rest der EU, wo der durchschnittliche Pessimismus bei 32 Prozent liegt.<\/p>\n<p>Und seien wir ehrlich, die Deutschen haben allen Grund zur Sorge. &#8220;Immer mehr Verbraucher in Deutschland haben Probleme, die Kosten f\u00fcr Energie, Lebensmittel und grundlegende Dienstleistungen zu decken. Mehr als drei Viertel der potenziellen K\u00e4ufer m\u00fcssen ihre Eink\u00e4ufe einschr\u00e4nken. Jeder Zweite von mehr als tausend Befragten gab zu, dass er nur das N\u00f6tigste kaufen kann&#8221;, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.welt.de\/wirtschaft\/plus242256731\/Inflation-Pessimist-Deutschland-Jetzt-beginnt-das-grosse-Sparen.html\">berichtet<\/a> der Journalist Carsten Dierig von der <em>Welt<\/em>.<\/p>\n<p>Die von Dierig befragten Experten erkl\u00e4ren, dass die Mittel der Verbraucher aufgrund der im Lande grassierenden Inflation sp\u00fcrbar geschrumpft sind. Der Einzelhandel mit Bekleidung und Unterhaltungselektronik hat dies besonders deutlich zu sp\u00fcren bekommen. In einer aktuellen Umfrage gaben 56 Prozent der Deutschen zu, dass sie derzeit wenig oder keine Kleidung kaufen. Das Gleiche gilt f\u00fcr die Verbraucher von elektronischen Ger\u00e4ten wie Fernsehern, Smartphones, Laptops und Spielkonsolen. In diesem Bereich m\u00fcssen sich 56 Prozent der deutschen Verbraucher zur\u00fcckhalten oder sogar auf den Einkauf verzichten.<\/p>\n<p>\u00c4hnlich verh\u00e4lt es sich bei Tankstellen und Apotheken \u2013 fast jeder zweite Befragte tankt seltener, und fast jeder vierte gibt zu, bei Medikamenten zu sparen. Im Rahmen weiterer Sparma\u00dfnahmen wollen viele Deutsche auf Lieferservices verzichten und weniger Essen zum Mitnehmen bestellen. Gleichzeitig wollen viele Verbraucher auch bei Freizeitaktivit\u00e4ten sparen \u2013 zum Beispiel bei Urlaubsreisen ins Ausland, Restaurant-, Bar- und Kinobesuchen, Abonnements in Fitnessstudios oder bei der Anzahl der Streaming-Dienste.<\/p>\n<p>96 Prozent gehen von weiteren Preissteigerungen aus. Mehr Geld planen die Befragten dagegen f\u00fcr den Kauf von Lebensmitteln und Hygieneartikeln ein. &#8220;Wobei das alles andere als freiwillig, sondern eher der allgemeinen Erwartung weiter steigender Preise geschuldet sein d\u00fcrfte&#8221;, betont Dierig.<\/p>\n<p>Und diese Annahmen sind nicht unbegr\u00fcndet. Seit einigen Monaten bricht die Inflationsrate in Deutschland immer neue Rekorde. Haupttreiber sind nach Angaben des Statistischen Bundesamtes Energie und Nahrungsmittel. Im Oktober zum Beispiel habe es Aufschl\u00e4ge von 43 Prozent bei Energieprodukten und von 20,3 Prozent bei Nahrungsmitteln gegeben, jeweils verglichen mit dem Vorjahresmonat.<\/p>\n<p>Die<em> Welt<\/em> zitiert eine Umfrage des M\u00fcnchner ifo Instituts f\u00fcr Wirtschaftsforschung, wonach die Deutschen bald noch mehr Geld an den Supermarktkassen lassen m\u00fcssen. Tatsache ist, dass zwei von drei Lebensmittelherstellern und 38 Prozent der Getr\u00e4nkehersteller beabsichtigen, ihre Endverbraucherpreise zu erh\u00f6hen \u2013 aufgrund der gestiegenen Rohstoff- und Produktionskosten.<\/p>\n<p>&#8220;Die Unternehmen in Deutschland haben ihre gestiegenen Einkaufspreise bislang nur langsam und unvollst\u00e4ndig an die Kunden weitergereicht&#8221;, hei\u00dft es in der Untersuchung.<\/p>\n<p>Sie erkl\u00e4ren, dass bisher nur 34 Prozent der gestiegenen Rohstoff- und Produktionskosten an die Endverbraucher weitergegeben wurden. Die geringe Nachfrage, der Wettbewerbsdruck und das Fortbestehen langfristiger Vertr\u00e4ge haben sich als hemmende Faktoren erwiesen. In den kommenden Monaten werden die Unternehmen ihre gestiegenen Kosten jedoch verst\u00e4rkt an die Endverbraucher weitergeben.<\/p>\n<p><strong>Ist Putin daran schuld? <br \/><\/strong><\/p>\n<p>Die deutschen Minister versuchen nat\u00fcrlich, gespielten Optimismus aufrechtzuerhalten. Aber selbst Wirtschaftsminister Robert Habeck muss zugeben, dass die Temperatur in seinen B\u00fcror\u00e4umen nicht h\u00f6her als 19 Grad sein darf \u2013 es muss W\u00e4rme gespart werden.<\/p>\n<p>&#8220;Die Industrie hat seit Jahresbeginn rund 25 Prozent des Gasverbrauchs eingespart, die Produktion ist nur um 1,4 Prozent zur\u00fcckgegangen. Nat\u00fcrlich sind energieintensive Branchen st\u00e4rker betroffen als andere Bereiche, aber dennoch zeigt es, dass Effizienzgewinne m\u00f6glich sind. Unter dem Druck der Preise sind wir in der Lage, marktwirtschaftliche Antworten zu geben. Dar\u00fcber darf man sich nicht freuen, weil die Lage so bitter ist. Aber es zeigt, wie robust dieses Land dasteht&#8221;, freute sich Habeck in einem <em>FAZ<\/em>&#8211;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.faz.net\/aktuell\/wirtschaft\/robert-habeck-ueber-die-energiewende-und-den-ukraine-krieg-18505516.html?premium\">Interview.<\/a>\u00a0<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FZu-viel-RT-geguckt%E2%80%93Wenn-Habeck-die-Argumente-ausgehen%3A9\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Das Wichtigste sei jetzt, Wladimir Putin zu zeigen, &#8220;wie gut die Demokratie hier funktioniert&#8221;. Der Minister versprach, dass sich Deutschland nicht in eine &#8220;Industriebrache&#8221; verwandeln werde. Aber schon die Formulierung einer solchen Frage kann die Deutschen nat\u00fcrlich nicht kaltlassen.<\/p>\n<p>Die Ampelkoalition sah in den diesj\u00e4hrigen Ereignissen eine Chance, ihren Traum vom weitestgehenden Verzicht auf schmutzige Kohlenwasserstoffenergie zu verwirklichen. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/wirtschaft\/energiewirtschaft-in-deutschland-co-ziel-verfehlt-ausbau-der-erneuerbaren-stockt-a-8f60e065-5ce9-4738-a1c0-ba09782112d9\">Laut<\/a>\u00a0<em>Spiegel<\/em> haben die Beh\u00f6rden jedoch Schwierigkeiten, Unternehmen zu finden, die unter den derzeitigen Bedingungen bereit sind, Windkraftanlagen zu bauen. Die hohe Inflation und die steigenden Kreditzinsen haben die Situation f\u00fcr die Unternehmen in diesem Jahr erneut versch\u00e4rft. Die Deutschen hingegen sind offen gesagt nicht gl\u00fccklich \u00fcber diese Information.<\/p>\n<p>&#8220;F\u00fcr meine Arbeit reise ich oft ins Ausland, auf alle Kontinente. In der Vergangenheit wurde Deutschland sehr bewundert und anerkannt, wir galten als Vorbild, als fortschrittlich, als Benchmark. Heute \u2013 und das macht mich sehr traurig \u2013 ist es oft nur ein m\u00fcdes L\u00e4cheln, ein Kopfsch\u00fctteln, v\u00f6lliges Unverst\u00e4ndnis oder sogar Ver\u00e4rgerung&#8221;, merkte ein Nutzer im Diskussionsforum an.<\/p>\n<p>Ein weiteres Problem ist der Anstieg der Kinderarmut. Heinz Hilgers, Pr\u00e4sident des Deutschen Kinderschutzbundes, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/wirtschaft\/russland-ukraine-krieg-kinderschutzbund-warnt-vor-anstieg-der-kinderarmut-in-deutschland-a-07da3022-4c76-4355-adae-caed668c0c7e\">erkl\u00e4rte<\/a> der Presse:<\/p>\n<blockquote>\n<p><em>&#8220;Die Inflation trifft Familien, die nur wenig Geld zur Verf<\/em><em>\u00fcgung haben, besonders hart. Die Kinderarmut wird im kommenden Jahr also noch einmal deutlich zunehmen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Hilgers warnte davor, dass Familien mit Kindern nicht von den Regelleistungen leben k\u00f6nnten \u2013 die Erh\u00f6hung komme zu sp\u00e4t und werde direkt von der Inflation aufgefangen. Er forderte eine dringendere Erh\u00f6hung der Leistungen.<\/p>\n<p>Aber schon die Art und Weise, wie das Problem dargestellt wird, ist urkomisch \u2013 der <em>Spiegel<\/em> bezeichnet die Folgen des Krieges in der Ukraine als mitverantwortlich f\u00fcr das Problem der Kinderarmut. Auch dies weckte bei einigen Lesern Zweifel. &#8220;Kinderarmut gab es in Deutschland schon vor dem Krieg in der Ukraine und der Inflation. Der Zustrom armer Menschen aus der ganzen Welt hat die Situation noch versch\u00e4rft. Der Hauptgrund liegt eher bei unseren Politikern als bei Putin&#8221;, schreibt ein Kommentator.<\/p>\n<p>&#8220;Putins Angriffskrieg ist schuld an der Kinderarmut in Deutschland \u2013 was sonst? Das ist genauso clever wie die <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.mk.ru\/politics\/2022\/12\/21\/bayden-zayavil-zelenskomu-chto-putin-ispolzuet-zimu-kak-oruzhie.html\">Behauptung<\/a>, dass er den Winter als Waffe benutzt&#8221;, findet ein anderer.<\/p>\n<p><em>Zuerst <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/vz.ru\/world\/2022\/12\/23\/1192183.html\">erschienen<\/a> bei Wsgljad.\u00a0<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/meinungsfreiheit.rtde.life\/kurzclips\/video\/153278-burgergeld-statt-hartz-iv\/\">B\u00fcrgergeld statt Hartz IV<\/a><em><\/em><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2Ffraktionsloser-farle-zur-energiekrise-faseln-von-moskaus-krieg-gr%C3%BCnen-tr%C3%A4ume-verwirklicht%3A0\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/158292-deutschland-verwandelt-sich-in-einen-almosenstaat\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutschland ist auf dem Weg zu einem &#8220;Almosenstaat&#8221;, warnen deutsche Sozialexperten. Ihnen zufolge drohen die explodierenden Energiepreise und die steigenden Lebenshaltungskosten die gewohnte Lebensweise der deutschen Gesellschaft zu sprengen \u2013 was dramatische Folgen f\u00fcr das Land haben k\u00f6nnte. Ende November hat NielsenIQ, ein Marktforschungsunternehmen f\u00fcr Verbraucherverhalten und Einzelhandel, eine Umfrage unter mehr als 10.000 Personen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1672214239"],"wp_automatic_camp":["217"],"9934025eae9cb61d4c94c1aa26fa62ac":["Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;"],"original_link":["https:\/\/de.rt.com\/inland\/158292-deutschland-verwandelt-sich-in-einen-almosenstaat\/"],"_thumbnail_id":["26437"],"jnews_social_counter_last_update":["1778489707"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2022-12-28 09:58:26\";}"]},"categories":[19,23],"tags":[179,768,38168,434,23354],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deutschland verwandelt sich in einen &quot;Almosenstaat&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;\" \/>\n<meta property=\"og:description\" content=\"Deutschland ist auf dem Weg zu einem &#8220;Almosenstaat&#8221;, warnen deutsche Sozialexperten. Ihnen zufolge drohen die explodierenden Energiepreise und die steigenden Lebenshaltungskosten die gewohnte Lebensweise der deutschen Gesellschaft zu sprengen \u2013 was dramatische Folgen f\u00fcr das Land haben k\u00f6nnte. Ende November hat NielsenIQ, ein Marktforschungsunternehmen f\u00fcr Verbraucherverhalten und Einzelhandel, eine Umfrage unter mehr als 10.000 Personen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T07:51:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;\",\"datePublished\":\"2022-12-28T07:51:15+00:00\",\"dateModified\":\"2022-12-28T07:51:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/\"},\"wordCount\":1626,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg\",\"keywords\":[\"Deutschland\",\"einen\",\"quotAlmosenstaatquot\",\"sich\",\"verwandelt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/\",\"name\":\"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg\",\"datePublished\":\"2022-12-28T07:51:15+00:00\",\"dateModified\":\"2022-12-28T07:51:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg\",\"width\":460,\"height\":259,\"caption\":\"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/","og_locale":"de_DE","og_type":"article","og_title":"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;","og_description":"Deutschland ist auf dem Weg zu einem &#8220;Almosenstaat&#8221;, warnen deutsche Sozialexperten. Ihnen zufolge drohen die explodierenden Energiepreise und die steigenden Lebenshaltungskosten die gewohnte Lebensweise der deutschen Gesellschaft zu sprengen \u2013 was dramatische Folgen f\u00fcr das Land haben k\u00f6nnte. Ende November hat NielsenIQ, ein Marktforschungsunternehmen f\u00fcr Verbraucherverhalten und Einzelhandel, eine Umfrage unter mehr als 10.000 Personen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-12-28T07:51:15+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;","datePublished":"2022-12-28T07:51:15+00:00","dateModified":"2022-12-28T07:51:15+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/"},"wordCount":1626,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg","keywords":["Deutschland","einen","quotAlmosenstaatquot","sich","verwandelt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/","url":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/","name":"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg","datePublished":"2022-12-28T07:51:15+00:00","dateModified":"2022-12-28T07:51:15+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Deutschland-verwandelt-sich-in-einen-quotAlmosenstaatquot.jpg","width":460,"height":259,"caption":"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-verwandelt-sich-in-einen-almosenstaat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Deutschland verwandelt sich in einen &quot;Almosenstaat&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/26436"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=26436"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/26436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/26437"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=26436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=26436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=26436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}