{"id":26390,"date":"2022-12-27T13:35:41","date_gmt":"2022-12-27T11:35:41","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/"},"modified":"2022-12-27T13:35:41","modified_gmt":"2022-12-27T11:35:41","slug":"viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/","title":{"rendered":"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/63aacdfb48fbef1d8d1ddd9a.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Dmitri Medwedew gab eine Prognose f\u00fcr 2023 ab. Er sagte unter anderem die Gr\u00fcndung eines Vierten Reiches durch Deutschland und die Eroberung der westlichen Gebiete der Ukraine durch Polen und Ungarn voraus. Elon Musk bezeichnete die Vorhersage als absurd.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der stellvertretende Vorsitzende des Sicherheitsrates und ehemalige Pr\u00e4sident Russlands Dmitri Medwedew hat am 26. Dezember auf seinem Telegram-Kanal geschrieben, dass die Menschen &#8220;vor dem neuen Jahr gerne Vorhersagen treffen und viele futuristische Hypothesen praktizieren, die mit Ideen des Unerwarteten und sogar des Absurden konkurrieren&#8221;. Er <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/medvedev_telegram\/237\">ver\u00f6ffentlichte<\/a> zehn Ereignisse, die seiner Meinung nach im Jahr 2023 stattfinden k\u00f6nnten. Die Liste sieht so aus:<\/p>\n<ul>\n<li>Anstieg der \u00d6lpreise auf 150 US-Dollar pro Barrel und der Gaspreise auf 5.000 US-Dollar pro 1.000 Kubikmeter;<\/li>\n<li>Gro\u00dfbritanniens R\u00fcckkehr in die Europ\u00e4ische Union;<\/li>\n<li>Zusammenbruch der Europ\u00e4ischen Union nach der R\u00fcckkehr des Vereinigten K\u00f6nigreichs und der Abschaffung des Euro als W\u00e4hrung der ehemaligen EU;<\/li>\n<li>Eroberung der westlichen Gebiete der ehemaligen Ukraine durch Polen und Ungarn;<\/li>\n<li>Gr\u00fcndung eines Vierten Reiches unter F\u00fchrungsrolle Deutschlands und der beigetretenen Satellitenstaaten Polen, Tschechische Republik, Slowakei, Rum\u00e4nien, Kiewer Republik sowie der baltischen L\u00e4nder und weiterer Ausgesto\u00dfener;<\/li>\n<li>Krieg zwischen Frankreich und dem Vierten Reich. Danach Teilung Europas und eine Neuaufteilung Polens;<\/li>\n<li>Trennung Nordirlands vom Vereinigten K\u00f6nigreich und Anschluss an die Republik Irland;<\/li>\n<li>B\u00fcrgerkrieg in den USA, Trennung von Kalifornien und Texas in unabh\u00e4ngige Staaten. Gr\u00fcndung des Unionsstaates Texas und Mexiko. Elon Musks Sieg bei der US-Pr\u00e4sidentschaftswahl in einigen Bundesstaaten, die nach dem B\u00fcrgerkrieg bei den Republikanern verbleiben werden;<\/li>\n<li>Verlagerung aller wichtigen B\u00f6rsen und Finanzaktivit\u00e4ten aus den USA und Europa nach Asien;<\/li>\n<li>Zusammenbruch des Finanzsystems von Bretton Woods einschlie\u00dflich des IWF und der Weltbank. Ablehnung von Euro und US-Dollar als Weltreservew\u00e4hrungen. R\u00fcckkehr des Goldstandards. \u00dcbergang zur aktiven Nutzung digitaler Fiat-W\u00e4hrungen.<\/li>\n<\/ul>\n<p>Mehrere Telegram-Kan\u00e4le <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/WarDonbass\/92278\">ver\u00f6ffentlichten<\/a>\u00a0eine Karte von Medwedews Vorhersagen. So k\u00f6nnte zum Beispiel der Zusammenbruch der Vereinigten Staaten laut Medwedew aussehen:<\/p>\n<p>Medwedews Vorhersage wurde auch auf Twitter geteilt.<\/p>\n<p>Der US-amerikanische Gesch\u00e4ftsmann Elon Musk nannte die zehn Vorhersagen von Dmitri Medwedew die absurdesten, die er je geh\u00f6rt habe. Er <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/elonmusk\/status\/1607565268150091778\">schrieb<\/a> auf Twitter:<\/p>\n<blockquote>\n<p><em>&#8220;Dies sind bei weitem die absurdesten Vorhersagen, die ich je geh\u00f6rt habe, und sie zeigen eine bemerkenswerte Ignoranz gegen\u00fcber dem Fortschritt der k\u00fcnstlichen Intelligenz und nachhaltiger Energie.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Zuvor hatte Musk die Prognosen als &#8220;episch&#8221; bezeichnet und darum gebeten, in einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/elonmusk\/status\/1607521467339612161\">Jahr<\/a> daran erinnert zu werden.<\/p>\n<p>Experten der d\u00e4nischen Investmentbank Saxo Bank \u00e4u\u00dfern sich jedes Jahr im Genre schockierender Prognosen, indem sie unwahrscheinliche Ereignisse von globalem Ausma\u00df vorhersagen, die erhebliche Auswirkungen auf die Weltwirtschaft haben k\u00f6nnten. Analysten der Saxo Bank prognostizierten beispielsweise im vergangenen Jahr, dass Pl\u00e4ne zum Ausstieg aus fossilen Brennstoffen in diesem Jahr aufgrund hoher Kosten auf Eis gelegt w\u00fcrden. Wie sich herausstellte, haben einige europ\u00e4ische L\u00e4nder, darunter Deutschland, dieses Jahr tats\u00e4chlich damit begonnen, Kohleenergie in das System zur\u00fcckzuf\u00fchren. Die Inflationsprognose in den USA von 15 Prozent hat sich nicht erf\u00fcllt, aber sie hat acht Prozent \u00fcberschritten und einen Rekord der vergangenen 40 Jahre aufgestellt. Die Bank prognostizierte auch einen weiteren Kalten Krieg und nannte als Ursache die Entwicklung der Hyperschalltechnologie, die das Wettrennen ins All ankurbeln werde.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/wirtschaft\/156856-oekonom-warnt-vor-schoenreden-alle-wirtschaftsindikatoren-deuten-nach-unten\/\">\u00d6konom warnt vor Sch\u00f6nreden: Alle Wirtschaftsindikatoren deuten nach unten<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/158268-viertes-reich-und-besetzung-westukraine\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dmitri Medwedew gab eine Prognose f\u00fcr 2023 ab. Er sagte unter anderem die Gr\u00fcndung eines Vierten Reiches durch Deutschland und die Eroberung der westlichen Gebiete der Ukraine durch Polen und Ungarn voraus. Elon Musk bezeichnete die Vorhersage als absurd. Der stellvertretende Vorsitzende des Sicherheitsrates und ehemalige Pr\u00e4sident Russlands Dmitri Medwedew hat am 26. Dezember auf [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1672141494"],"wp_automatic_camp":["217"],"03dff16cf68a4981a52ade70e2a93847":["Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023"],"original_link":["https:\/\/de.rt.com\/international\/158268-viertes-reich-und-besetzung-westukraine\/"],"_thumbnail_id":["26391"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2022-12-27 13:46:08\";}"],"jnews_social_counter_last_update":["1788192764"]},"categories":[19,23],"tags":[36041,82,1024,221,38133,5850,11804,6107,140,11664,33570,14420],"class_list":["post-26390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-besetzung","tag-der","tag-durch","tag-fuer","tag-medwedews","tag-polen","tag-prognose","tag-reich","tag-und","tag-ungarn","tag-viertes","tag-westukraine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023 - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023\" \/>\n<meta property=\"og:description\" content=\"Dmitri Medwedew gab eine Prognose f\u00fcr 2023 ab. Er sagte unter anderem die Gr\u00fcndung eines Vierten Reiches durch Deutschland und die Eroberung der westlichen Gebiete der Ukraine durch Polen und Ungarn voraus. Elon Musk bezeichnete die Vorhersage als absurd. Der stellvertretende Vorsitzende des Sicherheitsrates und ehemalige Pr\u00e4sident Russlands Dmitri Medwedew hat am 26. Dezember auf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-27T11:35:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023\",\"datePublished\":\"2022-12-27T11:35:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/12\\\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg\",\"keywords\":[\"Besetzung\",\"der\",\"durch\",\"f\u00fcr\",\"Medwedews\",\"Polen\",\"Prognose\",\"Reich\",\"und\",\"Ungarn\",\"viertes\",\"Westukraine\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/\",\"name\":\"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023 - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/12\\\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg\",\"datePublished\":\"2022-12-27T11:35:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/12\\\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/12\\\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg\",\"width\":460,\"height\":259,\"caption\":\"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023 - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/","og_locale":"de_DE","og_type":"article","og_title":"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023","og_description":"Dmitri Medwedew gab eine Prognose f\u00fcr 2023 ab. Er sagte unter anderem die Gr\u00fcndung eines Vierten Reiches durch Deutschland und die Eroberung der westlichen Gebiete der Ukraine durch Polen und Ungarn voraus. Elon Musk bezeichnete die Vorhersage als absurd. Der stellvertretende Vorsitzende des Sicherheitsrates und ehemalige Pr\u00e4sident Russlands Dmitri Medwedew hat am 26. Dezember auf [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-12-27T11:35:41+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023","datePublished":"2022-12-27T11:35:41+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg","keywords":["Besetzung","der","durch","f\u00fcr","Medwedews","Polen","Prognose","Reich","und","Ungarn","viertes","Westukraine"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/","url":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/","name":"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023 - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg","datePublished":"2022-12-27T11:35:41+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Viertes-Reich-und-Besetzung-der-Westukraine-durch-Polen-und-Ungarn.jpg","width":460,"height":259,"caption":"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/viertes-reich-und-besetzung-der-westukraine-durch-polen-und-ungarn-medwedews-prognose-fuer-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Viertes Reich und Besetzung der Westukraine durch Polen und Ungarn \u2013 Medwedews Prognose f\u00fcr 2023"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/26390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=26390"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/26390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/26391"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=26390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=26390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=26390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}