{"id":25551,"date":"2022-12-15T22:27:22","date_gmt":"2022-12-15T20:27:22","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/"},"modified":"2022-12-15T22:27:22","modified_gmt":"2022-12-15T20:27:22","slug":"rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/","title":{"rendered":"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/639b82ba48fbef0b4e6b98eb.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Chefredakteurin des Fernsehsenders RT, Margarita Simonjan, hat Deutschland vor &#8220;den schlimmsten Schl\u00e4gen&#8221; gewarnt. Damit reagierte sie auf die Aussage von Bundeskanzler Olaf Scholz, die Ukraine habe das Recht, nicht nur auf ihrem Territorium zuzuschlagen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Ebenso beschuldigte die Chefredakteurin Merkel und Scholz des Zynismus und der Heuchlerei:<\/p>\n<p>&#8220;Und gleichzeitig sagt Angela Merkel, dass sie die Zeit f\u00fcr die Ukraine nur hinausgez\u00f6gert haben. Und Scholz schreibt einen Programmartikel, in dem er sagt, die Russen sind Schurken, Putin ist ein schlechter Mensch, er hat die Minsker Vereinbarungen verletzt. Ihr wohnt ja nicht weit voneinander entfernt. Mensch, sprecht euch doch irgendwie ab! Ihr macht euch doch zum Narren! Ein Kanzler l\u00f6ste den anderen ab. All sie leben auf demselben au\u00dfenpolitischen Feld und sagen diametral entgegengesetzte Dinge.&#8221;<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/157347-rt-chefin-ueber-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Chefredakteurin des Fernsehsenders RT, Margarita Simonjan, hat Deutschland vor &#8220;den schlimmsten Schl\u00e4gen&#8221; gewarnt. Damit reagierte sie auf die Aussage von Bundeskanzler Olaf Scholz, die Ukraine habe das Recht, nicht nur auf ihrem Territorium zuzuschlagen. Ebenso beschuldigte die Chefredakteurin Merkel und Scholz des Zynismus und der Heuchlerei: &#8220;Und gleichzeitig sagt Angela Merkel, dass sie die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1671136559"],"wp_automatic_camp":["217"],"fbb386a1eb160f1324affc3b19287063":["RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;"],"original_link":["https:\/\/de.rt.com\/europa\/157347-rt-chefin-ueber-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/"],"_thumbnail_id":["25552"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2022-12-15 22:37:00\";}"],"jnews_social_counter_last_update":["1784138054"]},"categories":[19,23],"tags":[427,5451,23842,37567,1042,37568,139,30593,140,50,4250,1040],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;\" \/>\n<meta property=\"og:description\" content=\"Die Chefredakteurin des Fernsehsenders RT, Margarita Simonjan, hat Deutschland vor &#8220;den schlimmsten Schl\u00e4gen&#8221; gewarnt. Damit reagierte sie auf die Aussage von Bundeskanzler Olaf Scholz, die Ukraine habe das Recht, nicht nur auf ihrem Territorium zuzuschlagen. Ebenso beschuldigte die Chefredakteurin Merkel und Scholz des Zynismus und der Heuchlerei: &#8220;Und gleichzeitig sagt Angela Merkel, dass sie die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T20:27:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;\",\"datePublished\":\"2022-12-15T20:27:22+00:00\",\"dateModified\":\"2022-12-15T20:27:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\"},\"wordCount\":147,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg\",\"keywords\":[\"das\",\"quotWir\",\"RTChefin\",\"Sendeverboten\",\"tun\",\"tunquot\",\"\u00fcber\",\"umgehen\",\"und\",\"von\",\"weiterhin\",\"Werden\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\",\"name\":\"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg\",\"datePublished\":\"2022-12-15T20:27:22+00:00\",\"dateModified\":\"2022-12-15T20:27:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg\",\"width\":460,\"height\":259,\"caption\":\"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/","og_locale":"de_DE","og_type":"article","og_title":"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;","og_description":"Die Chefredakteurin des Fernsehsenders RT, Margarita Simonjan, hat Deutschland vor &#8220;den schlimmsten Schl\u00e4gen&#8221; gewarnt. Damit reagierte sie auf die Aussage von Bundeskanzler Olaf Scholz, die Ukraine habe das Recht, nicht nur auf ihrem Territorium zuzuschlagen. Ebenso beschuldigte die Chefredakteurin Merkel und Scholz des Zynismus und der Heuchlerei: &#8220;Und gleichzeitig sagt Angela Merkel, dass sie die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-12-15T20:27:22+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;","datePublished":"2022-12-15T20:27:22+00:00","dateModified":"2022-12-15T20:27:22+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/"},"wordCount":147,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg","keywords":["das","quotWir","RTChefin","Sendeverboten","tun","tunquot","\u00fcber","umgehen","und","von","weiterhin","Werden"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/","url":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/","name":"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg","datePublished":"2022-12-15T20:27:22+00:00","dateModified":"2022-12-15T20:27:22+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/RT-Chefin-ueber-das-Umgehen-von-Sendeverboten-\u2013-quotWir-tun-es.jpg","width":460,"height":259,"caption":"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-chefin-ueber-das-umgehen-von-sendeverboten-wir-tun-es-und-werden-es-weiterhin-tun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"RT-Chefin \u00fcber das Umgehen von Sendeverboten \u2013 &quot;Wir tun es und werden es weiterhin tun&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/25551"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=25551"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/25551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/25552"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=25551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=25551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=25551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}