{"id":25454,"date":"2022-12-14T21:54:23","date_gmt":"2022-12-14T19:54:23","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/"},"modified":"2022-12-14T21:54:23","modified_gmt":"2022-12-14T19:54:23","slug":"russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/","title":{"rendered":"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/6399aa9db480cc13fb0ad44b.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Ausl\u00e4ndische Firmen werden ihre &#8220;Jagd&#8221; nach Hochqualifizierten aus Russland intensivieren, sagte Ministerpr\u00e4sident Mischustin am Dienstag. Die Regierung m\u00fcsse \u00fcber Ma\u00dfnahmen nachdenken, die Russland &#8220;vor dem Verlust des intellektuellen und kulturellen Kapitals sch\u00fctzen&#8221;.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die russischen Beh\u00f6rden sollten konkrete Schritte ausarbeiten, um eine Talentabwanderung ins Ausland zu verhindern, sagte Russlands\u00a0Ministerpr\u00e4sident Michail Mischustin am Dienstag:<\/p>\n<blockquote>\n<p><em>&#8220;Es ist klar, dass ausl\u00e4ndische Organisationen jetzt versuchen werden, aktiver nach vielversprechenden Spezialisten, jungen und erfahrenen Wissenschaftlern zu jagen. Sie verbergen diesen Wunsch nicht einmal und erkl\u00e4ren dies \u00f6ffentlich&#8221;.<\/em><\/p>\n<\/blockquote>\n<p>Daher sei die Aufrechterhaltung des wissenschaftlichen und technischen Potenzials eine wichtige Aufgabe. Die Regierung m\u00fcsse im Detail \u00fcber Ma\u00dfnahmen nachdenken, die Russland &#8220;vor dem Verlust des intellektuellen und kulturellen Kapitals sch\u00fctzen&#8221;, und diejenigen unterst\u00fctzen, die weiterhin in Russland ihre Projekte entwickeln und bahnbrechende Ideen umsetzen wollen.<\/p>\n<p>Anfang November hat das russische Ministerium f\u00fcr digitale Entwicklung vorgeschlagen, attraktive Bedingungen f\u00fcr die R\u00fcckkehr von IT-Spezialisten zu schaffen, die wegen des Krieges in der Ukraine ausgereist waren. Minister Maksut Schadajew sagte damals: &#8220;Wir m\u00fcssen die Voraussetzungen daf\u00fcr schaffen, dass sie zur\u00fcckkommen wollen&#8221;. Die Aufgabe\u00a0seiner Beh\u00f6rde sei es, &#8220;in der Praxis zu zeigen, dass es sicher ist, hier weiter zu arbeiten&#8221;.<\/p>\n<p>Noch im Juni\u00a0erkl\u00e4rte der stellvertretende Innenminister Igor Subow, dass in Russland rund 170.000 IT-Spezialisten fehlen, da viele Berufst\u00e4tige das Land verlassen haben.\u00a0Die\u00a0Teilmobilmachung Ende September f\u00fchrte zu einer weiteren Fluchtwelle. Nach Angaben des britischen Beratungsunternehmens Oxford Economics sind allein im September etwa 200.000 Russen nach Kasachstan, 70.000 nach Georgien und 60.000 nach Armenien abgereist. Es gibt jedoch keine genauen Angaben, wie viele Menschen sich derzeit im Ausland aufhalten und dort auf Arbeitssuche sind.<\/p>\n<p>Laut <em>The Wall Street Journal<\/em> ist Serbien Ende November zum beliebtesten Ziel f\u00fcr russische IT-Mitarbeiter und hochqualifizierte Fachkr\u00e4fte geworden. Auch Unternehmer, K\u00fcnstler und Wissenschaftler sind laut dem Bericht nach Serbien gefl\u00fcchtet. Nach Angaben serbischer Beamter, die die Zeitung zitierte, sind seit Ende Februar zwischen 50.000 und 100.000 Menschen ins Land eingereist. Etwa 700 mit Russland verbundene Unternehmen h\u00e4tten dort ihre Niederlassungen er\u00f6ffnet.\u00a0Dar\u00fcber hinaus haben ausl\u00e4ndische Unternehmen einen Teil ihres russischen Personals nach Serbien verlegt.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/russland\/152822-russen-im-ausland-vorsitzende-des-foederationsrates-glaubt-an-rueckkehr\/\">Russen im Ausland: Vorsitzende des F\u00f6derationsrates glaubt an R\u00fcckkehr ausgewanderter B\u00fcrger<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/157183-premierminister-mischustin-warnt-vor-jagd\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ausl\u00e4ndische Firmen werden ihre &#8220;Jagd&#8221; nach Hochqualifizierten aus Russland intensivieren, sagte Ministerpr\u00e4sident Mischustin am Dienstag. Die Regierung m\u00fcsse \u00fcber Ma\u00dfnahmen nachdenken, die Russland &#8220;vor dem Verlust des intellektuellen und kulturellen Kapitals sch\u00fctzen&#8221;. Die russischen Beh\u00f6rden sollten konkrete Schritte ausarbeiten, um eine Talentabwanderung ins Ausland zu verhindern, sagte Russlands\u00a0Ministerpr\u00e4sident Michail Mischustin am Dienstag: &#8220;Es ist klar, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1671047867"],"wp_automatic_camp":["217"],"2dcbc6adab325e6468270f885af0ecd0":["Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen"],"original_link":["https:\/\/de.rt.com\/russland\/157183-premierminister-mischustin-warnt-vor-jagd\/"],"_thumbnail_id":["25455"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2022-12-14 21:58:47\";}"],"jnews_social_counter_last_update":["1778596915"]},"categories":[19,23],"tags":[37495,278,37496,37494,9770,126,50,359],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen\" \/>\n<meta property=\"og:description\" content=\"Ausl\u00e4ndische Firmen werden ihre &#8220;Jagd&#8221; nach Hochqualifizierten aus Russland intensivieren, sagte Ministerpr\u00e4sident Mischustin am Dienstag. Die Regierung m\u00fcsse \u00fcber Ma\u00dfnahmen nachdenken, die Russland &#8220;vor dem Verlust des intellektuellen und kulturellen Kapitals sch\u00fctzen&#8221;. Die russischen Beh\u00f6rden sollten konkrete Schritte ausarbeiten, um eine Talentabwanderung ins Ausland zu verhindern, sagte Russlands\u00a0Ministerpr\u00e4sident Michail Mischustin am Dienstag: &#8220;Es ist klar, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T19:54:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen\",\"datePublished\":\"2022-12-14T19:54:23+00:00\",\"dateModified\":\"2022-12-14T19:54:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg\",\"keywords\":[\"Abwanderung\",\"gegen\",\"Hochqualifizierten\",\"Mischustin\",\"Premier\",\"russland\",\"von\",\"Vorgehen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/\",\"name\":\"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg\",\"datePublished\":\"2022-12-14T19:54:23+00:00\",\"dateModified\":\"2022-12-14T19:54:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/","og_locale":"de_DE","og_type":"article","og_title":"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen","og_description":"Ausl\u00e4ndische Firmen werden ihre &#8220;Jagd&#8221; nach Hochqualifizierten aus Russland intensivieren, sagte Ministerpr\u00e4sident Mischustin am Dienstag. Die Regierung m\u00fcsse \u00fcber Ma\u00dfnahmen nachdenken, die Russland &#8220;vor dem Verlust des intellektuellen und kulturellen Kapitals sch\u00fctzen&#8221;. Die russischen Beh\u00f6rden sollten konkrete Schritte ausarbeiten, um eine Talentabwanderung ins Ausland zu verhindern, sagte Russlands\u00a0Ministerpr\u00e4sident Michail Mischustin am Dienstag: &#8220;Es ist klar, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-12-14T19:54:23+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen","datePublished":"2022-12-14T19:54:23+00:00","dateModified":"2022-12-14T19:54:23+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg","keywords":["Abwanderung","gegen","Hochqualifizierten","Mischustin","Premier","russland","von","Vorgehen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/","url":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/","name":"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg","datePublished":"2022-12-14T19:54:23+00:00","dateModified":"2022-12-14T19:54:23+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Russland-Premier-Mischustin-will-gegen-Abwanderung-von-Hochqualifizierten-vorgehen.jpg","width":460,"height":259,"caption":"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-premier-mischustin-will-gegen-abwanderung-von-hochqualifizierten-vorgehen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russland: Premier Mischustin will gegen Abwanderung von Hochqualifizierten vorgehen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/25454"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=25454"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/25454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/25455"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=25454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=25454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=25454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}