{"id":25119,"date":"2022-12-09T23:32:20","date_gmt":"2022-12-09T21:32:20","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/"},"modified":"2022-12-09T23:32:20","modified_gmt":"2022-12-09T21:32:20","slug":"zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/","title":{"rendered":"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/6393389948fbef4a81238bad.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Zwar konnte Berlin vor dem Hintergrund des Ukraine-Krieges &#8220;die gr\u00f6\u00dfte Investition in unsere Streitkr\u00e4fte seit ihrem Bestehen&#8221; durchsetzen, doch haben Bef\u00fcrworter dieser &#8220;Zeitenwende&#8221; bereits vor zehn Jahren an ihr gearbeitet. Wegen der Inflation ist die Summe einigen immer noch zu gering.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der Begriff &#8220;Zeitenwende&#8221; ist von der Jury der Gesellschaft f\u00fcr deutsche Sprache zum diesj\u00e4hrigen &#8220;Wort des Jahres&#8221; gew\u00e4hlt worden, &#8220;Krieg um Frieden&#8221; landete auf Platz zwei, wie es am Freitag hie\u00df. Vor allem im Zusammenhang mit dem Umdenken zu der milit\u00e4rischen Unterst\u00fctzung eines nicht-NATO-Staates im Krieg, der Ukraine, und einer nie zuvor da gewesenen Aufr\u00fcstung wurde der Begriff unter anderem von Bundeskanzler Olaf Scholz (SPD) aufgegriffen und gepr\u00e4gt.<\/p>\n<p>Medial ebenso wenig beachtet wie der in dieser Woche erschiene <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.icanw.de\/wp-content\/uploads\/2022\/12\/Offener-Brief_2022_ICAN-Partner_final.pdf\">Offene Brief<\/a> von zwanzig Nichtregierungsorganisationen, die eine &#8220;Zeitenwende hin zu mehr Sicherheit und Abr\u00fcstung&#8221; fordern, oder die bereits im Juli von einem breiten zivilgesellschaftlichen B\u00fcndnis veranstaltete Demonstration f\u00fcr eine &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/zivilezeitenwende.de\/\">Zivile Zeitenwende<\/a>&#8221; fand Ende November 2022 unter dem Titel &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.imi-online.de\/2022\/12\/07\/audios-vom-kongress-zeitenwende\/\">Zeitenwenden: Ukraine-Krieg und Aufr\u00fcstung<\/a>&#8221; der 26. Kongress der Informationsstelle Militarisierung (IMI) in T\u00fcbingen statt.<\/p>\n<p>IMI-Vorstand J\u00fcrgen Wagner stellte zun\u00e4chst mit einem R\u00fcckblick auf die lange Vorgeschichte der heutigen Ereignisse in der Ukraine der allzu h\u00e4ufigen Vereinfachung in der Berichterstattung die Komplexit\u00e4t entgegen, wonach der Westen durch seine aggressive Expansionspolitik eine Mitverantwortung f\u00fcr die katastrophale Lage tr\u00e4gt und daf\u00fcr, dass diese andauert. Da sowohl verhandelte Friedensvorgaben wie das Minsker Abkommen auch von ukrainischer Seite nicht eingehalten wurden und weiteren Gespr\u00e4chen, die zu einer Beilegung der Kampfhandlungen f\u00fchren k\u00f6nnten, eine Absage erteilt wurde, sei es laut Wagner offensichtlich, dass aktuell westlicherseits das Ziel verfolgt werde, durch Waffenlieferungen eine maximale Schw\u00e4chung Russlands herbeizuf\u00fchren. Die Weiterf\u00fchrung des aktuellen Kurses w\u00fcrde zwangsl\u00e4ufig auf einen jahrelangen blutigen Zerm\u00fcrbungskrieg mit unz\u00e4hligen Opfern auf beiden Seiten als Folge hinauslaufen. Die Bundesregierung m\u00fcsse sich f\u00fcr eine bedingungslose Aufnahme von Verhandlungen einsetzen.<\/p>\n<p>Stattdessen wird auf eine massive Aufr\u00fcstung gesetzt. So <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.wueste-welle.de\/mp3\/89252_Der_Totalumbau_der_Bundeswehr_Aufruestung_fuer_Grosmachtkriege_Martin_Kirsch.mp3\">kritisierte<\/a> IMI-Beirat Martin Kirsch den Umbau der Bundeswehr sowie die Aufr\u00fcstung f\u00fcr Gro\u00dfmachtkriege, die bereits lange vor dem Ukraine-Krieg begonnen, aber durch diesen an Fahrt aufgenommen habe. Mit dem NATO-Gipfel im Sommer dieses Jahres ist ein neues Streitkr\u00e4ftemodell eingef\u00fchrt worden, mit dem die F\u00e4higkeit erlangt werden solle, innerhalb von 30 Tagen 300.000 Soldaten verlegen zu k\u00f6nnen. Die Bundeswehr habe zugesagt, hierf\u00fcr 30.000 Soldaten zu stellen und der NATO einen ersten schweren Gro\u00dfverband nicht, wie urspr\u00fcnglich geplant, im Jahr 2027, sondern bereits im Jahr 2025 zur Verf\u00fcgung zu stellen. So werde die Bundeswehr konsequent darauf getrimmt, einen Krieg mit Russland f\u00fchren zu k\u00f6nnen. Ihre Strukturen w\u00fcrden derzeit daran angepasst und auch mithilfe des Sonderverm\u00f6gens das entsprechende Material beschafft, erkl\u00e4rte Kirsch.<\/p>\n<p>Eine neue \u00c4ra verst\u00e4rkter Konkurrenz gro\u00dfer M\u00e4chte hatte auch EU-Kommissionspr\u00e4sidentin Ursula von der Leyen deutlich angek\u00fcndigt. Damit einher geht laut Kirsch die entsprechende akute Aufr\u00fcstung mit Blick auf Russland und China, mit neuen NATO Battle Groups in Asien einerseits und Verst\u00e4rkungen der &#8220;Ostflanke&#8221; andererseits, mit dem Ukraine-Krieg als Hintergrund, vor dem es sich durchsetzen lie\u00dfe.<\/p>\n<p>Deutschlands herausgehobene Sonderrolle f\u00fcr das Milit\u00e4rb\u00fcndnis, die auch NATO-Generalsekret\u00e4r Stoltenberg j\u00fcngst immer offenkundiger <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/fromrussiawithlove.rtde.world\/international\/156016-nato-generalsekretaer-in-berlin-welt\/\">betonte,<\/a> wurde bereits von der fr\u00fcheren Verteidigungsministerin Annegret Kramp-Karrenbauer (CDU) vorbereitet, die schon vor zwei Jahren das Ziel ausgegeben hatte, dass Deutschland zehn Prozent der NATO-F\u00e4higkeiten zur Verf\u00fcgung stellen solle. Die Konturen dieses Plans seien nun klarer geworden, so Kirsch, und liefen darauf hinaus, dass die Bundeswehr 80.000 Soldaten samt Gesch\u00fctz in abgestufter Kampfbereitschaft halten m\u00fcsse.<\/p>\n<p>Kirsch setzte die entsprechenden \u00c4u\u00dferungen von Politikern wie Lars Klingbeil (SPD) dar\u00fcber, dass Deutschland eine milit\u00e4rische F\u00fchrungsrolle \u00fcbernehmen m\u00fcsse, in Beziehung zu dieser bereits viel l\u00e4nger vorangetriebenen Bestrebung, die sich schon bei der M\u00fcnchener Sicherheitskonferenz im Jahr 2012 gezeigt hatte. In der Tat wurden bereits vor zehn Jahren die Grundz\u00fcge dieser weniger pazifistischen deutschen Au\u00dfenpolitik von einer Reihe geneigter Vertreter von Denkfabriken, Politik und Medien ausgearbeitet, was sich unter anderem in einem Papier der Stiftung Sicherheit und Politik (SWP) und des German Marshall Funds (GMF) unter dem Titel &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.swp-berlin.org\/publications\/products\/projekt_papiere\/DeutAussenSicherhpol_SWP_GMF_2013.pdf\">Neue Macht \u2013 Neue Verantwortung<\/a> \u2013 Elemente einer deutschen Au\u00dfen- und Sicherheitspolitik f\u00fcr eine Welt im Umbruch&#8221; zeigte.<\/p>\n<p>Darin wurde noch die Haltung der deutschen \u00d6ffentlichkeit als eine Art Hindernis erw\u00e4hnt und war den Autoren als &#8220;innerstaatliche Dimension deutscher Au\u00dfenpolitik&#8221; ein Unterkapitel wert. Diesem m\u00fcsse mit &#8220;engagierterer Kommunikation mit der deutschen \u00d6ffentlichkeit&#8221; begegnet werden. Dazu ein Ausschnitt aus dem Papier von 2012:<\/p>\n<blockquote>\n<p><em>&#8220;Politik und \u00d6ffentlichkeit m\u00fcssen sich darauf einstellen, dass eine gr\u00f6\u00dfere deutsche Rolle auf globaler Ebene mit einem h\u00f6heren Aufwand an Ressourcen verbunden sein wird. Dabei sollte nicht untersch\u00e4tzt werden, dass die politische Kontrolle deutscher Au\u00dfenpolitik mit einer exponierteren Rolle schwieriger wird. Das kann Legitimationsprobleme im Inneren versch\u00e4rfen. Eine aktivere deutsche Au\u00dfenpolitik verlangt auch eine angemessene Begleitung und Kontrolle durch die Legislative. Daf\u00fcr sollten nicht zuletzt die personellen und finanziellen Ressourcen des Parlaments gest\u00e4rkt werden.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>In Bezug auf China und Russland, die als priorit\u00e4re Staaten unter den sogenannten &#8220;Herausforderern&#8221; (zu denen au\u00dferdem Indien und Brasilien geh\u00f6rten) aufgef\u00fchrt werden, hei\u00dft es darin:<\/p>\n<blockquote>\n<p><em>&#8220;\u2026 in Deutschlands Beziehungen zu den neuen wirtschaftlichen und politischen Kraftzentren der Welt (wird es) unweigerlich auch zu Konkurrenz und Konflikten kommen: um Einfluss, um den Zugang zu Ressourcen, aber auch um die Architektur der internationalen Ordnung sowie um die Geltung der Normen, die ihr zugrunde liegen. Deutschlands Interesse ist es, dass diese Konkurrenz und Konflikte in friedliche Bahnen gelenkt werden. Dazu bedarf es einer Anpassung der internationalen Ordnung, die noch immer die M\u00e4chteverteilung der Nachkriegszeit widerspiegelt. Die neuen M\u00e4chte m\u00fcssen dort angemessen repr\u00e4sentiert werden \u2013 auch, um eine (in Ans\u00e4tzen bereits sichtbare) neue Blockbildung zu verhindern.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Zum Tag der Deutschen Einheit im Jahr 2013 hat der damalige Bundespr\u00e4sident Joachim Gauck bereits die deutsche \u00d6ffentlichkeit darauf eingestimmt, dass Deutschland sich nicht l\u00e4nger &#8220;aus politischen, milit\u00e4rischen und \u00f6konomischen Konflikten&#8221; heraushalten k\u00f6nne und wieder eine Rolle in Europa und der Welt spielen m\u00fcsse, die seiner Gr\u00f6\u00dfe gerecht werde. Auf der gleichen Linie verk\u00fcndete dann auch der damalige Au\u00dfenminister Frank-Walter Steinmeier: &#8220;Deutschland ist zu gro\u00df, um Au\u00dfenpolitik nur von der Au\u00dfenlinie zu kommentieren.&#8221; Auch Ursula von der Leyen (CDU) beschrieb damals \u2013 noch vor Bekanntwerden der <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/fromrussiawithlove.rtde.world\/inland\/103824-faktisches-komplettversagen-opposition-gibt-von-der-leyen-gesamtverantwortung-in-berateraffaere\/\">Beraterskandale<\/a> \u2013 in ihrer Rolle als Verteidigungsministerin Deutschland als gro\u00dfes Land, das seine &#8220;internationale Verantwortung&#8221; wahrnehmen m\u00fcsse.<\/p>\n<p>Vor dem Hintergrund des Ukraine-Krieges werden derartige Ziele nun tatkr\u00e4ftig umgesetzt, wie Kirsch darlegte. So entstehe in Berlin derzeit ein territoriales F\u00fchrungskommando, das f\u00fcr die Heimatfront zust\u00e4ndig sei, aber auch zivil-milit\u00e4rische Eins\u00e4tze und Truppenverlegungen plane. Auch die Teilstreitkr\u00e4fte erhielten neue F\u00fchrungen, so etwa mit Blick auf die Marine in Rostock. F\u00fcr die NATO koordiniert Deutschland den Ostseeraum, der, wie auch Merle Weber auf dem Kongress beschrieb, seit Jahren immer weniger als attraktives Urlaubsziel, sondern immer mehr als milit\u00e4rstrategisches Schl\u00fcsselgebiet in Erscheinung trete, da bereits im Jahr 2020 der NATO-Block mit dem Gro\u00dfman\u00f6ver Defender Europe 20 den &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.imi-online.de\/2022\/12\/07\/audios-vom-kongress-zeitenwende\/\">Aufmarsch gegen Russland geprobt<\/a>&#8221; habe.<\/p>\n<p>Vom Westen Deutschlands aus, den niederrheinischen Orten Kalkar und Uedem, soll die Bundeswehr derweil den Luftraum des B\u00fcndnisgebiets milit\u00e4risch absichern. Zudem erweitere man das Weltraumkommando, was laut Kirsch ebenfalls nur gr\u00f6\u00dferen Milit\u00e4rm\u00e4chten m\u00f6glich sei und f\u00fcr etwas anderes als Gro\u00dfmachtkriege nicht notwendig sei, so Kirsch.<\/p>\n<blockquote>\n<p><em>&#8220;Mit den Taliban muss man sich nicht im Weltraum streiten.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Kirsch zitierte zudem die mehrfach in diesem Jahr von Bundeskanzler Scholz wiederholten Aussagen, wonach die Landes- und B\u00fcndnisverteidigung l\u00e4ngst nicht mehr innerhalb der Landesgrenzen Deutschlands stattfindet, sondern Mittel- und Osteuropa einschlie\u00dfe. In der Tat soll die Bundeswehr auch an der sogenannten Ostflanke der NATO &#8220;mehr Verantwortung&#8221; \u00fcbernehmen.<\/p>\n<p>Durch den Ukraine-Krieg findet insbesondere die milit\u00e4rische Komponente der von einigen schon lange herbeigesehnten &#8220;Zeitenwende&#8221; mehr Zuspruch, die &#8220;Legitimationsprobleme im Inneren&#8221; konnten zum Teil aufgeweicht und vor allem ein massives R\u00fcstungsbudget beschlossen werden, wie IMI-Vorstand Tobias Pfl\u00fcger in seinem Beitrag &#8220;Das Sonderverm\u00f6gen: Projekte \u2013 Struktur \u2013 Ideologie&#8221; aufzeigte.<\/p>\n<p>Neben den bereits zuvor bereitgestellten immensen Summen f\u00fcr das sogenannte Zwei-Prozent-Ziel der NATO, wonach\u00a0\u2013 ungeachtet der Wirtschaftskraft \u2013 jedes NATO-Land bis zum Jahr 2024 zwei Prozent seines BIP in die NATO-Aufr\u00fcstung zu investieren habe, trieb die Bundesregierung kurz nach dem 24. Februar das Sonderverm\u00f6gen voran, mit dem vormals umstrittene Anschaffungen wie <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/fromrussiawithlove.rtde.world\/europa\/156339-knapp-40-f-35-kampfjets\/\">F-35 Kampfjets<\/a> aus den USA finanziert werden sollen. Laut Pfl\u00fcger habe Deutschland schon lange den Anspruch, eine milit\u00e4rische F\u00fchrungsmacht zu werden und mit dem schuldenfinanzierten Sonderverm\u00f6gen st\u00fcnden nun auch die entsprechenden Ressourcen zur Verf\u00fcgung. Auf der Berlin Security Conference Ende November sagte Kanzler Olaf Scholz:<\/p>\n<blockquote>\n<p><em>&#8220;Wir sprechen hier \u00fcber die gr\u00f6\u00dfte Investition in unsere Streitkr\u00e4fte seit ihrem Bestehen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Doch dass die von vielen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/fromrussiawithlove.rtde.world\/inland\/155125-unbezahlbare-heizkosten-osnabrueck-richtet-waerme-inseln-fuer-buerger-ein\/\">fr\u00f6stelnden<\/a>, kurz oder <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.tech\/inland\/146592-waschlappen-performance-kritik-an-energiespartipps\/\">kaum duschenden<\/a> und an Lebensmitteln sparenden B\u00fcrgern vorweg kassierten dreistelligen Milliardenbetr\u00e4ge die <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/fromrussiawithlove.rtde.world\/inland\/89592-doppelt-haelt-besser-luftwaffe-stellt-zwei-regierungsflieger-g-20-japan\/\">pannenbehaftete<\/a>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/deutsch.rt.com\/inland\/79122-deutsche-militaer-ist-voelliger-murks-milliarden-berater-skandal\/\">Bundeswehr<\/a> so richtig auf Vordermann bringen, ist kaum zu beobachten. Und obwohl neben dem Sonderverm\u00f6gen auch der Wehretat auf einen historischen H\u00f6chststand angeschwollen ist, gibt es angesichts der Auswirkungen des Ukraine-Krieges und der damit verbundenen Politik neuen Anlass f\u00fcr Forderungen nach weiteren Unsummen f\u00fcr die Aufr\u00fcstung.<\/p>\n<p>Zwar war Deutschland im zweiten Jahr der Pandemie das Land mit dem drittgr\u00f6\u00dften R\u00fcstungsbudget in Mittel- und Westeuropa, seine H\u00f6he umgerechnet 56 Milliarden US-Dollar, doch hat die Inflation die Summe im Vergleich zum Vorjahr um 1,4 Prozent geschm\u00e4lert. Angesichts der in diesem Jahr noch drastischer angestiegenen Inflation \u2013 ein Faktor, der im Hinblick auf gesunkene Reall\u00f6hne insbesondere von Arbeitgeberverb\u00e4nden ungern diskutiert und stattdessen auch von arbeitgebernahen Wirtschaftsinstituten wie dem Institut der Deutschen Wirtschaft (IW) in K\u00f6ln als Risikofaktor f\u00fcr eine <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.iwkoeln.de\/presse\/iw-nachrichten\/christoph-schroeder-eine-stunde-laenger-fuer-die-tankfuellung-arbeiten.html\">angeblich drohende Lohn-Preis-Spirale<\/a> dargestellt wird, in der Arbeitnehmer mit vermeintlich exorbitanten Gehaltsforderungen eine Stagflation <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.diw.de\/de\/diw_01.c.839995.de\/nachrichten\/die_unbegruendete_angst_vor_der_lohn-preis-spirale.html\">riskieren<\/a> \u2013 ist wohl mit noch exzessiveren Forderungen nach weiteren Milliarden f\u00fcr die R\u00fcstung zu rechnen \u2013 von der gleichen Seite.\u00a0<\/p>\n<p>Schon im Oktober hatte der Bundesrechnungshof die Ausgabenpl\u00e4ne des &#8220;Sonderverm\u00f6gens Bundeswehr&#8221; bem\u00e4ngelt: Unter anderem h\u00e4tten die Gesamtausgaben f\u00fcr l\u00e4ngst eingeplante vierzig R\u00fcstungsvorhaben der Bundeswehr den Rahmen von 100 Milliarden Euro bereits \u00fcberschritten, insgesamt seien daf\u00fcr aber nur 60 Milliarden angegeben worden, so die Rechnungspr\u00fcfer. Auch sei eben kein Puffer f\u00fcr Inflation einkalkuliert, hie\u00df es in der R\u00fcge. Wom\u00f6glich wird auf diese Weise auf eine Verstetigung der erh\u00f6hten R\u00fcstungsausgaben hingearbeitet.<\/p>\n<p>Die \u00d6konomen des IW zeigten selbst auf, dass der seit rund drei Jahren andauernde Krisenmodus einen horrenden Wirtschaftsschaden angerichtet hat: &#8220;Ohne Pandemie und Krieg w\u00e4re die <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.iwkoeln.de\/presse\/pressemitteilungen\/michael-groemling-krieg-und-pandemie-kosten-420-milliarden-euro.html\">Wertsch\u00f6pfung<\/a> in Deutschland in den Jahren 2020 bis 2022 um insgesamt 420 Milliarden Euro h\u00f6her ausgefallen.&#8221; Dennoch beklagten Hubertus Bardt und Klaus-Heiner R\u00f6hl vom IW in einer Anfang der Woche ver\u00f6ffentlichten Kurzstudie mit dem Titel &#8220;Bundeswehr und Inflation\u00a0\u2013 Was bleibt von der Zeitenwende?&#8221; eine angebliche &#8220;Unterfinanzierung&#8221; des Milit\u00e4rs. Sie mahnten an, dass der &#8220;verteidigungspolitische Elan verflogen&#8221; sei, und dass &#8220;das Zwei-Prozent-Ziel (\u2026) trotz 100-Milliarden-Sonderverm\u00f6gen in weite Ferne&#8221; r\u00fccke, was sogleich als folgenreiches Problem f\u00fcr die gesteckten milit\u00e4rischen Ziele dargestellt wird:<\/p>\n<blockquote>\n<p><em>&#8220;Die 2023 r\u00fcckl\u00e4ufigen Ausgaben f\u00fcr Anschaffungen bewirken, dass die Schlie\u00dfung erkannter Ausstattungsdefizite der Bundeswehr nicht gelingt und die Einsatzbereitschaft niedrig bleibt.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Ausgerechnet die f\u00fcr viele B\u00fcrger bereits hochproblematische Inflation bietet den gegen Lohnerh\u00f6hungen wetternden, arbeitgebernahen Instituten einen Vorwand f\u00fcr Forderungen nach noch gr\u00f6\u00dferen Investitionen in die R\u00fcstung.<\/p>\n<p><strong>Mehr zum Thema <\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.tech\/inland\/141860-viel-geld-fur-wenig-sicherheit\/\">&#8220;Viel Geld f\u00fcr wenig Sicherheit&#8221; \u2013 Greenpeace warnt vor Erwerb von F-35-Bombern f\u00fcr die Bundeswehr<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/156713-zeitenwende-und-inflation-bloss-nicht\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zwar konnte Berlin vor dem Hintergrund des Ukraine-Krieges &#8220;die gr\u00f6\u00dfte Investition in unsere Streitkr\u00e4fte seit ihrem Bestehen&#8221; durchsetzen, doch haben Bef\u00fcrworter dieser &#8220;Zeitenwende&#8221; bereits vor zehn Jahren an ihr gearbeitet. Wegen der Inflation ist die Summe einigen immer noch zu gering. Der Begriff &#8220;Zeitenwende&#8221; ist von der Jury der Gesellschaft f\u00fcr deutsche Sprache zum diesj\u00e4hrigen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1670621583"],"wp_automatic_camp":["217"],"b773fc4c51c72fdf33d04de6aa87ab7e":["Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen"],"original_link":["https:\/\/de.rt.com\/inland\/156713-zeitenwende-und-inflation-bloss-nicht\/"],"_thumbnail_id":["25120"],"jnews_social_counter_last_update":["1778692337"],"enclosure":["https:\/\/www.wueste-welle.de\/mp3\/89252_Der_Totalumbau_der_Bundeswehr_Aufruestung_fuer_Grosmachtkriege_Martin_Kirsch.mp3\n50362017\naudio\/mpeg\n"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2022-12-09 23:34:17\";}"]},"categories":[19,23],"tags":[12090,48,37288,198,3340,800,37287,140,37289,5540],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen\" \/>\n<meta property=\"og:description\" content=\"Zwar konnte Berlin vor dem Hintergrund des Ukraine-Krieges &#8220;die gr\u00f6\u00dfte Investition in unsere Streitkr\u00e4fte seit ihrem Bestehen&#8221; durchsetzen, doch haben Bef\u00fcrworter dieser &#8220;Zeitenwende&#8221; bereits vor zehn Jahren an ihr gearbeitet. Wegen der Inflation ist die Summe einigen immer noch zu gering. Der Begriff &#8220;Zeitenwende&#8221; ist von der Jury der Gesellschaft f\u00fcr deutsche Sprache zum diesj\u00e4hrigen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-09T21:32:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen\",\"datePublished\":\"2022-12-09T21:32:20+00:00\",\"dateModified\":\"2022-12-09T21:32:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/\"},\"wordCount\":1969,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg\",\"keywords\":[\"blo\u00df\",\"den\",\"Elanquot\",\"Inflation\",\"lassen\",\"nicht\",\"quotverteidigungspolitischen\",\"und\",\"verpuffen\",\"Zeitenwende\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/\",\"name\":\"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg\",\"datePublished\":\"2022-12-09T21:32:20+00:00\",\"dateModified\":\"2022-12-09T21:32:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/","og_locale":"de_DE","og_type":"article","og_title":"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen","og_description":"Zwar konnte Berlin vor dem Hintergrund des Ukraine-Krieges &#8220;die gr\u00f6\u00dfte Investition in unsere Streitkr\u00e4fte seit ihrem Bestehen&#8221; durchsetzen, doch haben Bef\u00fcrworter dieser &#8220;Zeitenwende&#8221; bereits vor zehn Jahren an ihr gearbeitet. Wegen der Inflation ist die Summe einigen immer noch zu gering. Der Begriff &#8220;Zeitenwende&#8221; ist von der Jury der Gesellschaft f\u00fcr deutsche Sprache zum diesj\u00e4hrigen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-12-09T21:32:20+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen","datePublished":"2022-12-09T21:32:20+00:00","dateModified":"2022-12-09T21:32:20+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/"},"wordCount":1969,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg","keywords":["blo\u00df","den","Elanquot","Inflation","lassen","nicht","quotverteidigungspolitischen","und","verpuffen","Zeitenwende"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/","url":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/","name":"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg","datePublished":"2022-12-09T21:32:20+00:00","dateModified":"2022-12-09T21:32:20+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/12\/Zeitenwende-und-Inflation-\u2013-Bloss-nicht-den-quotverteidigungspolitischen-Elanquot-verpuffen.jpg","width":460,"height":259,"caption":"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/zeitenwende-und-inflation-bloss-nicht-den-verteidigungspolitischen-elan-verpuffen-lassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Zeitenwende und Inflation \u2013 Blo\u00df nicht den &quot;verteidigungspolitischen Elan&quot; verpuffen lassen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/25119"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=25119"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/25119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/25120"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=25119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=25119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=25119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}