{"id":23814,"date":"2022-11-22T09:22:50","date_gmt":"2022-11-22T07:22:50","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/"},"modified":"2022-11-22T09:22:50","modified_gmt":"2022-11-22T07:22:50","slug":"mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/","title":{"rendered":"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/637bc75848fbef06f21dd445.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Ukrainer prahlen offenbar mit ihren Kriegsverbrechen. Anders ist die Zurschaustellung der Folgen einer Massenerschie\u00dfung nicht zu erkl\u00e4ren. Die Reaktionen in Russland signalisieren, dass diese grausame Botschaft nicht folgenlos bleiben wird.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Wladislaw Sankin<\/em><\/p>\n<p>Wie brutal und unmenschlich diese Art der Konfliktl\u00f6sung an sich auch ist, aber auch im Krieg gibt es bestimmte Regeln und sogar Gesetze. So stellt die T\u00f6tung oder Verwundung eines K\u00e4mpfers, der seine Waffen gestreckt hat oder sich nicht mehr verteidigen kann, eine Verletzung der Gesetze des internationalen bewaffneten Konflikts dar. Dass ukrainische Soldaten diese Gesetze im Umgang mit russischen Kriegsgefangenen grob verletzen, ist seit Langem bekannt.<\/p>\n<p>Hin und wieder tauchen seit Anfang der russischen Milit\u00e4roperation in der Ukraine von den ukrainischen K\u00e4mpfern eigenh\u00e4ndig gedrehte Videos auf, die entweder die T\u00f6tung oder Verletzung russischer Gefangener zeigen. Doch die Zahl der Opfer dieser Brutalit\u00e4t lag in allen diesen F\u00e4llen zumindest laut Videos noch im einstelligen Bereich. Nach der Ver\u00f6ffentlichung des Drohnenvideos aus dem Dorf Makejewka in der Volksrepublik Lugansk am Freitag kann man nun vom ersten mit Videobeweisen dokumentierten Massenmord an Kriegsgefangenen sprechen. Laut diesem Video wurden mindestens zehn russische Soldaten auf dem Boden liegend mutma\u00dflich per Kopfschuss get\u00f6tet.<\/p>\n<p>In Russland sorgte nicht nur der Vorfall selbst f\u00fcr Wut und Entsetzen. Dass die Ukrainer nicht nur russische Kriegsgefangene erschie\u00dfen, sondern auch Zivilisten oder eigene Befehlsverweigerer, ist aus zahlreichen Zeugenaussagen hinreichend bekannt. Entsetzlich war die Tatsache, dass die ukrainischen Soldaten darauf verzichteten, diesen Massenmord zu vertuschen. Im Gegenteil, sie stellen es auch noch zur Schau, indem sie die Beweise daf\u00fcr ver\u00f6ffentlichten. Dieses Verhalten erinnert an Verbrechen der Nazis im Zweiten Weltkrieg oder der IS-Terroristen vor noch wenigen Jahren. Also an das absolut B\u00f6se, an das Unmenschliche. Denn selbst ein Verbrecher, der noch versucht, seine S\u00fcnden nur f\u00fcr sich zu behalten, indem er sein Verbrechen vertuscht, handelt menschlicher als derjenige, der mit dem begangenen Verbrechen prahlt.<\/p>\n<p>Auch wenn sie sich im Krieg als Opfer Russlands f\u00fchlen sollten, diese schmale Linie, die das Menschliche vom Unmenschlichen unterscheidet, scheint in der Ukraine schon mehrfach \u00fcberschritten worden zu sein. Au\u00dferdem sprechen die st\u00e4ndigen \u00f6ffentlichen Aufrufe zum Mord an Russen und die Zerst\u00f6rungswut in Sachen Denkm\u00e4ler und Kulturg\u00fcter daf\u00fcr, dass wieder eine Ideologie, die Gewalt und Vernichtung verherrlicht, zum ideologischen Standbein einer ganzen Nation geworden ist.<\/p>\n<p>Selbst der Westen konnte den Vorfall in Makejewka nicht ignorieren. In einigen Mainstream-Medien wird zumindest dar\u00fcber gesprochen. Die <em>New York Times<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/meinungsfreiheit.rtde.life\/europa\/155017-nyt-videos-von-angeblicher-toetung-russischer-soldaten-sind-echt\/\">h\u00e4lt <\/a>das Video nicht f\u00fcr eine Inszenierung, sondern f\u00fcr den Beweis f\u00fcr ein mutma\u00dfliches Kriegsverbrechen. &#8220;Wie kann denn so was echt sein?&#8221;, fragen sich dann auch deutsche Journalisten, die gewohnt sind, nur \u00fcber angebliche russische Kriegsverbrechen zu berichten.<\/p>\n<p>Aber die Russen, auch wenn sie solche tats\u00e4chlich begangen haben sollten, stellten Bilder ihrer Opfer bislang nicht derart zur Schau, wie dies bei ihren Gegnern in der Ukraine der Fall ist. Wer wissen will, wie die ukrainische Seite grunds\u00e4tzlich mit Bildern von Toten umgeht, sollte einmal die Hauptseite des terroristisch ausgerichteten ukrainischen regierungsnahen Hetzportals &#8220;Mirotworez&#8221; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/myrotvorets.center\/\">anschauen<\/a> (Achtung, die Bilder sind extrem verst\u00f6rend!).<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2Fkriegsverbrechen-auf-video-festgehalten-elf-russische-soldaten-von-ukrainern-hingerichtet%3Ad\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Bastarde seien diese Ukrainer, die die russischen Soldaten erschossen haben, sie sollten keine andere Strafe als &#8220;reine Bestrafung&#8221; (\u0447\u0438\u0441\u0442\u0430\u044f \u043a\u0430\u0440\u0430) bekommen, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/medvedev_telegram\/214\">kommentierte <\/a>der russische Ex-Pr\u00e4sident Dmitri Medwedew das Massaker. &#8220;Auch, wenn es Jahre dauert, sie zu finden<em>.<\/em>&#8220;<\/p>\n<p>Andere in Russland fragen sich, wie es dazu \u00fcberhaupt kommen konnte, dass die T\u00e4ter, junge M\u00e4nner aus dem grenznahen Charkow, die sich kaum von den Menschen im benachbarten russischen Belgorod unterscheiden, so etwas tun konnten. Die identifizierten ukrainischen Soldaten sollen laut russischen Angaben Absolventen einer Hochschule f\u00fcr Polizeibeamter in Charkow und ehemalige Teilnehmer eines in Russland popul\u00e4ren Sketch-Wettbewerbs sein. Das bedeutet, dass sie seinerzeit sicherlich zahlreiche informelle Kontakte nach Russland hatten.<em><\/em><\/p>\n<p>Die Journalistin, Schriftstellerin und Mitglied des russischen Menschenrechtsrates Marina Achmedowa <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/Marinaslovo\/5056\">versucht<\/a>, sich in die Psyche der Russen in der Ukraine zu versetzen, der Russen, die nun wegen der Hasspropaganda gegen alles Russische Russland und damit auch sich selbst hassen. Es h\u00e4tte eine solche Grausamkeit nicht gegeben, wenn die Gefangenen keine Russen gewesen w\u00e4ren, vermutet sie. Achmedowa merkt an, dass internationale Organisationen dieses Video zumindest zur Kenntnis nehmen, was die ukrainische Seite dazu veranlasste, eine Erkl\u00e4rung abzugeben, russische Soldaten w\u00fcrden von den Ukrainern in Notwehr erschossen.<\/p>\n<blockquote>\n<p><em>&#8220;Das liegt daran, dass die Ukraine von Tag zu Tag in ihrer Brutalit\u00e4t erwachsener wird und Grenzen \u00fcberschreitet, die selbst f\u00fcr Organisationen, die uns gegen\u00fcber voreingenommen sind, \u00fcberzogen sind.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Menschen in Russland, die nah an der Front sind, sehen im Video den Anlass, folgenschwere Konsequenzen zu ziehen. So sagt der bekannte Milit\u00e4rblogger Wladlen Tatarski in einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/voenkorKotenok\/42853\">Video-Kommentar<\/a>:<\/p>\n<blockquote>\n<p><em>&#8220;Alle, die an die Front gehen, m\u00fcssen bedenken, dass die Ukraine wie der Islamische Staat ist, nur in Europa. Es gibt keinen Grund, vor ihr zu kapitulieren, sondern bis zum Schluss Widerstand zu leisten, vor allem, wenn sich eine solche Gelegenheit bietet.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Auch der angesehene Milit\u00e4rkorrespondent Alexander Sladkow <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/Sladkov_plus\/6701\">deutet an<\/a>, dass die Get\u00f6teten sich nicht so kampflos h\u00e4tten ergeben d\u00fcrfen. &#8220;Unsere Schlussfolgerung &#8230; Vielleicht sollten wir doch nicht aufgeben? Vielleicht sollten wir auf jeden Fall bis zum Ende k\u00e4mpfen?&#8221;<\/p>\n<p>Er h\u00e4lt die Ver\u00f6ffentlichung des Videos f\u00fcr einen vors\u00e4tzlichen Akt der psychologischen Kriegsf\u00fchrung, um mehr gegenseitigen Hass zwischen den Kriegsparteien anzufachen. Dies sei im Interesse des Westens.\u00a0<\/p>\n<blockquote>\n<p><em>&#8220;Der Westen gie\u00dft \u00d6l in den Brennofen des Hasses. Der Westen beschmiert Kiew mehr und mehr mit unserem Blut.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Au\u00dferdem sei hier der Versuch erkennbar, mit diesem Video eine antiwestliche milit\u00e4rische Revolte in der Ukraine zu verhindern. Er erinnerte an den Appell des russischen Pr\u00e4sidenten am ersten Tag der Milit\u00e4roperation an das ukrainische Milit\u00e4r. Damals ging Putin davon aus, dass es einfacher sein wird, eine Einigung mit ukrainischen Armeeangeh\u00f6riger zu erzielen als mit Politikern in Kiew. Der NATO gehe es darum, eine Verbr\u00fcderung in den Sch\u00fctzengr\u00e4ben zu verhindern, so Sladkow.<\/p>\n<p>Der Feldkommandeur und Telegram-Blogger Alexander Chodakowski <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/aleksandr_skif\/2489\">erinnert<\/a> an das Gedicht des sowjetischen Schriftstellers im Gro\u00dfen Vaterl\u00e4ndischen Krieg Konstantin Simonow, der in ultimativer Form dazu aufrief, Faschisten zu t\u00f6ten (&#8220;T\u00f6te ihn, wenn dir dein Zuhause lieb ist&#8221;). Da aber ihm zufolge der Krieg in der Ukraine ein B\u00fcrgerkrieg ist, ruft er dazu auf, es den Ukrainern nicht mit gleicher M\u00fctze heimzuzahlen:<\/p>\n<p>&#8220;Wenn ich mir die Aufnahmen unserer gefangenen und get\u00f6teten Soldaten ansehe, ist das genau das, was ich sagen m\u00f6chte. Diejenigen, die das Drehbuch geschrieben haben, erwarten, dass wir es sagen (&#8220;T\u00f6te ihn&#8221;\u2013 <em>Anm. der Red.<\/em>). Und dieser Krieg muss im Sinne Tolstois verstanden werden: streng und ernsthaft, als eine schreckliche Notwendigkeit.&#8221;<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/pressefreiheit.rtde.tech\/europa\/146896-so-viel-wie-moglich-russen-ukrainischer-botschafter-kasachstan-ruege\/\">Wir m\u00fcssen so viele Russen wie m\u00f6glich t\u00f6ten&#8221; \u2013 Kasachstan r\u00fcgt Botschafter der Ukraine<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-vk\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/vk.com\/video_ext.php?oid=-134310637&amp;id=456253039&amp;hash=e7182d0dc2be570b\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/154896-mehr-oel-in-brennofen-hasses\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ukrainer prahlen offenbar mit ihren Kriegsverbrechen. Anders ist die Zurschaustellung der Folgen einer Massenerschie\u00dfung nicht zu erkl\u00e4ren. Die Reaktionen in Russland signalisieren, dass diese grausame Botschaft nicht folgenlos bleiben wird. Von Wladislaw Sankin Wie brutal und unmenschlich diese Art der Konfliktl\u00f6sung an sich auch ist, aber auch im Krieg gibt es bestimmte Regeln und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1669198325"],"wp_automatic_camp":["217"],"e44b996359d618de6219de5c1d0b499c":["&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen"],"original_link":["https:\/\/de.rt.com\/europa\/154896-mehr-oel-in-brennofen-hasses\/"],"_thumbnail_id":["23815"],"_wptgpro_p2tg_sent2tg":["a:0:{}"],"jnews_social_counter_last_update":["1788348740"]},"categories":[19,23],"tags":[133,36326,48,583,36327,29656,36137,797,33859,20104],"class_list":["post-23814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auf","tag-brennofen","tag-den","tag-des","tag-hassesquot","tag-kriegsgefangenen","tag-massenmord","tag-oel","tag-quotmehr","tag-reaktionen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen\" \/>\n<meta property=\"og:description\" content=\"Die Ukrainer prahlen offenbar mit ihren Kriegsverbrechen. Anders ist die Zurschaustellung der Folgen einer Massenerschie\u00dfung nicht zu erkl\u00e4ren. Die Reaktionen in Russland signalisieren, dass diese grausame Botschaft nicht folgenlos bleiben wird. Von Wladislaw Sankin Wie brutal und unmenschlich diese Art der Konfliktl\u00f6sung an sich auch ist, aber auch im Krieg gibt es bestimmte Regeln und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-22T07:22:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen\",\"datePublished\":\"2022-11-22T07:22:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/\"},\"wordCount\":1168,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg\",\"keywords\":[\"AUF\",\"Brennofen\",\"den\",\"des\",\"Hassesquot\",\"Kriegsgefangenen\",\"Massenmord\",\"\u00d6l\",\"quotMehr\",\"Reaktionen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/\",\"name\":\"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg\",\"datePublished\":\"2022-11-22T07:22:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen","og_description":"Die Ukrainer prahlen offenbar mit ihren Kriegsverbrechen. Anders ist die Zurschaustellung der Folgen einer Massenerschie\u00dfung nicht zu erkl\u00e4ren. Die Reaktionen in Russland signalisieren, dass diese grausame Botschaft nicht folgenlos bleiben wird. Von Wladislaw Sankin Wie brutal und unmenschlich diese Art der Konfliktl\u00f6sung an sich auch ist, aber auch im Krieg gibt es bestimmte Regeln und [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-11-22T07:22:50+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen","datePublished":"2022-11-22T07:22:50+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/"},"wordCount":1168,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg","keywords":["AUF","Brennofen","den","des","Hassesquot","Kriegsgefangenen","Massenmord","\u00d6l","quotMehr","Reaktionen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/","url":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/","name":"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg","datePublished":"2022-11-22T07:22:50+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/quotMehr-Oel-in-den-Brennofen-des-Hassesquot-\u2013-Reaktionen-auf.jpg","width":460,"height":259,"caption":"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/mehr-oel-in-den-brennofen-des-hasses-reaktionen-auf-massenmord-an-kriegsgefangenen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Mehr \u00d6l in den Brennofen des Hasses&quot; \u2013 Reaktionen auf Massenmord an Kriegsgefangenen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=23814"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/23815"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=23814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=23814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=23814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}