{"id":23718,"date":"2022-11-21T19:50:20","date_gmt":"2022-11-21T17:50:20","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/"},"modified":"2022-11-21T19:50:20","modified_gmt":"2022-11-21T17:50:20","slug":"pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/","title":{"rendered":"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/637b90f2b480cc2fb1579d36.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Schwere Sch\u00e4den, mangelhafte Wirkung, nicht erhobene Daten: Der Pharmariese Pfizer und die Zulassungsbeh\u00f6rden wussten von Beginn an \u00fcber massive Sicherheitsrisiken der mRNA-Vakzine Bescheid. Das geht laut Verein &#8220;\u00c4rzte f\u00fcr Aufkl\u00e4rung&#8221; aus den Zulassungsdokumenten hervor.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Susan Bonath<\/em><\/p>\n<p>Die COVID-19-Pandemie machte einige Pharmakonzerne so reich wie nie. In Windeseile brachten unter anderem der US-amerikanische Gigant Pfizer und sein deutscher &#8220;kleiner Bruder&#8221; BioNTech erstmals mRNA-Pr\u00e4parate &#8220;zur Vorbeugung von Infektionskrankheiten&#8221; auf den Markt \u2013 und mithilfe der Regierungen und staatlichen Institutionen eine langersehnte Profitmaschine ins Rollen. Doch die Massenimpfungen bargen weit mehr Unsicherheiten und Risiken, als \u00f6ffentlich kommuniziert wurde. Pfizer und die Beh\u00f6rden wussten das. Trotzdem werden nun sogar Kleinkinder geimpft.<\/p>\n<p>Zu diesem Ergebnis kam eine Arbeitsgruppe des Vereins &#8220;\u00c4rzte f\u00fcr Aufkl\u00e4rung&#8221; unter Biologin Sabine Stebel und Physiker Klaus Retzlaff. Sie wertete brisante Daten aus den Zulassungsstudien aus, die der Konzern Pfizer aufgrund eines Urteils des texanischen Richters Mark Pittman <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/icandecide.org\/article\/pfizers-documents-public-health-and-medical-professionals-for-transparency-documents-november-1-2022\/\">herausgeben musste<\/a>. Das Unternehmen hatte sie f\u00fcr 75 Jahre geheim halten wollen.<\/p>\n<p>In einem jetzt ver\u00f6ffentlichten\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.aerzte-fuer-aufklaerung.de\/wp-content\/uploads\/2022\/10\/2_5384512851597599474.pdf\">Papier<\/a> unter dem Titel &#8220;Was Pfizer wusste&#8221; zog die Arbeitsgruppe eine erste kritische Bilanz. Demnach h\u00e4tten die Konzerne fr\u00fchzeitig weitreichende Informationen \u00fcber mangelnde Wirksamkeit und ein im Vergleich zu klassischen Impfstoffen hohes Risiko f\u00fcr schwere Nebenwirkungen gehabt. Vielen Unsicherheiten seien sie bis heute nicht nachgegangen. Ein nachtr\u00e4glicher Ausschluss ungew\u00f6hnlich vieler Probanden erwecke den Verdacht von Manipulation.<\/p>\n<p><strong>Pr\u00e4parat l\u00e4nger im K\u00f6rper als berichtet<\/strong><\/p>\n<p>Zun\u00e4chst stellen die Autoren klar, dass es sich bei den Wirkstoffen nicht um eine nat\u00fcrliche Ribonukleins\u00e4ure (RNA) handele, die k\u00f6rpereigene Zellen zu Produzenten von viralem Spike-Protein machen soll. Vielmehr beinhalteten die Pr\u00e4parate in winzige Fettk\u00fcgelchen (Nano-Lipide) verpackte, k\u00fcnstlich ver\u00e4nderte und dadurch deutlich stabilere Boten-RNA, als sie in der Natur vorkommt. Und diese bleibt offenbar viel l\u00e4nger im K\u00f6rper als behauptet. So hie\u00df es stets, der Organismus baue diese binnen weniger Tage ab.<\/p>\n<p>Studien f\u00fchrte Pfizer dazu zwar ebenso wenig durch wie zum Verbleib der Lipid-Partikel und des produzierten Proteins \u2013 was aus den Dokumenten hervorgehe. Doch im Sommer habe etwa die US-amerikanische Seuchenschutzbeh\u00f6rde CDC die Behauptung vom schnellen Abbau der Inhaltsstoffe der Pr\u00e4parate gestrichen. Bereits zuvor hatten Wissenschaftler das Spike-Protein noch Monate nach der Injektion in den Lymphknoten nachgewiesen und dies auch publiziert.<\/p>\n<p>Pfizer berichte in seinen Papieren ebenfalls, dass sich Impfstoff-Partikel und Proteine nach 48 Stunden in verschiedenen Organen angesammelt h\u00e4tten, wie der Leber, der Milz und den weiblichen und m\u00e4nnlichen Fortpflanzungsorganen. Man k\u00f6nne, so die Autoren, also vorab nicht sagen, wo welche Zellen diese Spikes herstellten. Deren sch\u00e4dliche Wirkung sei bereits lange vor der Pandemie bekannt gewesen. Dies gehe etwa aus \u00e4lteren Patenten auf diesen Stoff und virologischen Lehrb\u00fcchern hervor, so die Autoren. Auch das deutsche Paul-Ehrlich-Institut (PEI) berichtete Anfang 2021 \u00fcber <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.pei.de\/DE\/newsroom\/pm\/jahr\/2021\/03-gewebeschaeden-zellfusion-covid-19-rolle-spikeprotein.html\">eine eigene Studie<\/a>, wonach das Spike-Protein schwere Zellsch\u00e4den verursacht.<\/p>\n<p><strong>Herzinfarkte und COVID-19 als Nebenwirkung<\/strong><\/p>\n<p>Wie bereits bekannt ist, verzichtete Pfizer unter dem Zeichen der Pandemie darauf, die Probanden \u00fcber l\u00e4ngere Zeitr\u00e4ume zu beobachten. Dies ist eigentlich vorgeschrieben in Zulassungsverfahren f\u00fcr Medikamente und Impfstoffe. Bereits sechs Monate nach ihrem Beginn entblindete der Konzern seine Zulassungsstudie; die Placebo-Gruppe wurde gro\u00dfteils geimpft und es gab keine Vergleichsgruppe mehr. Dennoch h\u00e4tten fr\u00fchzeitig brisante Daten zu Nebenwirkungen vorgelegen, so die Autoren.<\/p>\n<p>So seien Pfizer bis Ende Februar 2021 \u00fcber 42.000 F\u00e4lle von Nebenwirkungen gemeldet worden, darunter rund 2.600 schwerwiegende und \u00fcber 1.200 Todesf\u00e4lle. Bei etwa 9.400 Betroffenen sei der Ausgang der unerw\u00fcnschten Reaktion unbekannt. In der Impf-Gruppe seien viermal mehr Menschen an einem Herzinfarkt gestorben, als in der Placebo-Gruppe. Besonders merkw\u00fcrdig: Als eine der h\u00e4ufigsten Nebenwirkungen registrierte Pfizer demnach &#8220;COVID-19&#8221; \u2013 also genau das Problem, vor dem das Pr\u00e4parat sch\u00fctzen sollte. Insgesamt f\u00fchrte das Unternehmen schon damals mehr als 1.000 verschiedene Krankheitsbilder unter &#8220;unerw\u00fcnschte Reaktionen&#8221; auf.<\/p>\n<p><strong>Verschwiegene Risiken f\u00fcr Schwangere<\/strong><\/p>\n<p>Trotz bekannter gravierender Risiken sei das Pr\u00e4parat schnell f\u00fcr Schwangere empfohlen und an diese verimpft worden, r\u00fcgt die Arbeitsgruppe. Es sei etwa l\u00e4ngst bekannt gewesen, dass das Spike-Protein an den sogenannten ACE2-Rezeptor bindet. Diesen k\u00f6nne es damit theoretisch auch hemmen, was bis heute nicht ausgeschlossen worden sei. ACE-Hemmer k\u00f6nnten laut einer &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.arznei-telegramm.de\/html\/2006_07\/0607068_02.html\">Roten Liste<\/a>&#8221; von 2006 Nierensch\u00e4den, Fehlbildungen des Skeletts und des Sch\u00e4dels beim Ungeborenen hervorrufen, das Risiko daf\u00fcr sei fast dreifach erh\u00f6ht.<\/p>\n<p>Deshalb habe Pfizer schwangere Frauen in seiner ersten Zulassungsstudie ausgeschlossen. Allerdings habe es laut Dokumenten rund 270 ungeplante Schwangerschaften in der Impf-Gruppe gegeben. Problem: Nur zu 32 Schwangeren und vier Neugeborenen habe Pfizer Ende Februar Daten vorgelegt, wobei von 28 verstorbenen S\u00e4uglingen die Rede gewesen sei. Zu allen anderen gebe es keinerlei Informationen.<\/p>\n<p><strong>Impf-mRNA in der Muttermilch und nicht richtiggestellte Fake News<\/strong><\/p>\n<p>Die Beh\u00f6rden empfahlen die mRNA-Pr\u00e4parate zugleich f\u00fcr stillende M\u00fctter. Dabei h\u00e4tten Pfizer und BioNTech nie untersucht, ob sie in die Muttermilch \u00fcbergehen k\u00f6nnen. Politiker und Wissenschaftler verbreiteten damals das Ger\u00fccht \u00fcber die Massenmedien, die mRNA oder andere Bestandteile der Impfung gingen keinesfalls in die Muttermilch \u00fcber, darunter die \u00f6ffentlichen-rechtlichen Sender <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.swr3.de\/aktuell\/coronavirus\/studie-muttermilch-corona-impfung-100.html\"><em>SWR3<\/em><\/a> und <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.mdr.de\/wissen\/faktencheck\/faktencheck-impfung-muttermilch-100.html\"><em>MDR<\/em><\/a>.<\/p>\n<p>Diese &#8220;Faktenchecks&#8221; stehen bis heute im Internet, obwohl sie sich inzwischen als L\u00fcge entpuppt haben. So steht heute, gut ein Jahr sp\u00e4ter, fest: Die Boten-RNA kann sehr wohl in die Muttermilch eindringen. Dar\u00fcber berichteten unter anderem die<em><\/em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.pharmazeutische-zeitung.de\/spuren-von-impf-mrna-in-muttermilch-gefunden-135937\/\"><em>Pharmazeutische Zeitung<\/em><\/a>, das <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.aerzteblatt.de\/nachrichten\/137852\/Spuren-von-mRNA-Impfstoffen-in-Muttermilch-nachgewiesen-Stillen-moeglich\"><em>\u00c4rzteblatt<\/em><\/a>, aber auch der <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.mdr.de\/wissen\/babies-stillen-studie-mrna-impfung-spuren100.html\"><em>MDR<\/em><\/a> \u2013 ohne seinen fr\u00fcheren &#8220;Faktencheck&#8221; richtigzustellen.<\/p>\n<p>Das PEI berichtete schon vor einem Jahr von Verdachtsmeldungen von Nebenwirkungen, die gestillte S\u00e4uglinge von geimpften M\u00fcttern betrafen. In seinem zuletzt publizierten\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.pei.de\/SharedDocs\/Downloads\/DE\/newsroom\/dossiers\/sicherheitsberichte\/sicherheitsbericht-27-12-20-bis-30-06-22.pdf?__blob=publicationFile&amp;v=6\">Sicherheitsbericht<\/a> mit Angaben bis Ende Juni ist die Rede von 70 Meldef\u00e4llen dieser Art.<\/p>\n<p><strong>Erhebliche Sicherheitsl\u00fccken bei Kindern<\/strong><\/p>\n<p>F\u00fcr Kinder sehen die Arzneimittel-Richtlinien eigentlich besonders strenge Pr\u00fcfungen vor. Denn Kinder sind nicht nur Schutzbefohlene, sondern auch, wie es in der Medizin hei\u00dft, keine kleinen Erwachsenen. Doch bez\u00fcglich der Corona-Pr\u00e4parate lie\u00dfen die Beh\u00f6rden den Konzernen offensichtlich erhebliche Sicherheitsl\u00fccken durchgehen, wie die Autoren herausarbeiteten.<\/p>\n<p>So h\u00e4tten etwa 3.000 von 4.500 f\u00fcnf- bis elfj\u00e4hrigen Probanden die Zulassungsstudie vorzeitig abgebrochen. Zu ihnen gebe es keinen weiteren Angaben in den Papieren. Auch f\u00fcr Kleinkinder ab sechs Monaten h\u00e4tten die CDC Mitte Oktober gr\u00fcnes Licht gegeben, obwohl die Konzerne die Studie erst kurz zuvor gestartet hatten und diese bis 2025 laufen solle.<\/p>\n<p>Auch die Europ\u00e4ische Arzneimittelbeh\u00f6rde EMA und die EU-Kommission zogen kurz darauf nach. Letzte Woche empfahl auch die St\u00e4ndige Impfkommission (STIKO) am Robert Koch-Institut (RKI) die Pr\u00e4parate f\u00fcr Kleinkinder mit bestimmten Vorerkrankungen. Doch diese k\u00e4men in der Studie gar nicht vor.<\/p>\n<p>Die Erfahrung der letzten beiden Jahre zeigt au\u00dferdem: Echte oder angebliche Vorerkrankungen werden von Beh\u00f6rden gern herangezogen, um schwere Sch\u00e4den oder gar Todesf\u00e4lle kurz nach der Impfung vorschnell darauf zu schieben und genaue Untersuchungen zu vermeiden. So verzeichnete das Paul-Ehrlich-Institut (PEI) bereits acht gemeldete Sterbef\u00e4lle bei geimpften Kindern und Jugendlichen bis Ende des vergangenen Jahres. Trotz des unmittelbaren zeitlichen Zusammenhangs und der Tatsache, dass Kinder \u00e4u\u00dferst selten einfach tot umfallen, sieht das PEI keinen eindeutigen Bezug zur Impfung.<\/p>\n<p>Das PEI reagierte darauf noch auf andere Weise: Es publizierte die Daten zu gemeldeten Verdachtsf\u00e4llen auf schwere und t\u00f6dliche Nebenwirkungen bei geimpften Kindern einfach nicht mehr. Bereits seit Januar verschweigt es diese F\u00e4lle. Auch gegen\u00fcber der Presse <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.me\/inland\/150103-verdachtsfalle-schwerer-impfkomplikationen-bei-kindern\/\">verweigert<\/a> es jegliche Auskunft dazu.<\/p>\n<p><strong>Anw\u00e4ltin schreibt offenen Brief an STIKO<\/strong><\/p>\n<p>Die Rechtsanw\u00e4ltin Brigitte R\u00f6hrig wandte sich j\u00fcngst mit einem offenen Brief an die STIKO. In ihrem der Autorin vorliegenden Schreiben kritisierte sie deren <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rki.de\/DE\/Content\/Infekt\/EpidBull\/Archiv\/2022\/46\/Art_02.html\">Impfempfehlung<\/a> f\u00fcr vorerkrankte Kleinkinder scharf. So habe die Bundesregierung auf Anfrage keinerlei Daten zur Gef\u00e4hrdung von Kindern durch das Coronavirus liefern k\u00f6nnen. Objektiv gebe es keine Anzeichen f\u00fcr besondere Gefahren. Das Risiko durch die Injektionen sei wahrscheinlich vielfach gr\u00f6\u00dfer. Auch eine Fremdwirkung sei nicht gegeben.<\/p>\n<p>Dar\u00fcber hinaus \u00e4u\u00dferte sich die Anw\u00e4ltin f\u00fcr Medizinrecht \u00e4hnlich wie die Arbeitsgruppe. Die Daten der Konzerne seien h\u00f6chst mangelhaft, f\u00fcr Kinder mit Vorerkrankungen gebe es gar keine. Von den gesunden Kindern h\u00e4tten zwei von 200 eine schwere Nebenwirkung erlitten. Ein Nachweis f\u00fcr die behauptete Wirksamkeit fehle v\u00f6llig. Von einer positiven Nutzen-Risiko-Abw\u00e4gung k\u00f6nne keine Rede sei, so R\u00f6hrig.<\/p>\n<p>F\u00fcr die Anw\u00e4ltin ist es ein R\u00e4tsel, warum die Beh\u00f6rden trotz enormer Unsicherheiten anscheinend kritiklos mitspielen. Auch die Arbeitsgruppe sieht darin das gr\u00f6\u00dfte Problem. Obwohl die Konzerne in ihren Studien schon damals einger\u00e4umt h\u00e4tten, nichts Konkretes \u00fcber die Effektivit\u00e4t der Pr\u00e4parate und etwaige unbekannte Nebenwirkungen zu wissen, seien die Mittel reibungslos auf den Markt gelangt \u2013 unter bis heute massiv aufgeweichten Sicherheitsstandards.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.tech\/meinung\/154245-ignorierte-studien-corona-vakzine-mit\/\">Ignorierte Studien: Corona-Vakzine mit hohen Risiken f\u00fcrs Herz und umgekehrter Wirksamkeit?<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/155040-pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-wussten\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schwere Sch\u00e4den, mangelhafte Wirkung, nicht erhobene Daten: Der Pharmariese Pfizer und die Zulassungsbeh\u00f6rden wussten von Beginn an \u00fcber massive Sicherheitsrisiken der mRNA-Vakzine Bescheid. Das geht laut Verein &#8220;\u00c4rzte f\u00fcr Aufkl\u00e4rung&#8221; aus den Zulassungsdokumenten hervor. Von Susan Bonath Die COVID-19-Pandemie machte einige Pharmakonzerne so reich wie nie. In Windeseile brachten unter anderem der US-amerikanische Gigant Pfizer [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"3ea2100afe331da12411ea5046cfc35a":["Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten"],"original_link":["https:\/\/de.rt.com\/meinung\/155040-pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-wussten\/"],"_thumbnail_id":["23719"],"jnews_social_counter_last_update":["1784115611"]},"categories":[19,23],"tags":[3244,82,837,36253,36252,21414,139,140,18587],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten\" \/>\n<meta property=\"og:description\" content=\"Schwere Sch\u00e4den, mangelhafte Wirkung, nicht erhobene Daten: Der Pharmariese Pfizer und die Zulassungsbeh\u00f6rden wussten von Beginn an \u00fcber massive Sicherheitsrisiken der mRNA-Vakzine Bescheid. Das geht laut Verein &#8220;\u00c4rzte f\u00fcr Aufkl\u00e4rung&#8221; aus den Zulassungsdokumenten hervor. Von Susan Bonath Die COVID-19-Pandemie machte einige Pharmakonzerne so reich wie nie. In Windeseile brachten unter anderem der US-amerikanische Gigant Pfizer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T17:50:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten\",\"datePublished\":\"2022-11-21T17:50:20+00:00\",\"dateModified\":\"2022-11-21T17:50:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/\"},\"wordCount\":1482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg\",\"keywords\":[\"Beh\u00f6rden\",\"der\",\"Konzern\",\"mRNAPr\u00e4parate\",\"PfizerDokumente\",\"Risiken\",\"\u00fcber\",\"und\",\"Wussten\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/\",\"name\":\"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg\",\"datePublished\":\"2022-11-21T17:50:20+00:00\",\"dateModified\":\"2022-11-21T17:50:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg\",\"width\":460,\"height\":259,\"caption\":\"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/","og_locale":"de_DE","og_type":"article","og_title":"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten","og_description":"Schwere Sch\u00e4den, mangelhafte Wirkung, nicht erhobene Daten: Der Pharmariese Pfizer und die Zulassungsbeh\u00f6rden wussten von Beginn an \u00fcber massive Sicherheitsrisiken der mRNA-Vakzine Bescheid. Das geht laut Verein &#8220;\u00c4rzte f\u00fcr Aufkl\u00e4rung&#8221; aus den Zulassungsdokumenten hervor. Von Susan Bonath Die COVID-19-Pandemie machte einige Pharmakonzerne so reich wie nie. In Windeseile brachten unter anderem der US-amerikanische Gigant Pfizer [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-11-21T17:50:20+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten","datePublished":"2022-11-21T17:50:20+00:00","dateModified":"2022-11-21T17:50:20+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/"},"wordCount":1482,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg","keywords":["Beh\u00f6rden","der","Konzern","mRNAPr\u00e4parate","PfizerDokumente","Risiken","\u00fcber","und","Wussten"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/","url":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/","name":"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg","datePublished":"2022-11-21T17:50:20+00:00","dateModified":"2022-11-21T17:50:20+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Pfizer-Dokumente-Was-Konzern-und-Behoerden-ueber-Risiken-der-mRNA-Praeparate-wussten.jpg","width":460,"height":259,"caption":"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/pfizer-dokumente-was-konzern-und-behoerden-ueber-risiken-der-mrna-praeparate-wussten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Pfizer-Dokumente: Was Konzern und Beh\u00f6rden \u00fcber Risiken der mRNA-Pr\u00e4parate wussten"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23718"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=23718"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/23719"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=23718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=23718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=23718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}