{"id":23261,"date":"2022-11-16T08:41:05","date_gmt":"2022-11-16T06:41:05","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/"},"modified":"2022-11-16T08:41:05","modified_gmt":"2022-11-16T06:41:05","slug":"us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/","title":{"rendered":"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/6373ccd3b480cc1cd922b94e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Nach Ansichten des US-Abgeordneten Thomas Massie sollten die USA die milit\u00e4rische und wirtschaftliche Hilfe f\u00fcr die Ukraine so schnell wie m\u00f6glich einstellen. Zudem will Massie, dass die bereits bewilligte Unterst\u00fctzung rechtlich \u00fcberpr\u00fcft wird.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der republikanische US-Abgeordnete Thomas Massie hat erkl\u00e4rt, die Vereinigten Staaten sollten die Milit\u00e4r- und Wirtschaftshilfe f\u00fcr Kiew umgehend stoppen und dazu noch eine Untersuchung der bereits gezahlten Gelder einleiten. Diese Meinung <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/RepThomasMassie\/status\/1592190819993530371\">brachte<\/a>\u00a0der Politiker auf Twitter zum Ausdruck. Massie w\u00f6rtlich:<\/p>\n<blockquote>\n<p><em>&#8220;Wir sollten die Zahlungen an die Ukraine sofort einstellen und uns an eine gr\u00fcndliche Pr\u00fcfung der 60 Milliarden Dollar machen, die Joe Biden und der Kongress bereits dorthin geschickt haben.&#8221;<\/em><\/p>\n<\/blockquote>\n<p><em>Reuters<\/em> berichtete vor Kurzem, dass der Kreml auf die republikanische Mehrheit im Kongress nach den Zwischenwahlen hoffe. Moskau glaube angeblich, dass es Biden dadurch schwerer fallen werde, weitere Milit\u00e4rhilfepakete f\u00fcr Kiew zu genehmigen. Das <em>Wall Street Journal<\/em> f\u00fcgte hinzu, dass die republikanische Kontrolle \u00fcber das Repr\u00e4sentantenhaus die Politik des US-Pr\u00e4sidenten gegen\u00fcber der Ukraine erschweren k\u00f6nnte.<\/p>\n<p>Zuvor hatte der US-Verteidigungsexperte Harrison Cass auf die Notwendigkeit hingewiesen, der Ukraine die Finanzierung zu entziehen und eine diplomatische L\u00f6sung des Konflikts zu finden. Cass zufolge kann milit\u00e4rische\u00a0Hilfe die bewaffnete Konfrontation in der Ukraine nur verl\u00e4ngern.<\/p>\n<p>Nachdem Russland die Spezialoperation zur Befreiung des Donbass eingeleitet hatte, stellten die USA, das Vereinigte K\u00f6nigreich und die EU der ukrainischen Armee Milliarden von US-Dollar f\u00fcr Milit\u00e4rzwecke bereit. Moskau wies wiederholt darauf hin, dass der Westen versuche, die Kampfhandlungen in der Ukraine zu verl\u00e4ngern. Das russische Verteidigungsministerium betonte, dass Depots mit ausl\u00e4ndischen Waffen in der Ukraine zu legitimen Zielen f\u00fcr die russischen Luftstreitkr\u00e4fte geworden seien.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/kurz.rt.com\/3ail\">Wie die US-Regierung versucht, die Wahrnehmung \u00fcber die Milit\u00e4rhilfe f\u00fcr die Ukraine zu manipulieren<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/154473-us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach Ansichten des US-Abgeordneten Thomas Massie sollten die USA die milit\u00e4rische und wirtschaftliche Hilfe f\u00fcr die Ukraine so schnell wie m\u00f6glich einstellen. Zudem will Massie, dass die bereits bewilligte Unterst\u00fctzung rechtlich \u00fcberpr\u00fcft wird. Der republikanische US-Abgeordnete Thomas Massie hat erkl\u00e4rt, die Vereinigten Staaten sollten die Milit\u00e4r- und Wirtschaftshilfe f\u00fcr Kiew umgehend stoppen und dazu noch [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"8bb85917fdbd9401ede7c1f7b0a629d8":["US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine"],"original_link":["https:\/\/de.rt.com\/international\/154473-us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/"],"_thumbnail_id":["23262"],"jnews_social_counter_last_update":["1784002141"]},"categories":[19,23],"tags":[82,45,5375,355,221,7571,35941,127,35940],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine\" \/>\n<meta property=\"og:description\" content=\"Nach Ansichten des US-Abgeordneten Thomas Massie sollten die USA die milit\u00e4rische und wirtschaftliche Hilfe f\u00fcr die Ukraine so schnell wie m\u00f6glich einstellen. Zudem will Massie, dass die bereits bewilligte Unterst\u00fctzung rechtlich \u00fcberpr\u00fcft wird. Der republikanische US-Abgeordnete Thomas Massie hat erkl\u00e4rt, die Vereinigten Staaten sollten die Milit\u00e4r- und Wirtschaftshilfe f\u00fcr Kiew umgehend stoppen und dazu noch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-16T06:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine\",\"datePublished\":\"2022-11-16T06:41:05+00:00\",\"dateModified\":\"2022-11-16T06:41:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg\",\"keywords\":[\"der\",\"die\",\"Ende\",\"fordert\",\"f\u00fcr\",\"Hilfe\",\"sofortiges\",\"ukraine\",\"USAbgeordneter\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\",\"name\":\"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg\",\"datePublished\":\"2022-11-16T06:41:05+00:00\",\"dateModified\":\"2022-11-16T06:41:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg\",\"width\":460,\"height\":259,\"caption\":\"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/","og_locale":"de_DE","og_type":"article","og_title":"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine","og_description":"Nach Ansichten des US-Abgeordneten Thomas Massie sollten die USA die milit\u00e4rische und wirtschaftliche Hilfe f\u00fcr die Ukraine so schnell wie m\u00f6glich einstellen. Zudem will Massie, dass die bereits bewilligte Unterst\u00fctzung rechtlich \u00fcberpr\u00fcft wird. Der republikanische US-Abgeordnete Thomas Massie hat erkl\u00e4rt, die Vereinigten Staaten sollten die Milit\u00e4r- und Wirtschaftshilfe f\u00fcr Kiew umgehend stoppen und dazu noch [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-11-16T06:41:05+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine","datePublished":"2022-11-16T06:41:05+00:00","dateModified":"2022-11-16T06:41:05+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg","keywords":["der","die","Ende","fordert","f\u00fcr","Hilfe","sofortiges","ukraine","USAbgeordneter"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/","url":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/","name":"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg","datePublished":"2022-11-16T06:41:05+00:00","dateModified":"2022-11-16T06:41:05+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/US-Abgeordneter-fordert-sofortiges-Ende-der-Hilfe-fuer-die-Ukraine.jpg","width":460,"height":259,"caption":"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/us-abgeordneter-fordert-sofortiges-ende-der-hilfe-fuer-die-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"US-Abgeordneter fordert sofortiges Ende der Hilfe f\u00fcr die Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23261"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=23261"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/23262"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=23261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=23261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=23261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}