{"id":23199,"date":"2022-11-15T16:17:48","date_gmt":"2022-11-15T14:17:48","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/"},"modified":"2022-11-15T16:17:48","modified_gmt":"2022-11-15T14:17:48","slug":"nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/","title":{"rendered":"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter &#8230;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/637284a2b480cc0132636ce7.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Kurz nach dem R\u00fcckzug der russischen Armee aus Cherson trafen Nachrichten \u00fcber die Lockerung antirussischer Wirtschaftssanktionen ein. Da lie\u00df sich die russische Diplomatie den milit\u00e4risch so oder so unumg\u00e4nglichen Schritt auch noch vers\u00fc\u00dfen, sagt Tatjana Montjan.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Tatjana Montjan<\/em><\/p>\n<p>Am Freitag wurde bekannt, dass die Londoner B\u00f6rse ihre Pl\u00e4ne aufgegeben hat, den Handel mit russischem Metall zu verbieten. Dar\u00fcber hinaus hat das Vereinigte K\u00f6nigreich Finanzdienstleistungen erlaubt, die die Versorgung mit russischen D\u00fcngemitteln sicherstellen. Die Niederlande erlaubten den Abtransport von 20.000 Tonnen russischer D\u00fcngemittel aus Rotterdam, die dort wegen der Sanktionen festsa\u00dfen. Fl\u00fcssiggas von der Insel Sachalin konnte zum ersten Mal seit sechs Monaten nicht nur ohne Preisnachlass, sondern sogar mit einem Aufschlag auf den Marktpreis verkauft werden. Die T\u00fcrkei hat die Einrichtung eines Hubs f\u00fcr Erdgas auf ihrem Staatsgebiet angek\u00fcndigt und damit begonnen, russisches Gas teilweise in Rubel zu bezahlen. Die USA haben erkl\u00e4rt, dass sie keine Sanktionen gegen Indien\u00a0verh\u00e4ngen werden wegen dessen Kauf russischen Erd\u00f6ls oberhalb der US-Preisgrenzen.<\/p>\n<p>Und schlie\u00dflich der kurioseste Teil: Ist Ihnen auch aufgefallen, dass die &#8220;Schahid&#8221;-Drohnen und die Kaliber-Raketen am Himmel \u00fcber der Ukraine praktisch nicht mehr zu sehen sind? Und dies, wo man nur einen Schritt von der vollst\u00e4ndigen Zerst\u00f6rung des ukrainischen Energiesystems entfernt war, was unweigerlich zur Abwanderung von mindestens 10 Millionen Frauen, Kindern und der st\u00e4dtischen Bev\u00f6lkerung der Ukraine\u00a0in andere Teile\u00a0Europas gef\u00fchrt h\u00e4tte.<\/p>\n<p>Ich vermute, dass es die Europ\u00e4er waren, die angesichts eines drohenden migrationspolitischen Armageddons die US-Falken dazu brachten, einen Schritt zur\u00fcck zu machen und Verhandlungen mit Russland aufzunehmen. Die Tatsache, dass sich das <em>Speckreich<\/em> (<em>so bezeichnet Montjan das Kiewer Maidan-Regime &#8211; d. Red.<\/em>) unter der F\u00fchrung von Selenskij \u00fcberhaupt nicht um die humanit\u00e4re Katastrophe und das Leid der ukrainischen B\u00fcrger schert, ist allseits bekannt. Die jetzt erstmals in Kiew \u00f6ffentlich bekundete Verhandlungsbereitschaft ist nur mit einem entsprechenden Befehl aus Washington zu erkl\u00e4ren.\u00a0<\/p>\n<p>Alles in allem scheint es sehr wahrscheinlich, dass eine Art Vereinbarung getroffen wurde, deren Kernpunkt darin bestand, dass Russland sich still und leise aus Cherson zur\u00fcckzieht und die Zerst\u00f6rung der ukrainischen Elektrizit\u00e4tswirtschaft beendet wird. Es lohnt sich jedoch, die Situation aus einem anderen Blickwinkel zu betrachten, bevor man den Kreml daf\u00fcr mit Fl\u00fcchen \u00fcberzieht. Und trotz aller negativen Einstellung zu Hinterzimmerdeals im Allgemeinen sollten wir zugeben, dass die Handelsbilanz f\u00fcr den Kreml dieses Mal, so ungew\u00f6hnlich es klingt, positiv ist.<\/p>\n<p>Ich habe bereits geschrieben, dass der Abzug aus Cherson aufgrund der enormen logistischen Probleme eine milit\u00e4rische Notwendigkeit und nur eine Frage der Zeit war. Auf den Aufnahmen der Antonowski-Br\u00fccke, die im Netz kursieren, kann man sehr gut die Sch\u00e4den sehen, die durch den monatelangen ukrainischen Beschuss\u00a0von HIMARS-Raketen entstanden sind. Die Br\u00fccke ist eindeutig unpassierbar f\u00fcr Lastwagen. Es ist unrealistisch, t\u00e4glich die n\u00f6tigen Tonnen Munition und anderer milit\u00e4rischer G\u00fcter zu transportieren, um 35.000 bis 40.000 russische Soldaten zu versorgen, und es gibt auch einen Bedarf an nicht-milit\u00e4rischen G\u00fctern. Fr\u00fcher oder sp\u00e4ter h\u00e4tten Cherson und das gesamte rechte Ufer aufgegeben werden m\u00fcssen \u2013 die Frage war nur, wann\u00a0dieser Zeitpunkt sein w\u00fcrde und wie hoch die Verluste der Parteien bis dahin w\u00e4ren.<\/p>\n<p>Russland h\u00e4tte Cherson und den Br\u00fcckenkopf am rechten Dnjepr-Ufer halten k\u00f6nnen, allerdings unter hohen Kosten und gro\u00dfen Verlusten. Das Problem ist, dass die russische Armee mit ihren frisch mobilisierten K\u00e4mpfern derzeit objektiv nicht auf solche Operationen vorbereitet ist und die russische Gesellschaft nicht bereit ist, den Preis zu zahlen, der f\u00fcr Cherson zu zahlen gewesen w\u00e4re.<\/p>\n<p>Es scheint also, dass es dem Kreml gelungen ist, einen Verm\u00f6genswert \u2013 der ohnehin kaum zu halten war &#8211; gegen einige sehr reale Vorteile einzutauschen. Die vollst\u00e4ndige Liste dieser Verg\u00fcnstigungen ist uns noch nicht bekannt, aber wir werden die Situation weiter verfolgen und vielleicht k\u00f6nnen wir am Ende zumindest die allgemeinen Konturen des &#8220;Cherson-Deals&#8221; verstehen.<\/p>\n<p>Wie durch Zufall begann Russland p\u00fcnktlich zum Abzug aus Cherson pl\u00f6tzlich, im Donbass Fortschritte zu machen. Pawlowka, Opytnoe und Majorsk wurden eingenommen, und ich vermute, dass dies nicht die letzten Siedlungen in der N\u00e4he von Donezk sind, die von Russland \u00fcbernommen werden. Die Propaganda des Speckreichs zieht es vor, \u00fcber die &#8220;Verlegungen&#8221; der ukrainischen Streitkr\u00e4fte aus diesen Gebieten zu schweigen und ihre ganze Aufmerksamkeit auf Cherson zu richten.<\/p>\n<p>Nat\u00fcrlich muss Russland auch damit rechnen, dass die Ukraine ihren Teil der mutma\u00dflichen Vereinbarungen nicht einhalten wird. Auch wenn es dann nicht m\u00f6glich sein wird, schnell nach Cherson zur\u00fcckzukehren, ist es durchaus m\u00f6glich, ein paar Hundert Flugdrohnen und Marschflugk\u00f6rper in Richtung der ukrainischen Stromnetze zu starten.\u00a0<\/p>\n<p>In der Zwischenzeit m\u00fcssen die B\u00fcrger der Ukraine weiterhin mit Stromausf\u00e4llen von drei bis vier Stunden alle vier bis f\u00fcnf Stunden leben, was bei mehr oder weniger lang anhaltenden Fr\u00f6sten den Zusammenbruch des gesamten ukrainischen Energiesystems zur Folge haben kann. Objektiv sind dieses Mal beide Seiten daran interessiert, eine kleine Pause einzulegen. Russland muss Rohstoffe verkaufen, um den Staatshaushalt aufzuf\u00fcllen, und vor allem muss es Hunderttausende frisch mobilisierter K\u00e4mpfer ausbilden, bewaffnen und ausr\u00fcsten.\u00a0<\/p>\n<p>Die EU muss diesen Winter \u00fcberstehen, ohne dass Millionen aus den zugefrorenen St\u00e4dten der Ukraine in Scharen geflohener Ukrainer europ\u00e4ische Ressourcen zus\u00e4tzlich strapazieren. Die USA \u2013 und dar\u00fcber besteht trotz der unterschiedlichen Wahlkampfrhetorik ein partei\u00fcbergreifender Konsens \u2013 brauchen einen lang anhaltenden Konflikt, in dem Russland systematisch geschw\u00e4cht wird, eine kurze Pause ist f\u00fcr sie da nicht entscheidend.\u00a0<\/p>\n<p>Die einzigen, die mit der sich abzeichnenden Pause unzufrieden sind, sind die Machthaber in Kiew. F\u00fcr sie bedeutet die Pause einen Verlust an Tempo und eine St\u00e4rkung des Feindes in Gestalt der russischen Armee. Doch sie k\u00f6nnen nichts dagegen tun, weil sie ganz und gar abh\u00e4ngig sind von Waffenlieferungen und direkten Finanzspritzen westlicher G\u00f6nner. Ohne ausl\u00e4ndische Hilfe ist das Speckreich nicht lebensf\u00e4hig und wird auch gegen die russische Armee nicht l\u00e4nger als ein paar Wochen bestehen k\u00f6nnen.<\/p>\n<p>Nach dem Sieg des Kiewer Maidan, dem Besuch Burkhalters in Moskau und der Annexion der Krim gibt es f\u00fcr Russland und die Ukraine keine M\u00f6glichkeit mehr, auf der politischen Weltkarte langfristig nebeneinander zu existieren. Das war die Absicht der sehr erfahrenen und &#8220;angesehenen&#8221; &#8220;Partner aus dem Westen&#8221;, denen es bekannterma\u00dfen v\u00f6llig schnuppe ist, ob die Huronen die Mohikaner besiegen oder andersherum. Jetzt, nach der Annexion von vier weiteren Gebieten, sind ein friedliches Ende und langfristige Vereinbarungen erst recht unm\u00f6glich geworden.<\/p>\n<p>Deshalb habe ich seinerzeit gesagt, dass es keinen Sinn hat, mit Referenden und der Annexion einzelner\u00a0Gebiete\u00a0herumzuspielen. Es w\u00e4re logischer, die gesamte Ukraine auf einmal an Russland anzugliedern, so dass niemand auf die Idee k\u00e4me, es w\u00fcrde in Cherson enden. Das wird es nicht, und es ist h\u00f6chste Zeit, klarzustellen, dass Russland gezwungen sein wird, die Westgrenze der Ukraine zu erreichen, so unrealistisch das heute auch klingen mag. Verschwenden Sie also nicht Ihre Nerven\u00a0f\u00fcr taktische Truppenbewegungen. Gemessen an der Gr\u00f6\u00dfe der Gesamtaufgabe erscheinen all diese Bewegungen nichtig und klein.<\/p>\n<p>Dank seiner &#8220;angesehenen westlichen Partner&#8221; hat Russland doch noch eine Chance, den Weg der Samurai einzuschlagen \u2013 es muss sich daf\u00fcr im Inneren \u00e4ndern und neu aufstellen. Das, was jetzt geschieht, hat Wladimir Grubnik (<em>alias &#8220;Geist Neurusslands&#8221;, der <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/rtde.site\/russland\/133481-sagenumwobene-z-wie-buchstabe-zum-symbol-wurde\/\">Erfinder des &#8220;Z&#8221;-Zeichens<\/a> &#8211; d. Red.<\/em>) schon am 30. M\u00e4rz vorhergesehen, als er schrieb:<\/p>\n<blockquote>\n<p><em>&#8220;Lasst alle Hoffnung und jede Illusion fallen, zertretet euren Glauben, w\u00e4rmt euch nicht im Paternalismus. Stellt euch stattdessen den Realit\u00e4ten, denkt scharf und rechnet exakt. Nur dann wird das, was euch in den kommenden Monaten erwartet, f\u00fcr euch nicht schockierend oder unerkl\u00e4rlich sein. Die rosarote Brille wird so oder so zerspringen und ihr zerborstenes Glas wird euch blutige Wunden zuf\u00fcgen. Es wird in jedem Fall schmerzhaft werden. Aber nur dieser Schmerz kann f\u00fcr ein reinigendes Erwachen sorgen. Und daf\u00fcr, dass\u00a0wir uns im Spiegel so sehen, wie wir sind.<\/em><\/p>\n<p><em>Viele von uns dachten bis jetzt, ein junger Zwei-Meter-Blondling mit blauen Augen und durchtrainierten Muskeln zu sein, aber in Wirklichkeit sind wir ein m\u00fcder Mann mittleren Alters mit Schlafmangel, einer Reihe chronischer Krankheiten, einem Bierbauch, Kurzatmigkeit und psychischen Problemen. Was machen Sie jetzt damit? Sie sollten gl\u00fccklich sein! Freuen Sie sich, dass endlich, nach all dem patriotischen Pathos und kraftmaierischem Selbstbetrug, wir uns endlich so sehen k\u00f6nnen, wie wir sind. Auch wenn dieses Bild alles andere als das ertr\u00e4umte ist, so ist es doch real und nicht hoffnungslos.<\/em><\/p>\n<p><em>&#8216;Aber Sie sind immer noch ein z\u00e4her alter Mann, Rosenbohm!&#8217; Sehr, sehr robust \u2013 und dieser pummelige, erfrorene Mann mit Kurzatmigkeit und Bauch, der sich aufgerappelt hat, zur Vernunft gekommen ist, nicht mehr jammert und kr\u00fcmelt, seine fr\u00f6hliche Entschlossenheit an den Tag gelegt hat und w\u00fctend geworden ist, wie es sich geh\u00f6rt, kann immer noch so kr\u00e4ftig sch\u00fctteln, dass er jedes Hindernis aus dem Weg r\u00e4umt. Ganz zu schweigen von irgendeiner ehemaligen Ukraine<\/em>.<em>&#8220;<\/em><\/p>\n<\/blockquote>\n<p><strong><em>Tatjana Montjan<\/em>\u00a0<\/strong><em>ist eine prominente ukrainische Rechtsanw\u00e4ltin und Strafverteidigerin, Publizistin und Bloggerin mit Millionenpublikum. 2004 noch auf der Seite des ersten Maidan bezeichnete sie den Maidan im Herbst 2013 als Zerst\u00f6rung der ukrainischen Staatlichkeit und stellte sich entschieden gegen diesen. Vor Beginn der russischen milit\u00e4rischen Intervention musste sie Kiew verlassen, nachdem sie vor der UNO \u00fcber die Zust\u00e4nde in der Ukraine gesprochen hatte. Derzeit lebt sie im Donbass, engagiert sich f\u00fcr humanit\u00e4re Hilfe und f\u00fchrt t\u00e4gliche Videoblogs. Man kann ihr auf ihrem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/montyan2\">Telegram-Kanal<\/a> folgen. Ihr Kanal auf YouTube wurde im Fr\u00fchjahr durch das US-Unternehmen gel\u00f6scht.\u00a0<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/rtde.site\/russland\/154066-reaktionen-auf-rueckzug-russland-vom\/\">&#8220;Rettung unbezahlbarer Soldatenleben&#8221; \u2013 Reaktionen auf den R\u00fcckzug vom rechten Dnjepr-Ufer<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/154365-nach-cherson-fallen-auch-einige\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kurz nach dem R\u00fcckzug der russischen Armee aus Cherson trafen Nachrichten \u00fcber die Lockerung antirussischer Wirtschaftssanktionen ein. Da lie\u00df sich die russische Diplomatie den milit\u00e4risch so oder so unumg\u00e4nglichen Schritt auch noch vers\u00fc\u00dfen, sagt Tatjana Montjan. Von Tatjana Montjan Am Freitag wurde bekannt, dass die Londoner B\u00f6rse ihre Pl\u00e4ne aufgegeben hat, den Handel mit russischem [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"460b79466565f634cba4aa6d403ded0b":["Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ..."],"original_link":["https:\/\/de.rt.com\/meinung\/154365-nach-cherson-fallen-auch-einige\/"],"_thumbnail_id":["23200"],"jnews_social_counter_last_update":["1788390526"]},"categories":[19,23],"tags":[1475,5186,6252,4179,979,3095,4230,713,601,26874],"class_list":["post-23199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auch","tag-cherson","tag-einige","tag-fallen","tag-nach","tag-nichts","tag-nur","tag-sanktionen","tag-weiter","tag-zufall"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ... - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ...\" \/>\n<meta property=\"og:description\" content=\"Kurz nach dem R\u00fcckzug der russischen Armee aus Cherson trafen Nachrichten \u00fcber die Lockerung antirussischer Wirtschaftssanktionen ein. Da lie\u00df sich die russische Diplomatie den milit\u00e4risch so oder so unumg\u00e4nglichen Schritt auch noch vers\u00fc\u00dfen, sagt Tatjana Montjan. Von Tatjana Montjan Am Freitag wurde bekannt, dass die Londoner B\u00f6rse ihre Pl\u00e4ne aufgegeben hat, den Handel mit russischem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-15T14:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter &#8230;\",\"datePublished\":\"2022-11-15T14:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/\"},\"wordCount\":1665,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg\",\"keywords\":[\"auch\",\"Cherson\",\"einige\",\"fallen\",\"nach\",\"Nichts\",\"NUR\",\"Sanktionen\",\"weiter\",\"Zufall\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/\",\"name\":\"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ... - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg\",\"datePublished\":\"2022-11-15T14:17:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg\",\"width\":460,\"height\":259,\"caption\":\"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ...\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ... - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/","og_locale":"de_DE","og_type":"article","og_title":"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ...","og_description":"Kurz nach dem R\u00fcckzug der russischen Armee aus Cherson trafen Nachrichten \u00fcber die Lockerung antirussischer Wirtschaftssanktionen ein. Da lie\u00df sich die russische Diplomatie den milit\u00e4risch so oder so unumg\u00e4nglichen Schritt auch noch vers\u00fc\u00dfen, sagt Tatjana Montjan. Von Tatjana Montjan Am Freitag wurde bekannt, dass die Londoner B\u00f6rse ihre Pl\u00e4ne aufgegeben hat, den Handel mit russischem [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-11-15T14:17:48+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter &#8230;","datePublished":"2022-11-15T14:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/"},"wordCount":1665,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg","keywords":["auch","Cherson","einige","fallen","nach","Nichts","NUR","Sanktionen","weiter","Zufall"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/","url":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/","name":"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ... - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg","datePublished":"2022-11-15T14:17:48+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Nach-Cherson-fallen-auch-einige-Sanktionen-Nur-Zufall-nichts-weiter.jpg","width":460,"height":259,"caption":"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter ..."},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-cherson-fallen-auch-einige-sanktionen-nur-zufall-nichts-weiter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Nach Cherson fallen auch einige Sanktionen: Nur Zufall, nichts weiter &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=23199"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/23199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/23200"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=23199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=23199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=23199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}