{"id":22678,"date":"2022-11-08T16:40:00","date_gmt":"2022-11-08T14:40:00","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/"},"modified":"2022-11-08T16:40:00","modified_gmt":"2022-11-08T14:40:00","slug":"liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/","title":{"rendered":"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden"},"content":{"rendered":"<div class=\"Text-root Text-type_1 \">\n                Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Hier lesen Sie die neuesten Entwicklungen.\n            <\/div>\n<p><\/p>\n<div class=\"ArticleView-liveUpdates\">\n<div class=\"LiveUpdates-root\">\n<div class=\"LiveUpdates-content\">\n<ul class=\"LiveUpdates-list Listing-root\" data-listing=\"LiveUpdates\" data-count=\"10\">\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdates-date\">\n<p class=\"HeaderNews-root HeaderNews-type_2 \">\n                8.11.2022 16:39 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                16:39 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Russlands Verteidigungsminister Schoigu besucht Kommandopunkt im Einsatzgebiet<\/strong><\/p>\n<p>Der russische Verteidigungsminister, Sergei Schoigu, hat den Kommandopunkt der Vereinten Gruppierung der russischen Truppen inspiziert, die bei der milit\u00e4rischen Sonderoperation eingesetzt werden. Wie das Verteidigungsministerium auf Telegram bekannt gab, habe sich Schoigu\u00a0von dem Befehlshaber der Truppengruppierung, Sergei Surowikin, \u00fcber die Situation und die Handlungen des Gegners berichten lassen. Thematisiert worden sei dabei auch die Versorgung der Mobilisierten. Anschlie\u00dfend habe\u00a0der Verteidigungsminister\u00a0mehreren russischen Armeeangeh\u00f6rigen die Medaille &#8220;Goldener Stern&#8221; des Helden der Russischen F\u00f6deration, den Tapferkeitsorden und andere staatliche Auszeichnungen verliehen.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"ru\" dir=\"ltr\">\u0428\u043e\u0439\u0433\u0443 \u0437\u0430\u0441\u043b\u0443\u0448\u0430\u043b \u0434\u043e\u043a\u043b\u0430\u0434 \u043a\u043e\u043c\u0430\u043d\u0434\u0443\u044e\u0449\u0435\u0433\u043e \u041e\u0431\u044a\u0435\u0434\u0438\u043d\u0435\u043d\u043d\u043e\u0439 \u0433\u0440\u0443\u043f\u043f\u0438\u0440\u043e\u0432\u043a\u0438 \u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u0445 \u0432\u043e\u0439\u0441\u043a \u0421\u0435\u0440\u0433\u0435\u044f \u0421\u0443\u0440\u043e\u0432\u0438\u043a\u0438\u043d\u0430 \u043f\u043e \u0442\u0435\u043a\u0443\u0449\u0435\u0439 \u043e\u043f\u0435\u0440\u0430\u0442\u0438\u0432\u043d\u043e\u0439 \u043e\u0431\u0441\u0442\u0430\u043d\u043e\u0432\u043a\u0435, \u0441\u043e\u043e\u0431\u0449\u0430\u0435\u0442 \u041c\u041e \u0420\u0424:<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/87ib08vKF8\">https:\/\/t.co\/87ib08vKF8<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/Kt2T3pogXx\">pic.twitter.com\/Kt2T3pogXx<\/a><\/p>\n<p>\u2014 \u0422\u0410\u0421\u0421 (@tass_agency) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/tass_agency\/status\/1590000062431576065?ref_src=twsrc%5Etfw\">November 8, 2022<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                16:16 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Vize-Gouverneur des Gebietes Cherson: Alle Offensiven der ukrainischen Armee\u00a0an der Frontlinie gestoppt<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a669fb480cc5b5538ca65.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a669fb480cc5b5538ca65.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a669fb480cc5b5538ca65.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a669fb480cc5b5538ca65.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a669fb480cc5b5538ca65.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a669fb480cc5b5538ca65.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Auf dem Archivbild: Ein russischer Soldat<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Konstantin Michaltschewski<\/span><\/span><\/figcaption><\/figure>\n<p>Die ukrainischen Streitkr\u00e4fte h\u00e4tten versucht, die Verteidigungslinie bei Cherson zu durchbrechen. Die russische Armee\u00a0habe jedoch alle Angriffe der ukrainischen Soldaten abgewehrt. Dies <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/tass.ru\/armiya-i-opk\/16272505\">sagte<\/a> der stellvertretende Gouverneur des Gebietes Cherson, Kirill Stremoussow, am Dienstag gegen\u00fcber der russischen Nachrichtenagentur <em>TASS.<\/em>\u00a0Und er f\u00fcgte hinzu:<\/p>\n<p><em>&#8220;Die Lage ist so: Es gibt einige Angriffsversuche, aber unsere Soldaten sind im Einsatz, ebenso wie unsere Luftstreikr\u00e4fte. Es gibt keinen massiven Vormarsch.&#8221;<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                15:57 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>T\u00fcrkei bezahlt russisches Gas teilweise in Rubel<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a5defb480cc5b547059d4.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a5defb480cc5b547059d3.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a5defb480cc5b547059d4.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a5defb480cc5b547059d3.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a5defb480cc5b547059d4.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a5defb480cc5b547059d3.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Auf dem Bild: Verdichterstation Russkaja, Teil des Gas-Pipelinesystems, das Gas f\u00fcr Turkish Stream liefert<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Witali Timkiw<\/span><span class=\"RTImage-captionItem\"> \/ Sputnik<\/span><\/span><\/figcaption><\/figure>\n<p>Die T\u00fcrkei sei teilweise dazu \u00fcbergegangen, russische Gaslieferungen in Rubel zu bezahlen, so der t\u00fcrkische Energieminister Fatih D\u00f6nmez. In einem Interview mit dem Fernsehsender <em>TRT TV<\/em> sagte der Beamte:<\/p>\n<p><em>&#8220;Wie Sie wissen, ist eine Einigung erzielt worden, die Teilzahlung hat bereits begonnen. Wir beabsichtigen, unsere Arbeit in dieser Richtung zu intensivieren.&#8221;<\/em><\/p>\n<p>Ihm zufolge f\u00fchrten Ankara und Moskau derzeit technische Arbeiten\u00a0f\u00fcr den\u00a0Handel mit nationalen W\u00e4hrungen durch.<\/p>\n<p>Wladimir Putin und Recep Tayyip Erdo\u011fan hatten im September vereinbart, dass die T\u00fcrkei 25 Prozent der Gaslieferungen in Rubel bezahlen wird. Am 12. Oktober schlug Putin sodann in einer Rede auf der &#8220;Russian Energy Week&#8221; vor, den Transit von den Nord-Stream-Pipelines in die Schwarzmeerregion umzuleiten und in der T\u00fcrkei ein gro\u00dfes Gasdrehkreuz zur Versorgung Europas einzurichten. Erdo\u011fan seinerseits erkl\u00e4rte, er habe Anweisung erteilt, mit den Arbeiten an dieser Idee rasch zu beginnen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                15:38 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Ein M\u00e4dchen bei Beschuss von Donezk ums Leben gekommen<\/strong><\/p>\n<p>Bei dem Beschuss\u00a0des Donezker Stadtbezirkes Kirowski durch ukrainische Truppen ist eine Jugendliche ums Leben gekommen. Dies <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/TRO_DPR\/9518\">teilte<\/a>\u00a0der Stab der territorialen Verteidigung der\u00a0DVR am Dienstag mit. Sp\u00e4ter <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/kulemzin_donetsk\/10519\">erkl\u00e4rte<\/a> der B\u00fcrgermeister von Donezk, Alexei Kulemsin,\u00a0das Todesopfer sei\u00a0ein im Jahr 2007 geborenes M\u00e4dchen.<\/p>\n<p>Die Vertretung der Donezker Volksrepublik bei dem Gemeinsamen Zentrum f\u00fcr die Kontrolle und Koordinierung von Fragen im Zusammenhang mit ukrainischen Kriegsverbrechen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/s\/online_dnr_sckk\">berichtet<\/a>, dass am\u00a0Dienstag von der ukrainischen Seite insgesamt sieben Geschosse abgefeuert worden seien. Auf den <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/TRO_DPR\/9520\">Fotos<\/a>, die der Verteidigungsstab der DVR ver\u00f6ffentlichte, sind die Folgen des Beschusses zu sehen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                15:09 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>UN-Botschafterin der USA f\u00fcr Gespr\u00e4che in Kiew<\/strong><\/p>\n<p>Die US-Botschafterin bei den Vereinten Nationen, Linda Thomas-Greenfield, ist zu Gespr\u00e4chen in der ukrainischen Hauptstadt Kiew eingetroffen. Nach ihrer Ankunft mit dem Zug besuchte die Diplomatin zun\u00e4chst ein Getreidewerk, wie eine mitreisende Reporterin des Radiosenders <em>NPR<\/em> berichtete. Auf ihrem Twitter-Kanal schrieb\u00a0Linda Thomas-Greenfield dazu:<\/p>\n<p><em>&#8220;Ich freue mich darauf, mit dem ukrainischen Volk, den humanit\u00e4ren\u00a0F\u00fchrungskr\u00e4ften und Regierungsbeamten zusammenzuarbeiten.&#8221;<\/em><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Good morning from Kyiv ????????I&#8217;m looking forward to engaging with the Ukrainian people, humanitarian leaders, and government officials.<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/UnitedWithUkraine?src=hash&amp;ref_src=twsrc%5Etfw\">#UnitedWithUkraine<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/o6wk3DANW9\">pic.twitter.com\/o6wk3DANW9<\/a><\/p>\n<p>\u2014 Ambassador Linda Thomas-Greenfield (@USAmbUN) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/USAmbUN\/status\/1589953984261156865?ref_src=twsrc%5Etfw\">November 8, 2022<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                14:45 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Stadt Jassinowataja in Donezker Volksrepublik unter ukrainischem Beschuss \u2013 Brand\u00a0in Umspannwerk gemeldet<\/strong><\/p>\n<p>Ukrainische Truppen haben am Donnerstag die Stadt Jassinowataja in der Volksrepublik Donezk beschossen. Dies <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/s\/online_dnr_sckk\">teilte<\/a>\u00a0die Vertretung der Donezker Volksrepublik bei dem Gemeinsamen Zentrum f\u00fcr die Kontrolle und Koordinierung von Fragen im Zusammenhang mit ukrainischen Kriegsverbrechen mit. Insgesamt\u00a0h\u00e4tten die ukrainischen Streitkr\u00e4fte acht Geschosse auf Jassinowataja abgefeuert. Der Stab der territorialen Verteidigung erkl\u00e4rte, dass anschlie\u00dfend mehr als 4.600 Haushalte ohne Strom geblieben seien. In dem Umspannwerk, das die Stadt mit Strom versorgt,\u00a0sei ein Brand gemeldet worden. Der Chef der Stadtverwaltung, Dmitri Schewtschenko, ver\u00f6ffentlichte\u00a0ein\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/shevchenko_yas\/6584\">Video<\/a>, auf dem der\u00a0Brand zu sehen ist.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                14:27 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Russisches Verteidigungsministerium: Mehr als 500 ukrainische Soldaten binnen 24 Stunden get\u00f6tet<\/strong><\/p>\n<p>Der Sprecher des russischen Verteidigungsministeriums, Generalleutnant Igor Konaschenkow, gab sein t\u00e4gliches Briefing \u00fcber den Stand der russischen milit\u00e4rischen Sonderoperation in der Ukraine. Die russischen Streitkr\u00e4fte h\u00e4tten die Offensiven und Gegenoffensiven der ukrainischen\u00a0Armee in den Richtungen Kupjansk, Krasny-Liman, S\u00fcd-Donezk und Nikolajew-Kriwoi Rog <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/mod_russia\/21595\">gestoppt<\/a>. Infolgedessen seien \u00fcber 500 ukrainische Soldaten get\u00f6tet sowie f\u00fcnf Panzer, siebzehn gepanzerte Kampffahrzeuge, drei Sch\u00fctzenpanzer, vier Kleinlastwagen und vierzehn Fahrzeuge zerst\u00f6rt worden.<strong><\/strong><\/p>\n<p>Konaschenkow sagte auch, dass die operative und taktische Luftfahrt sowie die Raketentruppen und die Artillerie Russlands vier Gefechtsst\u00e4nde der ukrainischen Streitkr\u00e4fte, 64 ukrainische Artillerieeinheiten, drei Munitions- und Raketenartillerie-Waffendepots sowie ein Treibstofflager f\u00fcr die milit\u00e4rische Ausr\u00fcstung der ukrainischen Streitkr\u00e4fte zerst\u00f6rt h\u00e4tten. Der Sprecher f\u00fcgte hinzu, die russische Armee habe eine Radarstation des ukrainischen Flugabwehrraketensystems S-300 und ein US-amerikanisches AN\/TPQ-64-Batterieabwehrradar zerst\u00f6rt.<\/p>\n<p>Das russische Verteidigungsministerium teilte au\u00dferdem mit, dass die russische Luftwaffe einen Mi-24-Hubschrauber der ukrainischen Luftstreitkr\u00e4fte <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/mod_russia\/21596\">eliminiert<\/a>\u00a0habe, w\u00e4hrend die russische Flugabwehr ein Su-25-Flugzeug der ukrainischen Luftstreitkr\u00e4fte abgeschossen\u00a0habe. Dar\u00fcber hinaus seien sieben ukrainische unbemannte Luftfahrzeuge in der Luft zerst\u00f6rt und 17 Raketen der Mehrfachraketen-Systeme HIMARS und Olcha abgefangen worden.<\/p>\n<p>Seit Beginn der russischen Milit\u00e4roperation seien insgesamt 332 Flugzeuge, 171 Hubschrauber, 2.465 unbemannte Luftfahrzeuge, 388 Boden-Luft-Raketensysteme, 6.448 Panzer und andere gepanzerte Kampffahrzeuge, 884 Mehrfachraketenwerfer, 3.563 Feldartillerie- und M\u00f6rsergesch\u00fctze und 7.127 milit\u00e4rische Spezialfahrzeuge der ukrainischen Streitkr\u00e4fte <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/mod_russia\/21597\">zerst\u00f6rt<\/a> worden.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                13:55 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Russisches Au\u00dfenamt: Moskau stellt keine Bedingungen f\u00fcr Gespr\u00e4che mit Kiew<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a3fedb480cc18c12f28e7.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a3fedb480cc18c12f28e7.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a3fedb480cc18c12f28e7.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a3fedb480cc18c12f28e7.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a3fedb480cc18c12f28e7.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a3fedb480cc18c12f28e7.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Auf dem Archivbild: Das Geb\u00e4ude des russischen Au\u00dfenministeriums in Moskau<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">DIMITAR DILKOFF<\/span><span class=\"RTImage-captionItem\"> \/ AFP<\/span><\/span><\/figcaption><\/figure>\n<p>Russlands stellvertretender Au\u00dfenminister Andrei Rudenko teilt mit, dass Moskau keine Bedingungen f\u00fcr Verhandlungen mit Kiew stellt. Er weist darauf hin, dass der Kreml wiederholt Bereitschaft zu Verhandlungen signalisiert habe, die Ukraine habe diese Versuche aber stets abgewiesen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                13:43 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Ehemaliger Abgeordneter der Werchowna Rada: Selenskijs B\u00fcro erw\u00e4gt Option, Donbass aufzugeben<\/strong><\/p>\n<p>Ilja Kiwa, der ehemalige Abgeordnete der Werchowna Rada, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/The_Kyva\/4141\">sagte<\/a>, dass nach seinen Angaben das B\u00fcro des ukrainischen Pr\u00e4sidenten Wladimir Selenskij an einer Verhandlungsposition arbeite. Insbesondere werde eine Option erwogen, den Donbass sowie den Zugang zum Schwarzen und Asowschen Meer aufzugeben. Der neutrale Status der Ukraine und die teilweise Anerkennung neuer Gebiete der Russischen F\u00f6deration soll auch in Betracht gezogen werden. Voraussetzung sei, dass Selenskij an der Macht bleibe und die Feindseligkeiten vollst\u00e4ndig eingestellt w\u00fcrden. \u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"LiveUpdates-item Listing-item\">\n<div class=\"LiveUpdate-root\">\n<div class=\"LiveUpdate-date\">\n<p class=\"HeaderNews-root HeaderNews-type_6 \">\n                13:20 Uhr\n            <\/p>\n<\/div>\n<div class=\"LiveUpdate-content\">\n<div class=\"LiveUpdate-text\">\n<div class=\"Text-root Text-type_5 ViewText-root\">\n<p><strong>Pressesprecher des ukrainischen Pr\u00e4sidenten: Selenskij plant Teilnahme an G20-Gipfel<\/strong><\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a337eb480cc24040982f8.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a337eb480cc24040982f8.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a337eb480cc24040982f8.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a337eb480cc24040982f8.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a337eb480cc24040982f8.jpg\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/636a337eb480cc24040982f8.jpg\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Das Logo des G20-Gipfels<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\">Illustration by Rafael Henrique\/SOPA Images\/LightRocke<\/span><span class=\"RTImage-captionItem\"> \/ Gettyimages.ru<\/span><\/span><\/figcaption><\/figure>\n<p>Der Pressesprecher des ukrainischen Pr\u00e4sidenten gab bekannt, dass Selenskij am G20-Gipfel in Indonesien teilnehmen wolle. Er werde aber nicht pers\u00f6nlich anwesend sein, sondern eine Videobotschaft aufzeichnen oder online sprechen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<\/ul>\n<div class=\"Listing-isReact\" data-rtmodule=\"Listing\" onload=\"return {\n                page: '1',\n                limit: '10',\n                listing: '\/listing\/parent.6209f961b480cc2c7e35341b\/noprepare\/liveupdates\/10\/1',\n            };\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/131481-liveticker-ukraine-krieg-russisches-militar\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Hier lesen Sie die neuesten Entwicklungen. 8.11.2022 16:39 Uhr 16:39 Uhr Russlands Verteidigungsminister Schoigu besucht Kommandopunkt im Einsatzgebiet Der russische Verteidigungsminister, Sergei Schoigu, hat den Kommandopunkt [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"4c25214a3031f4eb517f32f0cac7c060":["Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden"],"original_link":["https:\/\/de.rt.com\/international\/131481-liveticker-ukraine-krieg-russisches-militar\/"],"_thumbnail_id":["22679"],"_wptg_p2tg_sent2tg":["2022-11-08 17:59:53"],"jnews_social_counter_last_update":["1778228761"]},"categories":[19,23],"tags":[34703,564,4029,795,2333,4231,4032,139,566,905],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden\" \/>\n<meta property=\"og:description\" content=\"Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Hier lesen Sie die neuesten Entwicklungen. 8.11.2022 16:39 Uhr 16:39 Uhr Russlands Verteidigungsminister Schoigu besucht Kommandopunkt im Einsatzgebiet Der russische Verteidigungsminister, Sergei Schoigu, hat den Kommandopunkt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-08T14:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden\",\"datePublished\":\"2022-11-08T14:40:00+00:00\",\"dateModified\":\"2022-11-08T14:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/\"},\"wordCount\":1239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg\",\"keywords\":[\"binnen\",\"Liveticker\",\"Milit\u00e4r\",\"Russisches\",\"Soldaten\",\"STUNDEN\",\"t\u00f6tet\",\"\u00fcber\",\"UkraineKrieg\",\"Ukrainische\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/\",\"name\":\"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg\",\"datePublished\":\"2022-11-08T14:40:00+00:00\",\"dateModified\":\"2022-11-08T14:40:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/","og_locale":"de_DE","og_type":"article","og_title":"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden","og_description":"Russland f\u00fchrt gemeinsam mit den Streitkr\u00e4ften der Donbass-Republiken eine Milit\u00e4roperation in der Ukraine durch. Der Westen reagiert mit immer neuen Waffenlieferungen an die Ukraine und beispiellosen Sanktionen gegen Russland. Hier lesen Sie die neuesten Entwicklungen. 8.11.2022 16:39 Uhr 16:39 Uhr Russlands Verteidigungsminister Schoigu besucht Kommandopunkt im Einsatzgebiet Der russische Verteidigungsminister, Sergei Schoigu, hat den Kommandopunkt [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-11-08T14:40:00+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden","datePublished":"2022-11-08T14:40:00+00:00","dateModified":"2022-11-08T14:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/"},"wordCount":1239,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg","keywords":["binnen","Liveticker","Milit\u00e4r","Russisches","Soldaten","STUNDEN","t\u00f6tet","\u00fcber","UkraineKrieg","Ukrainische"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/","url":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/","name":"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg","datePublished":"2022-11-08T14:40:00+00:00","dateModified":"2022-11-08T14:40:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Liveticker-Ukraine-Krieg-Russisches-Militaer-toetet-ueber-500-ukrainische-Soldaten-binnen.jpg","width":1620,"height":1080,"caption":"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/liveticker-ukraine-krieg-russisches-militaer-toetet-ueber-500-ukrainische-soldaten-binnen-24-stunden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Liveticker Ukraine-Krieg: Russisches Milit\u00e4r t\u00f6tet \u00fcber 500 ukrainische Soldaten binnen 24 Stunden"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/22678"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=22678"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/22678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/22679"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=22678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=22678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=22678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}