{"id":20003,"date":"2022-09-29T08:33:42","date_gmt":"2022-09-29T06:33:42","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/"},"modified":"2022-09-29T08:33:42","modified_gmt":"2022-09-29T06:33:42","slug":"pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/","title":{"rendered":"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/6331648248fbef5eb44757d7.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Im dritten Corona-Jahr stellt sich vielen Menschen die Frage nach den Gr\u00fcnden f\u00fcr ihren Gesundheitszustand. Chronisches Fatigue-Syndrom oder Long COVID nach Corona-Infektion? \u00dcberraschend best\u00e4tigt Medien-Promi von Hirschhausen die Existenz einer dritten Variante: des Post-Vac-Syndroms.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Bernhard Loyen<\/em><\/p>\n<p>Dr. Eckart von Hirschhausen gilt seit Beginn der Corona-Krise im Jahre 2020 als einer der\u00a0vehementesten Unterst\u00fctzer der politisch verordneten Ma\u00dfnahmen. Von Hirschhausen ist offizieller <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bmz.de\/de\/aktuelles\/zeitfragen\/sdg-3-97428\">Botschafter<\/a>\u00a0f\u00fcr &#8220;Globale Gesundheit der Agenda 2030 f\u00fcr das Bundesministerium f\u00fcr wirtschaftliche Zusammenarbeit und Entwicklung (BMZ)&#8221;. Zudem ist er als regelm\u00e4\u00dfiger Gast wie auch prominenter Darsteller diverser Fernsehformate, unter anderem als Fernsehmoderator, Kabarettist und Comedian, nachweislich ein gesch\u00e4tzter wie beliebter Medienprofi.<\/p>\n<p>Des Weiteren\u00a0hat er \u00fcber 20 B\u00fccher und H\u00f6rb\u00fccher <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.hirschhausen.com\/kontakt\/lebenslauf.php\">ver\u00f6ffentlicht<\/a>, so im Juni 2021 &#8220;Das Impfbuch f\u00fcr alle&#8221;, eine <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.impfen-info.de\/mediathek\/das-impfbuch\/\">Zusammenarbeit<\/a> mit dem Robert Koch-Institut (RKI) und der Bundeszentrale f\u00fcr gesundheitliche Aufkl\u00e4rung (BZgA). <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.deutsche-apotheker-zeitung.de\/news\/artikel\/2021\/06\/01\/anrufe-wegen-hirschhausen-buch-sind-vom-bmg-autorisiert\">Auflage<\/a>: drei Millionen kostenfrei erh\u00e4ltliche Exemplare. Seine pers\u00f6nliche Meinung und dementsprechende Einsch\u00e4tzungen und \u00c4u\u00dferungen erzielen daher eine nicht zu untersch\u00e4tzende, aber auch beabsichtigte <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.altenpflege-online.net\/artikel\/2022_03\/2022_03_01_hirschhausen_unterstuetzt_corona_impfkampagne\">gesellschaftliche Wirkung<\/a>. So hie\u00df es noch\u00a0im M\u00e4rz 2022: &#8220;Der Mediziner und Kabarettist Dr. Eckart von Hirschhausen wird zum Gesicht der Corona-Impfkampagne der Berufsgenossenschaft f\u00fcr Gesundheitsdienst und Wohlfahrtspflege (BGW).&#8221;<\/p>\n<p>In den Jahren 2020 bis 2022 unterst\u00fctzte von Hirschhausen jede <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=6ICCvrD-yPM\">Regierungskampagne<\/a> zum Thema Corona und produzierte mit der <em>ARD<\/em> dementsprechende Formate mit den Titeln: &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www1.wdr.de\/mediathek\/video\/sendungen\/video-hirschhausen-auf-intensiv-100.html\">Hirschhausen auf Intensiv<\/a>&#8220;, &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.daserste.de\/information\/ratgeber-service\/hirschhausens-check-up\/sendung\/hirschhausen-als-impfproband-100.html\">Hirschhausen als Impfproband<\/a>&#8221; und &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.daserste.de\/information\/ratgeber-service\/hirschhausens-check-up\/videos\/hirschhausen-corona-ohne-ende-video-102.html\">Corona ohne Ende?<\/a>&#8221; In der vierten Produktion: &#8220;Hirschhausen und Long-COVID \u2013 die Pandemie der Unbehandelten&#8221; erfolgt in der Mitte der Sendung die nun doch \u00fcberraschende Darstellung einer bis dato nur z\u00f6gerlich\u00a0aufgearbeiteten Realit\u00e4t in den \u00f6ffentlich-rechtlichen Medien: die Existenz massiver Impfnebenwirkungen, unter denen eine weiterhin unbekannte Zahl von B\u00fcrgern nach Erhalt eines COVID-19-Wirkstoffs zu leiden hat; sie d\u00fcrfte im vierstelligen Bereich liegen. Im &#8220;Impfbuch f\u00fcr alle&#8221; schreibt von Hirschhausen\u00a0zu diesem Thema auf <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infektionsschutz.de\/download\/5290-1628501514-BMG_Impfbuch-fu__r-alle.pdf\/\">Seite 35<\/a>:<\/p>\n<blockquote>\n<p><em>&#8220;Bei einer Impfung liegt der Fall anders. Denn der Impfling ist meist nicht krank\u00a0\u2013 sondern ein v\u00f6llig gesunder Mensch. Dieser Mensch will sich vor etwas sch\u00fctzen und er soll seine Mitmenschen dabei mit sch\u00fctzen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die bedenklichen Erkenntnisse aus den zur\u00fcckliegenden Monaten belegen: Ein Fremdschutz ist nicht zu 100 Prozent vorhanden. Zudem existiert eine stetig wachsende Zahl ehemals gesunder Menschen, die nach Erhalt von einer oder mehreren COVID-19-Impfungen lebenseinschr\u00e4nkend bis lebensbedrohlich erkrankten. Dazu erkl\u00e4rt von Hirschhausen nun in der aktuellen Dokumentation den Zuschauern:<\/p>\n<blockquote>\n<p><em>&#8220;Und in der Recherche sto\u00dfe ich auf ein weiteres untersch\u00e4tztes (sic!) Problem. In sehr, sehr seltenen F\u00e4llen kann die Corona-Impfung selbst Long COVID ausl\u00f6sen. Das Post-Vaccine-Syndrom (auch Post-Vac-Syndrom).&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Nein, keine Sensation, aber doch ein erstaunliches Zeichen, dass die <em>ARD<\/em>-Redaktion sich mit dem &#8220;Impfluenzer&#8221; von Hirschhausen darauf einigen konnte, dieses Thema in den Beitrag einzubauen. \u00dcber fast zwei Jahre wurden entsprechende Warnungen in den \u00f6ffentlich-rechtlichen Medien untersagt, unterbunden, bek\u00e4mpft und mutwillig vorenthalten. Eine <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.presseportal.de\/pm\/52678\/4855070\">Wahrnehmung<\/a> von Hirschhausens aus dem M\u00e4rz 2021 lautet (wiedergegeben wie im Original):<\/p>\n<blockquote>\n<p><em>&#8220;Er ist Wissenschaftsjournalist, TV-Moderator, seit kurzem Impfproband und gilt als\u00a0vielleicht bekanntester Mediziner des Landes (&#8230;). Der Wissenschaftsjournalist Dr. von Hirschhausen pl\u00e4diert daf\u00fcr, die\u00a0Hygieneregeln auf den Informationsaustausch zu \u00fcbertragen\u00a0und fragw\u00fcrdige Informationen nicht \u2013 analog zu Viren \u2013 unkontrolliert weiterzuverbreiten: &#8216;Tragt nicht bei zur Verwirrung und zum Bullshit.&#8217;<\/em><\/p>\n<p><em>Im Podcast stellt er klar: &#8216;Impfen ist sinnvoll, es ist sicher, es ist solidarisch&#8217;. Dem Mediziner zufolge g\u00e4be es kaum einen Impfstoff, der so umfangreich und an derart vielen Personen getestet wurde wie die Corona-Impfstoffe. Menschen mit Zweifeln r\u00e4t er, drei Aspekte abzuw\u00e4gen:\u00a0Was sind Wirkung oder Nutzen? Was sind die Risiken? Was ist der Preis des Unterlassens?&#8221;<\/em><\/p>\n<\/blockquote>\n<p><strong>Framing: Von der &#8220;Pandemie der Ungeimpften&#8221; zur &#8220;Pandemie der Unbehandelten&#8221;<\/strong><\/p>\n<p>Von Hirschhausen klingt heute vorsichtiger, nachdenklicher und abw\u00e4gender. Gr\u00fcnde daf\u00fcr sind seine eigenen Erfahrungen mit einer Corona-Infektion. Mitte M\u00e4rz 2022 wurde bei ihm eine &#8220;Akutinfektion&#8221; festgestellt, &#8220;mitten in der Drehzeit&#8221;, verr\u00e4t von Hirschhausen in der aktuellen Dokumentation:<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">von Hirschhausen dokumentiert seine Corona-Infektion und beschreibt Gerinnungsst\u00f6rungen, die er LongCovid zuschreibt. Sind Gerinnungsst\u00f6rungen nicht auch eine Nebenwirkung der Impfung? Ist er nicht mehrfach geimpft? <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/Eb7z92faBa\">pic.twitter.com\/Eb7z92faBa<\/a><\/p>\n<p>\u2014 Bastian Barucker (@BBarucker) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/BBarucker\/status\/1573650564528971777?ref_src=twsrc%5Etfw\">September 24, 2022<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Er \u00e4u\u00dfert die gro\u00dfe pers\u00f6nliche Angst vor dem Long-COVID-Ph\u00e4nomen. Ob er geimpft ist, l\u00e4sst sich nicht recherchieren, da sich zum Beitrag &#8220;Hirschhausen als Impfproband&#8221; die Information findet, dass von Hirschhausen in einer Placebo-Gruppe war, also zweimaliger Proband ohne Wirkstoff. Im Januar 2022 schrieb er in einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/kultur\/eckart-von-hirschhausen-schreibt-im-spiegel-wie-wir-mit-krisen-umgehen-sollten-a-5813879f-4ee3-4233-8e51-4812222273ac\">Gastbeitrag<\/a> f\u00fcr den <em>Spiegel\u00a0<\/em>(Bezahlschranke):<\/p>\n<blockquote>\n<p><em>&#8220;Das Wichtigste in einer Krise ist es, erst mal zuzugeben, dass man eine hat. Auch ganz pers\u00f6nlich. Ich zum Beispiel habe es nicht geschafft, eine Frau aus meinem privaten Umfeld und ihre Familie zu \u00fcberzeugen, sich gegen COVID-19 impfen zu lassen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Welche Krise muss\u00a0aber ein Mensch erst erleben, der einer gesunden Familie die COVID-19-Impfung dringlichst empfahl, jetzt aber verantwortlich ist f\u00fcr das t\u00e4gliche Leiden eines der Familienmitglieder durch das Post-Vac-Syndrom? Er schreibt im <em>Spiegel<\/em>-Beitrag: &#8220;Segensreicher Weise gibt es viele gro\u00dfartige aufkl\u00e4rerische Projekte mit Faktencheckern, Richtigstellern und Aufkl\u00e4rern.&#8221; Und wenn sich nun herauskristallisiert, dass die sich in einer Aufarbeitung in Teilen geirrt haben und nicht Teile der Verfasser von Inhalten des &#8220;viralen Bullshit&#8221;? Der anerkannte Immunologe Professor Andreas Radbruch fasst aktuell in einem <em>3sat<\/em>-Beitrag zusammen:<\/p>\n<blockquote>\n<p><em>&#8220;Wir verstehen immer noch nicht, was der Unterschied ist zwischen Schleimhautimmunit\u00e4t und dem Schutz vor schwerer Erkrankung. Und wir verstehen auch nicht, warum die Menschen so unterschiedlich auf genau den gleichen Impfstoff oder das gleiche Virus reagieren.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Bei keinem der geschilderten F\u00e4lle der <em>ARD<\/em>-Dokumentation zu Long COVID erf\u00e4hrt der Zuschauer, ob die dargestellten Protagonisten sich impfen lie\u00dfen, nat\u00fcrlich bis auf die Schilderung des tragischerweise vom Post-Vac-Syndrom Betroffenen. Die Erfahrungen der Wissenschaft belegen jedoch mittlerweile, dass die Symptomatik dreier chronischer, also l\u00e4nger anhaltender Beschwerden Kreuzungspunkte bei den Beschwerden aufweisen: Long COVID, das sogenannte <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.mecfs.de\/was-ist-me-cfs\/?pk_campaign=Aw-illness&amp;pk_kwd=WhatIsCFS\">ME\/CFS<\/a>\u00a0(Chronisches Fatigue-Syndrom) und, nun auch durch Dr. von Hirschhausen best\u00e4tigt, das Post-Vac-Syndrom. Laut der Dokumentation ist Long COVID &#8220;eine Krankheit mit bis zu 200 m\u00f6glichen Symptomen&#8221;. Sehr viel Raum f\u00fcr noch mehr Interpretationen.<\/p>\n<p>Die Recherche ergibt, dass zum Beispiel im ersten geschilderten Fall das junge M\u00e4dchen (Zitat aus der Doku: &#8220;Im vergangenen Winter haben sich besonders viele Kinder und Jugendliche infiziert, mehr als andere Altersgruppen&#8221;) geimpft war. Diese mehr als wichtige Information aber wird den Zuschauern vorenthalten. Die Mutter ist <em>taz<\/em>-Redakteurin und\u00a0informierte\u00a0wiederum laut <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/BBarucker\/status\/1573743387148255232\">Recherche<\/a> des Autors Bastian Barucker in einem <em>taz<\/em>&#8211;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.mecfs.de\/was-ist-me-cfs\/?pk_campaign=Aw-illness&amp;pk_kwd=WhatIsCFS\">Artikel<\/a> im M\u00e4rz 2022: &#8220;Vor zehn Wochen ist meine Familie an COVID-19 erkrankt. Alle waren voll geimpft, keiner hatte einen schweren Verlauf.&#8221;<\/p>\n<p>Am 14. September 2022 behauptete Bundesgesundheitsminister Karl Lauterbach in einem Twitter-<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Karl_Lauterbach\/status\/1569973301057044482\">Beitrag<\/a>:<\/p>\n<blockquote>\n<p><em>&#8220;Impfungen verhindern nach jetzigen Stand der Wissenschaft Long COVID. Besser BA.5 Impfung als BA.5 Infektion.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Besser? Er schreibt nicht &#8220;k\u00f6nnen verhindern&#8221;, sondern &#8220;verhindern&#8221;. Erneut eine mehr als gewagte Formulierung eines verantwortlichen Ministers.\u00a0Prof. Bernhard Schieffer, Direktor am Universit\u00e4tsklinikum Marburg und Leiter einer\u00a0Long-COVID-Ambulanz, wird in einem Artikel aus dem August 2022 mit den Worten <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.netdoktor.de\/magazin\/post-vac-syndrom-long-covid-nach-der-impfung\/#:~:text=Post%2DVac%20und%20Long%20Covid,der%20Impfung%E2%80%9C%2C%20erkl%C3%A4rt%20Schieffer.\">zitiert<\/a>:<\/p>\n<blockquote>\n<p><em>&#8220;Post-Vac und Long COVID sind prinzipiell dasselbe. Wir sehen keinen Unterschied: Im Grunde handelt es sich um Long COVID \u2013 nur eben nicht nach der Infektion, sondern aufgrund der Impfung.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Von Hirschhausen formuliert (noch) etwas <em>ARD<\/em>-probater:<\/p>\n<blockquote>\n<p><em>&#8220;Was mich wirklich beunruhigt<\/em><em>,<\/em><em> ist dieses Unwissen \u00fcber den Zusammenhang zwischen Impfung und potenziell Long COVID.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die dazu befragte Immunologin Prof. Carmen Scheibenbogen von der Berliner Charit\u00e9 gibt immerhin zu, dass &#8220;keinen sauberen Zahlen&#8221; existieren: &#8220;Ich glaube, da ist auch ein gewisser Nachholbedarf.&#8221; Der <em>ARD<\/em>-Zuschauer lernt dazu.<em>\u00a0<\/em>Prof. Scheibenbogen w\u00f6rtlich:<\/p>\n<blockquote>\n<p><em>&#8220;Ich glaube, viele \u00c4rzte scheuen sich auch davor, das laut zu sagen, weil sie nat\u00fcrlich (sic!) Angst haben, dass die Argumente den Impfgegnern dienen: &#8216;Wir haben es ja schon immer gesagt, die Impfung ist gef\u00e4hrlich.&#8217; Das ist nat\u00fcrlich nicht so.&#8221;<br \/><\/em><\/p>\n<\/blockquote>\n<p>Nicht? Im Fall eines\u00a0jungen Mannes mit Post-Vac-Syndrom nach COVID-19-Impfung berichtet der Vater:<\/p>\n<blockquote>\n<p><em>&#8220;Der (Sohn) hatte zum Schluss im Krankenhaus sieben Herzanf\u00e4lle, an einem Tag. (&#8230;) Er h\u00e4tte das nicht mehr \u00fcberlebt.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Gerettet hat den jungen Mann eine Blutw\u00e4sche, die die Familie in H\u00f6he &#8220;von \u00fcber 10.000 Euro&#8221; selbst bezahlen musste, da die Krankenkasse die Kosten nicht \u00fcbernehmen wollte. Die Begr\u00fcndung laut der Dokumentation:<\/p>\n<blockquote>\n<p><em>&#8220;Es fehlen Studien zum Argument der Blutw\u00e4sche.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der prominente &#8220;wohl bekannteste Mediziner des Landes<em>&#8221; <\/em>intervenierte daraufhin bei der zust\u00e4ndigen Kasse. Diese bewilligte dann eine Kosten\u00fcbernahme. Das ist lobenswert und sehr sch\u00f6n f\u00fcr die betroffene Familie, es macht sich gut f\u00fcr von Hirschhausen und die <em>ARD<\/em>, aber welcher betroffene Normalb\u00fcrger kann sich auf einen wirkungsvollen Medienprofi berufen? Auch von Hirschhausen unterzog sich einer <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.br.de\/nachrichten\/deutschland-welt\/hirschhausen-und-long-covid-die-pandemie-der-unbehandelten,TADeXmh\">Blutw\u00e4sche<\/a>. Die Kosten kann er sich finanziell entspannt allein leisten, da der regelm\u00e4\u00dfige Blick auf die Seite der Bill- und Melinda Gates Foundation zeigte: Der\u00a0engagierte Herr von Hirschhausen erhielt nach knapp 1,4 Millionen Euro im M\u00e4rz 2021 und im Mai 2022 nochmals rund <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.gatesfoundation.org\/about\/committed-grants\/2022\/05\/inv044726\">400.000 Euro<\/a> f\u00fcr seine Stiftung.<\/p>\n<p>Immerhin, von Hirschhausen scheint nachhaltig beeindruckt.\u00a0Patienten wie\u00a0der junge Mann mit ben\u00f6tigter Blutw\u00e4sche &#8220;werden in der Gesellschaft kaum gesehen. Wir setzen das Thema im Prinzip aus \u2013 inklusive des\u00a0Paul-Ehrlich-Instituts, die davon nichts wissen wollen&#8221;, beklagt er laut einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.stern.de\/kultur\/tv\/eckart-von-hirschhausen-trifft-long-covid-patienten-fuer-doku-32497012.html\">Artikel<\/a> des <em>Stern<\/em>. Markige Worte f\u00fcr einen Regierungs- und Medien-Impfluenzer. Der <em>Stern<\/em>-Artikel ist bereits aus dem Juni 2022 \u2013 die Dokumentation hingegen seit dem 29. Juni nur f\u00fcr Wissende und Suchende in der <em>ARD<\/em>-Mediathek <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.ardmediathek.de\/video\/hirschhausens-check-up\/hirschhausen-und-long-covid-die-pandemie-der-unbehandelten\/daserste\/Y3JpZDovL2Rhc2Vyc3RlLmRlL2hpcnNjaGhhdXNlbnMtY2hlY2stdXAvMjY4MjNmYTktMjBhNS00YzQ0LWEzNWEtZDJkZmM1ZTI3NGVk\">versteckt.<\/a>\u00a0Im <em>ARD<\/em>-Abendprogramm wurde der Beitrag noch nicht gesendet. Gibt es Gr\u00fcnde?<\/p>\n<p>M\u00f6glicher Grund Nummer 1: Auch Lauterbach wird in dem Beitrag interviewt. Die kritischen Zwischent\u00f6ne von Hirschhausens passen aber \u00fcberhaupt nicht gerade in die schleppend anlaufende Werbekampagne f\u00fcr die &#8220;bivalenten Impfstoffe&#8221;, die mittlerweile ans Tageslicht gekommen sind. Gab es Interventionen mit der Bitte einer verz\u00f6gerten Ausstrahlung? Offiziell ist die Queen daran schuld. So informiert die <em>ARD<\/em> auf den <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.daserste.de\/information\/ratgeber-service\/hirschhausens-check-up\/videos\/Hirschhausen-und-Long-Covid-die-Pandemie-der-Unbehandelten-100.html\">Hinweis<\/a> eines Zuschauers, dass &#8220;wegen der Trauerfeier f\u00fcr K\u00f6nigin Elisabeth II. die Ausstrahlung entfiel&#8221; und dass\u00a0&#8220;nach derzeitigem Stand am 17. Oktober 2022 um 20:15 Uhr&#8221; der Sendetermin nachgeholt wird. &#8220;Nach derzeitigem Stand&#8221;?<\/p>\n<p>Zum Thema Post-Vac-Syndrom befragte von Hirschhausen Minister Lauterbach irritierenderweise nicht. Der best\u00e4tigte aber auf die Frage, ob Deutschland aktuell &#8220;eine Pandemie der Unbehandelten&#8221; habe, zumindest, je nach Blickwinkel und Betrachtung: &#8220;Ja, das ist definitiv so.&#8221; Im Mai 2022 hat die Bundesregierung f\u00fcnf Millionen Euro f\u00fcr die <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bundesregierung.de\/breg-de\/suche\/long-covid-1919600\">Erforschung<\/a> von Long COVID und\u00a0ME\/CFS\u00a0zur Verf\u00fcgung gestellt. Dazu hei\u00dft es auf der Seite der Bundesregierung: &#8220;Forschungsprogramm zu Corona-Sp\u00e4tfolgen: Long COVID auf der Spur&#8221;. Korrekt m\u00fcsste es jedoch hei\u00dfen:\u00a0Forschungsprogramm zu Corona- und Corona-Impfungs-Sp\u00e4tfolgen.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/pressefreiheit.rtde.tech\/inland\/149253-was-bringt-omikron-booster-3\/\">Eckart von Hirschhausen: Systemrelevant oder Systemling?<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/149915-pandemie-unbehandelten-eckart-von-hirschhausen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im dritten Corona-Jahr stellt sich vielen Menschen die Frage nach den Gr\u00fcnden f\u00fcr ihren Gesundheitszustand. Chronisches Fatigue-Syndrom oder Long COVID nach Corona-Infektion? \u00dcberraschend best\u00e4tigt Medien-Promi von Hirschhausen die Existenz einer dritten Variante: des Post-Vac-Syndroms. Von Bernhard Loyen Dr. Eckart von Hirschhausen gilt seit Beginn der Corona-Krise im Jahre 2020 als einer der\u00a0vehementesten Unterst\u00fctzer der politisch [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"d42488a66103122daba184a3ec3ec0fb":["Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms"],"original_link":["https:\/\/de.rt.com\/meinung\/149915-pandemie-unbehandelten-eckart-von-hirschhausen\/"],"_thumbnail_id":["20004"],"_wptg_p2tg_sent2tg":["2022-09-29 08:36:26"],"jnews_social_counter_last_update":["1778484754"]},"categories":[19,23],"tags":[1438,82,583,23845,33577,530,33578,33576],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms\" \/>\n<meta property=\"og:description\" content=\"Im dritten Corona-Jahr stellt sich vielen Menschen die Frage nach den Gr\u00fcnden f\u00fcr ihren Gesundheitszustand. Chronisches Fatigue-Syndrom oder Long COVID nach Corona-Infektion? \u00dcberraschend best\u00e4tigt Medien-Promi von Hirschhausen die Existenz einer dritten Variante: des Post-Vac-Syndroms. Von Bernhard Loyen Dr. Eckart von Hirschhausen gilt seit Beginn der Corona-Krise im Jahre 2020 als einer der\u00a0vehementesten Unterst\u00fctzer der politisch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-29T06:33:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms\",\"datePublished\":\"2022-09-29T06:33:42+00:00\",\"dateModified\":\"2022-09-29T06:33:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/\"},\"wordCount\":1766,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg\",\"keywords\":[\"best\u00e4tigt\",\"der\",\"des\",\"Existenz\",\"Hirschhausen\",\"Pandemie\",\"PostVacSyndroms\",\"Unbehandelten\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/\",\"name\":\"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg\",\"datePublished\":\"2022-09-29T06:33:42+00:00\",\"dateModified\":\"2022-09-29T06:33:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg\",\"width\":460,\"height\":259,\"caption\":\"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/","og_locale":"de_DE","og_type":"article","og_title":"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms","og_description":"Im dritten Corona-Jahr stellt sich vielen Menschen die Frage nach den Gr\u00fcnden f\u00fcr ihren Gesundheitszustand. Chronisches Fatigue-Syndrom oder Long COVID nach Corona-Infektion? \u00dcberraschend best\u00e4tigt Medien-Promi von Hirschhausen die Existenz einer dritten Variante: des Post-Vac-Syndroms. Von Bernhard Loyen Dr. Eckart von Hirschhausen gilt seit Beginn der Corona-Krise im Jahre 2020 als einer der\u00a0vehementesten Unterst\u00fctzer der politisch [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-09-29T06:33:42+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms","datePublished":"2022-09-29T06:33:42+00:00","dateModified":"2022-09-29T06:33:42+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/"},"wordCount":1766,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg","keywords":["best\u00e4tigt","der","des","Existenz","Hirschhausen","Pandemie","PostVacSyndroms","Unbehandelten"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/","url":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/","name":"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg","datePublished":"2022-09-29T06:33:42+00:00","dateModified":"2022-09-29T06:33:42+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Pandemie-der-Unbehandelten-Hirschhausen-bestaetigt-Existenz-des-Post-Vac-Syndroms.jpg","width":460,"height":259,"caption":"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/pandemie-der-unbehandelten-hirschhausen-bestaetigt-existenz-des-post-vac-syndroms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Pandemie der Unbehandelten? Hirschhausen best\u00e4tigt Existenz des Post-Vac-Syndroms"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/20003"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=20003"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/20003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/20004"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=20003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=20003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=20003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}