{"id":19848,"date":"2022-09-27T06:30:00","date_gmt":"2022-09-27T04:30:00","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/"},"modified":"2022-09-27T06:30:00","modified_gmt":"2022-09-27T04:30:00","slug":"lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/","title":{"rendered":"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/6331d5df48fbef4e75525c09.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Weil es die Rote Armee und somit ein &#8220;totalit\u00e4res Regime&#8221; popularisieren w\u00fcrde \u2013 mit diesem Argument untersagte der Stadtrat des lettischen Ortes Salaspils die Gedenkfeier zum Jahrestag der Befreiung eines der grausamsten NS-Konzentrationslager Osteuropas.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Obwohl Salaspils eigentlich nicht als reines Todeslager wie etwa Sobib\u00f3r galt, war es de facto eines. In Salaspils wurden Kinder festgehalten, um sie als Blutspender f\u00fcr verwundete deutsche Soldaten einzusetzen, woran die kleinen H\u00e4ftlinge dann schnell starben. Bis zu\u00a07.000 sowjetische Kinder wurden in Salaspils ermordet.<\/p>\n<p>Dieser grausame Ort befindet sich nur 20 Kilometer von der lettischen Hauptstadt Riga entfernt und wurde am 26. September 1944 von der Roten Armee befreit. Die lettischen Beh\u00f6rden verbreiten in den letzten Jahren ihre Version der Geschichte, wonach Salaspils lediglich ein Arbeitslager war \u2013 erdr\u00fcckenden Beweisen zum Trotz. Die Behauptungen, das Lager sei ein KZ- oder Todeslager gewesen, erachten die lettischen Beh\u00f6rden\u00a0als russische Propaganda.<\/p>\n<p>Bereits\u00a0vor wenigen Jahren wurde eine Ausstellung \u00fcber die Verbrechen der Nazis und deren \u00f6rtliche Kollaborateure in Salaspils verboten. Nun darf man auch an die Befreiung des Lagers nicht mehr \u00f6ffentlich erinnern. Wie <em>Sputnik<\/em> mit Verweis auf die Russische Union Lettlands (RUL) berichtet, habe der Stadtrat eine Gedenkfeier zum Jahrestag der Befreiung untersagt.<\/p>\n<p>Traditionell finden Ende September auf dem Gel\u00e4nde der Gedenkst\u00e4tte Salaspils Veranstaltungen zum Gedenken an die KZ-H\u00e4ftlinge statt. Sie werden zeitlich mit der Befreiung des Lagers zusammengelegt. In diesem Jahr hat der lettische H\u00e4ftlingsverein &#8220;Erinnerung f\u00fcr die Zukunft&#8221; wie \u00fcblich die Veranstaltung f\u00fcr den 25. September angemeldet.<\/p>\n<p>Am Freitag, den 23. September, erhielten die Organisatoren ein von der Exekutivdirektorin des Gemeinderats von Salaspils, Silvia Purini, unterzeichnetes Ablehnungsschreiben. Darin informiert sie dar\u00fcber, dass das Ereignis verboten ist.<\/p>\n<p>Wie RUL mitteilte, sei der Grund f\u00fcr die Ablehnung, dass &#8220;der Zeitpunkt des Treffens mit dem \u00fcbereinstimmt, was die Ideologie des totalit\u00e4ren kommunistischen Besatzungsregimes der Sowjetunion w\u00e4hrend der Besetzung Lettlands als den Zeitpunkt definierte, an dem das Lager Salaspils angeblich &#8216;von der Roten Armee befreit&#8217; wurde. Dies geht aus den Ver\u00f6ffentlichungen und der Geschichtsschreibung aus der Zeit der sowjetischen Besatzung sowie aus den zeitgen\u00f6ssischen kremlnahen Medien hervor&#8221;.<\/p>\n<p>Purini bezieht sich auf lettische Forscher, deren Meinung zu den Umst\u00e4nden der Aufl\u00f6sung des Lagers Salaspils von den Behauptungen der &#8220;sowjetischen Besatzung&#8221; abweicht.<\/p>\n<p>Die Exekutivdirektorin verweist dabei auf Artikel 10 des &#8220;Gesetzes \u00fcber Versammlungen, Aufm\u00e4rsche und Mahnwachen&#8221;, wonach es verboten ist, &#8220;Veranstaltungen zu popularisieren und zu verherrlichen, die nationalsozialistische und kommunistische Ideologie enthalten, einschlie\u00dflich [&#8230;] Gedenktage f\u00fcr Schlachten und Siege [&#8230;] es sei denn, der Zweck der Veranstaltung besteht nicht in der Verherrlichung eines totalit\u00e4ren Regimes oder in der Rechtfertigung begangener Straftaten&#8221;.<\/p>\n<p>Aus der offiziellen Antwort des Gemeinderats geht hervor, dass der Opfer des Nazi-Konzentrationslagers in Salaspils nicht gedacht werden kann, weil dies die Rote Armee, das &#8220;sowjetische Besatzungsregime&#8221; und die kommunistische Ideologie f\u00f6rdert, merkten die Veranstalter dazu an.<\/p>\n<p>Der russische Sicherheitsdienst FSB<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/archive.ph\/20120803064856\/www.fsb.ru\/fsb\/history\/author\/single.htm!id%3D10318166@fsbPublication.html#selection-629.0-637.417\"> ver\u00f6ffentlichte <\/a>zahlreiche Zeugenaussagen \u00fcber die Grausamkeiten von Salaspils, die von den sowjetischen Ermittlern zeitnah nach der Befreiung gesammelt worden waren, darunter die Aussage des Zeugen K.A. Laugalaitis, eines ehemaligen H\u00e4ftlings des Konzentrationslagers Salaspils (vernommen am 2. November 1944):<\/p>\n<blockquote>\n<p><em>&#8220;Allein im M\u00e4rz 1943 wurden 20.000 Sowjetb\u00fcrger mit ihren Kindern sofort eingeliefert. Die SS nahm die Kinder sofort von ihren Eltern weg. Schreckliche Szenen spielten sich ab. M\u00fctter wollten ihre Kinder nicht abgeben, deutsche und lettische Polizisten rissen ihnen buchst\u00e4blich die Kinder aus den H\u00e4nden&#8230; S\u00e4uglinge und Kinder unter 5 Jahren wurden in einer separaten Baracke untergebracht, wo sie massenhaft starben. Allein innerhalb eines Jahres starben mehr als dreitausend Kinder auf diese Weise.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Das Gedenken an den Krieg, die Nazi-Verbrechen und die Befreiung durch die Rote Armee wird in Lettland wie auch in den anderen Staaten des Baltikums inzwischen auf vehemente Art und Weise bek\u00e4mpft. Im August wurde in Riga trotz erbitterten<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/vk.com\/video\/@rt_de?q=riga\">\u00a0Widerstands<\/a>\u00a0der russischen Minderheit und lettischer Antifaschisten der gr\u00f6\u00dfte Denkmalkomplex zu Ehren der Befreier mittels Bagger und Sprengung vernichtet. Spektakul\u00e4re Bilder der Zerst\u00f6rung wurden live im lettischen Fernsehen als Akt der Dekolonisierung \u00fcbertragen. In Russland sorgte der Abriss als Akt des &#8220;staatlich gef\u00f6rderten Barbarentums&#8221; und &#8220;pro-nazistischen Geschichtsrevisionismus&#8221; f\u00fcr Entsetzen.<\/p>\n<p><strong>Mehr zum Thema\u00a0<\/strong>\u2013<strong><\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/kurzclips\/video\/85877-lettland-uber-1000-teilnehmer-nehmen\/\">Lettland: \u00dcber 1.000 Teilnehmer nehmen an Europas einzigem Waffen-SS-Veteranenmarsch teil<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/149953-lettische-behorden-verbieten-gedenken-an-befreiung-ns-vernichtungslagers-salaspils\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weil es die Rote Armee und somit ein &#8220;totalit\u00e4res Regime&#8221; popularisieren w\u00fcrde \u2013 mit diesem Argument untersagte der Stadtrat des lettischen Ortes Salaspils die Gedenkfeier zum Jahrestag der Befreiung eines der grausamsten NS-Konzentrationslager Osteuropas. Obwohl Salaspils eigentlich nicht als reines Todeslager wie etwa Sobib\u00f3r galt, war es de facto eines. In Salaspils wurden Kinder festgehalten, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"c663a0ce94d45c7a602d91c6b62ac526":["Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils"],"original_link":["https:\/\/de.rt.com\/europa\/149953-lettische-behorden-verbieten-gedenken-an-befreiung-ns-vernichtungslagers-salaspils\/"],"_thumbnail_id":["19849"],"_wptg_p2tg_sent2tg":["2022-09-27 06:45:27"],"jnews_social_counter_last_update":["1788378876"]},"categories":[19,23],"tags":[5542,3244,583,19371,25246,33460,33461,1523],"class_list":["post-19848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-befreiung","tag-behoerden","tag-des","tag-gedenken","tag-lettische","tag-nsvernichtungslagers","tag-salaspils","tag-verbieten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils\" \/>\n<meta property=\"og:description\" content=\"Weil es die Rote Armee und somit ein &#8220;totalit\u00e4res Regime&#8221; popularisieren w\u00fcrde \u2013 mit diesem Argument untersagte der Stadtrat des lettischen Ortes Salaspils die Gedenkfeier zum Jahrestag der Befreiung eines der grausamsten NS-Konzentrationslager Osteuropas. Obwohl Salaspils eigentlich nicht als reines Todeslager wie etwa Sobib\u00f3r galt, war es de facto eines. In Salaspils wurden Kinder festgehalten, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-27T04:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils\",\"datePublished\":\"2022-09-27T04:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/\"},\"wordCount\":713,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg\",\"keywords\":[\"Befreiung\",\"Beh\u00f6rden\",\"des\",\"Gedenken\",\"lettische\",\"NSVernichtungslagers\",\"Salaspils\",\"verbieten\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/\",\"name\":\"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg\",\"datePublished\":\"2022-09-27T04:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg\",\"width\":460,\"height\":259,\"caption\":\"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/","og_locale":"de_DE","og_type":"article","og_title":"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils","og_description":"Weil es die Rote Armee und somit ein &#8220;totalit\u00e4res Regime&#8221; popularisieren w\u00fcrde \u2013 mit diesem Argument untersagte der Stadtrat des lettischen Ortes Salaspils die Gedenkfeier zum Jahrestag der Befreiung eines der grausamsten NS-Konzentrationslager Osteuropas. Obwohl Salaspils eigentlich nicht als reines Todeslager wie etwa Sobib\u00f3r galt, war es de facto eines. In Salaspils wurden Kinder festgehalten, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-09-27T04:30:00+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils","datePublished":"2022-09-27T04:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/"},"wordCount":713,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg","keywords":["Befreiung","Beh\u00f6rden","des","Gedenken","lettische","NSVernichtungslagers","Salaspils","verbieten"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/","url":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/","name":"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg","datePublished":"2022-09-27T04:30:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Lettische-Behoerden-verbieten-Gedenken-an-Befreiung-des-NS-Vernichtungslagers-Salaspils.jpg","width":460,"height":259,"caption":"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/lettische-behoerden-verbieten-gedenken-an-befreiung-des-ns-vernichtungslagers-salaspils\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Lettische Beh\u00f6rden verbieten Gedenken an Befreiung des NS-Vernichtungslagers Salaspils"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=19848"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/19849"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=19848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=19848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=19848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}