{"id":19666,"date":"2022-09-23T19:25:43","date_gmt":"2022-09-23T17:25:43","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/ein-heisser-winter-in-frankreich\/"},"modified":"2022-09-23T19:25:43","modified_gmt":"2022-09-23T17:25:43","slug":"ein-heisser-winter-in-frankreich","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/","title":{"rendered":"Ein hei\u00dfer Winter in Frankreich?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/632da4d648fbef77c24f95af.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                In Europa versch\u00e4rft sich eine Energiekrise von nie dagewesenem Ausma\u00df, deren wirtschaftliche und soziale Folgen wie ein Tsunami wirken k\u00f6nnten. Nicht nur Deutschland droht ein eiskalter Winter, auch in Frankreich scheint ein Blackout mittlerweile nicht mehr ausgeschlossen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Pierre L\u00e9vy<\/em><\/p>\n<p>Wird es \u00fcber die Weihnachtstage in Paris elektrischen Strom geben? Wenn die franz\u00f6sischen Kernkraftwerke, die gerade \u00fcberholt werden, bald wieder in Betrieb genommen werden k\u00f6nnen und auch noch das Wetter mitspielt (es lebe die &#8220;Klimaerw\u00e4rmung&#8221; &#8230;), dann sind Unterbrechungen der Stromversorgung wenig wahrscheinlich, beruhigt das franz\u00f6sische Strom\u00fcbertragungsnetz (<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.wikipedia.org\/wiki\/R%C3%A9seau_de_Transport_d%E2%80%99Electricit%C3%A9\">RTE<\/a>: <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/RTE_(entreprise)\">R\u00e9seau de transport d&#8217;\u00e9lectricit\u00e9<\/a>) seine Endverbraucher. Voraussetzung daf\u00fcr ist allerdings, dass man sich an die von der Regierung erlassenen Anweisungen zur &#8220;Sparsamkeit&#8221; h\u00e4lt.<\/p>\n<p>So wird eines der reichsten L\u00e4nder der Welt im 21. Jahrhundert dazu gebracht, einen Blackout zu erw\u00e4gen und zugleich zu befehlen, vorsorglich die Heizung herunterzudrehen. Es bedurfte eines &#8220;fortschrittlichen&#8221; Pr\u00e4sidenten, um solch einen tats\u00e4chlichen R\u00fcckschritt historischen Ausma\u00dfes zu begleiten. Mit einer d\u00fcsteren Anmut, die oft seinen Charme ausmacht, prophezeite Emmanuel Macron unl\u00e4ngst das &#8220;Ende des \u00dcberflusses&#8221;.<\/p>\n<p>Schwierigkeiten beim Zugang zu Kohlenwasserstoffen als Energietr\u00e4ger und damit verbunden schwindelerregende Preissteigerungen: In Europa beschleunigt sich eine Energiekrise von nie dagewesenem Ausma\u00df, deren wirtschaftliche und soziale Folgen wie ein Tsunami wirken k\u00f6nnten. Dabei sind vor allem drei Faktoren am Werk:<\/p>\n<p>Der erste davon ist &#8220;systemisch&#8221;, wie die Br\u00fcsseler Linguisten sagen w\u00fcrden, n\u00e4mlich das &#8220;mystische&#8221; Marktgeschehen. Insbesondere der Gashandel wurde nicht immer von Marktmechanismen bestimmt. Fr\u00fcher sicherten langfristige Vertr\u00e4ge sowohl den Erzeugerstaaten stabile Einnahmen als auch den K\u00e4ufern niedrige Preise. Das war, bevor die Lieferung von Gas &#8220;liberalisiert&#8221; wurde und die ehemaligen staatlichen Monopole (beispielsweise in Frankreich) dereguliert wurden \u2013 eine der wichtigsten &#8220;Errungenschaften&#8221; der Europ\u00e4ischen Union (EU).<\/p>\n<p>Der zweite Faktor bezieht sich auf das mittlerweile gemeinsame Schlagwort der globalisierten Eliten: die Reduzierung der CO2-Emissionen. So zielt das EU-System f\u00fcr den Handel mit CO2-Zertifikaten darauf ab, die Nutzung, aber auch die Produktion von kohlenstoffhaltiger Energie, bewusst zu verteuern. Die sozialdemokratische Regierung Spaniens, die sicher nicht als &#8220;Klimaskeptiker&#8221; verd\u00e4chtigt werden kann, pl\u00e4diert daf\u00fcr, die \u00d6kosteuer, die ebenfalls von Marktmechanismen bestimmt wird und einen enormen Anstieg verzeichnet hat, einzufrieren. Bisher ohne Erfolg.<\/p>\n<p>Der dritte Faktor schlie\u00dflich ist der, der das Feuer entfacht hat: die von den Staats- und Regierungschefs der EU gegen Moskau verh\u00e4ngten Sanktionen. Die EU traf die politische Entscheidung, zuerst die russische Kohle und wenig sp\u00e4ter das russische \u00d6l zu boykottieren, und drohte schlie\u00dflich noch, dasselbe auch f\u00fcr Erdgas aus den Pipelines zu tun, bevor schlie\u00dflich der Kreml folgerichtig mit Gegensanktionen einschritt und die \u00fcber Pipelines gelieferten Str\u00f6me selbst drastisch einschr\u00e4nkte. Das Ergebnis ist: Der Preis des Gases \u2013 f\u00fcr das die 27 EU-Mitglieder nun verzweifelt nach alternativen Anbietern suchen \u2013 stieg in weniger als einem Jahr um das Zw\u00f6lffache, was zu einem enormen Anstieg auch der Strompreise f\u00fchrte.<\/p>\n<p>Mit unglaublicher Dreistigkeit gab Ursula von der Leyen als Pr\u00e4sidentin der Europ\u00e4ischen Kommission \u00f6ffentlich Russland die Schuld an dieser Energiekrise. Eigentlich h\u00e4tte Moskau \u2013 auch w\u00e4hrend des Krieges in der Ukraine \u2013 seine Lieferungen gerne fortgesetzt, wenn Br\u00fcssel nicht geschworen h\u00e4tte, Russland mit einem Wirtschaftskrieg in die Knie zwingen zu wollen.<\/p>\n<p>Aber es scheint, dass die V\u00f6lker in der EU, die mit dem drastischen R\u00fcckgang ihrer Kaufkraft und weiteren sich abzeichnenden Einschr\u00e4nkungen konfrontiert sind, sich mehrheitlich immer weniger t\u00e4uschen lassen \u2013 von Prag bis Leipzig und von Athen \u00fcber Br\u00fcssel bis Neapel wachsen Protestbewegungen und finden Demonstrationen statt, mit denen Gespr\u00e4che mit Moskau statt der bedingungslosen Unterst\u00fctzung Kiews gefordert werden oder sogar die Er\u00f6ffnung der Ostseepipeline Nord Stream 2Pipeline verlangt wird \u2013 eine Aussicht, von der man in Br\u00fcssel nichts h\u00f6ren will.<\/p>\n<p>Und selbst in Frankreich, wo es weder die sogenannten &#8220;Links&#8221;-Parteien noch die Gewerkschaften wagen, das Prinzip infrage zu stellen, Moskau m\u00fcsse bestraft werden, sind die Eliten beunruhigt: &#8220;Zweifel und \u00dcberdruss drohen sich festzusetzen&#8221;, so die erschrockene Warnung eines in Le Monde (am 13. September) erschienenen Leitartikels. Die Tageszeitung weist darauf hin, dass die Sanktionen notwendig seien &#8220;und funktionieren&#8221; w\u00fcrden. N\u00e4hert sich der Krieg in der Ukraine bereits einem Ende? Keineswegs. Aber Russland &#8220;steht erst am Anfang eines langen wirtschaftlichen Leidensweges&#8221;, meint Le Monde insgeheim jubeln zu k\u00f6nnen und enth\u00fcllt damit unfreiwillig den wahren Zweck der Sanktionen.<\/p>\n<p>Vor allem aber w\u00fcrde &#8220;eine Kurs\u00e4nderung bei den Sanktionen darauf hinauslaufen, Wladimir Putin in seiner Vision eines feige gewordenen Europas zu best\u00e4rken, das unf\u00e4hig ist, seinen Platz in der Geschichte einzunehmen&#8221;, argumentiert die Zeitung und f\u00fcgt hinzu, dass &#8220;ein Abweichen von diesem Kurs (&#8230;) f\u00fcr das europ\u00e4ische Projekt fatal sein k\u00f6nnte&#8221;. Man m\u00fcsse also den Kurs halten, selbst auf Kosten &#8220;unseres Energiekomforts und unseres wirtschaftlichen Wohlstands&#8221;.<\/p>\n<p>Moskau bestrafen und die europ\u00e4ische Integration fortsetzen \u2013 das ist also letztendlich der Grund, warum wir in einigen Monaten m\u00f6glicherweise erfrieren werden. Sollten sich aber diese Erkenntnisse \u00fcber die kalte Wahrheit weiter verbreiten, k\u00f6nnte es in der EU doch noch ein hei\u00dfer Winter werden.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/pressefreiheit.rtde.tech\/kurzclips\/video\/149238-putin-kolossaler-fehler-gruene-agenda\/\">Putin: &#8220;Kolossaler Fehler&#8221; \u2013 Gr\u00fcne Agenda Schuld an den Energie-Preisexplosionen im Westen<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/149621-heisser-winter-in-frankreich\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Europa versch\u00e4rft sich eine Energiekrise von nie dagewesenem Ausma\u00df, deren wirtschaftliche und soziale Folgen wie ein Tsunami wirken k\u00f6nnten. Nicht nur Deutschland droht ein eiskalter Winter, auch in Frankreich scheint ein Blackout mittlerweile nicht mehr ausgeschlossen. Von Pierre L\u00e9vy Wird es \u00fcber die Weihnachtstage in Paris elektrischen Strom geben? Wenn die franz\u00f6sischen Kernkraftwerke, die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"d66238aea53b779deca48c2d311b6449":["Ein hei\u00dfer Winter in Frankreich?"],"original_link":["https:\/\/de.rt.com\/meinung\/149621-heisser-winter-in-frankreich\/"],"_thumbnail_id":["19667"],"_wptg_p2tg_sent2tg":["2022-09-23 19:35:35"],"jnews_social_counter_last_update":["1784098218"]},"categories":[19,23],"tags":[357,3320,30565,7753],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ein hei\u00dfer Winter in Frankreich? - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein hei\u00dfer Winter in Frankreich?\" \/>\n<meta property=\"og:description\" content=\"In Europa versch\u00e4rft sich eine Energiekrise von nie dagewesenem Ausma\u00df, deren wirtschaftliche und soziale Folgen wie ein Tsunami wirken k\u00f6nnten. Nicht nur Deutschland droht ein eiskalter Winter, auch in Frankreich scheint ein Blackout mittlerweile nicht mehr ausgeschlossen. Von Pierre L\u00e9vy Wird es \u00fcber die Weihnachtstage in Paris elektrischen Strom geben? Wenn die franz\u00f6sischen Kernkraftwerke, die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T17:25:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ein hei\u00dfer Winter in Frankreich?\",\"datePublished\":\"2022-09-23T17:25:43+00:00\",\"dateModified\":\"2022-09-23T17:25:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/\"},\"wordCount\":886,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg\",\"keywords\":[\"ein\",\"Frankreich\",\"hei\u00dfer\",\"Winter\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/\",\"name\":\"Ein hei\u00dfer Winter in Frankreich? - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg\",\"datePublished\":\"2022-09-23T17:25:43+00:00\",\"dateModified\":\"2022-09-23T17:25:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg\",\"width\":460,\"height\":259,\"caption\":\"Ein hei\u00dfer Winter in Frankreich?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein hei\u00dfer Winter in Frankreich?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ein hei\u00dfer Winter in Frankreich? - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/","og_locale":"de_DE","og_type":"article","og_title":"Ein hei\u00dfer Winter in Frankreich?","og_description":"In Europa versch\u00e4rft sich eine Energiekrise von nie dagewesenem Ausma\u00df, deren wirtschaftliche und soziale Folgen wie ein Tsunami wirken k\u00f6nnten. Nicht nur Deutschland droht ein eiskalter Winter, auch in Frankreich scheint ein Blackout mittlerweile nicht mehr ausgeschlossen. Von Pierre L\u00e9vy Wird es \u00fcber die Weihnachtstage in Paris elektrischen Strom geben? Wenn die franz\u00f6sischen Kernkraftwerke, die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-09-23T17:25:43+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ein hei\u00dfer Winter in Frankreich?","datePublished":"2022-09-23T17:25:43+00:00","dateModified":"2022-09-23T17:25:43+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/"},"wordCount":886,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg","keywords":["ein","Frankreich","hei\u00dfer","Winter"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/","url":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/","name":"Ein hei\u00dfer Winter in Frankreich? - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg","datePublished":"2022-09-23T17:25:43+00:00","dateModified":"2022-09-23T17:25:43+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Ein-heisser-Winter-in-Frankreich.jpg","width":460,"height":259,"caption":"Ein hei\u00dfer Winter in Frankreich?"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ein-heisser-winter-in-frankreich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ein hei\u00dfer Winter in Frankreich?"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19666"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=19666"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/19667"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=19666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=19666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=19666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}