{"id":19517,"date":"2022-09-21T19:09:30","date_gmt":"2022-09-21T17:09:30","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/"},"modified":"2022-09-21T19:09:30","modified_gmt":"2022-09-21T17:09:30","slug":"dax-duempelt-vor-sich-hin-euro-im-sinkflug","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/","title":{"rendered":"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/632b29bfb480cc1b945a9e1c.jpg\" \/><\/p>\n<p>Die Ank\u00fcndigung einer Teilmobilmachung in Russland verunsichert auch die Anleger an der deutschen B\u00f6rse. Nach der Ank\u00fcndigung des russischen Pr\u00e4sidenten k\u00fchlte sich die Stimmung auf dem Frankfurter Parkett merklich ab. Der DAX verlor zun\u00e4chst deutlich \u00fcber ein Prozent. Im Laufe des Tages konnte er seinen Verlust jedoch weitgehend wieder wettmachen und notiert aktuell im Plus.\u00a0<\/p>\n<p>Am Abend gibt die US-amerikanische Zentralbank FED ihren j\u00fcngsten Zinsentscheid bekannt. Gerechnet wird mit einer weiteren deutlichen Erh\u00f6hung des Leitzinses in den USA. Nach Angaben vom <em>Handelsblatt<\/em> rechnen Experten mit einer Erh\u00f6hung um 75 Basispunkte, aber auch ein Zinsschritt von \u00fcber einem Prozent halten H\u00e4ndler f\u00fcr m\u00f6glich. Die FED wird getrieben von Inflationssorgen. Zwar ist die Inflation in den USA leicht gesunken, liegt mit 8,3 Prozent jedoch noch immer deutlich \u00fcber den Erwartungen.\u00a0<\/p>\n<p>Begleitet wird die Aussicht auf eine satte Leitzinerh\u00f6hung f\u00fcr den US-Dollar im Gegenzug von einem weiteren Verfall des Euro, der inzwischen die Parit\u00e4t zum US-Dollar wieder unterschreitet und auch gegen\u00fcber dem Schweizer Franken immer st\u00e4rker ins Abseits ger\u00e4t. Anleger ziehen in den etwas &#8220;sichereren Hafen&#8221; US-Dollar um, zumal die Risiken in der Euro-Zone angesichts der russischenTeilmobilmachung und der Eskalation des Konflikts in der Ukraine weiter zugenommen haben. Hinzu kommen die d\u00fcsteren makro\u00f6konomischen Aussichten f\u00fcr Europa. Dass die gr\u00f6\u00dfte Volkswirtschaft der EU in die Rezesssion rutscht, gilt Experten inzwischen als sicher. Die &#8220;Gasumlage&#8221; wird zwar nach aller Voraussicht eingestampft werden, da der gr\u00f6\u00dfte deutsche Gas-Importeur Uniper verstaatlicht werden soll. Volkswirtschaftlich geht es in Deutschland zunehmend um das nackte \u00dcberleben. Der kontinuierliche Verfall des DAX zeigt auch daf\u00fcr die entsprechende Tendenz. Er hat in Jahresfrist \u00fcber 17 Prozent eingeb\u00fc\u00dft \u2013 und eine Kehrwende ist nicht in Sicht.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/international\/149517-nach-anordnung-teilmobilmachung-durch-putin\/\">Nach Anordnung der Teilmobilmachung durch Putin: \u00d6l- und Gaspreise steigen wieder deutlich<\/a><\/p>\n<\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/wirtschaft\/149546-dax-im-sinkflug\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ank\u00fcndigung einer Teilmobilmachung in Russland verunsichert auch die Anleger an der deutschen B\u00f6rse. Nach der Ank\u00fcndigung des russischen Pr\u00e4sidenten k\u00fchlte sich die Stimmung auf dem Frankfurter Parkett merklich ab. Der DAX verlor zun\u00e4chst deutlich \u00fcber ein Prozent. Im Laufe des Tages konnte er seinen Verlust jedoch weitgehend wieder wettmachen und notiert aktuell im Plus.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"0d1c3af3c9b75ae31b3990a09c83b894":["DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug"],"original_link":["https:\/\/de.rt.com\/wirtschaft\/149546-dax-im-sinkflug\/"],"_thumbnail_id":["19518"],"_wptg_p2tg_sent2tg":["2022-09-21 19:15:43"],"jnews_social_counter_last_update":["1784151440"]},"categories":[19,23],"tags":[8447,33186,1005,15634,434,33187,320],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug\" \/>\n<meta property=\"og:description\" content=\"Die Ank\u00fcndigung einer Teilmobilmachung in Russland verunsichert auch die Anleger an der deutschen B\u00f6rse. Nach der Ank\u00fcndigung des russischen Pr\u00e4sidenten k\u00fchlte sich die Stimmung auf dem Frankfurter Parkett merklich ab. Der DAX verlor zun\u00e4chst deutlich \u00fcber ein Prozent. Im Laufe des Tages konnte er seinen Verlust jedoch weitgehend wieder wettmachen und notiert aktuell im Plus.\u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T17:09:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug\",\"datePublished\":\"2022-09-21T17:09:30+00:00\",\"dateModified\":\"2022-09-21T17:09:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg\",\"keywords\":[\"Dax\",\"d\u00fcmpelt\",\"Euro\",\"HIN\",\"sich\",\"Sinkflug\",\"vor\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/\",\"name\":\"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg\",\"datePublished\":\"2022-09-21T17:09:30+00:00\",\"dateModified\":\"2022-09-21T17:09:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg\",\"width\":460,\"height\":259,\"caption\":\"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/","og_locale":"de_DE","og_type":"article","og_title":"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug","og_description":"Die Ank\u00fcndigung einer Teilmobilmachung in Russland verunsichert auch die Anleger an der deutschen B\u00f6rse. Nach der Ank\u00fcndigung des russischen Pr\u00e4sidenten k\u00fchlte sich die Stimmung auf dem Frankfurter Parkett merklich ab. Der DAX verlor zun\u00e4chst deutlich \u00fcber ein Prozent. Im Laufe des Tages konnte er seinen Verlust jedoch weitgehend wieder wettmachen und notiert aktuell im Plus.\u00a0 [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-09-21T17:09:30+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug","datePublished":"2022-09-21T17:09:30+00:00","dateModified":"2022-09-21T17:09:30+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg","keywords":["Dax","d\u00fcmpelt","Euro","HIN","sich","Sinkflug","vor"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/","url":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/","name":"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg","datePublished":"2022-09-21T17:09:30+00:00","dateModified":"2022-09-21T17:09:30+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/DAX-duempelt-vor-sich-hin-Euro-im-Sinkflug.jpg","width":460,"height":259,"caption":"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/dax-duempelt-vor-sich-hin-euro-im-sinkflug\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"DAX d\u00fcmpelt vor sich hin, Euro im Sinkflug"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19517"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=19517"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/19518"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=19517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=19517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=19517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}