{"id":19157,"date":"2022-09-15T20:34:24","date_gmt":"2022-09-15T18:34:24","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/"},"modified":"2022-09-15T20:34:24","modified_gmt":"2022-09-15T18:34:24","slug":"droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/","title":{"rendered":"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/632330dd48fbef4f4408685c.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Versuche der USA sind gescheitert, die Weltgemeinschaft zum Einnehmen ihrer Position in Bezug auf die Ukraine zu zwingen. Der gr\u00f6\u00dfere Teil der Welt ist nicht daran interessiert, in den Kampf zwischen Russland und dem Westen hineingezogen zu werden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Timofei Bordatschew<\/em><\/p>\n<p>Was wir derzeit erleben ist nicht der Kalte Krieg und Russland ist nicht die Sowjetunion. Eines der Zeichen der derzeitigen Ver\u00e4nderungen ist nicht die Spaltung der Welt in gegens\u00e4tzliche Lager, sondern die Anpassung an ver\u00e4nderte Bedingungen, infolge eines Konflikts unter Gro\u00dfm\u00e4chten. Dies k\u00f6nnte sehr wahrscheinlich ein Signal daf\u00fcr sein, dass wir in Zukunft keine Wiederherstellung der bipolaren internationalen Ordnung erleben werden, die von 1945 bis 1990 Bestand hatte.<\/p>\n<p>Die Haltung des gr\u00f6\u00dften Teils der Welt zu dem Konflikt zwischen Russland und dem Westen zeigt, dass die Menschheit jetzt viel geeinter und f\u00e4higer ist, sich den Gegebenheiten anzupassen; selbst an gro\u00dfe Herausforderungen, die bis vor kurzem noch nicht in Betracht gezogen wurden. Das widerlegt die Vorstellung, der amerikanische Zentrismus mache in Weltangelegenheiten weiterhin jedes Problem, das im Zusammenhang mit Washington steht, zum wichtigsten der Welt und k\u00f6nne zu einer globalen Spaltung f\u00fchren.<\/p>\n<p>Dies bedeutet jedoch nicht, dass Russland glauben sollte, sich automatisch die Unterst\u00fctzung der Mehrheit der Staaten sichern zu k\u00f6nnen, wenn es blo\u00df auf der richtigen Seite der Geschichte steht. Daran muss noch gearbeitet werden. Aber es w\u00e4re leichtsinnig anzunehmen, dass\u00a0die mehrheitliche Weigerung der Nationen der Welt, sich dem Wirtschaftskrieg des Westens gegen Russland anzuschlie\u00dfen, eine Unterst\u00fctzung f\u00fcr Moskaus Verhalten bedeutet. Wenngleich diese Nationen insgesamt 85 Prozent der Weltbev\u00f6lkerung repr\u00e4sentieren.<\/p>\n<p>Sechs Monate nach Beginn der Milit\u00e4roperation in der Ukraine zeigt die Dynamik der internationalen Haltung gegen\u00fcber dem politisch-milit\u00e4rischen Konflikt und seinen Teilnehmern, dass die meisten L\u00e4nder bereit sind, sich zu distanzieren. Die gro\u00dfe Ausnahme bildet hier China, dessen Politik zunehmend pro-russisch ist und mit der Eskalation seiner eigenen Probleme mit den USA weiterhin die wahre Tiefe des gegenseitigen Vertrauens zwischen Moskau und Peking unter Beweis stellt. Dieser Zusammenhang ergibt sich jedoch aus der Entwicklung der beiden L\u00e4nder in den vergangenen zwanzig Jahren und der objektiven Konvergenz ihrer Herangehensweisen an gro\u00dfe systemische Probleme \u2013 also nicht durch die unmittelbare Krise in Europa. Nat\u00fcrlich ist es noch zu fr\u00fch, um zu sagen, wie die internationale Ordnung in Zukunft aussehen wird, nachdem der Westen gezwungen wurde, seine historische Niederlage im Kampf um die Aufrechterhaltung der globalen Vorherrschaft einzugestehen. Sie wird allm\u00e4hlich geformt, auch wenn die f\u00fchrenden M\u00e4chte auf oft sehr gef\u00e4hrliche Weise die Grenzen ihrer Machtf\u00e4higkeiten und die Grenzen dessen definieren, was zul\u00e4ssig ist.<\/p>\n<p>Angesichts der Irrationalit\u00e4t eines gro\u00dfen l\u00e4nder\u00fcbergreifenden Krieges und dem Ausma\u00df von seit langem bestehenden Problemen, wird dieser Prozess wahrscheinlich viel l\u00e4nger dauern als fr\u00fchere Episoden radikaler Ver\u00e4nderungen in der internationalen Ordnung. Wir erleben jetzt eine der ersten Etappen einer dauerhaften weltpolitischen Neuausrichtung. Wir sprechen in der Tat vom Ende einer mehrere hundert Jahre dauernden Periode. Aber selbst in diesem Stadium k\u00f6nnen wir bereits einige Anzeichen f\u00fcr das Verhalten von M\u00e4chten erkennen, die systemische Faktoren in der Entwicklung der internationalen Politik sein werden. Es ist daher wichtig, dass ein Zeichen der stattfindenden Ver\u00e4nderungen nicht die Teilung der Welt in gegens\u00e4tzliche Lager ist, sondern \u2013 gr\u00f6\u00dftenteils \u2013 die Anpassung an die ver\u00e4nderten Bedingungen, die sich aus dem Konflikt ergeben.<\/p>\n<p>Aber selbst in diesem Stadium k\u00f6nnen wir bereits einige Anzeichen f\u00fcr das Verhalten von M\u00e4chten erkennen, die systemische Faktoren in der Entwicklung der internationalen Politik sein werden.<\/p>\n<p>Das Flaggschiff einer solchen Anpassung ist nat\u00fcrlich Indien, einer der bev\u00f6lkerungsreichsten Staaten, mit sehr ernsthaften Ambitionen in Bezug auf seine Rolle in der Welt. Bisher hat es noch nicht das wirtschaftliche, milit\u00e4rische oder gesellschaftliche Stadium erreicht, das\u00a0den Subkontinent zu einer wahren Gro\u00dfmacht machen w\u00fcrde. Aber gleichzeitig ist Indien der Vorreiter einer Mehrheit, die nicht die Absicht hat, sich in gegnerische Lager spalten zu lassen oder eine Quelle von Ressourcen f\u00fcr Rivalen wie Amerika, Russland oder China zu werden. Neu-Delhi hat best\u00e4ndig Handelsbeziehungen zu Moskau gepflegt und sich in den vergangenen Monaten zu einem der gr\u00f6\u00dften Au\u00dfenhandelspartner Russlands entwickelt.<\/p>\n<p>Indische Beamte betonen fortw\u00e4hrend, dass ihre Weltanschauung nicht antirussisch ist. Die Zur\u00fcckhaltung in einigen Bereichen, in Bezug auf die Zusammenarbeit mit Russland, h\u00e4ngt nur mit einer wohlbegr\u00fcndeten Angst zusammen, dass inl\u00e4ndische Gesch\u00e4ftsinteressen den Repressalien der USA ausgesetzt werden. Zudem wird Indien von den meisten Entwicklungsl\u00e4ndern in Asien, Afrika und Lateinamerika als Vorbild betrachtet. Wir sehen aber vor allem eines: Sechs Monate, nachdem sich die Krise zwischen Russland und dem Westen in einen politisch-milit\u00e4rischen Zusammensto\u00df verwandelt hat, wurde die Zahl der L\u00e4nder, die auch nur verbal bereit sind, die USA in ihrem Kampf gegen Moskau zu unterst\u00fctzen, mehr als halbiert.<\/p>\n<p>So wurde vergangene Woche versucht, die Unterst\u00fctzung der UN-Mitglieder f\u00fcr eine neue Erkl\u00e4rung zu gewinnen, mit der Russlands Vorgehen in der Ukraine-Frage verurteilt werden sollte. W\u00e4hrend mehr als 140 L\u00e4nder bei der UN-Generalversammlung im vergangenen M\u00e4rz eine \u00e4hnliche Resolution unterst\u00fctzten, folgten ihr diesmal nur 58 L\u00e4nder. Darunter sind insgesamt 30 formelle Mitglieder der von den USA gef\u00fchrten NATO, und mehrere weitere sind durch bilaterale Verteidigungsabkommen an Washington gebunden. Somit haben es mehr als zwei Drittel der internationalen Gemeinschaft vermieden, ihre Position zu europ\u00e4ischen Angelegenheiten festzulegen. Dies ist nat\u00fcrlich teilweise ein Ergebnis der russischen und chinesischen Diplomatie, die best\u00e4ndig darauf hinweist, dass die wahre Ursache des Krieges in Europa die Politik der USA ist.<\/p>\n<p>Diese Dynamik zeigt vor allem, dass die Entwicklungsl\u00e4nder verstehen, dass sie die M\u00f6glichkeit haben, eine bestimmte Wahl nicht zu treffen. Stattdessen ist eine Strategie der Distanz zu einem Konflikt vern\u00fcnftiger, und im aktuellen Kontext gerechtfertigt. In Europa ziehen sich die Angelegenheiten hin, und es bilden sich die Konturen eines langen Konflikts zwischen Russland und dem Westen, mit unterschiedlichen Graden\u00a0von Spannungen. Der gr\u00f6\u00dfte Teil der Welt indes wird sich zunehmend an das Leben unter diesen neuen Umst\u00e4nden anpassen. F\u00fcr die USA selbst hat die Abnahme ihrer F\u00e4higkeit, ihren Willen durchzusetzen, zu einer Strategie der Einsch\u00fcchterung und des Drucks auf unabh\u00e4ngige Akteure in der internationalen Gemeinschaft gef\u00fchrt.<\/p>\n<p>Aber auch diese Politik wird nicht erfolgreich sein. Selbst wenn Washington \u00fcber einen enormen Repressionsapparat verf\u00fcgte, w\u00fcrde dieser v\u00f6llig wirkungslos, wenn\u00a0die US-Regierung all\u00a0ihre internationalen Aktivit\u00e4ten in die Durchsetzung von &#8220;Sanktionen&#8221; konzentrierte. Allerdings k\u00f6nnen wir ein solches Szenario auch nicht g\u00e4nzlich ausschlie\u00dfen. Infolgedessen werden immer mehr L\u00e4nder sowohl mit Russland als auch mit dem Westen zusammenarbeiten. Und das Tempo dieser Zusammenarbeit wird von der M\u00f6glichkeit abh\u00e4ngen, etwas von beiden Seiten zu bekommen.<\/p>\n<p>Der Konflikt in Europa wiederum wird sich zunehmend lokalisieren und nur noch f\u00fcr die Hauptbeteiligten von unmittelbarem Interesse sein. W\u00e4hrend der Rest der Welt versuchen wird, sich nicht daran zu beteiligen. F\u00fcr Russland bedeutet dies, dass es offen und in der Lage sein muss, den Entwicklungsl\u00e4ndern das anzubieten, was sie brauchen \u2013 in den Bereichen Energie, Handelsg\u00fcter, Wissenschaft oder Bildung. Aber es besteht absolut keine Notwendigkeit, irgendjemanden in den Kampf um russische Interessen und Werte zu locken \u2013 genau das, was der Gro\u00dfteil der Welt vermeiden m\u00f6chte. So k\u00f6nnen wir relativ entspannt bleiben. Die Teilung der Welt in gegnerische Lager, die eine wesentliche Bedingung f\u00fcr den Ausbruch eines gr\u00f6\u00dferen Krieges ist, wird dadurch vermieden.<\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rt.com\/russia\/562689-us-ukraine-russia-struggle\/\">Englischen<\/a><\/em><\/p>\n<p><strong><em>Timofei Bordatschew <\/em><\/strong><em>ist Programmdirektor beim Waldai-Klub. Als Forscher ist er auf internationale Beziehungen und aktuelle Fragen der Weltpolitik spezialisiert, sowie auf die russisch-europ\u00e4ischen Beziehungen.<\/em><\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/pressefreiheit.rtde.tech\/russland\/148853-lawrow-kiew-meidet-verhandlungen-kollektiver\/\">Lawrow: Kiew meidet Verhandlungen, kollektiver Westen f\u00fcr Situation in der Ukraine verantwortlich<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/148964-droht-bei-neuen-bipolaren-weltordnung-grosser-krieg\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Versuche der USA sind gescheitert, die Weltgemeinschaft zum Einnehmen ihrer Position in Bezug auf die Ukraine zu zwingen. Der gr\u00f6\u00dfere Teil der Welt ist nicht daran interessiert, in den Kampf zwischen Russland und dem Westen hineingezogen zu werden. Von Timofei Bordatschew Was wir derzeit erleben ist nicht der Kalte Krieg und Russland ist nicht [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"79569244885136a0f41760058ad5f09d":["Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?"],"original_link":["https:\/\/de.rt.com\/meinung\/148964-droht-bei-neuen-bipolaren-weltordnung-grosser-krieg\/"],"_thumbnail_id":["19158"],"_wptg_p2tg_sent2tg":["2022-09-15 20:52:34"],"jnews_social_counter_last_update":["1784125207"]},"categories":[19,23],"tags":[363,32904,44,357,212,11211,130,213,214],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg? - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?\" \/>\n<meta property=\"og:description\" content=\"Die Versuche der USA sind gescheitert, die Weltgemeinschaft zum Einnehmen ihrer Position in Bezug auf die Ukraine zu zwingen. Der gr\u00f6\u00dfere Teil der Welt ist nicht daran interessiert, in den Kampf zwischen Russland und dem Westen hineingezogen zu werden. Von Timofei Bordatschew Was wir derzeit erleben ist nicht der Kalte Krieg und Russland ist nicht [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T18:34:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?\",\"datePublished\":\"2022-09-15T18:34:24+00:00\",\"dateModified\":\"2022-09-15T18:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/\"},\"wordCount\":1324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg\",\"keywords\":[\"bei\",\"bipolaren\",\"droht\",\"ein\",\"einer\",\"gr\u00f6\u00dfer\",\"krieg\",\"neuen\",\"Weltordnung\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/\",\"name\":\"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg? - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg\",\"datePublished\":\"2022-09-15T18:34:24+00:00\",\"dateModified\":\"2022-09-15T18:34:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg\",\"width\":460,\"height\":259,\"caption\":\"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg? - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/","og_locale":"de_DE","og_type":"article","og_title":"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?","og_description":"Die Versuche der USA sind gescheitert, die Weltgemeinschaft zum Einnehmen ihrer Position in Bezug auf die Ukraine zu zwingen. Der gr\u00f6\u00dfere Teil der Welt ist nicht daran interessiert, in den Kampf zwischen Russland und dem Westen hineingezogen zu werden. Von Timofei Bordatschew Was wir derzeit erleben ist nicht der Kalte Krieg und Russland ist nicht [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-09-15T18:34:24+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?","datePublished":"2022-09-15T18:34:24+00:00","dateModified":"2022-09-15T18:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/"},"wordCount":1324,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg","keywords":["bei","bipolaren","droht","ein","einer","gr\u00f6\u00dfer","krieg","neuen","Weltordnung"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/","url":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/","name":"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg? - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg","datePublished":"2022-09-15T18:34:24+00:00","dateModified":"2022-09-15T18:34:24+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/09\/Droht-bei-einer-neuen-bipolaren-Weltordnung-ein-grosser-Krieg.jpg","width":460,"height":259,"caption":"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/droht-bei-einer-neuen-bipolaren-weltordnung-ein-grosser-krieg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Droht bei einer neuen bipolaren Weltordnung ein gro\u00dfer Krieg?"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19157"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=19157"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/19157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/19158"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=19157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=19157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=19157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}