{"id":15950,"date":"2022-08-03T17:42:07","date_gmt":"2022-08-03T15:42:07","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/"},"modified":"2022-08-03T17:42:07","modified_gmt":"2022-08-03T15:42:07","slug":"ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/","title":{"rendered":"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/08\/62ea6fc048fbef45fa4401be.jpg\" \/><\/p>\n<p>Wolf Schneider ist NDR-Talkshow-Moderator, Buch-Autor und ehemaliger Dozent f\u00fcr Journalismus. Am Dienstag <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bild.de\/politik\/inland\/politik-inland\/deutschlands-oberster-sprachlehrer-wolf-schneider-gendern-ist-fuer-wichtigtuer-80889590.bild.html?wtmc=twttr.shr###wt_ref=https:\/t.co\/\">\u00e4u\u00dferte<\/a> sich der 97-J\u00e4hrige kritisch gegen\u00fcber der <em>Bild<\/em> zu der immer st\u00e4rker ideologisch aufgeladenen &#8220;Gender-Debatte&#8221;, die besonders von Moderatoren der \u00d6ffentlich-Rechtlichen, Beh\u00f6rden und Konzernen getragen wird. Er meint:<\/p>\n<blockquote>\n<p><em>&#8220;Die ganze Gender-Debatte ist eine Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben. Zwischen dem nat\u00fcrlichen und dem grammatischen Geschlecht besteht nicht der geringste Zusammenhang. Wie k\u00f6nnte es sonst das Weib hei\u00dfen, der L\u00f6we, die Schlange, das Pferd, obwohl sie alle dieselben zwei Geschlechter haben? Die F\u00fchrungskraft ist heute \u00fcberwiegend ein Mann \u2013 und keiner hat sich je beschwert. Die Liebe ist weiblich, dabei soll es bleiben.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Schneider gibt nachstehend einige abstruse Beispiele f\u00fcr die seiner Meinung nach &#8220;Verhohnepipelung der deutschen Sprache&#8221;.<strong><br \/><\/strong><\/p>\n<ul>\n<li>&#8220;Radfahrende&#8221; oder &#8220;Radfahrer*innen&#8221; \u2013 statt Radfahrer<\/li>\n<li>&#8220;Studierendenwerk&#8221; \u2013 statt Studentenwerk<\/li>\n<li>&#8220;Zu Fu\u00df gehende&#8221; \u2013 statt Fu\u00dfg\u00e4nger<\/li>\n<li>&#8220;B\u00fcrger:innen-Service&#8221; statt B\u00fcrgeramt<\/li>\n<li>&#8220;verstorbene Drogen gebrauchende&#8221; \u2013 statt Drogentote<\/li>\n<li>&#8220;ein Abonnement beziehende Person&#8221; \u2013 statt Abonnent<\/li>\n<li>&#8220;Kraftfahrzeug f\u00fchrende&#8221; oder &#8220;Autofahrerinnen und Autofahrer&#8221; \u2013 statt Autofahrer<\/li>\n<li>&#8220;Bankraubende&#8221; \u2013 statt Bankr\u00e4uber<\/li>\n<li>&#8220;des Terrors verd\u00e4chtigte Person&#8221;\u2013 statt Terrorist<\/li>\n<li>&#8220;Gastronomiebetriebsleitung&#8221; \u2013 statt Gastwirt<\/li>\n<li>&#8220;die Backenden&#8221; \u2013 statt die B\u00e4cker<\/li>\n<\/ul>\n<p>Laut einer <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/gesellschaft\/118493-forsa-umfrage-mehrheit-burger-ist\/\">Forsa-Umfrage<\/a> aus dem Sommer 2021 st\u00f6ren sich 75 Prozent der Befragten an der Sprachver\u00e4nderung im Fernsehen oder Radio. Auch viele J\u00fcngere\u00a0teilen diese Ansicht und nicht zuletzt wird f\u00fcr Ausl\u00e4nder die ohnehin schwierig zu erlernende deutsche Sprache zum v\u00f6lligen Spie\u00dfrutenlauf. Zudem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.juraforum.de\/news\/muessen-wir-alle-gendersprache-nutzen_257879\">lehnt<\/a> der Rat f\u00fcr\u00a0deutsche\u00a0Rechtschreibung die Verwendung von\u00a0Gendersternchen,\u00a0Gender-Gap und Gender-Doppelpunkten ab. Das \u00e4ndert jedoch nichts daran, dass vor allem seit dem Jahr 2020 besonders prominente Moderatoren und Kommentatoren in den zwangsfinanzierten GEZ-Medien rigoros davon Gebrauch machen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/123038-dieter-hallervorden-empfindet-gendern-als-vergewaltigung-der-sprache\/\">Dieter Hallervorden empfindet das Gendern als Vergewaltigung der Sprache<\/a><\/p>\n<\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/145166-ndr-ikone-schneider-ubers-gendern\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wolf Schneider ist NDR-Talkshow-Moderator, Buch-Autor und ehemaliger Dozent f\u00fcr Journalismus. Am Dienstag \u00e4u\u00dferte sich der 97-J\u00e4hrige kritisch gegen\u00fcber der Bild zu der immer st\u00e4rker ideologisch aufgeladenen &#8220;Gender-Debatte&#8221;, die besonders von Moderatoren der \u00d6ffentlich-Rechtlichen, Beh\u00f6rden und Konzernen getragen wird. Er meint: &#8220;Die ganze Gender-Debatte ist eine Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben. Zwischen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":15951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"fd51b2e65f937281afb8c67b32f7844a":["NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;"],"original_link":["https:\/\/de.rt.com\/inland\/145166-ndr-ikone-schneider-ubers-gendern\/"],"_thumbnail_id":["15951"],"_wptg_p2tg_sent2tg":["2022-08-03 17:50:08"],"jnews_social_counter_last_update":["1788222271"]},"categories":[19,23],"tags":[27937,45,21311,19987,375,25947,30164,30167,30165,23357,30166,50],"class_list":["post-15950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-ahnung","tag-die","tag-gendern","tag-habenquot","tag-keine","tag-leuten","tag-ndrikone","tag-quotwichtigtuerei","tag-schneider","tag-sprache","tag-uebers","tag-von"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;\" \/>\n<meta property=\"og:description\" content=\"Wolf Schneider ist NDR-Talkshow-Moderator, Buch-Autor und ehemaliger Dozent f\u00fcr Journalismus. Am Dienstag \u00e4u\u00dferte sich der 97-J\u00e4hrige kritisch gegen\u00fcber der Bild zu der immer st\u00e4rker ideologisch aufgeladenen &#8220;Gender-Debatte&#8221;, die besonders von Moderatoren der \u00d6ffentlich-Rechtlichen, Beh\u00f6rden und Konzernen getragen wird. Er meint: &#8220;Die ganze Gender-Debatte ist eine Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben. Zwischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-03T15:42:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/08\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;\",\"datePublished\":\"2022-08-03T15:42:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/\"},\"wordCount\":313,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg\",\"keywords\":[\"Ahnung\",\"die\",\"Gendern\",\"habenquot\",\"keine\",\"Leuten\",\"NDRIkone\",\"quotWichtigtuerei\",\"Schneider\",\"Sprache\",\"\u00fcbers\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/\",\"name\":\"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg\",\"datePublished\":\"2022-08-03T15:42:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg\",\"width\":460,\"height\":259,\"caption\":\"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/","og_locale":"de_DE","og_type":"article","og_title":"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;","og_description":"Wolf Schneider ist NDR-Talkshow-Moderator, Buch-Autor und ehemaliger Dozent f\u00fcr Journalismus. Am Dienstag \u00e4u\u00dferte sich der 97-J\u00e4hrige kritisch gegen\u00fcber der Bild zu der immer st\u00e4rker ideologisch aufgeladenen &#8220;Gender-Debatte&#8221;, die besonders von Moderatoren der \u00d6ffentlich-Rechtlichen, Beh\u00f6rden und Konzernen getragen wird. Er meint: &#8220;Die ganze Gender-Debatte ist eine Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben. Zwischen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-08-03T15:42:07+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/08\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;","datePublished":"2022-08-03T15:42:07+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/"},"wordCount":313,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/08\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg","keywords":["Ahnung","die","Gendern","habenquot","keine","Leuten","NDRIkone","quotWichtigtuerei","Schneider","Sprache","\u00fcbers","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/","url":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/","name":"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/08\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg","datePublished":"2022-08-03T15:42:07+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/08\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/08\/NDR-Ikone-Schneider-uebers-Gendern-quotWichtigtuerei-von-Leuten-die-von-Sprache.jpg","width":460,"height":259,"caption":"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ndr-ikone-schneider-uebers-gendern-wichtigtuerei-von-leuten-die-von-sprache-keine-ahnung-haben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"NDR-Ikone Schneider \u00fcbers Gendern: &quot;Wichtigtuerei von Leuten, die von Sprache keine Ahnung haben&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/15950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=15950"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/15950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/15951"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=15950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=15950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=15950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}