{"id":12981,"date":"2022-07-06T15:30:00","date_gmt":"2022-07-06T13:30:00","guid":{"rendered":"http:\/\/just-now.news\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/"},"modified":"2022-07-06T15:30:00","modified_gmt":"2022-07-06T13:30:00","slug":"george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/","title":{"rendered":"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c"},"content":{"rendered":"<div class=\"entry-content\">\n<p><\/p>\n<p>Ausgerechnet am 4. Juli erkl\u00e4rte der US-ungarische Milliard\u00e4r George Soros in einem Gastkommentar auf seiner Propagandaseite Project Syndicate dem US Supreme Court und der Republikanischen Partei den Krieg.<\/p>\n<p>\u201eDie amerikanische \u00d6ffentlichkeit ist durch den wachsenden Extremismus des Obersten US-Gerichtshofs alarmiert und erregt\u201c, behauptete Soros.  \u201eAber die W\u00e4hler m\u00fcssen die radikale Mehrheit des Gerichts als das anerkennen, was sie ist: Teil eines sorgf\u00e4ltig ausgearbeiteten Plans, die USA in ein repressives Regime zu verwandeln.\u201c<\/p>\n<div id=\"IC1-ad\" class=\"sponsor IC1\">\n<p class=\"ad-notice flipboard-remove\" fl:fl-noexcerpt=\"true\">Werbung \u2013 die Geschichte geht unten weiter<\/p>\n<div id=\"IC1\">\n<script>\n\t\t\t\t\tif( FFADS.units.IC1 && FFADS.units.IC1.ad_type == 'custom' && FFADS.units.IC1.custom_ads && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tdocument.getElementById( 'IC1' ).innerHTML = FFADS.units.IC1.custom_ads[0].code;\n\t\t\t\t\t\tif( ! FFADS.units.IC1.lazy_load ) eval( FFADS.units.IC1.custom_ads[0].rendering_script );\n\t\t\t\t\t}\n\t\t\t\t\telse if( FFADS.units.IC1 && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tif( 'IC' != 'SB' && 'IC' != 'SA' && FFADS.use_fixed_containers ) {\n\t\t\t\t\t\t\tlet max_wh = firefly_size_list_to_max_wh( FFADS.units.IC1.sizes );\n\t\t\t\t\t\t\tlet el = document.querySelector( '#IC1' );\n\t\t\t\t\t\t\tif( 'IC' != 'SA' && FFADS.slide_pixels ) {\n\t\t\t\t\t\t\t\tmax_wh[1] += parseInt( FFADS.slide_pixels );\n\t\t\t\t\t\t\t\tel.classList.add( 'sliding' );\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\tel.style.width = max_wh[0] + 'px';\n\t\t\t\t\t\t\tel.style.height = max_wh[1] + 'px';\n\t\t\t\t\t\t\tel.classList.add( 'fixed-size' );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tgoogletag.cmd.push( function() {\n\t\t\t\t\t\t\tFFADS.debug( 'googletag.displaying IC1' );\n\t\t\t\t\t\t\tgoogletag.display( 'IC1' );\n\t\t\t\t\t\t} );\n\t\t\t\t\t}\n\t\t\t\t\telse {\n\t\t\t\t\t\tdocument.querySelector( '#IC1-ad' ).style.display = 'none';}\n\t\t\t\t<\/script><\/div>\n<\/div>\n<p>Seit dem Fall des Eisernen Vorhangs im Jahr 1989 hat George Soros 32 Milliarden US-Dollar an \u201eSpenden\u201c f\u00fcr sein Einflusssystem namens \u201eOpen Society Foundations\u201c mobilisiert, um Regierungen und Marktpreise im ultimativen Insiderhandelsgesch\u00e4ft zu manipulieren.  In Zusammenarbeit mit der EU und USAID f\u00fchrt Open Society mit sogenannten Farbrevolutionen Krieg gegen konservative Regierungen auf der ganzen Welt und tr\u00e4gt die Schl\u00fcsselverantwortung f\u00fcr den aktuellen Krieg in der Ukraine.<\/p>\n<p>Trotzdem hat Soros das <em>Chuzpe<\/em> zu behaupten, dass \u201edie Demokratie jetzt ernsthaft gef\u00e4hrdet ist\u201c, von jedem, der es wagt, sich ihm zu widersetzen.  W\u00e4hrend Soros zu Recht vor der Gefahr autokratischer Regime in Russland und China warnt, behauptet sein verr\u00e4terischer Spruch \u201edie Bedrohung der USA durch die <strong>innere Feinde der Demokratie<\/strong> ist noch gr\u00f6\u00dfer.\u201c<\/p>\n<p><script>\n\t\t\t\t\tif( ! getCookie( 'ff_subbed' ) ) if( typeof FFADS.replace_ict != 'undefined' ) if( FFADS.replace_ict ) eval( FFADS.replace_ict );\n\t\t\t\t<\/script><\/p>\n<p>F\u00fcr den in Ungarn geborenen eingeb\u00fcrgerten B\u00fcrger geh\u00f6ren zu diesen \u201eHausfeinden\u201c der derzeitige Oberste Gerichtshof, \u201eder von Rechtsextremisten dominiert wird, und die Republikanische Partei von Donald Trump, die diese Extremisten vor Gericht gestellt hat\u201c.<\/p>\n<p>Soros sieht die Gefahr dieses \u201eradikalisierten\u201c Obersten Gerichtshofs in seiner strikten originalistischen Herangehensweise an das Gesetz: \u201eRichter Samuel Alito, der Verfasser der Mehrheitsmeinung, st\u00fctzte seine Entscheidung auf die Behauptung, dass die vierzehnte \u00c4nderung nur die Rechte sch\u00fctzt, die allgemein anerkannt wurden 1868, als die \u00c4nderung ratifiziert wurde.  Aber dieses Argument gef\u00e4hrdet viele andere Rechte, die seitdem anerkannt wurden, darunter das Recht auf Verh\u00fctung, die gleichgeschlechtliche Ehe und die Rechte von LGBTQ.\u201c<\/p>\n<div id=\"IC2-ad\" class=\"sponsor IC2\">\n<p class=\"ad-notice flipboard-remove\" fl:fl-noexcerpt=\"true\">Werbung \u2013 die Geschichte geht unten weiter<\/p>\n<div id=\"IC2\">\n<script>\n\t\t\t\t\tif( FFADS.units.IC2 && FFADS.units.IC2.ad_type == 'custom' && FFADS.units.IC2.custom_ads && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tdocument.getElementById( 'IC2' ).innerHTML = FFADS.units.IC2.custom_ads[0].code;\n\t\t\t\t\t\tif( ! FFADS.units.IC2.lazy_load ) eval( FFADS.units.IC2.custom_ads[0].rendering_script );\n\t\t\t\t\t}\n\t\t\t\t\telse if( FFADS.units.IC2 && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tif( 'IC' != 'SB' && 'IC' != 'SA' && FFADS.use_fixed_containers ) {\n\t\t\t\t\t\t\tlet max_wh = firefly_size_list_to_max_wh( FFADS.units.IC2.sizes );\n\t\t\t\t\t\t\tlet el = document.querySelector( '#IC2' );\n\t\t\t\t\t\t\tif( 'IC' != 'SA' && FFADS.slide_pixels ) {\n\t\t\t\t\t\t\t\tmax_wh[1] += parseInt( FFADS.slide_pixels );\n\t\t\t\t\t\t\t\tel.classList.add( 'sliding' );\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\tel.style.width = max_wh[0] + 'px';\n\t\t\t\t\t\t\tel.style.height = max_wh[1] + 'px';\n\t\t\t\t\t\t\tel.classList.add( 'fixed-size' );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tgoogletag.cmd.push( function() {\n\t\t\t\t\t\t\tFFADS.debug( 'googletag.displaying IC2' );\n\t\t\t\t\t\t\tgoogletag.display( 'IC2' );\n\t\t\t\t\t\t} );\n\t\t\t\t\t}\n\t\t\t\t\telse {\n\t\t\t\t\t\tdocument.querySelector( '#IC2-ad' ).style.display = 'none';}\n\t\t\t\t<\/script><\/div>\n<\/div>\n<p>Soros scheint anzuerkennen, dass viele der von Aktivistengerichten beanspruchten \u201eRechte\u201c, wie das \u201eRecht auf Empf\u00e4ngnisverh\u00fctung, gleichgeschlechtliche Ehe und LGBTQ-Rechte\u201c, eigentlich nicht in der Verfassung zu finden sind und umgangen werden m\u00fcssten der Legislative, nicht von aktivistischen Richtern.<\/p>\n<p>\u201eEs gibt nur einen Weg, den Obersten Gerichtshof zu z\u00fcgeln: die Republikanische Partei in einem Erdrutsch aus dem Amt zu werfen\u201c, schreibt Soros, r\u00e4umt aber ein, dass dies nicht einfach sein wird:<\/p>\n<p><em>\u201eAber wenn es darum geht, einen Erdrutschsieg gegen die radikalisierten Republikaner zu organisieren, stehen die Gegner vor fast un\u00fcberwindbaren Hindernissen.  Die Republikaner haben nicht nur den Obersten Gerichtshof und viele untergeordnete Gerichte mit extremistischen Richtern besetzt.  In Staaten wie Florida, Georgia und Texas haben sie eine Reihe von Gesetzen erlassen, die das W\u00e4hlen sehr erschweren.  <\/em><\/p>\n<p><em>W\u00e4hrend sich diese Gesetze auf die Entrechtung von Afroamerikanern, anderen Minderheiten und jungen W\u00e4hlern im Allgemeinen konzentrieren, besteht ihr letztendliches Ziel darin, den Republikanern zu helfen, Wahlen zu gewinnen.  Wie ein Bundesrichter in Florida k\u00fcrzlich schrieb, als er eines dieser Gesetze aufhob, wurden sie \u201emit der Absicht erlassen, Floridas Wahlsystem so umzustrukturieren, dass die Republikanische Partei gegen\u00fcber der Demokratischen Partei beg\u00fcnstigt wird\u201c.  <\/em><\/p>\n<p><em>Diese Gesetze w\u00e4ren schon schlimm genug, wenn sie nur darauf abzielten, wer w\u00e4hlen darf.  Aber die Republikaner gehen jetzt sogar noch weiter, indem sie den Prozess der Stimmenausz\u00e4hlung und der Wahlzertifizierung angreifen.  Von Gesetzes\u00e4nderungen, um die Subversion des Wahlsystems zu erleichtern, bis hin zur Rekrutierung von Gl\u00e4ubigen<strong> Trumps gro\u00dfe L\u00fcge<\/strong> dass ihm die Wahlen 2020 gestohlen wurden, um den Prozess zu \u00fcberwachen, beobachten wir, wie die Republikaner unser System der Demokratie von allen Seiten angreifen.  Und auch hier hat der radikale Oberste Gerichtshof seinen Teil dazu beigetragen, indem er das Bundeswahlrechtsgesetz ausgeh\u00f6hlt und eine Neuverteilung der Wahlkreise durch nackte Partisanen zugelassen hat, um die Stimmrechte von Minderheiten zu schw\u00e4chen.\u201c<\/em><\/p>\n<div id=\"IC3-ad\" class=\"sponsor IC3\">\n<p class=\"ad-notice flipboard-remove\" fl:fl-noexcerpt=\"true\">Werbung \u2013 die Geschichte geht unten weiter<\/p>\n<div id=\"IC3\">\n<script>\n\t\t\t\t\tif( FFADS.units.IC3 && FFADS.units.IC3.ad_type == 'custom' && FFADS.units.IC3.custom_ads && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tdocument.getElementById( 'IC3' ).innerHTML = FFADS.units.IC3.custom_ads[0].code;\n\t\t\t\t\t\tif( ! FFADS.units.IC3.lazy_load ) eval( FFADS.units.IC3.custom_ads[0].rendering_script );\n\t\t\t\t\t}\n\t\t\t\t\telse if( FFADS.units.IC3 && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tif( 'IC' != 'SB' && 'IC' != 'SA' && FFADS.use_fixed_containers ) {\n\t\t\t\t\t\t\tlet max_wh = firefly_size_list_to_max_wh( FFADS.units.IC3.sizes );\n\t\t\t\t\t\t\tlet el = document.querySelector( '#IC3' );\n\t\t\t\t\t\t\tif( 'IC' != 'SA' && FFADS.slide_pixels ) {\n\t\t\t\t\t\t\t\tmax_wh[1] += parseInt( FFADS.slide_pixels );\n\t\t\t\t\t\t\t\tel.classList.add( 'sliding' );\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\tel.style.width = max_wh[0] + 'px';\n\t\t\t\t\t\t\tel.style.height = max_wh[1] + 'px';\n\t\t\t\t\t\t\tel.classList.add( 'fixed-size' );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tgoogletag.cmd.push( function() {\n\t\t\t\t\t\t\tFFADS.debug( 'googletag.displaying IC3' );\n\t\t\t\t\t\t\tgoogletag.display( 'IC3' );\n\t\t\t\t\t\t} );\n\t\t\t\t\t}\n\t\t\t\t\telse {\n\t\t\t\t\t\tdocument.querySelector( '#IC3-ad' ).style.display = 'none';}\n\t\t\t\t<\/script><\/div>\n<\/div>\n<p>\u201eWir m\u00fcssen alles tun, um zu verhindern\u201c, dass die Republikaner im November 2022 an die Macht kommen, schreibt Soros und \u00f6ffnet damit scheinbar die Schleusen f\u00fcr eine weitere Runde kompromisslosen Betrugs der Demokraten.<\/p>\n<p>Gl\u00fccklicherweise wissen die amerikanischen Patrioten jetzt nach dem historischen Betrug von 2020, was auf dem Spiel steht, und organisieren sich in Projekten wie der Precinct Strategy.<\/p>\n<p>Spiel weiter, George.<\/p>\n<\/p>\n<p class=\"article-ask\"><span class=\"ask\"><script>\n  if( getParameterByName( \"utm_source\" ) == \"testpage\" ) {\n    !function(e,t,a,n,g){e[n]=e[n]||[],e[n].push({\"gtm.start\":(new Date).getTime(),event:\"gtm.js\"});var m=t.getElementsByTagName(a)[0],r=t.createElement(a);r.async=!0,r.src=\"https:\/\/www.googletagmanager.com\/gtm.js?id=GTM-PL4PD49\",m.parentNode.insertBefore(r,m)}(window.parent,window.parent.document,\"script\",\"dataLayer\");\n    var iframe=window.parent.document.createElement(\"iframe\");iframe.src=\"https:\/\/www.googletagmanager.com\/ns.html?id=GTM-PL4PD49\";iframe.height=\"0\";iframe.width=\"0\";iframe.style=\"display:none;visibility:hidden\";window.parent.document.body.appendChild(iframe);\n    window.parent[\"$$mm-analytics\"] = window.parent[\"$$mm-analytics\"] || {};if (typeof window.parent[\"$$mm-analytics\"].firstEmbed === \"undefined\") {window.parent[\"$$mm-analytics\"].firstEmbed = Date.now();}\n    let as1 = document.createElement( \"script\" );\n    as1.src = \"https:\/\/bucket1.mm-syringe.com\/prod\/configs\/ee2300c8-43d2-7f0b-dac0-40aaf31c9d3d.js\";\n    document.body.appendChild( as1 );\n    let as2 = document.createElement( \"script\" );\n    as2.src = \"https:\/\/bucket1.mm-syringe.com\/prod\/injector\/injector.1.5.3.js\";\n    document.body.appendChild( as2 );\n  }\n<\/script><\/p>\n<div class=\"apester-media\" data-token=\"5f10a39f94902bc81d3d59a7\" data-context=\"true\" data-tags=\"\" data-fallback=\"true\" height=\"350\"><\/div>\n<p><script id=\"apester_script\" src=\"https:\/\/static.apester.com\/js\/sdk\/latest\/apester-sdk.js\" async><\/script><script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-EFE91RJVSQ\"><\/script><script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag(\\\\\\'js\\\\\\', new Date());\n  gtag(\\\\\\'config\\\\\\', \\\\\\'G-EFE91RJVSQ\\\\\\');\n<\/script><script type=\"text\/javascript\">\n\tfunction e(e){var t=!(arguments.length>1&&void 0!==arguments[1])||arguments[1],c=document.createElement(\"script\");c.src=e,t?c.type=\"module\":(c.async=!0,c.type=\"text\/javascript\",c.setAttribute(\"nomodule\",\"\"));var n=document.getElementsByTagName(\"script\")[0];n.parentNode.insertBefore(c,n)}function t(t,c,n){var a,o,r;null!==(a=t.marfeel)&&void 0!==a||(t.marfeel={}),null!==(o=(r=t.marfeel).cmd)&&void 0!==o||(r.cmd=[]),t.marfeel.config=n,t.marfeel.config.accountId=c;var i=\"https:\/\/sdk.mrf.io\/statics\";e(\"\".concat(i,\"\/marfeel-sdk.js?id=\").concat(c),!0),e(\"\".concat(i,\"\/marfeel-sdk.es5.js?id=\").concat(c),!1)}!function(e,c){var n=arguments.length>2&&void 0!==arguments[2]?arguments[2]:{};t(e,c,n)}(window,1573,{} \/*config*\/);\n<\/script><\/span><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thegatewaypundit.com\/2022\/07\/george-soros-declares-war-supreme-court-republican-party-enemies-democracy\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ausgerechnet am 4. Juli erkl\u00e4rte der US-ungarische Milliard\u00e4r George Soros in einem Gastkommentar auf seiner Propagandaseite Project Syndicate dem US Supreme Court und der Republikanischen Partei den Krieg. \u201eDie amerikanische \u00d6ffentlichkeit ist durch den wachsenden Extremismus des Obersten US-Gerichtshofs alarmiert und erregt\u201c, behauptete Soros. \u201eAber die W\u00e4hler m\u00fcssen die radikale Mehrheit des Gerichts als das [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["1161"],"7f04f6ffa35342c7e9a96c826d555e58":["George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c\n"],"original_link":["https:\/\/www.thegatewaypundit.com\/2022\/07\/george-soros-declares-war-supreme-court-republican-party-enemies-democracy\/"],"_thumbnail_id":["12982"],"wp_automatic_remove_first_image":["yes"],"jnews_social_counter_last_update":["1778530201"]},"categories":[25],"tags":[134,2570,48,82,1030,27054,350,3333,130,6801,2504,10228,5890,140],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c\" \/>\n<meta property=\"og:description\" content=\"Ausgerechnet am 4. Juli erkl\u00e4rte der US-ungarische Milliard\u00e4r George Soros in einem Gastkommentar auf seiner Propagandaseite Project Syndicate dem US Supreme Court und der Republikanischen Partei den Krieg. \u201eDie amerikanische \u00d6ffentlichkeit ist durch den wachsenden Extremismus des Obersten US-Gerichtshofs alarmiert und erregt\u201c, behauptete Soros. \u201eAber die W\u00e4hler m\u00fcssen die radikale Mehrheit des Gerichts als das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T13:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"greatreset\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"greatreset\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/\"},\"author\":{\"name\":\"greatreset\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/8afb4cd92b68572db7902c13a349ffcb\"},\"headline\":\"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c\",\"datePublished\":\"2022-07-06T13:30:00+00:00\",\"dateModified\":\"2022-07-06T13:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/\"},\"wordCount\":731,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg\",\"keywords\":[\"DEM\",\"Demokratie\",\"den\",\"der\",\"erkl\u00e4rt\",\"Feinde\",\"George\",\"Gerichtshof\",\"krieg\",\"Obersten\",\"Partei\",\"republikanischen\",\"soros\",\"und\"],\"articleSection\":[\"USA\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/\",\"url\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/\",\"name\":\"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg\",\"datePublished\":\"2022-07-06T13:30:00+00:00\",\"dateModified\":\"2022-07-06T13:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/8afb4cd92b68572db7902c13a349ffcb\",\"name\":\"greatreset\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a088df625d49991c090e78c8b9542592?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a088df625d49991c090e78c8b9542592?s=96&d=mm&r=g\",\"caption\":\"greatreset\"},\"url\":\"https:\/\/now-news.de\/de\/author\/greatreset\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/","og_locale":"de_DE","og_type":"article","og_title":"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c","og_description":"Ausgerechnet am 4. Juli erkl\u00e4rte der US-ungarische Milliard\u00e4r George Soros in einem Gastkommentar auf seiner Propagandaseite Project Syndicate dem US Supreme Court und der Republikanischen Partei den Krieg. \u201eDie amerikanische \u00d6ffentlichkeit ist durch den wachsenden Extremismus des Obersten US-Gerichtshofs alarmiert und erregt\u201c, behauptete Soros. \u201eAber die W\u00e4hler m\u00fcssen die radikale Mehrheit des Gerichts als das [&hellip;]","og_url":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-07-06T13:30:00+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg","type":"image\/jpeg"}],"author":"greatreset","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"greatreset","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/"},"author":{"name":"greatreset","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/8afb4cd92b68572db7902c13a349ffcb"},"headline":"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c","datePublished":"2022-07-06T13:30:00+00:00","dateModified":"2022-07-06T13:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/"},"wordCount":731,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg","keywords":["DEM","Demokratie","den","der","erkl\u00e4rt","Feinde","George","Gerichtshof","krieg","Obersten","Partei","republikanischen","soros","und"],"articleSection":["USA"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/","url":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/","name":"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg","datePublished":"2022-07-06T13:30:00+00:00","dateModified":"2022-07-06T13:30:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/George-Soros-erklaert-dem-Obersten-Gerichtshof-und-der-Republikanischen-Partei.jpeg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/usa\/george-soros-erklaert-dem-obersten-gerichtshof-und-der-republikanischen-partei-den-krieg-feinde-der-demokratie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"George Soros erkl\u00e4rt dem Obersten Gerichtshof und der Republikanischen Partei den Krieg: \u201eFeinde der Demokratie\u201c"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/8afb4cd92b68572db7902c13a349ffcb","name":"greatreset","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a088df625d49991c090e78c8b9542592?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a088df625d49991c090e78c8b9542592?s=96&d=mm&r=g","caption":"greatreset"},"url":"https:\/\/now-news.de\/de\/author\/greatreset\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/12981"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=12981"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/12981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/12982"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=12981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=12981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=12981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}