{"id":12519,"date":"2022-07-01T17:44:48","date_gmt":"2022-07-01T15:44:48","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/"},"modified":"2022-07-01T17:44:48","modified_gmt":"2022-07-01T15:44:48","slug":"inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/","title":{"rendered":"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/62bed9a348fbef14773f70db.jpg\" \/><\/p>\n<p>Im Juni 2022 erreichte die Inflation in der Euro-Zone ein Rekordhoch. Um gegenzusteuern, will die Europ\u00e4ische Zentralbank (EZB) mit einer Zinserh\u00f6hung reagieren.<\/p>\n<p>Wie das Portal <em>CNBC<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.cnbc.com\/2022\/07\/01\/euro-zone-inflation-8point6percent-in-june-ecb-to-hike-rates-for-first-time-in-11-years.html\">berichtet<\/a>, lag die Inflation im gesamten Euroraum im vergangenen Monat bei 8,6 Prozent. Dies gehe aus den am Freitag ver\u00f6ffentlichten vorl\u00e4ufigen Zahlen des europ\u00e4ischen Statistikamtes &#8220;Eurostat&#8221; hervor. Damit wurde die Vorhersage einer <em>Reuters<\/em>-Umfrage unter Wirtschaftsexperten von 8,4 Prozent noch \u00fcbertroffen. Im Mai hatte die Inflationsrate noch 8,1 Prozent betragen. Die Geldentwertung in der Euro-Zone n\u00e4hert sich der 9-Prozent-Marke weiter an.<\/p>\n<p>In Deutschland sei jedoch entgegen der Erwartungen die Inflationsrate um 0,5 Prozentpunkte im Vergleich zum Vormonat zur\u00fcckgegangen. Nach Meinung von Experten sei dies auf die j\u00fcngsten staatlichen Subventionen zur\u00fcckzuf\u00fchren, die die Auswirkungen der steigenden Energiepreise abmildern sollen. Allerdings sei ein Ende der Inflation nicht abzusehen.<\/p>\n<p>In anderen L\u00e4ndern der Euro-Zone seien, im Unterschied zu Deutschland, gegenl\u00e4ufige Tendenzen zu beobachten. Sowohl Frankreich als auch Spanien hatte im Juni neue Inflationsrekorde zu verzeichnen. Madrid erwarte laut <em>Reuters<\/em> zum ersten Mal seit 1985 eine \u00dcberschreitung der Zehn-Prozent-Marke.<\/p>\n<p><strong>Reaktionen der Europ\u00e4ischen Zentralbank<\/strong><\/p>\n<p>Die EZB, darauf eingeschworen, den Preisanstieg zu bek\u00e4mpfen, wird vermutlich Ende Juli zusammentreten, um eine Zinserh\u00f6hung anzuk\u00fcndigen. Darauf wird die \u00d6ffentlichkeit seit Wochen in der Wirtschaftsberichterstattung vorbereitet. Die Euro-Zentralbank hat verlauten lassen, dass sie die Zinsen im September abermals anheben wird. Wenn die EZB diese Politik tats\u00e4chlich umsetzen sollte, d\u00fcrfte der Leitzins in diesem Jahr in den positiven Bereich zur\u00fcckkehren \u2013 durchaus eine Sensation. Seit 2014 hatte die EZB eine Negativ-Zinspolitik verfolgt.<\/p>\n<p>Anfang dieser Woche griff EZB-Pr\u00e4sidentin Christine Lagarde zu vergleichsweise d\u00fcsteren T\u00f6nen: &#8220;Wenn sich die Inflationsaussichten nicht verbessern, haben wir gen\u00fcgend Informationen, um schneller zu handeln&#8221;, meinte Lagarde vor einem Publikum im portugiesischen Sintra \u00fcber die Zeit nach der \u00fcbern\u00e4chsten Zinserh\u00f6hung im September.<\/p>\n<p>Allerdings d\u00fcrften die tr\u00fcben Konjunkturprognosen f\u00fcr die kommenden Monate weitere Fragen f\u00fcr die Geldpolitik in der Euro-Zone aufwerfen. Denn falls die Zentralbank die Zinss\u00e4tze zu schnell anheben sollte, k\u00f6nnte dies das Wirtschaftswachstum in einer Periode, die bereits von einer Abschw\u00e4chung gekennzeichnet ist, noch weiter behindern.<\/p>\n<p><strong>Konjunkturaussichten d\u00fcster<\/strong><\/p>\n<p>Die neuesten Konjunkturdaten zeigen deutlich, dass in der Euro-Zone bereits ein R\u00fcckgang der Wirtschaftsleistung eingetreten ist. Die Frage ist allein, ob bereits in diesem Jahr oder erst 2023 eine massive Rezession eintreten wird.<\/p>\n<p>Mindestens f\u00fcr das Jahr 2023 rechnen \u00d6konomen mit einem R\u00fcckgang des Bruttoinlandsprodukts (BIP) um 0,8 Prozent. Dabei wird auf EU- und EZB-Ebene gerne vermieden, von einer Rezession zu sprechen. Auch die EZB-Chefin \u00fcbte sich in Optimismus:<\/p>\n<blockquote>\n<p><em>&#8220;Wir erwarten immer noch positive Wachstumsraten aufgrund der inl\u00e4ndischen Puffer gegen den Verlust der Wachstumsdynamik&#8221;,<\/em><\/p>\n<\/blockquote>\n<p>sagte Lagarde noch Anfang dieser Woche. Die EZB prognostizierte im Juni eine BIP-Rate von 2,8 Prozent f\u00fcr die Region in diesem Jahr. Neue Zahlen sollen im September ver\u00f6ffentlicht werden.<\/p>\n<p>Der Chefvolkswirt der EZB, Philip Lane, meinte gegen\u00fcber <em>CNBC<\/em> wenig \u00fcberraschend, man m\u00fcsse in den kommenden Monaten wachsam bleiben \u2013 und mit &#8220;zwei Risiken umgehen&#8221;: der Inflation einerseits und der Rezession andererseits.<\/p>\n<p>Wie die <em>FAZ<\/em> bereits Mitte Juni <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.faz.net\/aktuell\/finanzen\/so-wird-die-ezb-in-diesem-jahr-wohl-die-zinsen-anheben-18101952.html\">schrieb<\/a>, d\u00fcrften nach einer eher geringen EZB-Zinserh\u00f6hung um einen Viertelprozentpunkt Ende Juli ein gr\u00f6\u00dferer Zinsschritt im September erfolgen \u2013 und dann &#8220;noch mehrere Trippelschritte in diesem Jahr&#8221;. So k\u00f6nnte der sogenannte Einlagensatz bis zum Jahresende auf 0,75 Prozent steigen. Damit w\u00e4re die Negativzinspolitik dann beendet.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/rtde.site\/wirtschaft\/142370-gaspreise-in-europa-erreichen-hochsten\/\">Gaspreise in Europa erreichen h\u00f6chsten Stand seit M\u00e4rz<\/a><\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/wirtschaft\/142422-inflation-in-euro-zone-erreicht\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Juni 2022 erreichte die Inflation in der Euro-Zone ein Rekordhoch. Um gegenzusteuern, will die Europ\u00e4ische Zentralbank (EZB) mit einer Zinserh\u00f6hung reagieren. Wie das Portal CNBC\u00a0berichtet, lag die Inflation im gesamten Euroraum im vergangenen Monat bei 8,6 Prozent. Dies gehe aus den am Freitag ver\u00f6ffentlichten vorl\u00e4ufigen Zahlen des europ\u00e4ischen Statistikamtes &#8220;Eurostat&#8221; hervor. Damit wurde die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"340439b89b9e45b9d9648b5b1790b4e3":["Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?"],"original_link":["https:\/\/de.rt.com\/wirtschaft\/142422-inflation-in-euro-zone-erreicht\/"],"_thumbnail_id":["12520"],"_wptg_p2tg_sent2tg":["2022-07-01 17:58:32"],"jnews_social_counter_last_update":["1778331420"]},"categories":[19,23],"tags":[48,45,3073,9872,20377,1082,198,21886,13724],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins? - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?\" \/>\n<meta property=\"og:description\" content=\"Im Juni 2022 erreichte die Inflation in der Euro-Zone ein Rekordhoch. Um gegenzusteuern, will die Europ\u00e4ische Zentralbank (EZB) mit einer Zinserh\u00f6hung reagieren. Wie das Portal CNBC\u00a0berichtet, lag die Inflation im gesamten Euroraum im vergangenen Monat bei 8,6 Prozent. Dies gehe aus den am Freitag ver\u00f6ffentlichten vorl\u00e4ufigen Zahlen des europ\u00e4ischen Statistikamtes &#8220;Eurostat&#8221; hervor. Damit wurde die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-01T15:44:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?\",\"datePublished\":\"2022-07-01T15:44:48+00:00\",\"dateModified\":\"2022-07-01T15:44:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg\",\"keywords\":[\"den\",\"die\",\"erh\u00f6ht\",\"erreicht\",\"Eurozone\",\"EZB\",\"Inflation\",\"Leitzins\",\"Rekordhoch\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/\",\"name\":\"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins? - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg\",\"datePublished\":\"2022-07-01T15:44:48+00:00\",\"dateModified\":\"2022-07-01T15:44:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg\",\"width\":460,\"height\":259,\"caption\":\"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins? - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/","og_locale":"de_DE","og_type":"article","og_title":"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?","og_description":"Im Juni 2022 erreichte die Inflation in der Euro-Zone ein Rekordhoch. Um gegenzusteuern, will die Europ\u00e4ische Zentralbank (EZB) mit einer Zinserh\u00f6hung reagieren. Wie das Portal CNBC\u00a0berichtet, lag die Inflation im gesamten Euroraum im vergangenen Monat bei 8,6 Prozent. Dies gehe aus den am Freitag ver\u00f6ffentlichten vorl\u00e4ufigen Zahlen des europ\u00e4ischen Statistikamtes &#8220;Eurostat&#8221; hervor. Damit wurde die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-07-01T15:44:48+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?","datePublished":"2022-07-01T15:44:48+00:00","dateModified":"2022-07-01T15:44:48+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg","keywords":["den","die","erh\u00f6ht","erreicht","Eurozone","EZB","Inflation","Leitzins","Rekordhoch"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/","url":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/","name":"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins? - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg","datePublished":"2022-07-01T15:44:48+00:00","dateModified":"2022-07-01T15:44:48+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Inflation-in-Euro-Zone-erreicht-Rekordhoch-\u2013-Erhoeht-die-EZB-den.jpg","width":460,"height":259,"caption":"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/inflation-in-euro-zone-erreicht-rekordhoch-erhoeht-die-ezb-den-leitzins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Inflation in Euro-Zone erreicht Rekordhoch \u2013 Erh\u00f6ht die EZB den Leitzins?"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/12519"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=12519"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/12519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/12520"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=12519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=12519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=12519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}