{"id":109826,"date":"2026-09-02T21:42:16","date_gmt":"2026-09-02T19:42:16","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/"},"modified":"2026-09-02T21:42:16","modified_gmt":"2026-09-02T19:42:16","slug":"so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/","title":{"rendered":"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion"},"content":{"rendered":"<div class=\"Text-root Text-type_1 \">\n                Das Interesse an &#8220;RT DE&#8221; ist offenbar so gro\u00df, dass das Magazin &#8220;Republik&#8221; ihm gleich ein eigenes Podium widmet. Unter dem Titel &#8220;Russische Desinformation und die Schweizer Neutralit\u00e4t&#8221; diskutieren ausgew\u00e4hlte Expertinnen und Experten \u00fcber Russland, &#8220;RT DE&#8221; und die Schweizer Politik.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Hans-Ueli L\u00e4ppli<\/em><\/p>\n<p><strong><\/strong>Es gibt Themen, die lassen die Schweizer Medien einfach nicht los. <em>RT DE<\/em> geh\u00f6rt offenbar inzwischen dazu. Am 14. September l\u00e4dt das links-progressive Online-Magazin <em>Republik<\/em> in Z\u00fcrich zu einer Podiumsdiskussion \u00fcber &#8220;<a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.republik.ch\/veranstaltungen\/russische-desinformation-und-die-schweizer-neutralitat\">Russische Desinformation und die Schweizer Neutralit\u00e4t<\/a>&#8220;.<\/p>\n<p>Unter der Moderation von Bundeshausredakteurin Priscilla Imboden sollen ausgew\u00e4hlte &#8220;Russland-ExpertInnen&#8221; dar\u00fcber diskutieren, wie Russland angeblich versucht, die politische Debatte in der Schweiz zu beeinflussen \u2013 und welche Rolle Medien wie <em>RT DE<\/em> dabei spielen.<\/p>\n<p>Die politische Richtung des Abends ist dabei bereits in der Ank\u00fcndigung erkennbar. Russland wird als Akteur dargestellt, der demokratische Gesellschaften schw\u00e4chen wolle und sich in den Abstimmungskampf \u00fcber die Neutralit\u00e4tsinitiative einmische. Kritische Stimmen gegen\u00fcber der vorherrschenden Schweizer Russland- und Ukraine-Politik d\u00fcrften es auf diesem Podium entsprechend schwer haben.<\/p>\n<p><strong>Go Woke, Go Broke<\/strong><\/p>\n<p>Auff\u00e4llig ist allerdings, dass ausgerechnet die <em>Republik<\/em>\u00a0<em>RT DE<\/em> eine solche Aufmerksamkeit schenkt.<\/p>\n<p>Denn die <em>Republik<\/em> steht beispielhaft f\u00fcr ein progressives, woke-gepr\u00e4gtes Medienmodell, das zunehmend um seine gesellschaftliche und wirtschaftliche Relevanz k\u00e4mpfen muss. Umwelt- und Klimathemen, Wokeness, moralische Deutungshoheit sowie ein starkes Dauerfeuer gegen AfD und SVP geh\u00f6ren zum festen politischen Deutungsrahmen solcher Medien. Die Botschaft lautet dabei nicht selten: Wir kennen die richtige Haltung \u2013 und wer informiert sein will, sollte uns lesen.<\/p>\n<p>Doch dieses Gesch\u00e4ftsmodell scheint an Grenzen zu sto\u00dfen. Sinkende Abonnentenzahlen, hohe Verluste und negatives Eigenkapital zeigen, dass politische Haltung allein noch kein tragf\u00e4higes Medienmodell ergibt. Zwar konnte die <em>Republik<\/em> 2024\/25 wieder einen Gewinn ausweisen, gleichzeitig blieb das Eigenkapital mit rund 1,7 Millionen Franken negativ.<\/p>\n<p>Kurz gesagt: Progressive Medien k\u00e4mpfen zunehmend um Aufmerksamkeit und Relevanz, w\u00e4hrend sie gleichzeitig anderen Medien wie <em>RT DE<\/em> erkl\u00e4ren, was &#8220;Desinformation&#8221; ist. Eine kritische Analyse der eigenen Medienblase w\u00e4re dabei mindestens ebenso interessant. Wer analysiert eigentlich wen?<\/p>\n<p>Nat\u00fcrlich ist es legitim, <em>RT DE<\/em> kritisch zu untersuchen, doch eine ernsthafte Debatte \u00fcber Desinformation sollte in beide Richtungen schauen.<\/p>\n<p>Die Arbeit des Senders ist inzwischen so gro\u00df, dass die <em>Republik<\/em>\u00a0ihm gleich einen eigenen Podiumsabend widmet.<\/p>\n<p>Dabei wird <em>RT DE<\/em> erneut als Teil einer russischen Desinformationskampagne dargestellt. Was dabei gerne ausgeblendet wird, ist die Tatsache, dass <em>RT DE<\/em> eine alternative Perspektive auf internationale Politik bietet und Themen aufgreift, die in westlichen Medien h\u00e4ufig anders oder gar nicht dargestellt werden.<\/p>\n<p>Gerade deshalb ist die Aufmerksamkeit der <em>Republik<\/em> interessant. Wer <em>RT DE<\/em> kritisieren will, sollte sich mit seinen tats\u00e4chlichen Inhalten auseinandersetzen und nicht jede vom westlichen Mainstream abweichende Sichtweise automatisch als Propaganda abstempeln.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttps:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png 850w,\n                https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png 1960w,            \" ><source data-srcset=\" \nhttps:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png 460w,\n              https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-original lazyload\" data-src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png\" alt=\"\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png\" alt=\"\"><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><\/span><span class=\"RTImage-source\"><a rel=\"nofollow\" target=\"_blank\" class=\"RTImage-captionItem Link-root\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.republik.ch\/veranstaltungen\/russische-desinformation-und-die-schweizer-neutralitat\">Printscreen Republik<\/a><\/span><\/figcaption><\/figure>\n<p><em>RT DE<\/em> entfaltet jedenfalls gen\u00fcgend Wirkung, um selbst bei seinen sch\u00e4rfsten Kritikern <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.republik.ch\/veranstaltungen\/russische-desinformation-und-die-schweizer-neutralitat\" target=\"_blank\" rel=\"noopener noreferrer\">einen eigenen Abend zu bekommen<\/a> \u2013 nat\u00fcrlich in stilgerechter woker Atmosph\u00e4re: Meditationsmatten statt Redaktionsst\u00fchle, Klangschalen statt Argumente und sanfte Atem\u00fcbungen zur gemeinsamen Verarbeitung der n\u00e4chsten <em>RT<\/em>-Schlagzeile.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/schweiz\/290222-anti-tagi-putin-derangement-syndrom\/\">Anti-Tagi: Medien-Watchdog mit Biss \u2013 heute: NZZ-Russland-L\u00fcgen, Blick-Hysterie, SRF-AfD-Bashing<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v740oci\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/schweiz\/290420-so-viel-interesse-an-rt\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Interesse an &#8220;RT DE&#8221; ist offenbar so gro\u00df, dass das Magazin &#8220;Republik&#8221; ihm gleich ein eigenes Podium widmet. Unter dem Titel &#8220;Russische Desinformation und die Schweizer Neutralit\u00e4t&#8221; diskutieren ausgew\u00e4hlte Expertinnen und Experten \u00fcber Russland, &#8220;RT DE&#8221; und die Schweizer Politik. Von Hans-Ueli L\u00e4ppli Es gibt Themen, die lassen die Schweizer Medien einfach nicht los. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":109827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"ff1222c3eecadbcddb6c10e5870016da":["So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion"],"original_link":["https:\/\/de.rt.com\/schweiz\/290420-so-viel-interesse-an-rt\/"],"_thumbnail_id":["109827"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-09-02 21:46:28\";}"],"jnews_social_counter_last_update":["1788385589"]},"categories":[19,23],"tags":[60849,35735,275,19855,3570,580,2107,28370,3424,11607],"class_list":["post-109826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-daraus","tag-dequot","tag-eine","tag-interesse","tag-machen","tag-medien","tag-podiumsdiskussion","tag-quotrt","tag-schweizer","tag-viel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion\" \/>\n<meta property=\"og:description\" content=\"Das Interesse an &#8220;RT DE&#8221; ist offenbar so gro\u00df, dass das Magazin &#8220;Republik&#8221; ihm gleich ein eigenes Podium widmet. Unter dem Titel &#8220;Russische Desinformation und die Schweizer Neutralit\u00e4t&#8221; diskutieren ausgew\u00e4hlte Expertinnen und Experten \u00fcber Russland, &#8220;RT DE&#8221; und die Schweizer Politik. Von Hans-Ueli L\u00e4ppli Es gibt Themen, die lassen die Schweizer Medien einfach nicht los. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T19:42:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion\",\"datePublished\":\"2026-09-02T19:42:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png\",\"keywords\":[\"daraus\",\"DEquot\",\"eine\",\"Interesse\",\"machen\",\"Medien\",\"Podiumsdiskussion\",\"quotRT\",\"Schweizer\",\"viel\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/\",\"name\":\"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png\",\"datePublished\":\"2026-09-02T19:42:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png\",\"width\":1678,\"height\":398,\"caption\":\"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/","og_locale":"de_DE","og_type":"article","og_title":"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion","og_description":"Das Interesse an &#8220;RT DE&#8221; ist offenbar so gro\u00df, dass das Magazin &#8220;Republik&#8221; ihm gleich ein eigenes Podium widmet. Unter dem Titel &#8220;Russische Desinformation und die Schweizer Neutralit\u00e4t&#8221; diskutieren ausgew\u00e4hlte Expertinnen und Experten \u00fcber Russland, &#8220;RT DE&#8221; und die Schweizer Politik. Von Hans-Ueli L\u00e4ppli Es gibt Themen, die lassen die Schweizer Medien einfach nicht los. [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-09-02T19:42:16+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/6a98045d48fbef22811b84e7.png","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion","datePublished":"2026-09-02T19:42:16+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png","keywords":["daraus","DEquot","eine","Interesse","machen","Medien","Podiumsdiskussion","quotRT","Schweizer","viel"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/","url":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/","name":"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png","datePublished":"2026-09-02T19:42:16+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/So-viel-Interesse-an-quotRT-DEquot-Schweizer-Medien-machen-daraus.png","width":1678,"height":398,"caption":"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/so-viel-interesse-an-rt-de-schweizer-medien-machen-daraus-eine-podiumsdiskussion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"So viel Interesse an &quot;RT DE&quot;: Schweizer Medien machen daraus eine Podiumsdiskussion"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/109826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=109826"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/109826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/109827"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=109826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=109826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=109826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}