{"id":109742,"date":"2026-09-01T17:51:38","date_gmt":"2026-09-01T15:51:38","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/"},"modified":"2026-09-01T17:51:38","modified_gmt":"2026-09-01T15:51:38","slug":"drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/","title":{"rendered":"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg\" \/><\/p>\n<div class=\"ArticleView-bottomShares\">\n<div class=\"ShareBlock-isReact\" data-rtcomponent=\"ShareBlock\" onload=\"return {\n        socials: JSON.parse('\\u005B\\u0022facebook\\u0022,\\u0022fbmessage\\u0022,\\u0022xtwitter\\u0022,\\u0022whatsapp\\u0022,\\u0022telegram\\u0022,\\u0022mailto\\u0022,\\u0022pocket\\u0022,\\u0022copylink\\u0022,\\u0022pdflink\\u0022\\u005D'),\n        direction: JSON.parse('\\u0022row\\u0022'),\n        type: JSON.parse('\\u0022hasFull\\u0022'),\n        params: JSON.parse('\\u007B\\u0022counters\\u0022\\u003Atrue,\\u0022href\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/de.rt.com\\\\\\\/inland\\\\\\\/290366\\u002Ddrohne\\u002Din\\u002Dleipzig\\u002Dbundesregierung\\u002Dbeschuldigt\\u002Drussland\\\\\\\/\\u0022,\\u0022shortUrl\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/kurz.rt.com\\\\\\\/681q\\u0022\\u007D'),\n    };\"><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/290366-drohne-in-leipzig-bundesregierung-beschuldigt-russland\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Source link<\/p>\n","protected":false},"author":3,"featured_media":58637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"42317f20647b549a06a3d110b3520518":["Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt"],"original_link":["https:\/\/de.rt.com\/inland\/290366-drohne-in-leipzig-bundesregierung-beschuldigt-russland\/"],"_thumbnail_id":["58637"],"jnews_social_counter_last_update":["1788375989"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-09-01 17:55:30\";}"]},"categories":[19,23],"tags":[3645,3807,26825,35284,3356,21240,795,126,374],"class_list":["post-109742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-beschuldigt","tag-bundesregierung","tag-drohne","tag-gekuendigt","tag-haus","tag-leipzig","tag-russisches","tag-russland","tag-wird"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt\" \/>\n<meta property=\"og:description\" content=\"Source link\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T15:51:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt\",\"datePublished\":\"2026-09-01T15:51:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/\"},\"wordCount\":14,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"keywords\":[\"beschuldigt\",\"Bundesregierung\",\"Drohne\",\"gek\u00fcndigt\",\"Haus\",\"Leipzig\",\"Russisches\",\"russland\",\"wird\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/\",\"name\":\"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"datePublished\":\"2026-09-01T15:51:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"width\":460,\"height\":259,\"caption\":\"China beginnt mit Umzingelungs\u00fcbungen rund um Taiwan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/","og_locale":"de_DE","og_type":"article","og_title":"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt","og_description":"Source link","og_url":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-09-01T15:51:38+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt","datePublished":"2026-09-01T15:51:38+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/"},"wordCount":14,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","keywords":["beschuldigt","Bundesregierung","Drohne","gek\u00fcndigt","Haus","Leipzig","Russisches","russland","wird"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/","url":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/","name":"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","datePublished":"2026-09-01T15:51:38+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","width":460,"height":259,"caption":"China beginnt mit Umzingelungs\u00fcbungen rund um Taiwan"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/drohne-in-leipzig-bundesregierung-beschuldigt-russland-russisches-haus-wird-gekuendigt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Drohne in Leipzig: Bundesregierung beschuldigt Russland \u2013 Russisches Haus wird gek\u00fcndigt"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/109742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=109742"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/109742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/58637"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=109742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=109742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=109742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}