{"id":10790,"date":"2022-06-14T12:27:23","date_gmt":"2022-06-14T10:27:23","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/"},"modified":"2022-06-14T12:27:23","modified_gmt":"2022-06-14T10:27:23","slug":"ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/","title":{"rendered":"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/62a6f8c2b480cc3dec64d0ab.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                U\u011fur \u015eahin \u00e4u\u00dfert sich zuversichtlich \u00fcber einen Sommer mit milden Virus-Varianten. F\u00fcr den Herbst zeigt sich der BioNTech-Chef jedoch besorgt, vor allem aber hinsichtlich neuer Impfstoff-Bestellungen. Bei klinischen Studien gehe es nicht so sehr darum, ob &#8220;der angepasste Impfstoff sicher ist&#8221;. Auffrischungsimpfungen werden n\u00f6tig sein.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>von Bernhard Loyen<\/em><\/p>\n<p>Der Mitbegr\u00fcnder, -inhaber und Chef des Mainzer Unternehmens BioNTech\u00a0U\u011fur \u015eahin zeigt sich aktuell in einem l\u00e4ngeren\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.handelsblatt.com\/unternehmen\/innovationweek\/medizinischer-fortschritt-biontech-chef-ugur-sahin-wir-stecken-mitten-in-einer-revolution\/28419174.html\">Interview<\/a> mit dem <em>Handelsblatt\u00a0<\/em>beim Thema k\u00fcnftiger Absatzm\u00e4rkte mehr als zufrieden.\u00a0Die mRNA-Technologie, die sich &#8220;bei Corona-Impfstoffen bew\u00e4hrt&#8221; h\u00e4tte,\u00a0stelle f\u00fcr\u00a0\u015eahin eine &#8220;der idealen Arzneimitteltechnologien f\u00fcr die Onkologie&#8221; (der medizinischen Disziplin, die sich insbesondere mit der Behandlung von Krebserkrankungen befasst) dar. BioNTech habe demnach &#8220;rund 20 Onkologie-Programme in der Entwicklung&#8221;. Ziel\u00a0sei es, in den n\u00e4chsten drei bis f\u00fcnf Jahren &#8220;die ersten Produkte in der Krebstherapie auf den Markt zu bringen&#8221;.<\/p>\n<p>Warum im Bereich der Onkologie-Produktentwicklung drei bis f\u00fcnf Jahre ben\u00f6tigt werden, f\u00fcr den aktuellen Comirnaty-Impfstoff aus dem Hause BioNTech jedoch nur <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.businessinsider.de\/wissenschaft\/gesundheit\/biontech-chef-ugur-sahin-spricht-ueber-seinen-corona-impfstoff-d\/\">wenige Monate<\/a>, wollte das immerhin dreik\u00f6pfige Interviewer-Team leider nicht erl\u00e4utert bekommen. Aber dazu sp\u00e4ter noch mehr, ganz zum Schluss des Artikels.<\/p>\n<p>Zum Thema Prognosen hinsichtlich kommender Krisenentwicklungen in Coronazeiten zeigt sich\u00a0\u015eahin vorsichtiger und nur bedingt euphorisch.\u00a0Sollte es in Deutschland zu einer Welle der Omikron-Variante BA.5<strong>\u00a0<\/strong>im Sommer kommen, w\u00fcrde sie laut seiner Einsch\u00e4tzung &#8220;kleiner sein als bei den vorherigen Omikron-Virusvarianten BA.1 und BA.2.&#8221;, angesichts der Tatsache, dass in Afrika die BA.5-Welle &#8220;nicht die Dynamik entfaltet hat&#8221;. Es folgt eine wirklich \u00fcberraschende Erl\u00e4uterung zu den\u00a0Rahmenbedingungen der Modifizierung des aktuellen\u00a0Comirnaty-Impfstoffs.\u00a0\u015eahin erkl\u00e4rt w\u00f6rtlich:<\/p>\n<blockquote>\n<p><em>&#8220;Die Anpassung der mRNA-Sequenz erfolgt z\u00fcgig innerhalb weniger Tage. Unsere Produktionsanlagen k\u00f6nnen wir so umstellen, dass erste Impfstoffe binnen drei Monaten verf\u00fcgbar sind. Wir k\u00f6nnten also schnell reagieren.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Auch auf diese Antwort folgt keine unmittelbare Gegenfrage. Im Januar dieses Jahres wurden \u00e4hnliche\u00a0Zeitangaben seitens des BioNTech-Chefs <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.aerzteblatt.de\/nachrichten\/131229\/Biontech-und-Pfizer-starten-klinische-Studie-zu-Omikron-Impfstoff\">abgegeben<\/a>. Die Marktzulassung eines auf die Omikron-Variante modifizierten Wirkstoffs <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.boerse-online.de\/nachrichten\/aktien\/biontech-angepasster-covid-impfstoff-koennte-bis-herbst-genehmigt-werden-1031502525\">verz\u00f6gert<\/a> sich jedoch durch j\u00fcngst verlautbarte Mitteilungen des Unternehmens nun aktuell bis zum Herbst.\u00a0Kommende Impfstoffmodifikationen stellen f\u00fcr\u00a0\u015eahin nichtsdestotrotz kein &#8220;Nadel\u00f6hr&#8221; mehr dar, dies sei &#8220;ein Routineprozess, den wir Hunderte Male gemacht haben&#8221;.\u00a0<\/p>\n<p>Die folgende \u00c4u\u00dferung von\u00a0\u015eahin k\u00f6nnte man sehr gelinde ausgedr\u00fcckt als irritierend bezeichnen, sie nimmt n\u00e4mlich Bezug auf die immer h\u00e4ufiger berichtete Wahrnehmungen stetig steigender\u00a0Zahlen von Impfnebenwirkungen in Teilen der Bev\u00f6lkerung. Seitens der Politiker und der Medien werden sie aktuell zunehmend anerkannt, akzeptiert und als &#8220;Post-Vac-Syndrom&#8221; betitelt. Das Syndrom beschreibt andauernde und vor allem belastende Symptome nach einer Coronaimpfung, wie zum Beispiel Kopfschmerzen, Erm\u00fcdung, Schwindel, Herzrasen bis hin zu neurologischen Ausf\u00e4llen, wie Gesichtsl\u00e4hmungen oder Muskelverspannungen an den H\u00e4nden. Die <em>Frankfurter Allgemeine Zeitung<\/em> beschrieb das hinter einer <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.faz.net\/aktuell\/politik\/inland\/wenn-die-corona-impfung-krank-macht-das-post-vac-syndrom-18086619.html?session\">Bezahlschranke<\/a> am 8. Juni mit dem Titel &#8220;Post-Vac-Syndrom: Wenn die Corona-Impfung krank macht&#8221;.<\/p>\n<p>F\u00fcr Aufsehen sorgte die Twitter-Reaktion des Bundesgesundheitsministers Lauterbach auf die Publikation eines <em>Spiegel<\/em>-Artikels vom 12. Juni zum gleichen Thema:<\/p>\n<blockquote>\n<p><em>&#8220;Guter Artikel. Post-Vac-Syndrom muss besser untersucht werden. Wir empfehlen die Impfung gegen COVID und gegen Post-COVID. Der Nutzen \u00fcbersteigt das Risiko in jeder Altersgruppe. Trotzdem ist Post-Vac kein Tabuthema und muss erforscht und behandelt werden.&#8221;<\/em><\/p>\n<\/blockquote>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Guter Artikel. Post-Vac-Syndrom muss besser untersucht werden. Wir empfehlen die Impfung gegen COVID und gegen Post-COVID. Der Nutzen \u00fcbersteigt das Risiko in jeder Altersgruppe. Trotzdem ist Post-Vac kein Tabuthema und muss erforscht und behandelt werden. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/XrE5NaMTUq\">https:\/\/t.co\/XrE5NaMTUq<\/a><\/p>\n<p>\u2014 Prof. Karl Lauterbach (@Karl_Lauterbach) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Karl_Lauterbach\/status\/1536102844616650760?ref_src=twsrc%5Etfw\">June 12, 2022<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Erneut ohne Nachfrage der\u00a0<em>Handelsblatt<\/em>-Interviewer verpuffte \u015eahins \u00c4u\u00dferung auf die Frage, ob BioNTech bis zum Herbst &#8220;rechtzeitig&#8221; einen auf Omikron zugeschnittenen Wirkstoff produzieren k\u00f6nne, da die &#8220;Politik hofft, im Herbst einen Impfstoff anbieten zu k\u00f6nnen&#8221;:<\/p>\n<blockquote>\n<p><em>&#8220;Wir f\u00fchren seit Jahren klinische Studien mit individualisierten Krebsimpfstoffen durch, das bedeutet eine Impfstoffanpassung f\u00fcr jeden einzelnen Patienten. Was bisher am meisten Zeit in Anspruch genommen hat, sind die zus\u00e4tzlichen klinischen Studien. <\/em><\/p>\n<p><em>In denen ging es nicht so sehr um die Frage, ob der angepasste Impfstoff sicher ist, sondern ob ein mono- oder ein bivalenter Impfstoff bessere Immunantworten induziert. Diese Entscheidung wird hoffentlich Ende des Monats getroffen werden.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die Frage, &#8220;ob der angepasste Impfstoff sicher ist&#8221;, war und ist also f\u00fcr den Pharma-Produzenten eher sekund\u00e4r, von nicht so herausragender Notwendigkeit? Dagegen beziehen sich die angesprochenen mono- oder bivalenten\u00a0Eigenschaften nur auf die Frage, ob\u00a0ein modifizierter Impfstoff die F\u00e4higkeit besitzt, nur gegen eine oder gegen mehrere Erregervarianten sch\u00fctzen zu k\u00f6nnen. Eine tiefergehende Frage zum Thema, wie Erfahrungen mit &#8220;individualisierten Krebsimpfstoffen&#8221; mit den aktuellen Problemen von Herstellung und Wirkung von neuartigen mRNA-COVID-Wirkstoffen zusammenh\u00e4ngen, w\u00e4re sicherlich f\u00fcr viele Leser von gr\u00f6\u00dferem Interesse gewesen.<\/p>\n<p>Auf die Frage, wie eine &#8220;optimale Strategie&#8221; auss\u00e4he, mit der sich &#8220;die Staaten und die EU, &#8230; ihre Kunden&#8221;\u00a0auf den kommenden Herbst vorbereiten sollten, antwortete der BioNTech-Chef, er sei unzufrieden hinsichtlich einer fehlenden &#8220;international abgestimmten Strategie als Grundlage&#8221;, die das Unternehmen aber f\u00fcr die &#8220;Massenproduktion von Impfstoffen&#8221; unbedingt ben\u00f6tige:<\/p>\n<blockquote>\n<p><em>&#8220;Das hei\u00dft, wir m\u00fcssen fr\u00fch genug wissen, auf welche Variante \u2013 also zum Beispiel BA.2 oder BA.4\/5 \u2013 wir die Corona-Impfstoffe anpassen und f\u00fcr die bevorstehende Infektionssaison produzieren sollen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Diese geforderte Strategie solle sich, so\u00a0\u015eahin, an &#8220;wissenschaftlichen und m\u00f6glichst aktuellen epidemiologischen Daten orientieren&#8221;, um noch zu erg\u00e4nzen:<\/p>\n<blockquote>\n<p><em>&#8220;Wir m\u00fcssen das Rad nicht neu erfinden. Es gibt ein etabliertes System, das wir von der Anpassung von Influenza-Impfstoffen kennen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Influenza und Corona im Vergleich? Warum ist solch ein Vergleich zul\u00e4ssig bei Impfstofftypen, jedoch nicht hinsichtlich der virologischen Erreger? Und woran hapert es dann seit Monaten \u2013 bezogen auf die &#8220;erhofften&#8221; Bestellungen und die Produktion von Omikron-Wirkstoffen \u2013 gegen\u00fcber dem mittlerweile nur noch bedingt wirkenden Delta-Vakzin? Fragen \u00fcber Fragen, die leider vonseiten des Trios beim \u00a0<em>Handelsblatt<\/em> nicht gestellt wurden. Weitere Erkenntnisse von Herrn\u00a0\u015eahin im Interview lauten:<\/p>\n<blockquote>\n<p><em>&#8220;Eine Impfung wie auch eine durchgemachte Infektion sch\u00fctzen bei dieser Virusart nur tempor\u00e4r. Das Virus ver\u00e4ndert sich st\u00e4ndig, die Infektiosit\u00e4t nimmt zu, und es gibt keine Anzeichen daf\u00fcr, dass dieser Prozess langsamer wird. Wir werden mit gro\u00dfer Wahrscheinlichkeit auch k\u00fcnftig Impfstoffe brauchen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die B\u00fcrger m\u00f6gen sich schon einmal darauf einstellen, dass &#8220;wir, \u00e4hnlich wie bei der Influenza, immer wieder Auffrischungsimpfungen mit ver\u00e4nderten Vakzinen&#8221; brauchen werden. Zur Erinnerung: eine Influenza-Impfung\u00a0soll\u00a0im\u00a0Allgemeinen f\u00fcr 6 bis 12 Monate sch\u00fctzen. Innerhalb einer Grippesaison ist daher also keine Auffrischimpfung notwendig. Deutschland <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.destatis.de\/DE\/Themen\/Laender-Regionen\/Internationales\/Thema\/bevoelkerung-arbeit-soziales\/gesundheit\/Influenza-2.html\">erreichte<\/a> 2019 eine Influenza-Impfquote von 39 Prozent. Daher bezieht sich wohl der Informationswert auf die Aussage &#8220;mit ver\u00e4nderten Vakzinen&#8221;. Zu den Zeitabl\u00e4ufen zwischen den angek\u00fcndigten regelm\u00e4\u00dfigen Impfungen blitzt immerhin ein Funke Ehrlichkeit bei\u00a0\u015eahin auf:<\/p>\n<blockquote>\n<p><em>&#8220;Die Intervalle h\u00e4ngen von mehreren Faktoren ab, daher m\u00f6chte ich jetzt nicht spekulieren.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Es folgte dann ein l\u00e4ngerer Part \u00fcber den zuk\u00fcnftigen, schon anvisierten Milliardenmarkt der mRNA Krebs-Medikamente, wobei auch hier immer wieder erkenntnisbereichernde Statements vom BioNTech-Chef eingestreut werden. Eindeutige Zahlen hinsichtlich schwindender Effizienz des aktuell einzigen COVID-Impfstoffs von BioNTech resultieren vielleicht auch aus folgendem Realit\u00e4tssinn:<\/p>\n<blockquote>\n<p><em>&#8220;Heute wissen wir viel mehr \u00fcber die Mechanismen des Immunsystems, \u00fcber die Erkrankung selbst und sind mit den Technologien viel weiter. Es ist unheimlich dichtes Wissen vorhanden. Wir k\u00f6nnen fr\u00fcher und besser einsch\u00e4tzen, was nicht funktionieren wird. So k\u00f6nnen wir die Wahrscheinlichkeit f\u00fcr den Erfolg neuer Arzneien und Therapien erh\u00f6hen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der Mann ruht mit seinen Erkenntnissen offenbar in sich selbst, da die zur\u00fcckliegenden Monate ihm gezeigt haben, dass seine Auftragsb\u00fccher immer voll bleiben, das Vertrauen vonseiten der Politiker und gutgl\u00e4ubiger Menschen weltweit noch vorhanden sind. So kann &#8220;die Wahrscheinlichkeit f\u00fcr den Erfolg neuer Arzneien und Therapien&#8221; in der Entwicklung mit Ruhe von au\u00dfen begleitet werden, oder \u2013 wie es der israelische\u00a0Premierminister Benjamin Netanjahu stellvertretend f\u00fcr sein Land und weltweiter Impfkampagnen im Januar 2021 etwas salopp <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.jpost.com\/israel-news\/netanyahu-to-davos-israel-is-worlds-laboratory-for-immunity-656901\">formulierte<\/a>:<\/p>\n<blockquote>\n<p><em>&#8220;Israel ist &#8216;das Weltlabor f\u00fcr Immunit\u00e4t&#8217;.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Biotechnologie bleibe &#8220;ein sehr schwieriges Gesch\u00e4ft&#8221;, sagt \u015eahin. Aber nicht etwa bezogen auf &#8220;die\u00a0Wahrscheinlichkeit f\u00fcr den Erfolg neuer Arzneien und Therapien&#8221;, sondern die Konkurrenz h\u00e4tte deutlich zugenommen, &#8220;nicht nur in den USA&#8221;. Die Angst eines urpl\u00f6tzlichen Milliard\u00e4rs vor bald wieder schwindenden Absatzm\u00e4rkten? F\u00fcr dieses Problem gibt es ja den Kollegen Bourla vom US-Partner Pfizer, der weiterhin sehr guten, pers\u00f6nlichen Kontakt auch nach Br\u00fcssel und speziell zu Ursula von der Leyen pflegt.\u00a0Das Interview-Trio fragt dann, die Pandemie h\u00e4tte doch &#8220;Milliarden in die Kasse von BioNTech gebracht, wof\u00fcr werden Sie die ausgeben?&#8221;<\/p>\n<p>Neben Investitionen zum Beispiel in &#8220;BioNTainer&#8221;, also Spezial-Container aus dem Hause BioNTech, die ben\u00f6tigt werden, um k\u00fcnftige Impfstoffproduktionen blo\u00df nicht aus den eigenen H\u00e4nden und Laboren geben zu m\u00fcssen. Und um damit laut Pressemitteilung &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/investors.biontech.de\/de\/news-releases\/news-release-details\/biontech-gibt-update-zu-plaenen-fuer-produktion-und-entwicklung\">Pl\u00e4ne f\u00fcr Produktion<\/a>\u00a0und Entwicklung von mRNA-Impfstoffen in Afrika&#8221; voranzubringen, erl\u00e4utert U\u011fur \u015eahin im weiteren Interview seine pers\u00f6nliche Transhumanismus-Zukunfts-Gedankenwelt:\u00a0<\/p>\n<blockquote>\n<p><em>&#8220;Ich finde die Frage sehr spannend, ob es gelingen kann, Zellen im K\u00f6rper zu verj\u00fcngen und neu zu programmieren. Das ist eine riesige Herausforderung, die aber im Reagenzglas schon m\u00f6glich ist.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Diese \u00dcberlegungen dienen zum Gl\u00fcck nat\u00fcrlich nur\u00a0der\u00a0Vision, &#8220;Krankheiten erst gar nicht entstehen zu lassen\u00a0oder bei folgenschweren Verletzungen, zum Beispiel einem Herzinfarkt oder einem Hirnschlag, eine Regeneration zu beschleunigen&#8221;. Abschlie\u00dfend folgt die besonders f\u00fcr die Stadtk\u00e4mmerer von Mainz wichtige Information, dass\u00a0BioNTech auch k\u00fcnftig &#8220;ein eigenst\u00e4ndiges Unternehmen bleiben&#8221; werde. Im November 2021 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.swr.de\/swraktuell\/rheinland-pfalz\/mainz\/biontech-millionen-finanzieren-biotechnologie-standort-100.html\">meldete<\/a> der <em>SWR<\/em>, dass die Stadt Mainz\u00a0nach Sch\u00e4tzungen Gewerbesteuerzahlungen von BioNTech in einer H\u00f6he von rund einer Milliarde Euro erhalten wird.<\/p>\n<p>Das Unternehmen sei angetreten, um Produkte auf den Markt zu bringen, &#8220;um das Leben von Menschen weiter zu verbessern&#8221;. Auch da h\u00e4tte man sich von einem investigativen Interview-Trio erw\u00fcnscht, dass sie bei Herrn\u00a0\u015eahin ein paar S\u00e4tze herauskitzeln \u00fcber das nachweisliche Leiden derjenigen Menschen, die durch ein BioNTech-Produkt ihr Leben nicht noch weiter &#8220;verbessert&#8221; bekamen. Aber leider Fehlanzeige.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-youtube\">\n<div class=\"YouTubeEmbed lazyload\" data-rtmodule=\"YouTubeEmbed\" id=\"jjWeI3m2r14\" onload=\"return {\n            covers: JSON.parse('\\u007B\\u0022small\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/i.ytimg.com\\\\\\\/vi\\\\\\\/jjWeI3m2r14\\\\\\\/hqdefault.jpg\\u0022,\\u0022medium\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/i.ytimg.com\\\\\\\/vi\\\\\\\/jjWeI3m2r14\\\\\\\/sddefault.jpg\\u0022,\\u0022large\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/i.ytimg.com\\\\\\\/vi\\\\\\\/jjWeI3m2r14\\\\\\\/sddefault.jpg\\u0022\\u007D'),\n            iframeSrc: JSON.parse('\\u0022\\\\\\\/\\\\\\\/www.youtube.com\\\\\\\/embed\\\\\\\/jjWeI3m2r14\\u0022'),\n            youtubeId: JSON.parse('\\u0022jjWeI3m2r14\\u0022'),\n        };\"><\/p>\n<div class=\"YouTubeEmbed-cover\"><button class=\"YouTubeEmbed-button\"><svg class=\"YouTubeEmbed-playButton\" height=\"100%\" version=\"1.1\" viewbox=\"0 0 68 48\" width=\"100%\"><path class=\"YouTubeEmbed-playButtonBg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#212121\" fill-opacity=\"0.8\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div>\n<\/div>\n<\/div>\n<p>\u015eahin<strong>\u00a0<\/strong>hegt \u00fcbrigens keinerlei Absichten, Aktien-Anteile zu verkaufen. Ganz zum Schluss des Interviews kommt wieder die Unzufriedenheit von\u00a0U\u011fur \u015eahin zum Vorschein.\u00a0Im Vergleich &#8220;zur Corona-Impfstoff-Entwicklung geht es in der Krebstherapie qu\u00e4lend langsam voran&#8221;, \u00fcbergibt das Handelsblatt-Trio den Beschwerde-Ball wieder an \u015eahin.\u00a0Das sei leider so, \u00fcbernimmt der CEO das freundliche Zuspiel. Die Entwicklung neuer Medikamente &#8220;muss schneller werden, keine Frage&#8221;. Ohne R\u00fccksicht auf die &#8220;Wahrscheinlichkeit f\u00fcr den Erfolg neuer Arzneien und Therapien, Herr\u00a0\u015eahin?&#8221; So m\u00f6chte man eigentlich spontan fragen, nicht so das Handelsblatt. Wie das verbessert werden k\u00f6nnte, lautet daher dort die Frage. Die Idee von Herrn \u015eahin, sein Vorschlag lautet:<\/p>\n<blockquote>\n<p><em>&#8220;Im Grunde k\u00f6nnte man die Erkenntnisse aus der Corona-Impfstoffentwicklung auf den Onkologie-Bereich \u00fcbertragen und damit die Entwicklung von Krebsmitteln erheblich beschleunigen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Gott bewahre, werden da viele\u00a0Post-Vac-Syndrom-Leidende denken, ganz im Gegensatz zu den innerlich jubilierenden BioNTech-Aktion\u00e4ren.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/140636-pei-ruckt-impf-meldedaten-heraus\/\">PEI r\u00fcckt Impf-Meldedaten heraus: \u00dcber 1.000 gesch\u00e4digte und neun verstorbene Minderj\u00e4hrige<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/140899-biontech-chef-ugur-sahin-ist\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>U\u011fur \u015eahin \u00e4u\u00dfert sich zuversichtlich \u00fcber einen Sommer mit milden Virus-Varianten. F\u00fcr den Herbst zeigt sich der BioNTech-Chef jedoch besorgt, vor allem aber hinsichtlich neuer Impfstoff-Bestellungen. Bei klinischen Studien gehe es nicht so sehr darum, ob &#8220;der angepasste Impfstoff sicher ist&#8221;. Auffrischungsimpfungen werden n\u00f6tig sein. von Bernhard Loyen Der Mitbegr\u00fcnder, -inhaber und Chef des Mainzer [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"8bbfe4f3d38d920143deba70894d72a1":["&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage"],"original_link":["https:\/\/de.rt.com\/meinung\/140899-biontech-chef-ugur-sahin-ist\/"],"_thumbnail_id":["10791"],"_wptg_p2tg_sent2tg":["2022-06-14 12:42:05"],"jnews_social_counter_last_update":["1784142057"]},"categories":[19,23],"tags":[24402,24404,82,1777,275,16962,221,8019,24403,24401,23084,3737,24405,22337],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage\" \/>\n<meta property=\"og:description\" content=\"U\u011fur \u015eahin \u00e4u\u00dfert sich zuversichtlich \u00fcber einen Sommer mit milden Virus-Varianten. F\u00fcr den Herbst zeigt sich der BioNTech-Chef jedoch besorgt, vor allem aber hinsichtlich neuer Impfstoff-Bestellungen. Bei klinischen Studien gehe es nicht so sehr darum, ob &#8220;der angepasste Impfstoff sicher ist&#8221;. Auffrischungsimpfungen werden n\u00f6tig sein. von Bernhard Loyen Der Mitbegr\u00fcnder, -inhaber und Chef des Mainzer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T10:27:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage\",\"datePublished\":\"2022-06-14T10:27:23+00:00\",\"dateModified\":\"2022-06-14T10:27:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/\"},\"wordCount\":1849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg\",\"keywords\":[\"angepasste\",\"BioNTechChef\",\"der\",\"eher\",\"eine\",\"Frage\",\"f\u00fcr\",\"Impfstoff\",\"istquot\",\"quotOb\",\"\u015eahin\",\"scheint\",\"sekund\u00e4re\",\"sicher\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/\",\"name\":\"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg\",\"datePublished\":\"2022-06-14T10:27:23+00:00\",\"dateModified\":\"2022-06-14T10:27:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage","og_description":"U\u011fur \u015eahin \u00e4u\u00dfert sich zuversichtlich \u00fcber einen Sommer mit milden Virus-Varianten. F\u00fcr den Herbst zeigt sich der BioNTech-Chef jedoch besorgt, vor allem aber hinsichtlich neuer Impfstoff-Bestellungen. Bei klinischen Studien gehe es nicht so sehr darum, ob &#8220;der angepasste Impfstoff sicher ist&#8221;. Auffrischungsimpfungen werden n\u00f6tig sein. von Bernhard Loyen Der Mitbegr\u00fcnder, -inhaber und Chef des Mainzer [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-06-14T10:27:23+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage","datePublished":"2022-06-14T10:27:23+00:00","dateModified":"2022-06-14T10:27:23+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/"},"wordCount":1849,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg","keywords":["angepasste","BioNTechChef","der","eher","eine","Frage","f\u00fcr","Impfstoff","istquot","quotOb","\u015eahin","scheint","sekund\u00e4re","sicher"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/","url":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/","name":"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg","datePublished":"2022-06-14T10:27:23+00:00","dateModified":"2022-06-14T10:27:23+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/quotOb-der-angepasste-Impfstoff-sicher-istquot-scheint-fuer-BioNTech-Chef-Sahin.jpg","width":460,"height":259,"caption":"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ob-der-angepasste-impfstoff-sicher-ist-scheint-fuer-biontech-chef-sahin-eine-eher-sekundaere-frage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Ob der angepasste Impfstoff sicher ist&quot; scheint f\u00fcr BioNTech-Chef \u015eahin eine eher sekund\u00e4re Frage"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10790"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=10790"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/10791"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=10790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=10790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=10790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}