{"id":106914,"date":"2026-07-15T19:34:08","date_gmt":"2026-07-15T17:34:08","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/"},"modified":"2026-07-15T19:34:08","modified_gmt":"2026-07-15T17:34:08","slug":"amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/","title":{"rendered":"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/6a57a1a348fbef7e0567fcfe.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die gegenseitige Abneigung zwischen dem amtierenden und dem gew\u00e4hlten Pr\u00e4sidenten Kolumbiens ist so gro\u00df, dass die Zeremonie der Macht\u00fcbergabe in einen Skandal zu m\u00fcnden droht. Petro erkennt das Wahlergebnis nicht an und will deswegen de la Espriella keine Hand geben.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Bei einer Regierungsberatung in Bogot\u00e1 hat der scheidende kolumbianische Pr\u00e4sident Gustavo Petro am Dienstag den Abgrund zwischen ihm und dem gew\u00e4hlten Staatschef Abelardo de la Espriella weiter aufgerissen. Der linke Politiker <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/actualidad.rt.com\/actualidad\/616841-petro-anunciar-ir-posesion-abelardo-espriella\">wiederholte<\/a> seine These, wonach es einen Wahlbetrug gegeben habe. Daher erkenne er den rechten Politiker nicht als Staatschef an. Mit Blick auf die bevorstehende Inaugurationszeremonie de la Espriellas sagte Petro:<\/p>\n<blockquote>\n<p><em>&#8220;Am 7. August werde ich nicht da sein und ihm\u00a0nicht die Hand geben. Er mag sagen, was er will. Aber er wei\u00df, warum. Weil das ein Betrug ist.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>In diesem Zusammenhang k\u00fcndigte der amtierende Pr\u00e4sident an, dass er am Donnerstag weitere Beweise\u00a0f\u00fcr den angeblichen Wahlbetrug vorlegen und weitere Klagen einreichen werde. Durch seine strafrechtlichen Beschwerden wolle er durchsetzen, dass man das Wahlergebnis f\u00fcr ung\u00fcltig erkl\u00e4re, betonte Petro.<\/p>\n<p>Bei der Pr\u00e4sidentenwahl war de la Espriella auf rund 49,6 Prozent der Stimmen gekommen, w\u00e4hrend sein Rivale aus dem linken Lager, Iv\u00e1n Cepeda, rund 48,7 Prozent auf sich vereinigt hatte. Petro selbst durfte gem\u00e4\u00df der Verfassung nicht mehr antreten.<\/p>\n<p>Internationale Beobachter lobten die Transparenz und Effizienz des Urnengangs. Dennoch lie\u00df der verschwindend kleine Abstand von 0,96 Prozent der Stimmen das linke Lager von einem m\u00f6glichen Betrug sprechen. Cepeda gestand seine knappe Niederlage zwar ein, rief aber die Kolumbianer zum &#8220;zivilen Ungehorsam&#8221; auf.<\/p>\n<p>Petro warf dem rechten Politiker vor, f\u00fcr seinen Sieg die Souver\u00e4nit\u00e4t Kolumbiens aufgegeben zu haben. Damit\u00a0bezog sich der amtierende Pr\u00e4sident darauf, dass sein US-Amtskollege Donald Trump noch w\u00e4hrend des Wahlkampfs offen f\u00fcr de la Espriella geworben hatte.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/europa\/284752-toedlicher-streit-zwischen-drei-kameraden\/\">T\u00f6dlicher Streit zwischen drei Kameraden in Ukraine: Chilene erschie\u00dft zwei Kolumbianer<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v78sodo\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/amerika\/285955-kontaktlose-praesidentschaftsuebergabe-in-kolumbien\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die gegenseitige Abneigung zwischen dem amtierenden und dem gew\u00e4hlten Pr\u00e4sidenten Kolumbiens ist so gro\u00df, dass die Zeremonie der Macht\u00fcbergabe in einen Skandal zu m\u00fcnden droht. Petro erkennt das Wahlergebnis nicht an und will deswegen de la Espriella keine Hand geben. Bei einer Regierungsberatung in Bogot\u00e1 hat der scheidende kolumbianische Pr\u00e4sident Gustavo Petro am Dienstag den [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":106915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1784137003"],"wp_automatic_camp":["217"],"b4f60cfebbd75f20847130ffe4eb6cbc":["Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben"],"original_link":["https:\/\/de.rt.com\/amerika\/285955-kontaktlose-praesidentschaftsuebergabe-in-kolumbien\/"],"_thumbnail_id":["106915"],"jnews_social_counter_last_update":["1784144260"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-07-15 19:37:43\";}"]},"categories":[19,23],"tags":[74657,38373,45,73576,789,8748,21583,800,26776],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben\" \/>\n<meta property=\"og:description\" content=\"Die gegenseitige Abneigung zwischen dem amtierenden und dem gew\u00e4hlten Pr\u00e4sidenten Kolumbiens ist so gro\u00df, dass die Zeremonie der Macht\u00fcbergabe in einen Skandal zu m\u00fcnden droht. Petro erkennt das Wahlergebnis nicht an und will deswegen de la Espriella keine Hand geben. Bei einer Regierungsberatung in Bogot\u00e1 hat der scheidende kolumbianische Pr\u00e4sident Gustavo Petro am Dienstag den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T17:34:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/6a57a1a348fbef7e0567fcfe.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben\",\"datePublished\":\"2026-07-15T17:34:08+00:00\",\"dateModified\":\"2026-07-15T17:34:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg\",\"keywords\":[\"Abelardo\",\"Amts\u00fcbergabe\",\"die\",\"Espriella\",\"geben\",\"hand\",\"Kolumbien\",\"nicht\",\"Petro\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/\",\"name\":\"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg\",\"datePublished\":\"2026-07-15T17:34:08+00:00\",\"dateModified\":\"2026-07-15T17:34:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg\",\"width\":460,\"height\":259,\"caption\":\"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/","og_locale":"de_DE","og_type":"article","og_title":"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben","og_description":"Die gegenseitige Abneigung zwischen dem amtierenden und dem gew\u00e4hlten Pr\u00e4sidenten Kolumbiens ist so gro\u00df, dass die Zeremonie der Macht\u00fcbergabe in einen Skandal zu m\u00fcnden droht. Petro erkennt das Wahlergebnis nicht an und will deswegen de la Espriella keine Hand geben. Bei einer Regierungsberatung in Bogot\u00e1 hat der scheidende kolumbianische Pr\u00e4sident Gustavo Petro am Dienstag den [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-07-15T17:34:08+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/6a57a1a348fbef7e0567fcfe.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben","datePublished":"2026-07-15T17:34:08+00:00","dateModified":"2026-07-15T17:34:08+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg","keywords":["Abelardo","Amts\u00fcbergabe","die","Espriella","geben","hand","Kolumbien","nicht","Petro"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/","url":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/","name":"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg","datePublished":"2026-07-15T17:34:08+00:00","dateModified":"2026-07-15T17:34:08+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/Amtsuebergabe-in-Kolumbien-Petro-will-Abelardo-de-la-Espriella-nicht.jpg","width":460,"height":259,"caption":"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/amtsuebergabe-in-kolumbien-petro-will-abelardo-de-la-espriella-nicht-die-hand-geben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Amts\u00fcbergabe in Kolumbien: Petro will Abelardo de la Espriella nicht die Hand geben"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/106914"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=106914"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/106914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/106915"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=106914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=106914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=106914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}