{"id":10683,"date":"2022-06-13T06:30:00","date_gmt":"2022-06-13T04:30:00","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/"},"modified":"2022-06-13T06:30:00","modified_gmt":"2022-06-13T04:30:00","slug":"russland-und-das-bologna-system-den-albtraum-vergessen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/","title":{"rendered":"Russland und das Bologna-System: Den Albtraum vergessen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/62a10d40b480cc6d36659bfd.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Argumente, die das Bologna-System verteidigen, sind hohl. Es gibt keinen Grund, russische Studenten weiterhin gem\u00e4\u00df fremder Formate und Programme zu unterrichten, die in der russischen Umgebung nicht funktionieren, so unsere Gastautorin Anna Schafran.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Ein Kommentar von Anna Schafran<\/em><\/p>\n<p>Was die Russen gut k\u00f6nnen, ist lernen. Nach dem Sieg bei Poltawa hat Peter der Gro\u00dfe einen Toast auf die schwedischen Lehrer ausgesprochen. Die gefangenen Schweden verzogen das Gesicht, aber sie tranken. Denn sie konnten sich nirgendwo verkriechen. Den Grundstein f\u00fcr das russische Hochschulsystem legte Peters Tochter Elisabeth. Schon sehr bald brachte die Moskauer Universit\u00e4t Spezialisten hervor, die denen an den alten westlichen Universit\u00e4ten in nichts nachstanden.<\/p>\n<p>In den ersten Jahren der Sowjetunion gab es Bestrebungen, sowohl die Schul- als auch die Hochschulbildung zu modernisieren und zu verbessern, aber bald wurde klar, dass es nichts Besseres als das klassische System gab. Und die Menschen, die an den sowjetischen Universit\u00e4ten ausgebildet wurden, machten die UdSSR zu einer der zwei m\u00e4chtigsten Nationen der Welt.<\/p>\n<p>In den 1990er-Jahren wurde alles Sowjetische als falsch und erfolglos angesehen. W\u00e4re Wladimir Putin nicht gewesen, so h\u00e4tte Russland meines Erachtens Mitte der Nullerjahre jegliche Souver\u00e4nit\u00e4t verloren und w\u00e4re das US-\u00c4quivalent zu Kanada geworden: Nur eine formale Unabh\u00e4ngigkeit \u2013 eben in dem Sinne, dass nichts von Kanada abh\u00e4ngig ist.<\/p>\n<p>F\u00fcr uns w\u00e4re das gleichbedeutend mit dem Tod. Russland kann keine unterw\u00fcrfige Haltung einnehmen. Und, nebenbei bemerkt, hat Peter der Gro\u00dfe, auch wenn er links und rechts europ\u00e4ische Normen durchsetzte, dies nur getan, um Russland zu st\u00e4rken. Doch die Reformer der 1990er-Jahre und ihre Nachfolger entnahmen dem gesamten reichen euro-atlantischen Arsenal aus irgendeinem Grund nur das, was Russland schw\u00e4cher machte.<\/p>\n<p>Was verkehrt am Bologna-System ist? Es erm\u00f6glicht nicht die Ausbildung einer ausreichenden Zahl qualifizierter Fachkr\u00e4fte, auf deren Arbeit das wirtschaftliche Wohlergehen und die technische Souver\u00e4nit\u00e4t eines jeden Staates beruhen. Ich bin dem Irrglauben begegnet, dass der Bologna-Prozess ein klassisches europ\u00e4isches Bildungssystem darstelle und dass eine Abkehr davon gleichbedeutend mit der Preisgabe einer jahrhundertealten universit\u00e4ren und akademischen Bildung sei.<\/p>\n<p>Aber nein, genau das Gegenteil! Die Bologna-Deklaration wurde 1999 unterzeichnet und sie verfolgte ein einfaches Ziel. Die L\u00e4nder des vereinten Europas sollten abgesahnt werden, damit die besten Studenten aus den weniger wohlhabenden ost- und s\u00fcdeurop\u00e4ischen L\u00e4ndern keine Probleme bei der Integration in Westeuropa haben w\u00fcrden. Das gleiche Schicksal war f\u00fcr unsere Studenten vorgesehen. Die F\u00e4higsten w\u00fcrden von den westeurop\u00e4ischen Staubsauger-Hirnsaugern mitgenommen werden.<\/p>\n<p>Heute erinnert sich kaum noch jemand daran, doch in den sp\u00e4ten 1990er-Jahren war George Soros der Hauptsponsor der heimischen Wissenschaft. Nat\u00fcrlich tat er dies nicht aus N\u00e4chstenliebe, sondern um die Abh\u00e4ngigkeit zu festigen und die Unabh\u00e4ngigkeit der russischen Wissenschaft zu zerst\u00f6ren. Schlie\u00dflich bewegte sich unser Land in jenen Jahren am Rande eines Abgrunds, dessen Tiefe wir erst jetzt erkennen.<\/p>\n<p>Ich m\u00f6chte darauf hinweisen, dass die Vereinigten Staaten &#8211; unser wichtigster geopolitischer Konkurrent &#8211; dem Bologna-System nicht beigetreten sind. Aber auch China bricht wirtschaftliche Rekorde, ohne den neu erfundenen europ\u00e4ischen Hirnsauger zu kopieren.<\/p>\n<p>Weshalb also sollten wir unsere Studenten weiterhin gem\u00e4\u00df fremder Formate und Programme unterrichten, die in unserer Umgebung nicht gut funktionieren? Die St\u00e4rke des sowjetischen Bildungswesens bestand darin, dass die Abg\u00e4nger sofort arbeitsf\u00e4hige Spezialisten waren, die ohne weitere Ausbildung oder zus\u00e4tzlichem Praktika f\u00e4hig waren, sofort mit der Arbeit zu beginnen. Und wo das Analogon eines westlichen Master-Abschlusses n\u00f6tig war, wie in der Medizin, dort gab es nach dem medizinischen Staatsexamen die praktische fach\u00e4rztliche Ausbildung.<\/p>\n<p>Es ist inzwischen offensichtlich, dass wir sehr ernste Probleme mit der Vorbereitung von spezialisiertem Personal haben, wor\u00fcber sowohl die Vertreter der Industrie als auch die Dozenten selbst sprechen.<\/p>\n<p>Dieses Gebiet ist von strategischer Bedeutung, um die technologische Souver\u00e4nit\u00e4t des Landes zu gew\u00e4hrleisten, insbesondere unter Ber\u00fccksichtigung der Sanktionen, die niemand ausdr\u00fccklich aufheben wird. Wir ben\u00f6tigen also das beste System, und das war zweifelsohne das sowjetische.<\/p>\n<p>Leider hat man heute den Eindruck, dass die Beh\u00f6rden im Bildungswesen mit allen Mitteln versuchen, Dinge zu erhalten, die nicht funktionieren. Weil es bereits zur Routine geworden ist. Doch alle Argumente, die das Bologna-System verteidigen, sind voller Sinnlosigkeit. Tatsache ist, dass die Fachrichtungen zerst\u00f6rt wurden und dass danach die Personalprobleme begannen. Das bedeutet, dass wir nichts Neues erfinden und lediglich das bisherige erfolgreiche System wiederherstellen m\u00fcssen. Gl\u00fccklicherweise erinnern sich die meisten P\u00e4dagogen noch sehr gut daran, wie es war und was zu tun ist.<\/p>\n<p>In Russland kommt es bedauerlicherweise oft vor, dass der Gesetzgeber ein Problem sieht und operativ Beschl\u00fcsse fasst, um es zu l\u00f6sen. In Ministerien und Abteilungen aber kommt es zu Verz\u00f6gerungen. Wir d\u00fcrfen uns jetzt nicht mit halben Sachen zufriedengeben. Qualifizierte Fachkr\u00e4fte sind eine strategische Angelegenheit. Das hei\u00dft, die Zeit ist gekommen, das Bologna-System als schlechten Albtraum zu vergessen.<\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/russian.rt.com\/opinion\/1010995-shafran-rossiya-bolonskaya-sistema-uhod\">Russischen<\/a>.<\/em><\/p>\n<p><em>Anna Schafran <\/em><em>ist eine Fernseh- und Radiomoderatorin. Sie hat ein Buch mit dem Titel &#8220;Der Staat der Ehre. Die Monarchie als Zukunft Russlands&#8221; geschrieben und ver\u00f6ffentlicht. Seit 2020 arbeitet sie als unabh\u00e4ngige Moderatorin eigener Radio- und Fernsehsendungen und bloggt im Internet. Shafran ist ihr Pseudonym, ihr richtiger Name ist Palyukh.<strong><\/strong>[Mehr zur <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/uznayvse.ru\/znamenitosti\/biografiya-anna-shafran.html\">Autorin<\/a>] <br \/><\/em><\/p>\n<p><strong>Mehr zum Thema <\/strong>&#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/test.rtde.tech\/russland\/139453-aus-fur-bologna-reform-russland\/\">Aus f\u00fcr Bologna-Reform: Russland beendet Teilnahme an europ\u00e4ischem Hochschulsystem <\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/140585-russland-und-bologna-system-albtraum-vergessen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Argumente, die das Bologna-System verteidigen, sind hohl. Es gibt keinen Grund, russische Studenten weiterhin gem\u00e4\u00df fremder Formate und Programme zu unterrichten, die in der russischen Umgebung nicht funktionieren, so unsere Gastautorin Anna Schafran. Ein Kommentar von Anna Schafran Was die Russen gut k\u00f6nnen, ist lernen. Nach dem Sieg bei Poltawa hat Peter der Gro\u00dfe einen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"f9e652bec2f08bcb9f2f757159ddbeb8":["Russland und das Bologna-System: Den Albtraum vergessen"],"original_link":["https:\/\/de.rt.com\/meinung\/140585-russland-und-bologna-system-albtraum-vergessen\/"],"_thumbnail_id":["10684"],"_wptg_p2tg_sent2tg":["2022-06-13 06:42:52"],"jnews_social_counter_last_update":["1784142363"]},"categories":[19,23],"tags":[18993,24246,427,48,126,140,24185],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Russland und das Bologna-System: Den Albtraum vergessen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russland und das Bologna-System: Den Albtraum vergessen\" \/>\n<meta property=\"og:description\" content=\"Argumente, die das Bologna-System verteidigen, sind hohl. Es gibt keinen Grund, russische Studenten weiterhin gem\u00e4\u00df fremder Formate und Programme zu unterrichten, die in der russischen Umgebung nicht funktionieren, so unsere Gastautorin Anna Schafran. Ein Kommentar von Anna Schafran Was die Russen gut k\u00f6nnen, ist lernen. Nach dem Sieg bei Poltawa hat Peter der Gro\u00dfe einen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-13T04:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russland und das Bologna-System: Den Albtraum vergessen\",\"datePublished\":\"2022-06-13T04:30:00+00:00\",\"dateModified\":\"2022-06-13T04:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/\"},\"wordCount\":912,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg\",\"keywords\":[\"Albtraum\",\"BolognaSystem\",\"das\",\"den\",\"russland\",\"und\",\"VERGESSEN\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/\",\"name\":\"Russland und das Bologna-System: Den Albtraum vergessen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg\",\"datePublished\":\"2022-06-13T04:30:00+00:00\",\"dateModified\":\"2022-06-13T04:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Russland und das Bologna-System: Den Albtraum vergessen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russland und das Bologna-System: Den Albtraum vergessen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russland und das Bologna-System: Den Albtraum vergessen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/","og_locale":"de_DE","og_type":"article","og_title":"Russland und das Bologna-System: Den Albtraum vergessen","og_description":"Argumente, die das Bologna-System verteidigen, sind hohl. Es gibt keinen Grund, russische Studenten weiterhin gem\u00e4\u00df fremder Formate und Programme zu unterrichten, die in der russischen Umgebung nicht funktionieren, so unsere Gastautorin Anna Schafran. Ein Kommentar von Anna Schafran Was die Russen gut k\u00f6nnen, ist lernen. Nach dem Sieg bei Poltawa hat Peter der Gro\u00dfe einen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-06-13T04:30:00+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russland und das Bologna-System: Den Albtraum vergessen","datePublished":"2022-06-13T04:30:00+00:00","dateModified":"2022-06-13T04:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/"},"wordCount":912,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg","keywords":["Albtraum","BolognaSystem","das","den","russland","und","VERGESSEN"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/","url":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/","name":"Russland und das Bologna-System: Den Albtraum vergessen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg","datePublished":"2022-06-13T04:30:00+00:00","dateModified":"2022-06-13T04:30:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Russland-und-das-Bologna-System-Den-Albtraum-vergessen.jpg","width":460,"height":259,"caption":"Russland und das Bologna-System: Den Albtraum vergessen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-und-das-bologna-system-den-albtraum-vergessen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russland und das Bologna-System: Den Albtraum vergessen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10683"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=10683"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/10684"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=10683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=10683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=10683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}