{"id":106826,"date":"2026-07-14T06:30:00","date_gmt":"2026-07-14T04:30:00","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/"},"modified":"2026-07-14T06:30:00","modified_gmt":"2026-07-14T04:30:00","slug":"in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/","title":{"rendered":"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/6a54e25cb480cc6f9a5767f8.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Bis zu f\u00fcnf Jahre ins Gef\u00e4ngnis soll, wer &#8220;das Existenzrecht des Staates Israel leugnet&#8221;. Dass der von Hessen vorgeschlagene, offensichtlich verfassungswidrige Eingriff in die Meinungsfreiheit den Bundesrat passiert hat, zeigt vor allem eins: Deutschlands wachsende Aggression nach au\u00dfen richtet sich auch nach innen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Alexandra Nollok<\/em><\/p>\n<p>Deutsche Politiker sind erfindungsreich, wenn es darum geht, die von ihnen milit\u00e4risch und diplomatisch unterst\u00fctzte Vernichtung der Pal\u00e4stinenser durch Israel zu rechtfertigen. Sie verharmlosen oder leugnen live gestreamte Verbrechen, weichen konsequent den Fragen aus und verschleiern, welche R\u00fcstungslieferungen sie genehmigen. Aggressiv geht die Justiz derweil gegen jene vor, die \u00f6ffentlich ein Ende des Abschlachtens mit deutschen Waffen fordern \u2013 je evidenter die israelischen Gr\u00e4ueltaten werden, desto rabiater.<\/p>\n<p>Doch all ihre Resolutionen und Verbote, die Strafverfolgung und Polizeigewalt konnten die Proteste zwar eind\u00e4mmen, aber nicht stoppen. \u00dcber den Umweg der Hessischen Landesregierung haben sie nun erneut zugeschlagen. Per <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bundesrat.de\/DE\/plenum\/bundesrat-kompakt\/26\/1067\/1067-pk.html%20\">Gesetzesinitiative<\/a> , die vergangene Woche vom Bundesrat mehrheitlich gebilligt wurde, wollen sie nun den Volksverhetzungsparagrafen 130 im Strafgesetzbuch um folgende Passage erweitern:<\/p>\n<blockquote>\n<p><em>&#8220;Mit Freiheitsstrafe bis zu f\u00fcnf Jahren oder mit Geldstrafe wird bestraft, wer in einer Weise, die geeignet ist, die Bereitschaft zu antisemitischen Gewalt- oder Willk\u00fcrma\u00dfnahmen zu f\u00f6rdern, \u00f6ffentlich oder in einer Versammlung das Existenzrecht des Staates Israel leugnet oder zur Beseitigung des Staates Israel aufruft.&#8221;<\/em><\/p>\n<\/blockquote>\n<p><strong>Kriminalisierend und verfassungswidrig<\/strong><\/p>\n<p>Abgesehen davon, dass das V\u00f6lkerrecht kein Existenzrecht f\u00fcr Nationalstaaten vorsieht \u2013 sie k\u00f6nnen sich jederzeit aufl\u00f6sen, neu gr\u00fcnden, teilen, was seit jeher auch passiert \u2013, ist die schwammige Formulierung schnell beliebig interpretierbar. Wenn beispielsweise jemand nur den Stopp deutscher Waffenlieferungen fordert, um Israels genozidales Vorgehen gegen die Pal\u00e4stinenser zu beenden, k\u00f6nnte die Justiz ihm bereits einen &#8220;Vernichtungswunsch&#8221; durch vermeintliche Beeintr\u00e4chtigung von Israels &#8220;Verteidigungsf\u00e4higkeit&#8221; unterstellen.<\/p>\n<p>Tats\u00e4chlich \u00fcberziehen Polizei und Staatsanwaltschaften schon jetzt propal\u00e4stinensische Demonstranten mit Repressalien. Von Oktober 2023 bis November 2025 leiteten diese allein in Berlin fast 12.000 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rbb24.de\/panorama\/beitrag\/2025\/12\/berlin-polizei-tausende-ermittlungen-nahost-konflikt-antisemitismus.html\">Ermittlungsverfahren<\/a> vor allem wegen \u00c4u\u00dferungsdelikten ein, darunter vorneweg die Parole &#8220;From the River to the Sea\u2026&#8221;. Viele Verfahren stellen die Gerichte zwar am Ende ein, einige h\u00e4ngen je nach pers\u00f6nlicher Interpretation, jedoch teils saftigeren Geldstrafen. Wie die Autorin erfuhr, nimmt die Verfolgung vermeintlich &#8220;israelfeindlicher&#8221; \u00c4u\u00dferungen in Deutschland derzeit eher zu als ab.<\/p>\n<p>Dabei gibt es seitens der Rechtswissenschaft kaum Zweifel daran, dass der hessische Gesetzentwurf <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.lto.de\/recht\/meinung\/m\/bundesrat-straftatbestand-leugnung-existenzrecht-israel-verfassungswidrig\">verfassungswidrig<\/a> sein d\u00fcrfte. Sogar die wissenschaftlichen Dienste des Bundestages <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bundestag.de\/resource\/blob\/1182798\/WD-3-064-26.pdf\">bekr\u00e4ftigten<\/a> diese Auffassung im Mai. Dennoch stimmten mit Ausnahme von Bremen und Mecklenburg-Vorpommern alle Bundesl\u00e4ndern zu. Die beiden Genannten enthielten sich, weil die mitregierende Linkspartei dagegen war, ihre Koalitionspartner aber daf\u00fcr.<\/p>\n<p><strong>Nicht der erste Versuch<\/strong><\/p>\n<p>Das ist nicht der erste Versuch dieser Art, die grundrechtlich verbriefte Meinungs- und Pressefreiheit per Sonderrecht f\u00fcr Israel auszuhebeln. Im vorletzten Jahr <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bundesrat.de\/SharedDocs\/drucksachen\/2023\/0601-0700\/647-2-23.pdf?__blob=publicationFile&amp;v=1\">scheiterte<\/a> ein \u00e4hnlicher Antrag aus Nordrhein-Westfalen und Schleswig-Holstein vor der L\u00e4nderkammer wegen mutma\u00dflicher Verfassungswidrigkeit.\u00a0<\/p>\n<p>Erfolgreich war gegen die <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rosalux.de\/fileadmin\/rls_uploads\/pdfs\/Studien\/Studien_6-26_UNRWA_Web.pdf\">Kriminalisierung<\/a> der BDS-Kampagne per Resolution bereits im Jahr 2019, die laut einer aktuellen Studie der Rosa-Luxemburg-Stiftung ma\u00dfgeblich auf Betreiben israelischer Lobbyorganisationen zustande kam. Die Kampagne fordert Boykott, Desinvestition und Sanktionen gegen Israel, solange der Staat die v\u00f6lkerrechtswidrige Besatzung fortf\u00fchrt \u2013 alles Mittel, die von internationalem Recht gedeckt, ja sogar erw\u00fcnscht w\u00e4ren.<\/p>\n<p>Damals war sogar die AfD mit einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/dserver.bundestag.de\/btd\/19\/097\/1909757.pdf\">Antrag<\/a> unter dem Titel &#8220;BDS-Bewegung verurteilen \u2012 Existenz des Staates Israel sch\u00fctzen&#8221; vorangeschritten. Dem wollte Kraft &#8220;Brandmauer&#8221; keiner zustimmen. So zogen CDU, CSU, SPD und FDP schnurstracks mit einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bundestag.de\/webarchiv\/textarchiv\/2019\/kw20-de-bds-642892\">eigenen<\/a> gemeinsamen Antrag nach. Der wurde schlie\u00dflich mehrheitlich angenommen und in eine Resolution gegossen. Denn etwas v\u00f6lkerrechtlich Legitimes per Gesetz zu verbieten, schien damals wohl noch nicht m\u00f6glich. Auswirkungen hat der Vorsto\u00df dennoch. Zahlreiche Urteile gegen Pal\u00e4stina-Aktivisten verweisen n\u00e4mlich darauf.<\/p>\n<p><strong>Neue Mehrheiten im Bundestag?<\/strong><\/p>\n<p>Heute k\u00f6nnte es anders laufen und das Gesetz den Bundestag sogar passieren. CDU und CSU d\u00fcrften geschlossen daf\u00fcr stimmen. M\u00f6gliche Abweichler in der mitregierenden SPD k\u00f6nnten Teile der Opposition wettmachen. F\u00fcrsprecher werden sich wohl in allen anderen Fraktionen finden: bei den Gr\u00fcnen, vielleicht einige proisraelische sogenannte &#8220;Antideutsche&#8221; bei den Linken und erst recht in der AfD.<\/p>\n<p>Die AfD ist nicht nur bei der Anti-BDS-Resolution mit einem Antrag vorangegangen. Bereits Anfang Oktober 2023 setzte sie sich als erste auch f\u00fcr das <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bundestag.de\/presse\/hib\/kurzmeldungen-971082\">Verbot<\/a> pal\u00e4stinensischer Diaspora-Organisationen ein, wie das linke Gefangenen-Netzwerk Samidoun sowie die sich selbst als marxistisch betrachtende Partei PFLP. Auch hier zog die Regierung schnell nach.<\/p>\n<p>Zur gleichen Zeit <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.radiohamburg.de\/aktuelles\/hamburg\/Hamburger-CDU-und-AfD-fordern-Verbot-von-Pro-Pal%C3%A4stina-Demo-id980131.html\">forderte<\/a>\u00a0 die Hamburger AfD-Fraktion gemeinsam mit der CDU ein Verbot aller Pro-Pal\u00e4stina-Demonstrationen. Vor einem Jahr <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/afdbundestag.de\/statt-pro-palaestinensischer-parteinahme-sollte-wadephul-politik-im-interesse-deutschlands-machen\/\">warf<\/a> die Partei im Bundestag dem deutschen CDU-Au\u00dfenminister Johann Wadephul sogar vor, die Pal\u00e4stinenser mehr zu unterst\u00fctzen als Israel. Die Fakten belegen das Gegenteil.<\/p>\n<p><strong>Aggressiv, repressiv, antisemitisch<\/strong><\/p>\n<p>Die Begr\u00fcndung Hessens f\u00fcr den neuen Straftatbestand klingt <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/staatskanzlei.hessen.de\/presse\/gesetzentwurf-zur-leugnung-des-existenzrechts-israels-vorgestellt%20\">diesmal<\/a> besonders aggressiv. Danach relativiere der Gebrauch des Slogans &#8220;Vom Fluss bis zum Meer \u2013 Pal\u00e4stina wird frei sein&#8221; sogar den Holocaust und billige unterschwellige Gewalt gegen\u00fcber allen Juden \u2013 auch in Deutschland.<\/p>\n<p>Das ist nicht nur eine geistige Verrenkung nach mittelalterlicher Manier, etwa von der Kunst, wie sie etwa der deutsche Inlandsgeheimdienst mit seiner Interpretation von &#8220;Extremismus&#8221; in seinen Berichten und Pressemitteilungen betreibt. Es ist auch eine klassisch antisemitische Verkn\u00fcpfung deutscher Juden mit dem Nationalstaat Israel, der seit Jahrzehnten auf V\u00f6lkerrecht und Menschenrechte pfeift. Deutsche Politiker setzen damit einfach mal voraus, dass Juden in aller Welt nur Israel treu sein k\u00f6nnten.<\/p>\n<p>Dass es Hessens Landesregierung unter Ministerpr\u00e4sident Boris Rhein (CDU) dabei eher nicht um &#8220;j\u00fcdisches Leben&#8221; im Allgemeinen geht, hat sie h\u00f6chstselbst belegt: Allein zwischen Januar und Mai dieses Jahres trommelte ihr Antisemitismusbeauftragter Uwe Becker (CDU) dreimal f\u00fcr ein Verbot des antizionistischen Vereins &#8220;J\u00fcdische Stimme&#8221; ( <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/staatskanzlei.hessen.de\/presse\/antisemitismusbeauftragter-kritisiert-missbrauch-des-holocaust-gedenkens\">hier<\/a> , <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/staatskanzlei.hessen.de\/presse\/wer-gegen-die-voelkerverstaendigung-hetzt-und-gewaltaufrufe-unterstuetzt-gehoert-verboten\">hier<\/a> und <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/staatskanzlei.hessen.de\/presse\/der-verein-ist-keine-stimme-des-friedens-sondern-eine-stimme-des-hasses\">hier<\/a> ).<\/p>\n<p>Er bezichtigte die j\u00fcdische Organisation darin, &#8220;antisemitisch&#8221; zu <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/reel\/C_x_eqlyA3M\/\">hetzen<\/a> \u2013 w\u00e4hrend er selbst bei einer Ehrung israelischer Soldaten mit einer Gro\u00dfisrael-Troph\u00e4e postete. Pal\u00e4stinensern das Lebensrecht absprechen und die T\u00f6tung von mittlerweile \u00fcber 75.000 Menschen, darunter 20.000 Kinder, zu bejubeln, ist in Deutschland offensichtlich kein Problem. Man k\u00f6nnte dahinter Rassismus vermuten.<\/p>\n<p><strong>Kritiker zum Schweigen bringen<\/strong><\/p>\n<p>Sollte der Entwurf den Bundestag passieren und in ein Gesetz gegossen werden, k\u00f6nnte der Staat damit zumindest vorerst jeden Protest pr\u00e4ventiv verbieten, der nur ansatzweise irgendetwas mit Israel zu tun hat. Gerichte bek\u00e4men Instrumente an die Hand, um V\u00f6lkermord- und R\u00fcstungsgegner reihenweise zu inhaftieren, wenn sie nur irgendeine Parole mitgerufen haben, die man irgendwie als &#8220;Israelfeindschaft&#8221; interpretieren k\u00f6nnte \u2013 selbst dann, wenn sich dieser zum Beispiel gegen den in Deutschland ans\u00e4ssigen israelischen R\u00fcstungskonzern Elbit Systems richten w\u00fcrde.<\/p>\n<p>Doch nicht nur Aktivisten w\u00fcrde so ein Gesetz noch weiter kriminalisieren und einsch\u00fcchtern, sondern auch die wenigen Journalisten, die sich \u00fcberhaupt noch trauen, \u00fcber israelische Verbrechen kritisch zu berichten. Dann m\u00fcsste die Politik nicht mehr den Umweg \u00fcber die EU nehmen, welche bekanntlich auf Deutschlands Antrag hin den deutschen <em>Red.Media<\/em> -Gr\u00fcnder H\u00fcseyin Do\u011fru existenzvernichtend sanktioniert hat und daf\u00fcr ausdr\u00fccklich dessen Berichterstattung \u00fcber Pal\u00e4stina-Proteste an einer Universit\u00e4t <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/eur-lex.europa.eu\/legal-content\/DE\/TXT\/?uri=OJ:L_202500965\">anf\u00fchrt<\/a> .<\/p>\n<p>Um Juden geht es den Antragstellern und Abnickern ganz sicher nicht. Es geht darum, unliebsame Meinungen zum Schweigen zu bringen, die Pressearbeit politisch zu regulieren und unerw\u00fcnschte Fakten zu verschleiern \u2013 notfalls mit Gewalt. Das kriegsl\u00fcsterne Deutschland wird Ruhe haben vor kritischen Stimmen im eigenen Land. Imperialistische &#8220;Drecksarbeit&#8221; erforderte eben gehorsame B\u00fcrger \u2013 aggressive Au\u00dfenpolitik richtet sich immer auch nach innen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/meinung\/284844-deutsche-staatsraeson-wer-korrekter-jude\/\">Deutsche Staatsr\u00e4son: Wer ein korrekter Jude ist, bestimmt der Verfassungsschutz<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v7a5hiy\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async defer src=\"https:\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/285731-in-knast-per-staatsraeson-bundesrat\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bis zu f\u00fcnf Jahre ins Gef\u00e4ngnis soll, wer &#8220;das Existenzrecht des Staates Israel leugnet&#8221;. Dass der von Hessen vorgeschlagene, offensichtlich verfassungswidrige Eingriff in die Meinungsfreiheit den Bundesrat passiert hat, zeigt vor allem eins: Deutschlands wachsende Aggression nach au\u00dfen richtet sich auch nach innen. Von Alexandra Nollok Deutsche Politiker sind erfindungsreich, wenn es darum geht, die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":106827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1784004028"],"wp_automatic_camp":["217"],"aeb313d0ad0a6f025642d983c5c93165":["In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg"],"original_link":["https:\/\/de.rt.com\/meinung\/285731-in-knast-per-staatsraeson-bundesrat\/"],"_thumbnail_id":["106827"],"jnews_social_counter_last_update":["1784107924"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-07-14 06:41:36\";}"]},"categories":[19,23],"tags":[74619,133,74618,21086,48,16201,42052],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg\" \/>\n<meta property=\"og:description\" content=\"Bis zu f\u00fcnf Jahre ins Gef\u00e4ngnis soll, wer &#8220;das Existenzrecht des Staates Israel leugnet&#8221;. Dass der von Hessen vorgeschlagene, offensichtlich verfassungswidrige Eingriff in die Meinungsfreiheit den Bundesrat passiert hat, zeigt vor allem eins: Deutschlands wachsende Aggression nach au\u00dfen richtet sich auch nach innen. Von Alexandra Nollok Deutsche Politiker sind erfindungsreich, wenn es darum geht, die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T04:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/6a54e25cb480cc6f9a5767f8.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg\",\"datePublished\":\"2026-07-14T04:30:00+00:00\",\"dateModified\":\"2026-07-14T04:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/\"},\"wordCount\":1259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg\",\"keywords\":[\"Abweg\",\"AUF\",\"autokratischem\",\"Bundesrat\",\"den\",\"Knast\",\"Staatsr\u00e4son\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/\",\"name\":\"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg\",\"datePublished\":\"2026-07-14T04:30:00+00:00\",\"dateModified\":\"2026-07-14T04:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg\",\"width\":460,\"height\":259,\"caption\":\"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/","og_locale":"de_DE","og_type":"article","og_title":"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg","og_description":"Bis zu f\u00fcnf Jahre ins Gef\u00e4ngnis soll, wer &#8220;das Existenzrecht des Staates Israel leugnet&#8221;. Dass der von Hessen vorgeschlagene, offensichtlich verfassungswidrige Eingriff in die Meinungsfreiheit den Bundesrat passiert hat, zeigt vor allem eins: Deutschlands wachsende Aggression nach au\u00dfen richtet sich auch nach innen. Von Alexandra Nollok Deutsche Politiker sind erfindungsreich, wenn es darum geht, die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-07-14T04:30:00+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/6a54e25cb480cc6f9a5767f8.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg","datePublished":"2026-07-14T04:30:00+00:00","dateModified":"2026-07-14T04:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/"},"wordCount":1259,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg","keywords":["Abweg","AUF","autokratischem","Bundesrat","den","Knast","Staatsr\u00e4son"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/","url":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/","name":"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg","datePublished":"2026-07-14T04:30:00+00:00","dateModified":"2026-07-14T04:30:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/07\/In-den-Knast-per-Staatsraeson-Bundesrat-auf-autokratischem-Abweg.jpg","width":460,"height":259,"caption":"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/in-den-knast-per-staatsraeson-bundesrat-auf-autokratischem-abweg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"In den Knast per Staatsr\u00e4son: Bundesrat auf autokratischem Abweg"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/106826"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=106826"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/106826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/106827"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=106826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=106826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=106826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}